{"id":3674,"date":"2020-07-15T21:49:33","date_gmt":"2020-07-15T19:49:33","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=3674"},"modified":"2020-07-15T21:53:21","modified_gmt":"2020-07-15T19:53:21","slug":"una-fiscalita-equa-e-semplice-la-commissione-propone-nuove-misure","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/una-fiscalita-equa-e-semplice-la-commissione-propone-nuove-misure\/","title":{"rendered":"Una fiscalit\u00e0 equa e semplice, la Commissione europea propone nuove misure"},"content":{"rendered":"<p><span class=\"dropcap dropcap3\">L<\/span>a <strong>Commissione europea<\/strong> ha adottato oggi un nuovo ambizioso pacchetto fiscale per garantire che la politica dell&#8217;UE in materia di tassazione sostenga la ripresa economica e la crescita a lungo termine dell&#8217;Europa.<\/p>\n<p>Il pacchetto si fonda sui due pilastri dell&#8217;equit\u00e0 e della semplicit\u00e0. Per la Commissione europea una fiscalit\u00e0 equa rimane una priorit\u00e0 assoluta, in quanto strumento per proteggere le entrate pubbliche che avr\u00e0 un ruolo importante nel breve periodo per la ripresa economica dell&#8217;UE e, nel lungo periodo, per la sua prosperit\u00e0.<\/p>\n<p>Il pacchetto di oggi mira a promuovere l&#8217;<strong>equit\u00e0 fiscale<\/strong>, intensificando la lotta contro gli abusi fiscali, riducendo la concorrenza fiscale sleale e aumentando la trasparenza fiscale. Parallelamente il pacchetto si concentra sulla semplificazione delle norme e delle procedure fiscali per migliorare il contesto in cui operano le imprese in tutta l&#8217;UE, anche mediante la rimozione di ostacoli fiscali e oneri amministrativi a carico dei contribuenti in molti settori, in modo che sia pi\u00f9 facile per le imprese prosperare e crescere nel mercato unico.<\/p>\n<p>Il pacchetto odierno si compone di <strong>tre<\/strong> iniziative distinte ma correlate:<\/p>\n<ul>\n<li>il <strong>piano d&#8217;azione in materia fiscale<\/strong> presenta 25 diverse azioni per una fiscalit\u00e0 pi\u00f9 semplice, pi\u00f9 equa e pi\u00f9 in sintonia con l&#8217;economia moderna nei prossimi anni. Queste azioni renderanno la vita pi\u00f9 semplice ai contribuenti onesti, rimuovendo ostacoli in ogni fase, dalla registrazione alla risoluzione delle controversie, passando per la dichiarazione, il pagamento e la verifica. Il piano d&#8217;azione aiuter\u00e0 gli Stati membri a sfruttare il potenziale dei dati e delle nuove tecnologie, a lottare pi\u00f9 efficacemente contro la frode fiscale, a migliorare il rispetto dell&#8217;obbligo tributario e a ridurre gli oneri amministrativi;<\/li>\n<li>la <strong>proposta sulla cooperazione amministrativa<\/strong> (DAC 7) estende le norme dell&#8217;UE in materia di trasparenza fiscale alle piattaforme digitali, in modo che coloro che fanno profitto con la vendita di beni o servizi sulle piattaforme paghino anch&#8217;essi una giusta quota di tasse. La nuova proposta garantir\u00e0 che gli Stati membri scambino automaticamente informazioni sui ricavi generati dai venditori sulle piattaforme online. La proposta intende inoltre rafforzare e chiarire le norme in altri ambiti in cui gli Stati membri collaborano per lottare contro gli abusi fiscali, ad esempio mediante controlli fiscali congiunti;<\/li>\n<li>la <strong>comunicazione sulla buona governance in materia fiscale<\/strong> \u00e8 incentrata sulla promozione di una fiscalit\u00e0 equa e sul contrasto della concorrenza fiscale sleale, nell&#8217;UE e a livello internazionale. A tal fine la Commissione propone una riforma del codice di condotta, che affronti le questioni relative alla concorrenza fiscale e contrasti le pratiche fiscali dannose all&#8217;interno dell&#8217;UE. Propone inoltre di migliorare la lista UE delle giurisdizioni non cooperative, che riguarda i paesi terzi che si rifiutano di seguire le norme convenute a livello internazionale. Finora la lista ha incoraggiato i paesi terzi ad adottare norme di buona governance in materia fiscale, ma occorre fare di pi\u00f9. La comunicazione illustra inoltre l&#8217;approccio dell&#8217;UE alla cooperazione in materia di fiscalit\u00e0 con i paesi in via di sviluppo, in linea con l&#8217;Agenda 2030 per lo sviluppo sostenibile.<\/li>\n<\/ul>\n<p>Il pacchetto odierno costituisce la prima parte di un&#8217;ambiziosa agenda globale dell&#8217;UE in materia fiscale per i prossimi anni. La Commissione lavorer\u00e0 anche su un nuovo approccio alla tassazione delle imprese per il XXI secolo, per affrontare le sfide dell&#8217;economia digitale e garantire che tutte le multinazionali paghino una giusta quota di tasse.<\/p>\n<p>Nel contesto del Green Deal la Commissione presenter\u00e0 proposte per garantire che la fiscalit\u00e0 sostenga l&#8217;obiettivo dell&#8217;UE di raggiungere la neutralit\u00e0 climatica entro il 2050. Questo approccio poliedrico alla riforma della fiscalit\u00e0 nell&#8217;UE mira a rendere la tassazione pi\u00f9 equa, pi\u00f9 verde e adatta all&#8217;economia moderna, contribuendo in tal modo a una crescita sostenibile, inclusiva e a lungo termine.<\/p>\n<p>Valdis <strong>Dombrovskis<\/strong>, Vicepresidente esecutivo per Un&#8217;economia al servizio delle persone, ha dichiarato: <em>&#8220;Oggi pi\u00f9 che mai gli Stati membri hanno bisogno di entrate fiscali sicure per investire nelle persone e nelle imprese che ne hanno pi\u00f9 bisogno. Al tempo stesso, dobbiamo abbattere gli ostacoli fiscali, cos\u00ec che le imprese dell&#8217;UE riescano pi\u00f9 facilmente a innovare, investire e crescere. Il pacchetto fiscale odierno ci porta nella giusta direzione, contribuendo a rendere la fiscalit\u00e0 pi\u00f9 equa, pi\u00f9 semplice e pi\u00f9 adatta al nostro mondo digitale.&#8221;<\/em><\/p>\n<p>Paolo <strong>Gentiloni<\/strong>, Commissario per l&#8217;Economia, ha dichiarato: &#8220;<em>Una fiscalit\u00e0 equa rappresenta il trampolino che consentir\u00e0 alla nostra economia di riprendersi dalla crisi. Quando si tratta di pagare le tasse, dobbiamo rendere la vita pi\u00f9 facile a imprese e cittadini onesti e pi\u00f9 difficile a truffatori ed evasori. Queste proposte aiuteranno gli Stati membri ad assicurarsi le entrate di cui hanno bisogno per investire nelle persone e nelle infrastrutture, creando nel contempo un contesto fiscale migliore per i cittadini e le imprese in tutta Europa.&#8221;<\/em><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Commissione europea ha adottato oggi un nuovo ambizioso pacchetto fiscale per garantire che la politica dell&#8217;UE in materia di tassazione sostenga la ripresa economica e la crescita a lungo termine dell&#8217;Europa. Il pacchetto si fonda sui due pilastri dell&#8217;equit\u00e0 e della semplicit\u00e0. Per la Commissione europea una fiscalit\u00e0 equa rimane una priorit\u00e0 assoluta, in [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1115,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41],"tags":[1030,1156,42],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Una fiscalit\u00e0 equa e semplice, la Commissione europea propone nuove misure -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/una-fiscalita-equa-e-semplice-la-commissione-propone-nuove-misure\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Una fiscalit\u00e0 equa e semplice, la Commissione europea propone nuove misure -\" \/>\n<meta property=\"og:description\" content=\"La Commissione europea ha adottato oggi un nuovo ambizioso pacchetto fiscale per garantire che la politica dell&#8217;UE in materia di tassazione sostenga la ripresa economica e la crescita a lungo termine dell&#8217;Europa. Il pacchetto si fonda sui due pilastri dell&#8217;equit\u00e0 e della semplicit\u00e0. Per la Commissione europea una fiscalit\u00e0 equa rimane una priorit\u00e0 assoluta, in [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/una-fiscalita-equa-e-semplice-la-commissione-propone-nuove-misure\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-15T19:49:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-07-15T19:53:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/06\/tasse-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"807\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/una-fiscalita-equa-e-semplice-la-commissione-propone-nuove-misure\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/una-fiscalita-equa-e-semplice-la-commissione-propone-nuove-misure\/\",\"name\":\"Una fiscalit\u00e0 equa e semplice, la Commissione europea propone nuove misure -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/una-fiscalita-equa-e-semplice-la-commissione-propone-nuove-misure\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/una-fiscalita-equa-e-semplice-la-commissione-propone-nuove-misure\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/06\/tasse-1.jpg\",\"datePublished\":\"2020-07-15T19:49:33+00:00\",\"dateModified\":\"2020-07-15T19:53:21+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/una-fiscalita-equa-e-semplice-la-commissione-propone-nuove-misure\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/una-fiscalita-equa-e-semplice-la-commissione-propone-nuove-misure\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/una-fiscalita-equa-e-semplice-la-commissione-propone-nuove-misure\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/06\/tasse-1.jpg\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/06\/tasse-1.jpg\",\"width\":807,\"height\":720,\"caption\":\"tasse\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/una-fiscalita-equa-e-semplice-la-commissione-propone-nuove-misure\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Una fiscalit\u00e0 equa e semplice, la Commissione europea propone nuove misure\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Una fiscalit\u00e0 equa e semplice, la Commissione europea propone nuove misure -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/una-fiscalita-equa-e-semplice-la-commissione-propone-nuove-misure\/","og_locale":"it_IT","og_type":"article","og_title":"Una fiscalit\u00e0 equa e semplice, la Commissione europea propone nuove misure -","og_description":"La Commissione europea ha adottato oggi un nuovo ambizioso pacchetto fiscale per garantire che la politica dell&#8217;UE in materia di tassazione sostenga la ripresa economica e la crescita a lungo termine dell&#8217;Europa. Il pacchetto si fonda sui due pilastri dell&#8217;equit\u00e0 e della semplicit\u00e0. Per la Commissione europea una fiscalit\u00e0 equa rimane una priorit\u00e0 assoluta, in [&hellip;]","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/una-fiscalita-equa-e-semplice-la-commissione-propone-nuove-misure\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2020-07-15T19:49:33+00:00","article_modified_time":"2020-07-15T19:53:21+00:00","og_image":[{"width":807,"height":720,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/06\/tasse-1.jpg","type":"image\/jpeg"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/una-fiscalita-equa-e-semplice-la-commissione-propone-nuove-misure\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/una-fiscalita-equa-e-semplice-la-commissione-propone-nuove-misure\/","name":"Una fiscalit\u00e0 equa e semplice, la Commissione europea propone nuove misure -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/una-fiscalita-equa-e-semplice-la-commissione-propone-nuove-misure\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/una-fiscalita-equa-e-semplice-la-commissione-propone-nuove-misure\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/06\/tasse-1.jpg","datePublished":"2020-07-15T19:49:33+00:00","dateModified":"2020-07-15T19:53:21+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/una-fiscalita-equa-e-semplice-la-commissione-propone-nuove-misure\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/una-fiscalita-equa-e-semplice-la-commissione-propone-nuove-misure\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/una-fiscalita-equa-e-semplice-la-commissione-propone-nuove-misure\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/06\/tasse-1.jpg","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/06\/tasse-1.jpg","width":807,"height":720,"caption":"tasse"},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/una-fiscalita-equa-e-semplice-la-commissione-propone-nuove-misure\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"Una fiscalit\u00e0 equa e semplice, la Commissione europea propone nuove misure"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/3674"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=3674"}],"version-history":[{"count":3,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/3674\/revisions"}],"predecessor-version":[{"id":3679,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/3674\/revisions\/3679"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/1115"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=3674"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=3674"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=3674"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}