{"id":3755,"date":"2020-07-24T10:23:47","date_gmt":"2020-07-24T08:23:47","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=3755"},"modified":"2020-07-24T10:28:58","modified_gmt":"2020-07-24T08:28:58","slug":"5-per-mille-2019anticipata-la-pubblicazione-degli-elenchi","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/5-per-mille-2019anticipata-la-pubblicazione-degli-elenchi\/","title":{"rendered":"Agenzia entrate: 5 per mille 2019 Anticipata la pubblicazione degli elenchi"},"content":{"rendered":"<p><span class=\"dropcap dropcap3\">L<\/span>\u2019<strong>Agenzia delle Entrate<\/strong> ha pubblicato in anticipo, rispetto alla data del 31 luglio 2020 prevista dall\u2019articolo 156 del <strong>DL Rilancio<\/strong>, gli elenchi per la destinazione del 5 per mille 2019, con i dati relativi alle preferenze espresse dai contribuenti nella propria dichiarazione dei redditi.<\/p>\n<p>In tal modo, l\u2019Agenzia ha inteso dare una risposta concreta e il pi\u00f9 vicino possibile alle esigenze dei beneficiari: oltre 58mila enti tra volontariato, ricerca sanitaria e scientifica, associazioni sportive dilettantistiche, beni culturali e paesaggistici ed enti gestori delle aree protette, cui s\u2019aggiungono 8.032Comuni.<\/p>\n<p>L\u2019elenco degli enti ammessi e di quelli esclusi \u00e8 quindi gi\u00e0 online insieme alle scelte e agli importi attribuiti,ed \u00e8 consultabile sul sito dell\u2019Agenzia delle Entrate, nell\u2019area tematica \u201c5 per mille\u201d. 5 per mille: i numeri del 2019 \u2013<\/p>\n<p>L\u2019elenco degli ammessi comprende in totale 58.636enti, suddivisi per categoria: in cima alla classifica gli enti del volontariato (47.522),a seguire le associazioni sportive dilettantistiche (10.372), gli enti impegnati nella ricerca scientifica (500), quelli che operano nel settore della sanit\u00e0 (106), gli enti dei beni culturali e paesaggistici (112) e gli enti gestori delle aree protette (24).<\/p>\n<p>In particolare, ai Comuni per il 2019, sono destinati 14,9milioni di euro. Le preferenze dei contribuenti: ricerca in testa -L\u2019Associazione italiana per la ricerca sul cancro (Airc) occupa anche per il 2019 il primo posto sia tra gli enti impegnati nel settore della ricerca sanitaria sia tra quelli che operano in quello della ricerca scientifica.<\/p>\n<p>Per il primo ambito, sono oltre 412mila le scelte espresse con un importo totale che supera i 18,6 milioni di euro.<\/p>\n<p>Per quanto riguarda, invece, la ricerca scientifica i contribuenti che hanno espresso la preferenza per l\u2019Airc superano 1 milione, con oltre 40 milionidi euro di beneficio.<\/p>\n<p>In totale,l\u2019importo destinato all\u2019Airc nel settore della ricerca scientifica e della ricerca sanitaria, ammonta a 58,6 milioni di euro, cui si aggiungono pi\u00f9 di 7,7 milioni di euro per le scelte espresse nella categoria del volontariato.<\/p>\n<div class=\"page\" data-page-number=\"1\" data-loaded=\"true\">\n<div class=\"annotationLayer\"><\/div>\n<\/div>\n<div class=\"page\" data-page-number=\"2\" data-loaded=\"true\"><\/div>\n<p>&nbsp;<\/p>\n<div id=\"mainContainer\">\n<div id=\"viewerContainer\" tabindex=\"0\">\n<div id=\"viewer\" class=\"pdfViewer\">\n<div class=\"page\" data-page-number=\"2\" data-loaded=\"true\">\n<div class=\"annotationLayer\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019Agenzia delle Entrate ha pubblicato in anticipo, rispetto alla data del 31 luglio 2020 prevista dall\u2019articolo 156 del DL Rilancio, gli elenchi per la destinazione del 5 per mille 2019, con i dati relativi alle preferenze espresse dai contribuenti nella propria dichiarazione dei redditi. In tal modo, l\u2019Agenzia ha inteso dare una risposta concreta e [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1923,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41],"tags":[1182,393,1183],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Agenzia entrate: 5 per mille 2019 Anticipata la pubblicazione degli elenchi -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/5-per-mille-2019anticipata-la-pubblicazione-degli-elenchi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Agenzia entrate: 5 per mille 2019 Anticipata la pubblicazione degli elenchi -\" \/>\n<meta property=\"og:description\" content=\"L\u2019Agenzia delle Entrate ha pubblicato in anticipo, rispetto alla data del 31 luglio 2020 prevista dall\u2019articolo 156 del DL Rilancio, gli elenchi per la destinazione del 5 per mille 2019, con i dati relativi alle preferenze espresse dai contribuenti nella propria dichiarazione dei redditi. In tal modo, l\u2019Agenzia ha inteso dare una risposta concreta e [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/5-per-mille-2019anticipata-la-pubblicazione-degli-elenchi\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-24T08:23:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-07-24T08:28:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/10\/tasse-fisco-finanza-imposte.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/5-per-mille-2019anticipata-la-pubblicazione-degli-elenchi\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/5-per-mille-2019anticipata-la-pubblicazione-degli-elenchi\/\",\"name\":\"Agenzia entrate: 5 per mille 2019 Anticipata la pubblicazione degli elenchi -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/5-per-mille-2019anticipata-la-pubblicazione-degli-elenchi\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/5-per-mille-2019anticipata-la-pubblicazione-degli-elenchi\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/10\/tasse-fisco-finanza-imposte.jpg\",\"datePublished\":\"2020-07-24T08:23:47+00:00\",\"dateModified\":\"2020-07-24T08:28:58+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/5-per-mille-2019anticipata-la-pubblicazione-degli-elenchi\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/5-per-mille-2019anticipata-la-pubblicazione-degli-elenchi\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/5-per-mille-2019anticipata-la-pubblicazione-degli-elenchi\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/10\/tasse-fisco-finanza-imposte.jpg\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/10\/tasse-fisco-finanza-imposte.jpg\",\"width\":960,\"height\":640},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/5-per-mille-2019anticipata-la-pubblicazione-degli-elenchi\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Agenzia entrate: 5 per mille 2019 Anticipata la pubblicazione degli elenchi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Agenzia entrate: 5 per mille 2019 Anticipata la pubblicazione degli elenchi -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/5-per-mille-2019anticipata-la-pubblicazione-degli-elenchi\/","og_locale":"it_IT","og_type":"article","og_title":"Agenzia entrate: 5 per mille 2019 Anticipata la pubblicazione degli elenchi -","og_description":"L\u2019Agenzia delle Entrate ha pubblicato in anticipo, rispetto alla data del 31 luglio 2020 prevista dall\u2019articolo 156 del DL Rilancio, gli elenchi per la destinazione del 5 per mille 2019, con i dati relativi alle preferenze espresse dai contribuenti nella propria dichiarazione dei redditi. In tal modo, l\u2019Agenzia ha inteso dare una risposta concreta e [&hellip;]","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/5-per-mille-2019anticipata-la-pubblicazione-degli-elenchi\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2020-07-24T08:23:47+00:00","article_modified_time":"2020-07-24T08:28:58+00:00","og_image":[{"width":960,"height":640,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/10\/tasse-fisco-finanza-imposte.jpg","type":"image\/jpeg"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/5-per-mille-2019anticipata-la-pubblicazione-degli-elenchi\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/5-per-mille-2019anticipata-la-pubblicazione-degli-elenchi\/","name":"Agenzia entrate: 5 per mille 2019 Anticipata la pubblicazione degli elenchi -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/5-per-mille-2019anticipata-la-pubblicazione-degli-elenchi\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/5-per-mille-2019anticipata-la-pubblicazione-degli-elenchi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/10\/tasse-fisco-finanza-imposte.jpg","datePublished":"2020-07-24T08:23:47+00:00","dateModified":"2020-07-24T08:28:58+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/5-per-mille-2019anticipata-la-pubblicazione-degli-elenchi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/5-per-mille-2019anticipata-la-pubblicazione-degli-elenchi\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/5-per-mille-2019anticipata-la-pubblicazione-degli-elenchi\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/10\/tasse-fisco-finanza-imposte.jpg","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/10\/tasse-fisco-finanza-imposte.jpg","width":960,"height":640},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/5-per-mille-2019anticipata-la-pubblicazione-degli-elenchi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"Agenzia entrate: 5 per mille 2019 Anticipata la pubblicazione degli elenchi"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/3755"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=3755"}],"version-history":[{"count":2,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/3755\/revisions"}],"predecessor-version":[{"id":3757,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/3755\/revisions\/3757"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/1923"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=3755"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=3755"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=3755"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}