{"id":3816,"date":"2020-07-31T10:25:02","date_gmt":"2020-07-31T08:25:02","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=3816"},"modified":"2020-07-31T10:25:02","modified_gmt":"2020-07-31T08:25:02","slug":"coronavirus-in-7-giorni-23-nuovi-casi-rispetto-alla-settimana-precedente","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-in-7-giorni-23-nuovi-casi-rispetto-alla-settimana-precedente\/","title":{"rendered":"Coronavirus, in 7 giorni +23% nuovi casi rispetto alla settimana precedente"},"content":{"rendered":"<p><span class=\"dropcap dropcap3\">I<\/span>l monitoraggio indipendente della Fondazione GIMBE rileva nella settimana 22-28 luglio, rispetto alla precedente, un incremento del 23,3% dei nuovi casi (1.736 vs 1.408), a fronte di un lieve aumento del numero di tamponi diagnostici.<\/p>\n<p>Relativamente ai dati ospedalieri, se i pazienti in terapia intensiva diminuiscono (40 vs 49), quelli ricoverati con sintomi sono in lieve aumento (749 vs 732).<\/p>\n<p>In dettaglio:<br \/>\nDecessi: 50 (+0,1%)<br \/>\nTerapia intensiva: -9 (-18,4%)<br \/>\nRicoverati con sintomi: +17 (+2,3%)<br \/>\nNuovi casi totali: +1.736 (+0,7%)<br \/>\nTamponi diagnostici: +17.859 (+10,4%)<br \/>\nTamponi totali: +28.080 (+9,3%)<\/p>\n<p>\u00abNell\u2019ultima settimana \u2013 afferma <strong>Nino Cartabellotta<\/strong>, Presidente della Fondazione GIMBE \u2013 due spie rosse confermano la necessit\u00e0 di mantenere alta la guardia, senza allarmismi ma con senso di grande responsabilit\u00e0 individuale e collettiva\u00bb.<\/p>\n<p>Infatti, oltre al netto aumento dei nuovi casi (+ 23,3% rispetto alla settimana precedente), per la prima volta si registra un\u2019inversione di tendenza nel trend dei pazienti ospedalizzati con sintomi, che era in costante discesa da inizio aprile. Una ragione in pi\u00f9 per rendere disponibile il numero dei nuovi pazienti ricoverati e dimessi dall\u2019ospedale e dalle terapie intensive quotidianamente, visto che i dati si riferiscono solo al \u201csaldo\u201d, ovvero al numero dei posti letto occupati, quale indice del sovraccarico ospedaliero.<\/p>\n<p>Nel quadro di un netto incremento dei nuovi casi nella settimana 22-28 luglio rispetto alla precedente (+328) si rilevano notevoli variazioni regionali: solo in 6 Regioni i casi sono in riduzione, mentre in 15 sono in aumento. Incremento moderato in Emilia-Romagna (+70), Prov. Aut. Trento (+65) e Campania (+56), netta riduzione in Veneto (-73). Parametrando i nuovi casi alla popolazione residente, tra le Regioni che fanno registrare il maggior incremento per 100.000 abitanti, svetta la Provincia Autonoma di Trento (13,86), seguita da Valle D\u2019Aosta (7,96), Emilia-Romagna (7,56), Molise (7,53) e Basilicata (7,28).<\/p>\n<p>\u00abQuale indicatore della diffusione del contagio \u2013 spiega Cartabellotta \u2013 abbiamo rivalutato la distribuzione geografica dei 12.609 casi attivi al 28 luglio, i cosiddetti casi \u201cattualmente positivi\u201d secondo la denominazione della Protezione Civile, aumentati di 361 unit\u00e0 rispetto alla settimana precedente\u00bb. Il 53% si concentra in Lombardia (6.678); un ulteriore 37,4% si distribuisce tra Emilia-Romagna (1.459), Lazio (942), Piemonte (801), Veneto (754), Campania (393), Toscana (363); i rimanenti 1.219 casi (9,6%) in 14 Regioni e Province autonome.<\/p>\n<p>In generale, i dati confermano sia il quadro epidemiologico di circolazione endemica del virus, sia il trend in aumento dei nuovi casi dopo due settimane di relativa stabilit\u00e0, siano essi legati a nuovi focolai o a casi di \u201cimportazione\u201d dall\u2019estero.<\/p>\n<p>\u00abDavanti a numeri in rialzo rispetto alle settimane precedenti \u2013 conclude il Presidente \u2013 la comunicazione della politica e delle Istituzioni deve essere oggettiva, equilibrata e coerente. La pandemia \u00e8 ancora in corso, il virus \u00e8 vivo e vegeto e vanno mantenuti tutti i comportamenti individuali raccomandati da mesi, oltre che le misure di sorveglianza epidemiologica. Non \u00e8 pi\u00f9 accettabile disorientare i cittadini strumentalizzando la pandemia per fini esclusivamente politici, contrapponendo posizioni estreme: da un lato negazionismo, minimizzazioni del fenomeno e deplorevoli comportamenti individuali, dall\u2019altro la proroga dello stato di emergenza nazionale\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il monitoraggio indipendente della Fondazione GIMBE rileva nella settimana 22-28 luglio, rispetto alla precedente, un incremento del 23,3% dei nuovi casi (1.736 vs 1.408), a fronte di un lieve aumento del numero di tamponi diagnostici. Relativamente ai dati ospedalieri, se i pazienti in terapia intensiva diminuiscono (40 vs 49), quelli ricoverati con sintomi sono in [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2731,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[128],"tags":[877,880],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Coronavirus, in 7 giorni +23% nuovi casi rispetto alla settimana precedente -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-in-7-giorni-23-nuovi-casi-rispetto-alla-settimana-precedente\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Coronavirus, in 7 giorni +23% nuovi casi rispetto alla settimana precedente -\" \/>\n<meta property=\"og:description\" content=\"Il monitoraggio indipendente della Fondazione GIMBE rileva nella settimana 22-28 luglio, rispetto alla precedente, un incremento del 23,3% dei nuovi casi (1.736 vs 1.408), a fronte di un lieve aumento del numero di tamponi diagnostici. Relativamente ai dati ospedalieri, se i pazienti in terapia intensiva diminuiscono (40 vs 49), quelli ricoverati con sintomi sono in [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-in-7-giorni-23-nuovi-casi-rispetto-alla-settimana-precedente\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-31T08:25:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/03\/Schermata-2020-03-23-alle-09.57.14.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1800\" \/>\n\t<meta property=\"og:image:height\" content=\"1040\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-in-7-giorni-23-nuovi-casi-rispetto-alla-settimana-precedente\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-in-7-giorni-23-nuovi-casi-rispetto-alla-settimana-precedente\/\",\"name\":\"Coronavirus, in 7 giorni +23% nuovi casi rispetto alla settimana precedente -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-in-7-giorni-23-nuovi-casi-rispetto-alla-settimana-precedente\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-in-7-giorni-23-nuovi-casi-rispetto-alla-settimana-precedente\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/03\/Schermata-2020-03-23-alle-09.57.14.png\",\"datePublished\":\"2020-07-31T08:25:02+00:00\",\"dateModified\":\"2020-07-31T08:25:02+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-in-7-giorni-23-nuovi-casi-rispetto-alla-settimana-precedente\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-in-7-giorni-23-nuovi-casi-rispetto-alla-settimana-precedente\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-in-7-giorni-23-nuovi-casi-rispetto-alla-settimana-precedente\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/03\/Schermata-2020-03-23-alle-09.57.14.png\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/03\/Schermata-2020-03-23-alle-09.57.14.png\",\"width\":1800,\"height\":1040},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-in-7-giorni-23-nuovi-casi-rispetto-alla-settimana-precedente\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Coronavirus, in 7 giorni +23% nuovi casi rispetto alla settimana precedente\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Coronavirus, in 7 giorni +23% nuovi casi rispetto alla settimana precedente -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-in-7-giorni-23-nuovi-casi-rispetto-alla-settimana-precedente\/","og_locale":"it_IT","og_type":"article","og_title":"Coronavirus, in 7 giorni +23% nuovi casi rispetto alla settimana precedente -","og_description":"Il monitoraggio indipendente della Fondazione GIMBE rileva nella settimana 22-28 luglio, rispetto alla precedente, un incremento del 23,3% dei nuovi casi (1.736 vs 1.408), a fronte di un lieve aumento del numero di tamponi diagnostici. Relativamente ai dati ospedalieri, se i pazienti in terapia intensiva diminuiscono (40 vs 49), quelli ricoverati con sintomi sono in [&hellip;]","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-in-7-giorni-23-nuovi-casi-rispetto-alla-settimana-precedente\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2020-07-31T08:25:02+00:00","og_image":[{"width":1800,"height":1040,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/03\/Schermata-2020-03-23-alle-09.57.14.png","type":"image\/png"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-in-7-giorni-23-nuovi-casi-rispetto-alla-settimana-precedente\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-in-7-giorni-23-nuovi-casi-rispetto-alla-settimana-precedente\/","name":"Coronavirus, in 7 giorni +23% nuovi casi rispetto alla settimana precedente -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-in-7-giorni-23-nuovi-casi-rispetto-alla-settimana-precedente\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-in-7-giorni-23-nuovi-casi-rispetto-alla-settimana-precedente\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/03\/Schermata-2020-03-23-alle-09.57.14.png","datePublished":"2020-07-31T08:25:02+00:00","dateModified":"2020-07-31T08:25:02+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-in-7-giorni-23-nuovi-casi-rispetto-alla-settimana-precedente\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-in-7-giorni-23-nuovi-casi-rispetto-alla-settimana-precedente\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-in-7-giorni-23-nuovi-casi-rispetto-alla-settimana-precedente\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/03\/Schermata-2020-03-23-alle-09.57.14.png","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/03\/Schermata-2020-03-23-alle-09.57.14.png","width":1800,"height":1040},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-in-7-giorni-23-nuovi-casi-rispetto-alla-settimana-precedente\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"Coronavirus, in 7 giorni +23% nuovi casi rispetto alla settimana precedente"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/3816"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=3816"}],"version-history":[{"count":1,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/3816\/revisions"}],"predecessor-version":[{"id":3817,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/3816\/revisions\/3817"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/2731"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=3816"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=3816"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=3816"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}