{"id":3876,"date":"2020-08-08T10:11:09","date_gmt":"2020-08-08T08:11:09","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=3876"},"modified":"2020-08-08T10:11:09","modified_gmt":"2020-08-08T08:11:09","slug":"autostrade-sindacati-9-e-10-agosto-confermato-sciopero-nazionale","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/autostrade-sindacati-9-e-10-agosto-confermato-sciopero-nazionale\/","title":{"rendered":"Autostrade, Sindacati: 9 e 10 agosto confermato sciopero nazionale"},"content":{"rendered":"<p><span class=\"dropcap dropcap3\">S<\/span>ciopero nazionale di 4 ore del personale, anche stagionale, delle concessionarie autostradali il 9 e 10 agosto che interesser\u00e0 nella giornata di domenica gli addetti all\u2019esazione ai caselli e luned\u00ec il personale tecnico amministrativo\u201d.<\/p>\n<p>A proclamare la protesta sono Filt Cgil, Uiltrasporti, Sla Cisal e Ugl Viabilit\u00e0 e Logistica \u201ca seguito delle relazioni sindacali critiche ed in alcuni casi addirittura inesistenti con le associazioni datoriali Fise Acap e Federreti e con le dirigenze aziendali dei concessionari, che rischiano di mettere a repentaglio la tenuta del contratto nazionale.<\/p>\n<p>\u201cAlla base della protesta &#8211; spiegano le organizzazioni sindacali &#8211; il ricorso eccessivo alla cassa integrazione, anche dopo la fine del lock down, e le modifiche unilaterali a orari e turni di lavoro rispetto alle previsioni del contratto nazionale, che in alcune concessioni hanno avuto conseguenze sul servizio agli utenti per il mancato rispetto delle norme del Ministero dei Trasporti sui presidi minimi dei caselli. Una situazione aggravata dall\u2019emergenza pandemia che ha penalizzato occupazione e redditi del settore, dall\u2019incertezza per l\u2019assegnazione delle concessioni scadute e dalla situazione di Aspi, ancora da chiarire su vari aspetti tra i quali il lavoro.<\/p>\n<p>\u201cDalle 2 alle 6, dalle 10 alle 14 e dalle 18 alle 22 di domenica 9 &#8211; riferiscono infine Filt Cgil, Uiltrasporti, Sla Cisal e Ugl Viabilit\u00e0 e Logistica &#8211; si fermeranno gli addetti all\u2019esazione ai caselli e il personale turnista non sottoposto alla regolamentazione dello sciopero. Stop al personale tecnico e amministrativo, compresi gli addetti ai servizi commerciali, le ultime 4 ore del proprio turno di luned\u00ec 10 agosto. Dallo sciopero resta escluso tutto il personale sottoposto alla legge sullo sciopero ed alla regolamentazione provvisoria del settore, compresi gli addetti alla sicurezza della circolazione\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sciopero nazionale di 4 ore del personale, anche stagionale, delle concessionarie autostradali il 9 e 10 agosto che interesser\u00e0 nella giornata di domenica gli addetti all\u2019esazione ai caselli e luned\u00ec il personale tecnico amministrativo\u201d. A proclamare la protesta sono Filt Cgil, Uiltrasporti, Sla Cisal e Ugl Viabilit\u00e0 e Logistica \u201ca seguito delle relazioni sindacali critiche [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2604,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[29],"tags":[1217,1218,1216],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Autostrade, Sindacati: 9 e 10 agosto confermato sciopero nazionale -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/autostrade-sindacati-9-e-10-agosto-confermato-sciopero-nazionale\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Autostrade, Sindacati: 9 e 10 agosto confermato sciopero nazionale -\" \/>\n<meta property=\"og:description\" content=\"Sciopero nazionale di 4 ore del personale, anche stagionale, delle concessionarie autostradali il 9 e 10 agosto che interesser\u00e0 nella giornata di domenica gli addetti all\u2019esazione ai caselli e luned\u00ec il personale tecnico amministrativo\u201d. A proclamare la protesta sono Filt Cgil, Uiltrasporti, Sla Cisal e Ugl Viabilit\u00e0 e Logistica \u201ca seguito delle relazioni sindacali critiche [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/autostrade-sindacati-9-e-10-agosto-confermato-sciopero-nazionale\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2020-08-08T08:11:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/03\/highway-3392100_1280.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"853\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/autostrade-sindacati-9-e-10-agosto-confermato-sciopero-nazionale\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/autostrade-sindacati-9-e-10-agosto-confermato-sciopero-nazionale\/\",\"name\":\"Autostrade, Sindacati: 9 e 10 agosto confermato sciopero nazionale -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/autostrade-sindacati-9-e-10-agosto-confermato-sciopero-nazionale\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/autostrade-sindacati-9-e-10-agosto-confermato-sciopero-nazionale\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/03\/highway-3392100_1280.jpg\",\"datePublished\":\"2020-08-08T08:11:09+00:00\",\"dateModified\":\"2020-08-08T08:11:09+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/autostrade-sindacati-9-e-10-agosto-confermato-sciopero-nazionale\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/autostrade-sindacati-9-e-10-agosto-confermato-sciopero-nazionale\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/autostrade-sindacati-9-e-10-agosto-confermato-sciopero-nazionale\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/03\/highway-3392100_1280.jpg\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/03\/highway-3392100_1280.jpg\",\"width\":1280,\"height\":853},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/autostrade-sindacati-9-e-10-agosto-confermato-sciopero-nazionale\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Autostrade, Sindacati: 9 e 10 agosto confermato sciopero nazionale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Autostrade, Sindacati: 9 e 10 agosto confermato sciopero nazionale -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/autostrade-sindacati-9-e-10-agosto-confermato-sciopero-nazionale\/","og_locale":"it_IT","og_type":"article","og_title":"Autostrade, Sindacati: 9 e 10 agosto confermato sciopero nazionale -","og_description":"Sciopero nazionale di 4 ore del personale, anche stagionale, delle concessionarie autostradali il 9 e 10 agosto che interesser\u00e0 nella giornata di domenica gli addetti all\u2019esazione ai caselli e luned\u00ec il personale tecnico amministrativo\u201d. A proclamare la protesta sono Filt Cgil, Uiltrasporti, Sla Cisal e Ugl Viabilit\u00e0 e Logistica \u201ca seguito delle relazioni sindacali critiche [&hellip;]","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/autostrade-sindacati-9-e-10-agosto-confermato-sciopero-nazionale\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2020-08-08T08:11:09+00:00","og_image":[{"width":1280,"height":853,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/03\/highway-3392100_1280.jpg","type":"image\/jpeg"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/autostrade-sindacati-9-e-10-agosto-confermato-sciopero-nazionale\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/autostrade-sindacati-9-e-10-agosto-confermato-sciopero-nazionale\/","name":"Autostrade, Sindacati: 9 e 10 agosto confermato sciopero nazionale -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/autostrade-sindacati-9-e-10-agosto-confermato-sciopero-nazionale\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/autostrade-sindacati-9-e-10-agosto-confermato-sciopero-nazionale\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/03\/highway-3392100_1280.jpg","datePublished":"2020-08-08T08:11:09+00:00","dateModified":"2020-08-08T08:11:09+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/autostrade-sindacati-9-e-10-agosto-confermato-sciopero-nazionale\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/autostrade-sindacati-9-e-10-agosto-confermato-sciopero-nazionale\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/autostrade-sindacati-9-e-10-agosto-confermato-sciopero-nazionale\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/03\/highway-3392100_1280.jpg","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/03\/highway-3392100_1280.jpg","width":1280,"height":853},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/autostrade-sindacati-9-e-10-agosto-confermato-sciopero-nazionale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"Autostrade, Sindacati: 9 e 10 agosto confermato sciopero nazionale"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/3876"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=3876"}],"version-history":[{"count":1,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/3876\/revisions"}],"predecessor-version":[{"id":3877,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/3876\/revisions\/3877"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/2604"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=3876"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=3876"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=3876"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}