{"id":3926,"date":"2020-08-15T17:33:03","date_gmt":"2020-08-15T15:33:03","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=3926"},"modified":"2020-08-15T17:33:03","modified_gmt":"2020-08-15T15:33:03","slug":"decreto-rilancio-la-pa-non-ha-pagato-11-miliardi-di-debiti-ai-fornitori","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/decreto-rilancio-la-pa-non-ha-pagato-11-miliardi-di-debiti-ai-fornitori\/","title":{"rendered":"Decreto rilancio: la PA non ha pagato 11 miliardi di debiti ai fornitori"},"content":{"rendered":"<div class=\"page\" title=\"Page 1\">\n<div class=\"section\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p><span class=\"dropcap dropcap3\">A<\/span>nche quando le risorse economiche sono accessibili ad un costo molto contenuto, la Pubblica Amministrazione (PA) non paga i propri fornitori. La denuncia e\u0300 sollevata dalla CGIA di Mestre che torna ad occuparsi di un tema che sta molto a cuore a centinaia e centinaia di migliaia di imprese che lavorano per lo Stato.<\/p>\n<p>Cosa e\u0300 successo nelle ultime settimane ? Tramite la Cassa Depositi e Prestiti (CDP), il decreto Rilancio ha messo a disposizione delle Aziende Sanitarie Locali (ASL), delle Regioni e degli enti locali 12 miliardi di euro per liquidare i debiti commerciali maturati prima della fine del 2019. Entro lo scorso 7 luglio, termine entro il quale le articolazioni periferiche della PA dovevano presentare la richiesta di denaro alla CDP, sembra che, secondo alcune indiscrezioni riportate dalla stampa specializzata, sia stato richiesto solo un miliardo.<\/p>\n<p>La conferma di questo clamoroso flop emerge dalla lettura delle bozze del decreto Agosto: all\u2019art. 55 il Governo ha riaperto i termini per la presentazione della domanda alla CDP. Pertanto, ASL, Regioni ed enti locali potranno chiedere l\u2019anticipazione di liquidita\u0300 per pagare i creditori tra il 21 settembre e il 9 ottobre prossimi.<\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"page\" title=\"Page 2\">\n<div class=\"section\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p>\uf0b7 Altro che indignarsi per i 600 euro: e\u0300 piu\u0300 immorale non pagare 11 miliardi di debiti<\/p>\n<p>\u201cIn questi giorni tutta l\u2019opinione pubblica e\u0300 indignata per i 600 euro di bonus incassati da parlamentari e consiglieri regionali \u2013 denuncia il coordinatore dell\u2019Ufficio studi Paolo Zabeo \u2013 ma, a nostro avviso, e\u0300 decisamente piu\u0300 immorale che moltissime ASL, Regioni e Comuni non abbiano pagato 11 miliardi di euro ai propri creditori, sebbene la CDP abbia messo a disposizione un prestito trentennale ad un tasso dell\u20191,22 per cento.<\/p>\n<p>Per risolvere l\u2019eccessivo stock di debito commerciale accumulato dalla PA c\u2019e\u0300 solo una cosa da fare: bisogna consentire la compensazione secca, diretta e universale tra i debiti dell\u2019Amministrazione verso le imprese e le passivita\u0300 fiscali e contributive in capo a queste ultime. Grazie a questo automatismo potremmo risolvere questa cattiva abitudine in tempi ragionevolmente brevi, salvaguardando il futuro di tantissime imprese\u201d.<\/p>\n<p>Stando al trend in atto in questi ultimi anni, i ritardi dei pagamenti penalizzerebbero soprattutto le Pmi.<\/p>\n<p>\u201cDalla segnalazione riportata dalla Corte dei Conti 1 &#8211; afferma il segretario Renato Mason &#8211; si starebbe consolidando una tendenza in atto da alcuni anni che vede le Amministrazioni pubbliche saldare con puntualita\u0300 le fatture di importo maggiore e ritardare intenzionalmente la liquidazione di quelle di dimensione meno elevate. Una modalita\u0300 operativa che, ovviamente, penalizzerebbe le piccole imprese che, generalmente, lavorano in appalti o forniture di importi nettamente inferiori a quelli \u201criservati\u201d alle attivita\u0300 produttive di dimensione superiore. Senza liquidita\u0300 molte Pmi non hanno futuro e, paradossalmente, rischiano di chiudere per troppi crediti inesigibili\u201d.<\/p>\n<p>Nel 2\u00b0 trimestre di quest\u2019anno 8 ministeri su 13 hanno pagato in forte ritardo. Gli altri non hanno aggiornato i dati<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"page\" title=\"Page 3\">\n<div class=\"section\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p>A dimostrazione della difficolta\u0300 in cui versano le aziende che lavorano con la PA, segnaliamo i tempi di pagamento dei ministeri italiani. Nel secondo trimestre di quest\u2019anno 8 su 13 hanno pagato in ritardo i propri fornitori. Gli altri 5 non hanno ancora aggiornato l\u2019indice di tempestivita\u0300 dei pagamenti che misura i giorni di ritardo o di anticipo in cui vengono saldati i fornitori rispetto alle scadenze previste dal contratto . La situazione piu\u0300 difficile e\u0300 in capo alle attivita\u0300 economiche che hanno lavorato per il ministero dell\u2019Interno: tra aprile e giugno sono state liquidate mediamente con 62 giorni di ritardo .<\/p>\n<p>Seguono le aziende che hanno instaurato un rapporto commerciale con il ministero delle Politiche Agricole (61 giorni di ritardo) e quelle con il ministero dell\u2019Ambiente (+53 giorni). Forti ritardi nei pagamenti hanno registrato anche il ministero delle Infrastrutture e dei Trasporti (+ 49 giorni), i Beni Culturali (+30 giorni), la Difesa (+16 giorni), l\u2019Economia e Finanze (+14 giorni) e lo Sviluppo Economico (+12,5 giorni).<\/p>\n<p>Contravvenendo alle disposizioni di legge, cinque ministeri (Lavoro, Esteri, Giustizia, Salute e Istruzione) non hanno ancora aggiornato i dati del secondo trimestre. Quelli della Giustizia e della Salute, non come tutte le altre Amministrazioni pubbliche, oltre all\u2019 Indice di Tempestivita\u0300 nei Pagamenti (calcolato ai sensi dell\u2019art. 9 del D.P.C.M. del 22 settembre 2014) hanno l\u2019obbligo di pubblicare sul proprio sito anche il numero dei creditori e l\u2019ammontare complessivo dei debiti (art. 33 comma 1 del D.Lgs n. 33\/2013 cosi\u0300 come modificato dall\u2019art. 29 del D.Lgs. 97\/2016) maturati ogni trimestre e alla fine di ciascun anno per le seguenti voci di spesa: somministrazioni, forniture, appalti e prestazioni professionali.<\/p>\n<p>Dal 2013, a seguito del recepimento nel nostro ordinamento della normativa europea contro i ritardi di pagamento (Direttiva UE\/2011\/7), i tempi di pagamento nelle transazioni commerciali tra enti pubblici italiani e aziende private non possono superare di norma i 30 giorni (60 per alcune tipologie di forniture, in particolare quelle sanitarie) hanno addirittura ancora reso disponibili gli indici di tempestivita\u0300 del primo trimestre del 2020 .<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"page\" title=\"Page 4\">\n<div class=\"section\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p>Secondo le stime della Banca d\u2019Italia i debiti della nostra PA ammontano a 53 miliardi<\/p>\n<p>Secondo gli ultimi dati disponibili riportati nella \u201cRelazione annuale 2018\u201d, presentata il 31 maggio 2019 dalla Banca d\u2019Italia, l\u2019ammontare complessivo dei debiti commerciali della nostra PA sarebbe pari a circa 53 miliardi di euro, meta\u0300 dei quali ascrivibili ai ritardi di pagamento .<\/p>\n<p>L\u2019utilizzo del condizionale e\u0300 d\u2019obbligo, visto che il periodico monitoraggio condotto dai ricercatori di via Nazionale si basa su indagini campionarie condotte sulle imprese e dalle segnalazioni di vigilanza da cui emergono dei risultati che, secondo gli stessi estensori delle stime, sono caratterizzati da un elevato grado di incertezza . Tuttavia, di una cosa siamo certi: le statistiche di Bruxelles ci dicono che, nonostante gli sforzi fatti in questi ultimi anni, la nostra PA e\u0300 comunque tra le peggiori pagatrici d\u2019Europa.<\/p>\n<\/div>\n<\/div>\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"page\" title=\"Page 5\">\n<div class=\"section\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<div class=\"section\">\n<div class=\"layoutArea\">\n<div class=\"column\"><\/div>\n<\/div>\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Anche quando le risorse economiche sono accessibili ad un costo molto contenuto, la Pubblica Amministrazione (PA) non paga i propri fornitori. La denuncia e\u0300 sollevata dalla CGIA di Mestre che torna ad occuparsi di un tema che sta molto a cuore a centinaia e centinaia di migliaia di imprese che lavorano per lo Stato. Cosa [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2154,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[162],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Decreto rilancio: la PA non ha pagato 11 miliardi di debiti ai fornitori -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/decreto-rilancio-la-pa-non-ha-pagato-11-miliardi-di-debiti-ai-fornitori\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Decreto rilancio: la PA non ha pagato 11 miliardi di debiti ai fornitori -\" \/>\n<meta property=\"og:description\" content=\"Anche quando le risorse economiche sono accessibili ad un costo molto contenuto, la Pubblica Amministrazione (PA) non paga i propri fornitori. La denuncia e\u0300 sollevata dalla CGIA di Mestre che torna ad occuparsi di un tema che sta molto a cuore a centinaia e centinaia di migliaia di imprese che lavorano per lo Stato. Cosa [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/decreto-rilancio-la-pa-non-ha-pagato-11-miliardi-di-debiti-ai-fornitori\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2020-08-15T15:33:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/12\/tasse.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"605\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/decreto-rilancio-la-pa-non-ha-pagato-11-miliardi-di-debiti-ai-fornitori\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/decreto-rilancio-la-pa-non-ha-pagato-11-miliardi-di-debiti-ai-fornitori\/\",\"name\":\"Decreto rilancio: la PA non ha pagato 11 miliardi di debiti ai fornitori -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/decreto-rilancio-la-pa-non-ha-pagato-11-miliardi-di-debiti-ai-fornitori\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/decreto-rilancio-la-pa-non-ha-pagato-11-miliardi-di-debiti-ai-fornitori\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/12\/tasse.jpg\",\"datePublished\":\"2020-08-15T15:33:03+00:00\",\"dateModified\":\"2020-08-15T15:33:03+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/decreto-rilancio-la-pa-non-ha-pagato-11-miliardi-di-debiti-ai-fornitori\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/decreto-rilancio-la-pa-non-ha-pagato-11-miliardi-di-debiti-ai-fornitori\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/decreto-rilancio-la-pa-non-ha-pagato-11-miliardi-di-debiti-ai-fornitori\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/12\/tasse.jpg\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/12\/tasse.jpg\",\"width\":960,\"height\":605},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/decreto-rilancio-la-pa-non-ha-pagato-11-miliardi-di-debiti-ai-fornitori\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Decreto rilancio: la PA non ha pagato 11 miliardi di debiti ai fornitori\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Decreto rilancio: la PA non ha pagato 11 miliardi di debiti ai fornitori -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/decreto-rilancio-la-pa-non-ha-pagato-11-miliardi-di-debiti-ai-fornitori\/","og_locale":"it_IT","og_type":"article","og_title":"Decreto rilancio: la PA non ha pagato 11 miliardi di debiti ai fornitori -","og_description":"Anche quando le risorse economiche sono accessibili ad un costo molto contenuto, la Pubblica Amministrazione (PA) non paga i propri fornitori. La denuncia e\u0300 sollevata dalla CGIA di Mestre che torna ad occuparsi di un tema che sta molto a cuore a centinaia e centinaia di migliaia di imprese che lavorano per lo Stato. Cosa [&hellip;]","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/decreto-rilancio-la-pa-non-ha-pagato-11-miliardi-di-debiti-ai-fornitori\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2020-08-15T15:33:03+00:00","og_image":[{"width":960,"height":605,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/12\/tasse.jpg","type":"image\/jpeg"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/decreto-rilancio-la-pa-non-ha-pagato-11-miliardi-di-debiti-ai-fornitori\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/decreto-rilancio-la-pa-non-ha-pagato-11-miliardi-di-debiti-ai-fornitori\/","name":"Decreto rilancio: la PA non ha pagato 11 miliardi di debiti ai fornitori -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/decreto-rilancio-la-pa-non-ha-pagato-11-miliardi-di-debiti-ai-fornitori\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/decreto-rilancio-la-pa-non-ha-pagato-11-miliardi-di-debiti-ai-fornitori\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/12\/tasse.jpg","datePublished":"2020-08-15T15:33:03+00:00","dateModified":"2020-08-15T15:33:03+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/decreto-rilancio-la-pa-non-ha-pagato-11-miliardi-di-debiti-ai-fornitori\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/decreto-rilancio-la-pa-non-ha-pagato-11-miliardi-di-debiti-ai-fornitori\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/decreto-rilancio-la-pa-non-ha-pagato-11-miliardi-di-debiti-ai-fornitori\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/12\/tasse.jpg","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/12\/tasse.jpg","width":960,"height":605},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/decreto-rilancio-la-pa-non-ha-pagato-11-miliardi-di-debiti-ai-fornitori\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"Decreto rilancio: la PA non ha pagato 11 miliardi di debiti ai fornitori"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/3926"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=3926"}],"version-history":[{"count":1,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/3926\/revisions"}],"predecessor-version":[{"id":3927,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/3926\/revisions\/3927"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/2154"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=3926"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=3926"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=3926"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}