{"id":4040,"date":"2020-09-02T18:51:11","date_gmt":"2020-09-02T16:51:11","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=4040"},"modified":"2020-09-02T18:51:11","modified_gmt":"2020-09-02T16:51:11","slug":"il-ministro-patuanelli-riceve-il-presidente-della-cna","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/il-ministro-patuanelli-riceve-il-presidente-della-cna\/","title":{"rendered":"Il Ministro Patuanelli riceve il presidente della CNA"},"content":{"rendered":"<p><span class=\"dropcap dropcap3\">U<\/span>n piano capace di creare un contesto favorevole allo sviluppo imprenditoriale, con un occhio effettivamente attento alle micro e piccole imprese, che abbia nella dotazione infrastrutturale adeguata e nell\u2019eliminazione di vincoli e freni all\u2019iniziativa privata le due direttrici fondamentali.<\/p>\n<p>Solo cos\u00ec l\u2019opportunit\u00e0 offerta dall\u2019Unione europea con il Recovery Fund potr\u00e0 contribuire in maniera robusta al rilancio della nostra economia.\u00a0 A chiederlo il presidente nazionale della CNA, Daniele Vaccarino, nell\u2019incontro tenuto oggi con il ministro dello Sviluppo economico, Stefano Patuanelli, nella sede del dicastero.<\/p>\n<p>CNA \u00e8 convinta che necessit\u00e0 primaria di ogni politica economica, in particolare per quanto riguarda l\u2019introduzione di incentivi, \u00e8 quella di guardare alle piccole imprese superando il concetto vago di Pmi e il susseguente modello degli incentivi a taglia unica: tra un\u2019impresa con cinque addetti e una con 240 esistono evidenti, eclatanti differenze.<br \/>\nTre i punti focali della strategia di rilancio del sistema produttivo proposta da CNA: 1) Potenziamento del piano transizione 4.0; 2) Credito; 3) Riqualificazione del patrimonio edilizio\/efficientamento energetico.<\/p>\n<p>Le modifiche introdotte dall\u2019ultima Legge di Bilancio al Piano transizione 4.0 hanno conferito linearit\u00e0 e coerenza agli interventi. Per CNA ora serve una spinta pi\u00f9 incisiva, rialzando le aliquote dei crediti d\u2019imposta, allungando l\u2019arco temporale degli incentivi perlomeno a tre anni, conservando le misure pi\u00f9 trasversali (quali il super-ammortamento e la Nuova Sabatini), sostenendo la formazione.<\/p>\n<p>Negli ultimi anni si \u00e8 assistito a un persistente allontanamento delle banche da micro e piccole imprese, che sempre pi\u00f9 non trovano risposte adeguate alle proprie esigenze di credito. CNA chiede di coinvolgere, allora, tutti i soggetti in grado di facilitare l\u2019accesso al credito di micro e piccole imprese, a partire dai consorzi fidi. A tal fine andrebbe istituito un Fondo rotativo gestito dai Confidi vigilati dalla Banca d\u2019Italia per erogare finanziamenti fino a 50mila euro.<\/p>\n<p>CNA apprezza il rinnovato impegno del Governo per sostenere riqualificazione, efficientamento energetico, manutenzione e messa in sicurezza del patrimonio immobiliare nazionale, pubblico e privato. Per rendere ancora pi\u00f9 efficaci le misure adottate occorre estenderne la durata perlomeno al prossimo triennio, allineare alla stessa scadenza le deroghe introdotte al Codice degli appalti, ampliare il novero degli immobili interessati al Superbonus ai capannoni industriali.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un piano capace di creare un contesto favorevole allo sviluppo imprenditoriale, con un occhio effettivamente attento alle micro e piccole imprese, che abbia nella dotazione infrastrutturale adeguata e nell\u2019eliminazione di vincoli e freni all\u2019iniziativa privata le due direttrici fondamentali. Solo cos\u00ec l\u2019opportunit\u00e0 offerta dall\u2019Unione europea con il Recovery Fund potr\u00e0 contribuire in maniera robusta al [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4041,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[56],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Il Ministro Patuanelli riceve il presidente della CNA -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/il-ministro-patuanelli-riceve-il-presidente-della-cna\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il Ministro Patuanelli riceve il presidente della CNA -\" \/>\n<meta property=\"og:description\" content=\"Un piano capace di creare un contesto favorevole allo sviluppo imprenditoriale, con un occhio effettivamente attento alle micro e piccole imprese, che abbia nella dotazione infrastrutturale adeguata e nell\u2019eliminazione di vincoli e freni all\u2019iniziativa privata le due direttrici fondamentali. Solo cos\u00ec l\u2019opportunit\u00e0 offerta dall\u2019Unione europea con il Recovery Fund potr\u00e0 contribuire in maniera robusta al [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/il-ministro-patuanelli-riceve-il-presidente-della-cna\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-02T16:51:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/09\/Schermata-2020-09-02-alle-18.50.01.png\" \/>\n\t<meta property=\"og:image:width\" content=\"990\" \/>\n\t<meta property=\"og:image:height\" content=\"632\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/il-ministro-patuanelli-riceve-il-presidente-della-cna\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/il-ministro-patuanelli-riceve-il-presidente-della-cna\/\",\"name\":\"Il Ministro Patuanelli riceve il presidente della CNA -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/il-ministro-patuanelli-riceve-il-presidente-della-cna\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/il-ministro-patuanelli-riceve-il-presidente-della-cna\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/09\/Schermata-2020-09-02-alle-18.50.01.png\",\"datePublished\":\"2020-09-02T16:51:11+00:00\",\"dateModified\":\"2020-09-02T16:51:11+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/il-ministro-patuanelli-riceve-il-presidente-della-cna\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/il-ministro-patuanelli-riceve-il-presidente-della-cna\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/il-ministro-patuanelli-riceve-il-presidente-della-cna\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/09\/Schermata-2020-09-02-alle-18.50.01.png\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/09\/Schermata-2020-09-02-alle-18.50.01.png\",\"width\":990,\"height\":632},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/il-ministro-patuanelli-riceve-il-presidente-della-cna\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il Ministro Patuanelli riceve il presidente della CNA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il Ministro Patuanelli riceve il presidente della CNA -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/il-ministro-patuanelli-riceve-il-presidente-della-cna\/","og_locale":"it_IT","og_type":"article","og_title":"Il Ministro Patuanelli riceve il presidente della CNA -","og_description":"Un piano capace di creare un contesto favorevole allo sviluppo imprenditoriale, con un occhio effettivamente attento alle micro e piccole imprese, che abbia nella dotazione infrastrutturale adeguata e nell\u2019eliminazione di vincoli e freni all\u2019iniziativa privata le due direttrici fondamentali. Solo cos\u00ec l\u2019opportunit\u00e0 offerta dall\u2019Unione europea con il Recovery Fund potr\u00e0 contribuire in maniera robusta al [&hellip;]","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/il-ministro-patuanelli-riceve-il-presidente-della-cna\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2020-09-02T16:51:11+00:00","og_image":[{"width":990,"height":632,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/09\/Schermata-2020-09-02-alle-18.50.01.png","type":"image\/png"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/il-ministro-patuanelli-riceve-il-presidente-della-cna\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/il-ministro-patuanelli-riceve-il-presidente-della-cna\/","name":"Il Ministro Patuanelli riceve il presidente della CNA -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/il-ministro-patuanelli-riceve-il-presidente-della-cna\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/il-ministro-patuanelli-riceve-il-presidente-della-cna\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/09\/Schermata-2020-09-02-alle-18.50.01.png","datePublished":"2020-09-02T16:51:11+00:00","dateModified":"2020-09-02T16:51:11+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/il-ministro-patuanelli-riceve-il-presidente-della-cna\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/il-ministro-patuanelli-riceve-il-presidente-della-cna\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/il-ministro-patuanelli-riceve-il-presidente-della-cna\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/09\/Schermata-2020-09-02-alle-18.50.01.png","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/09\/Schermata-2020-09-02-alle-18.50.01.png","width":990,"height":632},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/il-ministro-patuanelli-riceve-il-presidente-della-cna\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"Il Ministro Patuanelli riceve il presidente della CNA"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/4040"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=4040"}],"version-history":[{"count":1,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/4040\/revisions"}],"predecessor-version":[{"id":4042,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/4040\/revisions\/4042"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/4041"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=4040"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=4040"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=4040"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}