{"id":4084,"date":"2020-09-10T11:14:59","date_gmt":"2020-09-10T09:14:59","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=4084"},"modified":"2020-09-10T11:14:59","modified_gmt":"2020-09-10T09:14:59","slug":"legambiente-la-riapertura-delle-scuole-e-il-piu-importante-cantiere-civico-che-il-nostro-paese-si-trova-ad-affrontare","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/legambiente-la-riapertura-delle-scuole-e-il-piu-importante-cantiere-civico-che-il-nostro-paese-si-trova-ad-affrontare\/","title":{"rendered":"Legambiente: \u201cLa riapertura delle scuole \u00e8 il pi\u00f9 importante cantiere civico che il nostro Paese si trova ad affrontare&#8221;"},"content":{"rendered":"<p><span class=\"dropcap dropcap3\">A<\/span> meno di una settimana dal suono della campanella, Legambiente lancia un appello al presidente del Consiglio Giuseppe Conte, alla ministra dell\u2019istruzione Lucia Azzolina, all\u2019Anci e Upi affinch\u00e8 in questa ripartenza delle scuole, gi\u00e0 in forte affanno e tra mille difficolt\u00e0, non si metta in secondo piano il tema della sostenibilit\u00e0 ambientale su cui bisogna puntare e investire seriamente, senza fare passi indietro.<\/p>\n<p>Quattro i grandi nodi da affrontare se davvero si vogliono scuole pi\u00f9 green, sostenibili, sicure e inclusive: il cantiere dell\u2019edilizia scolastica e il tema dell\u2019efficientamento energetico su cui occorre indirizzare una parte dei fondi del Recovery fund, gli spazi scolastici da riqualificare e i servizi da potenziare come ad esempio il tempo pieno e le mense, incentivando la mobilit\u00e0 sostenibile rafforzando ad esempio i collegamenti ciclabili e pedonali casa-scuola.<\/p>\n<p>A parlar chiaro sono anche i nuovi dati (2019) raccolti dall\u2019Osservatorio Ecosistema Scuola sulla base dell\u2019indagine effettuata su 5.600 edifici scolastici dei capoluoghi di provincia e che l\u2019associazione ambientalista anticipa in parte oggi con un\u2019anteprima.<\/p>\n<p>Nella Penisola il\u00a029,1% degli edifici scolastici necessita manutenzione urgente,\u00a0il 58,6% per cento delle scuole non hanno l&#8217;agibilit\u00e0,\u00a0senza dimenticare quelle in area sismica,\u00a0il 9,8% sono in area sismica 1, di questi solo il 20,2% \u00e8 stato progettato o successivamente adeguato alla normativa tecnica di costruzione antisismica; il 35,8% degli edifici sono in area sismica 2, di questi solo il 10,6% \u00e8 stato progettato o successivamente adeguato alla normativa tecnica di costruzione antisismica.<\/p>\n<p>Negli ultimi 5 anni si \u00e8 intervento sul 51,8% degli edifici con interventi\u00a0che riguardano l&#8217;impiantistica, la prevenzione incendi, l&#8217;ambito igienico-sanitario, i solai, le barriere architettoniche. Sul fronte dell\u2019efficientamento energetico,\u00a0solo il 6,4% degli edifici scolastici sono in classe energetica A, il 34,5% in classe G.\u00a0Sul 16,3% degli edifici sono stati realizzati negli ultimi 5 anni interventi di efficientamento energetico\u00a0riguardanti gli infissi, l&#8217;isolamento, caldaie e impianti di energia rinnovabile.<\/p>\n<p>Ritardi anche che sul fronte dei servizi e mobilit\u00e0, stando ai dati raccolti\u00a0solo nel 13,9% delle scuole \u00e8 previsto il servizio pre post scuola e il 18,4% degli edifici scolastici ha piste ciclabili nelle aree antistanti. Un quadro quello tracciato da Legambiente che indica i principali ritardi su cui occorre al pi\u00f9 presto intervenire, senza dimenticare che in questa ripartenza sar\u00e0 fondamentale anche la sfida educativa e culturale legata alla consapevolezza di giusti comportamenti e stili di vita sostenibile da assumere nella propria vita quotidiana anche per la prevenzione dal virus.<\/p>\n<p>Per questo l\u2019associazione ambientalista nei giorni scorsi \u00e8 anche intervenuta sulla questione dell\u2019utilizzo della mascherina chirurgica monouso a scuola, definendola una decisione senza senso, in quanto occorre fornire agli studenti le mascherine riutilizzabili certificate sollecitandoli e invogliandoli a utilizzare le lavabili per ridurre il quantitativo di usa e getta che circola nel Paese, e garantendo comunque la tutela della salute.<\/p>\n<p>\u201cLa pandemia \u2013 dichiara\u00a0Vanessa Pallucchi, vicepresidente di Legambiente\u00a0\u2013 ha messo a nudo fragilit\u00e0 e disuguaglianze del nostro sistema scolastico. Per questo \u00e8 fondamentale mettere in campo una progettualit\u00e0 e degli investimenti mirati che guardino ben oltre l\u2019emergenza.<\/p>\n<p>Nell&#8217;anno in cui l&#8217;insegnamento dell&#8217;educazione civica\u00a0ritorna materia curricolare, la riapertura delle scuole si presenta come il pi\u00f9 importante cantiere civico del Paese su cui non sono ammessi pi\u00f9 ritardi. Per questo auspichiamo che parte dei fondi del Recovery Fund vengano indirizzati in primis\u00a0sulla messa sicurezza e l\u2019efficientamento energetico degli edifici, la rigenerazione degli spazi educativi\u00a0e la qualit\u00e0 e estensione dei servizi scolastici, senza tralasciare la possibilit\u00e0 di sostenere processi di economia circolare sulla\u00a0questione banchi e mascherine.<\/p>\n<p>Inoltre la dovuta prevenzione del rischio Covid sia da stimolo per concepire una scuola diversa, di prossimit\u00e0, di piccoli gruppi in presenza senza togliere la dimensione comunitaria che anche la didattica a distanza pu\u00f2 contribuire ad accrescere se gestita in maniera attiva da parte degli studenti; senza dimenticare che prevenire significa assumere comportamenti civici responsabili e consapevoli, senza di essi tutti gli accorgimenti tecnici e strumentali (mascherine, banchi, ecc.) rischiano di vanificarsi.<\/p>\n<p>Altro grande tema riguarda gli\u00a0spazi scolastici\u00a0da riqualificare, i trasporti e i servizi da potenziare\u00a0come ad esempio il servizio pre e post scuola che, stando ai dati raccolti da Legambiente \u00e8 garantito nel 13,9% degli istituti,\u00a0anche se gi\u00e0 molte di esse stanno annunciando di non poterlo assicurare in questa prima fase.<\/p>\n<p>Tra gli altri dati raccolti invece dall\u2019Osservatorio Ecosistema Scuola emerge che\u00a0il 46% degli edifici scolastici dispone di strutture per lo sport, tra palestre e impianti sportivi all\u2019aperto; il 32,2% hanno strutture sportive che vengono aperte al pubblico in orario extrascolastico. Il 63,9% degli edifici dispongono di giardini o aree verdi fruibili. Ora bisogner\u00e0 capire come gli istituti scolastici riutilizzeranno questi spazi anche alla luce dei protocolli anticovid.<\/p>\n<p>Anche su questi tre fronti \u2013 spazi, servizi scolastici e trasporti &#8211; Legambiente chiede massima attenzione in termini di sostenibilit\u00e0\u00a0ad esempio\u00a0prestando attenzione alla questione mense e lunch box\u00a0dove si rischia di aumentare l\u2019utilizzo di prodotti usa e getta e di conseguenza di generare rifiuti di plastica, ed infine\u00a0potenziando la mobilit\u00e0 sostenibile\u00a0al fine di scongiurare un utilizzo in massa dell&#8217;auto privata.<\/p>\n<p>Legambiente a tal riguardo ricorda che il\u00a018,4% degli edifici scolastici ha piste ciclabili nelle aree antistanti, il 65,8% \u00e8 raggiungibile con lo scuolabus, il 51,9% da trasporti pubblici urbani e il 42,1% da trasporti pubblici interurbani.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A meno di una settimana dal suono della campanella, Legambiente lancia un appello al presidente del Consiglio Giuseppe Conte, alla ministra dell\u2019istruzione Lucia Azzolina, all\u2019Anci e Upi affinch\u00e8 in questa ripartenza delle scuole, gi\u00e0 in forte affanno e tra mille difficolt\u00e0, non si metta in secondo piano il tema della sostenibilit\u00e0 ambientale su cui bisogna [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1782,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[133],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Legambiente: \u201cLa riapertura delle scuole \u00e8 il pi\u00f9 importante cantiere civico che il nostro Paese si trova ad affrontare&quot; -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/legambiente-la-riapertura-delle-scuole-e-il-piu-importante-cantiere-civico-che-il-nostro-paese-si-trova-ad-affrontare\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Legambiente: \u201cLa riapertura delle scuole \u00e8 il pi\u00f9 importante cantiere civico che il nostro Paese si trova ad affrontare&quot; -\" \/>\n<meta property=\"og:description\" content=\"A meno di una settimana dal suono della campanella, Legambiente lancia un appello al presidente del Consiglio Giuseppe Conte, alla ministra dell\u2019istruzione Lucia Azzolina, all\u2019Anci e Upi affinch\u00e8 in questa ripartenza delle scuole, gi\u00e0 in forte affanno e tra mille difficolt\u00e0, non si metta in secondo piano il tema della sostenibilit\u00e0 ambientale su cui bisogna [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/legambiente-la-riapertura-delle-scuole-e-il-piu-importante-cantiere-civico-che-il-nostro-paese-si-trova-ad-affrontare\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-10T09:14:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/09\/formazione.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"685\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/legambiente-la-riapertura-delle-scuole-e-il-piu-importante-cantiere-civico-che-il-nostro-paese-si-trova-ad-affrontare\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/legambiente-la-riapertura-delle-scuole-e-il-piu-importante-cantiere-civico-che-il-nostro-paese-si-trova-ad-affrontare\/\",\"name\":\"Legambiente: \u201cLa riapertura delle scuole \u00e8 il pi\u00f9 importante cantiere civico che il nostro Paese si trova ad affrontare\\\" -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/legambiente-la-riapertura-delle-scuole-e-il-piu-importante-cantiere-civico-che-il-nostro-paese-si-trova-ad-affrontare\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/legambiente-la-riapertura-delle-scuole-e-il-piu-importante-cantiere-civico-che-il-nostro-paese-si-trova-ad-affrontare\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/09\/formazione.jpg\",\"datePublished\":\"2020-09-10T09:14:59+00:00\",\"dateModified\":\"2020-09-10T09:14:59+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/legambiente-la-riapertura-delle-scuole-e-il-piu-importante-cantiere-civico-che-il-nostro-paese-si-trova-ad-affrontare\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/legambiente-la-riapertura-delle-scuole-e-il-piu-importante-cantiere-civico-che-il-nostro-paese-si-trova-ad-affrontare\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/legambiente-la-riapertura-delle-scuole-e-il-piu-importante-cantiere-civico-che-il-nostro-paese-si-trova-ad-affrontare\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/09\/formazione.jpg\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/09\/formazione.jpg\",\"width\":960,\"height\":685},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/legambiente-la-riapertura-delle-scuole-e-il-piu-importante-cantiere-civico-che-il-nostro-paese-si-trova-ad-affrontare\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Legambiente: \u201cLa riapertura delle scuole \u00e8 il pi\u00f9 importante cantiere civico che il nostro Paese si trova ad affrontare&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Legambiente: \u201cLa riapertura delle scuole \u00e8 il pi\u00f9 importante cantiere civico che il nostro Paese si trova ad affrontare\" -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/legambiente-la-riapertura-delle-scuole-e-il-piu-importante-cantiere-civico-che-il-nostro-paese-si-trova-ad-affrontare\/","og_locale":"it_IT","og_type":"article","og_title":"Legambiente: \u201cLa riapertura delle scuole \u00e8 il pi\u00f9 importante cantiere civico che il nostro Paese si trova ad affrontare\" -","og_description":"A meno di una settimana dal suono della campanella, Legambiente lancia un appello al presidente del Consiglio Giuseppe Conte, alla ministra dell\u2019istruzione Lucia Azzolina, all\u2019Anci e Upi affinch\u00e8 in questa ripartenza delle scuole, gi\u00e0 in forte affanno e tra mille difficolt\u00e0, non si metta in secondo piano il tema della sostenibilit\u00e0 ambientale su cui bisogna [&hellip;]","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/legambiente-la-riapertura-delle-scuole-e-il-piu-importante-cantiere-civico-che-il-nostro-paese-si-trova-ad-affrontare\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2020-09-10T09:14:59+00:00","og_image":[{"width":960,"height":685,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/09\/formazione.jpg","type":"image\/jpeg"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/legambiente-la-riapertura-delle-scuole-e-il-piu-importante-cantiere-civico-che-il-nostro-paese-si-trova-ad-affrontare\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/legambiente-la-riapertura-delle-scuole-e-il-piu-importante-cantiere-civico-che-il-nostro-paese-si-trova-ad-affrontare\/","name":"Legambiente: \u201cLa riapertura delle scuole \u00e8 il pi\u00f9 importante cantiere civico che il nostro Paese si trova ad affrontare\" -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/legambiente-la-riapertura-delle-scuole-e-il-piu-importante-cantiere-civico-che-il-nostro-paese-si-trova-ad-affrontare\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/legambiente-la-riapertura-delle-scuole-e-il-piu-importante-cantiere-civico-che-il-nostro-paese-si-trova-ad-affrontare\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/09\/formazione.jpg","datePublished":"2020-09-10T09:14:59+00:00","dateModified":"2020-09-10T09:14:59+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/legambiente-la-riapertura-delle-scuole-e-il-piu-importante-cantiere-civico-che-il-nostro-paese-si-trova-ad-affrontare\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/legambiente-la-riapertura-delle-scuole-e-il-piu-importante-cantiere-civico-che-il-nostro-paese-si-trova-ad-affrontare\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/legambiente-la-riapertura-delle-scuole-e-il-piu-importante-cantiere-civico-che-il-nostro-paese-si-trova-ad-affrontare\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/09\/formazione.jpg","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/09\/formazione.jpg","width":960,"height":685},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/legambiente-la-riapertura-delle-scuole-e-il-piu-importante-cantiere-civico-che-il-nostro-paese-si-trova-ad-affrontare\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"Legambiente: \u201cLa riapertura delle scuole \u00e8 il pi\u00f9 importante cantiere civico che il nostro Paese si trova ad affrontare&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/4084"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=4084"}],"version-history":[{"count":1,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/4084\/revisions"}],"predecessor-version":[{"id":4085,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/4084\/revisions\/4085"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/1782"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=4084"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=4084"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=4084"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}