{"id":410,"date":"2019-04-13T20:33:35","date_gmt":"2019-04-13T18:33:35","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=410"},"modified":"2019-04-13T20:33:35","modified_gmt":"2019-04-13T18:33:35","slug":"digitale-pronti-155milioni-di-euro-per-le-imprese","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/digitale-pronti-155milioni-di-euro-per-le-imprese\/","title":{"rendered":"Digitale: pronti 15,5milioni di euro per le imprese"},"content":{"rendered":"<p><span class=\"dropcap dropcap3\">P<\/span>ronti 15,5 milioni di euro per la digitalizzazione delle imprese. Parte domani il nuovo bando nazionale per i voucher 4.0 lanciato dalle Camere di commercio per permettere alle aziende italiane di agganciare la quarta rivoluzione industriale.<\/p>\n<p>Per ciascuna impresa saranno messe a disposizione risorse fino a 10mila euro di valore che potranno essere utilizzate dagli imprenditori per acquistare servizi di consulenza, formazione e tecnologie in ambito 4.0.<\/p>\n<p>Le aziende avranno tempo fino al 15 luglio di quest\u2019anno per richiedere l\u2019erogazione del voucher presso la propria Camera di riferimento oppure consultando il portale nazionale <a href=\"http:\/\/www.puntoimpresadigitale.camcom.it\">http:\/\/www.puntoimpresadigitale.camcom.it<\/a> nella sezione voucher.<\/p>\n<p>Potranno beneficiare delle agevolazioni le singole micro, piccole e medie imprese e i gruppi da 3 a 20 imprese che presentano un progetto condiviso finalizzato all\u2019introduzione delle tecnologie digitali abilitanti.<\/p>\n<blockquote class=\"td_pull_quote td_pull_center\"><p><em>Attraverso i voucher \u00a0le Camere di commercio offrono un sostegno concreto a favore della digitalizzazione delle imprese, soprattutto quelle di dimensioni pi\u00f9 piccole che fanno pi\u00f9 fatica a trovare le risorse per innovarsi<\/em>.<\/p><\/blockquote>\n<p>E\u2019 quanto ha sottolineato il <strong>presidente di Unioncamere, Carlo Sangalli,<\/strong> secondo cui \u201c<em>con i Pid, in poco tempo, abbiamo facilitato oltre 41mila imprenditori ad adottare le tecnologie 4.0. In particolare attraverso i nostri servizi di assessment utilizzati gi\u00e0 da circa 10mila imprese per misurare la propria maturit\u00e0 digitale e\u00a0 capacit\u00e0 di formazione. Servizi che hanno coinvolto oltre 28mila partecipanti per accompagnarli verso la digital transformation\u201d.<\/em><\/p>\n<p>Salgono cos\u00ec a 44 milioni euro le risorse complessive stanziate dal Sistema camerale da quando a giugno 2017 \u00e8 stata avviata la rete degli 88 Punti Impresa Digitale delle Camere di commercio presente in tutta Italia, per favorire la diffusione della cultura e della pratica della digitalizzazione.<\/p>\n<p>Tra il 2017 e il 2018 sono state gi\u00e0 circa 4mila le imprese che hanno avuto accesso ai 28,5 milioni di euro erogati attraverso i voucher.<\/p>\n<p>E quest\u2019anno rispetto alle scorse edizioni ci sono importanti novit\u00e0 per la spendibilit\u00e0 delle risorse assegnate.<\/p>\n<p>I voucher potranno, infatti, essere investiti non pi\u00f9 solo in formazione e consulenza, ma anche per l\u2019acquisto di nuove tecnologie, macchinari e software 4.0 da inserire in azienda fino ad un massimo del 50% delle spese ammissibili.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pronti 15,5 milioni di euro per la digitalizzazione delle imprese. Parte domani il nuovo bando nazionale per i voucher 4.0 lanciato dalle Camere di commercio per permettere alle aziende italiane di agganciare la quarta rivoluzione industriale. Per ciascuna impresa saranno messe a disposizione risorse fino a 10mila euro di valore che potranno essere utilizzate dagli [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":9,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[130],"tags":[173,174,171,68,172],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Digitale: pronti 15,5milioni di euro per le imprese -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/digitale-pronti-155milioni-di-euro-per-le-imprese\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Digitale: pronti 15,5milioni di euro per le imprese -\" \/>\n<meta property=\"og:description\" content=\"Pronti 15,5 milioni di euro per la digitalizzazione delle imprese. Parte domani il nuovo bando nazionale per i voucher 4.0 lanciato dalle Camere di commercio per permettere alle aziende italiane di agganciare la quarta rivoluzione industriale. Per ciascuna impresa saranno messe a disposizione risorse fino a 10mila euro di valore che potranno essere utilizzate dagli [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/digitale-pronti-155milioni-di-euro-per-le-imprese\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2019-04-13T18:33:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/07\/5.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1068\" \/>\n\t<meta property=\"og:image:height\" content=\"761\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/digitale-pronti-155milioni-di-euro-per-le-imprese\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/digitale-pronti-155milioni-di-euro-per-le-imprese\/\",\"name\":\"Digitale: pronti 15,5milioni di euro per le imprese -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/digitale-pronti-155milioni-di-euro-per-le-imprese\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/digitale-pronti-155milioni-di-euro-per-le-imprese\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/07\/5.jpg\",\"datePublished\":\"2019-04-13T18:33:35+00:00\",\"dateModified\":\"2019-04-13T18:33:35+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/digitale-pronti-155milioni-di-euro-per-le-imprese\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/digitale-pronti-155milioni-di-euro-per-le-imprese\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/digitale-pronti-155milioni-di-euro-per-le-imprese\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/07\/5.jpg\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/07\/5.jpg\",\"width\":1068,\"height\":761},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/digitale-pronti-155milioni-di-euro-per-le-imprese\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Digitale: pronti 15,5milioni di euro per le imprese\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Digitale: pronti 15,5milioni di euro per le imprese -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/digitale-pronti-155milioni-di-euro-per-le-imprese\/","og_locale":"it_IT","og_type":"article","og_title":"Digitale: pronti 15,5milioni di euro per le imprese -","og_description":"Pronti 15,5 milioni di euro per la digitalizzazione delle imprese. Parte domani il nuovo bando nazionale per i voucher 4.0 lanciato dalle Camere di commercio per permettere alle aziende italiane di agganciare la quarta rivoluzione industriale. Per ciascuna impresa saranno messe a disposizione risorse fino a 10mila euro di valore che potranno essere utilizzate dagli [&hellip;]","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/digitale-pronti-155milioni-di-euro-per-le-imprese\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2019-04-13T18:33:35+00:00","og_image":[{"width":1068,"height":761,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/07\/5.jpg","type":"image\/jpeg"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/digitale-pronti-155milioni-di-euro-per-le-imprese\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/digitale-pronti-155milioni-di-euro-per-le-imprese\/","name":"Digitale: pronti 15,5milioni di euro per le imprese -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/digitale-pronti-155milioni-di-euro-per-le-imprese\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/digitale-pronti-155milioni-di-euro-per-le-imprese\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/07\/5.jpg","datePublished":"2019-04-13T18:33:35+00:00","dateModified":"2019-04-13T18:33:35+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/digitale-pronti-155milioni-di-euro-per-le-imprese\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/digitale-pronti-155milioni-di-euro-per-le-imprese\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/digitale-pronti-155milioni-di-euro-per-le-imprese\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/07\/5.jpg","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/07\/5.jpg","width":1068,"height":761},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/digitale-pronti-155milioni-di-euro-per-le-imprese\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"Digitale: pronti 15,5milioni di euro per le imprese"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/410"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=410"}],"version-history":[{"count":1,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/410\/revisions"}],"predecessor-version":[{"id":411,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/410\/revisions\/411"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/9"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=410"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=410"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=410"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}