{"id":4110,"date":"2020-09-14T12:36:03","date_gmt":"2020-09-14T10:36:03","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=4110"},"modified":"2020-09-14T12:37:26","modified_gmt":"2020-09-14T10:37:26","slug":"il-gruppo-ebano-vince-la-3-edizione-del-best-managed-companies-di-deloitte-per-il-secondo-anno-consecutivo","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/il-gruppo-ebano-vince-la-3-edizione-del-best-managed-companies-di-deloitte-per-il-secondo-anno-consecutivo\/","title":{"rendered":"Il Gruppo Ebano vince la 3\u00b0 edizione del \u201cBest Managed Companies\u201d di \u00a0Deloitte"},"content":{"rendered":"<p><span class=\"dropcap dropcap3\">I<\/span>l <a href=\"http:\/\/www.gruppoebano.com\">Gruppo Ebano<\/a> \u00e8 tra i vincitori della 3\u00b0 edizione del \u201cBest Managed Companies\u201d, iniziativa promossa da Deloitte per supportare e premiare le aziende italiane eccellenti per capacit\u00e0 organizzativa, strategia e performance.<\/p>\n<p>Valutati da Deloitte sono stati 6 pillar: Strategia, Competenze e Innovazione, Corporate Social Responsibility, Impegno e Cultura Aziendale, Governance e Misurazione delle Performance, Internazionalizzazione.<\/p>\n<p>La realt\u00e0 imprenditoriale fondata e guidata dal presidente della Piccola Industria di Confindustria <strong>Carlo Robiglio<\/strong> opera in settori complementari tra loro: dall\u2019editoria al marketing, dall\u2019e-commerce alla formazione a distanza.<\/p>\n<p>Ed \u00e8 la formazione a distanza uno dei punti di forza, grazie alla controllata Cef Publishing, leader di mercato nella realizzazione e nell\u2019erogazione di corsi professionali per il mercato consumer, con pi\u00f9 di 50 mila iscritti negli ultimi undici anni.<\/p>\n<p>Il Gruppo Ebano, con 9 societ\u00e0 controllate, 15 partnership produttive, pi\u00f9 di 250 dipendenti e collaboratori, tramite la controllata Cef Publishing, \u00e8 anche certificata dal programma Elite di Borsa Italiana per i requisiti di affidabilit\u00e0 e trasparenza richiesti dai principali investitori istituzionali.<\/p>\n<p>Il Gruppo \u00e8 fortemente impegnato nel sociale e nella sostenibilit\u00e0. La politica aziendale di Ebano, volta a perseguire alti standard in termini di sostenibilit\u00e0 e impatto sociale, ha permesso, attraverso la partecipata Cef Publishing, di ottenere la Certificazione b Corp\u00ae, rilasciata dalla B Corporation, l\u2019ente non-profit americano.<\/p>\n<p>\u201cCongratulazioni al Gruppo Ebano per questo importante riconoscimento\u201d, dichiarano <strong>Ernesto Lanzillo<\/strong>, Private Leader per l\u2019Italia, Grecia e Malta, e <strong>Andrea Restelli<\/strong>, Partner Deloitte e responsabile BMC.<\/p>\n<p>\u201cLe aziende premiate in questa terza edizione hanno dimostrato non solo eccellenza, ma anche grande capacit\u00e0 e resilienza nell\u2019affrontare la crisi determinata dalla pandemia da Covid-19 in atto.<\/p>\n<p>La valutazione delle candidate si \u00e8 infatti protratta pi\u00f9 a lungo del previsto proprio per permetterci di approfondire le modalit\u00e0 di gestione dell\u2019emergenza da parte delle candidate. Le 59 Best Managed Companies di questa edizione sono quindi lo specchio di un\u2019Italia fatta di eccellenze che, facendo leva sui propri punti di forza e attraverso una gestione oculata, sta superando con successo un periodo di incertezza senza precedenti\u201d.<\/p>\n<p>&#8220;Questo premio- dichiara Carlo Robiglio- va a tutti i nostri collaboratori per la grande capacit\u00e0 di resilienza, di reazione e vicinanza all&#8217;impresa che hanno saputo dimostrare in questo difficile momento per il Paese riuscendo a trasformare un momento di difficolt\u00e0 in un volano di opportunit\u00e0.\u00a0 Ancor pi\u00f9 velocemente durante questo periodo cos\u00ec complesso abbiamo dovuto e saputo innovare i processi e l&#8217;approccio che abbiamo nella formazione a distanza \u00e8 stato un valido ed indispensabile supporto nel prosieguo di tante attivit\u00e0 che non si sono interrotte ma anzi si intensificate.&#8221;<\/p>\n<div align=\"center\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Il Gruppo Ebano \u00e8 tra i vincitori della 3\u00b0 edizione del \u201cBest Managed Companies\u201d, iniziativa promossa da Deloitte per supportare e premiare le aziende italiane eccellenti per capacit\u00e0 organizzativa, strategia e performance. Valutati da Deloitte sono stati 6 pillar: Strategia, Competenze e Innovazione, Corporate Social Responsibility, Impegno e Cultura Aziendale, Governance e Misurazione delle Performance, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3102,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[133],"tags":[251,285,378,250],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Il Gruppo Ebano vince la 3\u00b0 edizione del \u201cBest Managed Companies\u201d di \u00a0Deloitte -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/il-gruppo-ebano-vince-la-3-edizione-del-best-managed-companies-di-deloitte-per-il-secondo-anno-consecutivo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il Gruppo Ebano vince la 3\u00b0 edizione del \u201cBest Managed Companies\u201d di \u00a0Deloitte -\" \/>\n<meta property=\"og:description\" content=\"Il Gruppo Ebano \u00e8 tra i vincitori della 3\u00b0 edizione del \u201cBest Managed Companies\u201d, iniziativa promossa da Deloitte per supportare e premiare le aziende italiane eccellenti per capacit\u00e0 organizzativa, strategia e performance. Valutati da Deloitte sono stati 6 pillar: Strategia, Competenze e Innovazione, Corporate Social Responsibility, Impegno e Cultura Aziendale, Governance e Misurazione delle Performance, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/il-gruppo-ebano-vince-la-3-edizione-del-best-managed-companies-di-deloitte-per-il-secondo-anno-consecutivo\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-14T10:36:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-09-14T10:37:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/05\/Schermata-2020-05-12-alle-12.38.12.png\" \/>\n\t<meta property=\"og:image:width\" content=\"681\" \/>\n\t<meta property=\"og:image:height\" content=\"447\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/il-gruppo-ebano-vince-la-3-edizione-del-best-managed-companies-di-deloitte-per-il-secondo-anno-consecutivo\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/il-gruppo-ebano-vince-la-3-edizione-del-best-managed-companies-di-deloitte-per-il-secondo-anno-consecutivo\/\",\"name\":\"Il Gruppo Ebano vince la 3\u00b0 edizione del \u201cBest Managed Companies\u201d di \u00a0Deloitte -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/il-gruppo-ebano-vince-la-3-edizione-del-best-managed-companies-di-deloitte-per-il-secondo-anno-consecutivo\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/il-gruppo-ebano-vince-la-3-edizione-del-best-managed-companies-di-deloitte-per-il-secondo-anno-consecutivo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/05\/Schermata-2020-05-12-alle-12.38.12.png\",\"datePublished\":\"2020-09-14T10:36:03+00:00\",\"dateModified\":\"2020-09-14T10:37:26+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/il-gruppo-ebano-vince-la-3-edizione-del-best-managed-companies-di-deloitte-per-il-secondo-anno-consecutivo\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/il-gruppo-ebano-vince-la-3-edizione-del-best-managed-companies-di-deloitte-per-il-secondo-anno-consecutivo\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/il-gruppo-ebano-vince-la-3-edizione-del-best-managed-companies-di-deloitte-per-il-secondo-anno-consecutivo\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/05\/Schermata-2020-05-12-alle-12.38.12.png\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/05\/Schermata-2020-05-12-alle-12.38.12.png\",\"width\":681,\"height\":447},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/il-gruppo-ebano-vince-la-3-edizione-del-best-managed-companies-di-deloitte-per-il-secondo-anno-consecutivo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il Gruppo Ebano vince la 3\u00b0 edizione del \u201cBest Managed Companies\u201d di \u00a0Deloitte\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il Gruppo Ebano vince la 3\u00b0 edizione del \u201cBest Managed Companies\u201d di \u00a0Deloitte -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/il-gruppo-ebano-vince-la-3-edizione-del-best-managed-companies-di-deloitte-per-il-secondo-anno-consecutivo\/","og_locale":"it_IT","og_type":"article","og_title":"Il Gruppo Ebano vince la 3\u00b0 edizione del \u201cBest Managed Companies\u201d di \u00a0Deloitte -","og_description":"Il Gruppo Ebano \u00e8 tra i vincitori della 3\u00b0 edizione del \u201cBest Managed Companies\u201d, iniziativa promossa da Deloitte per supportare e premiare le aziende italiane eccellenti per capacit\u00e0 organizzativa, strategia e performance. Valutati da Deloitte sono stati 6 pillar: Strategia, Competenze e Innovazione, Corporate Social Responsibility, Impegno e Cultura Aziendale, Governance e Misurazione delle Performance, [&hellip;]","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/il-gruppo-ebano-vince-la-3-edizione-del-best-managed-companies-di-deloitte-per-il-secondo-anno-consecutivo\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2020-09-14T10:36:03+00:00","article_modified_time":"2020-09-14T10:37:26+00:00","og_image":[{"width":681,"height":447,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/05\/Schermata-2020-05-12-alle-12.38.12.png","type":"image\/png"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/il-gruppo-ebano-vince-la-3-edizione-del-best-managed-companies-di-deloitte-per-il-secondo-anno-consecutivo\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/il-gruppo-ebano-vince-la-3-edizione-del-best-managed-companies-di-deloitte-per-il-secondo-anno-consecutivo\/","name":"Il Gruppo Ebano vince la 3\u00b0 edizione del \u201cBest Managed Companies\u201d di \u00a0Deloitte -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/il-gruppo-ebano-vince-la-3-edizione-del-best-managed-companies-di-deloitte-per-il-secondo-anno-consecutivo\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/il-gruppo-ebano-vince-la-3-edizione-del-best-managed-companies-di-deloitte-per-il-secondo-anno-consecutivo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/05\/Schermata-2020-05-12-alle-12.38.12.png","datePublished":"2020-09-14T10:36:03+00:00","dateModified":"2020-09-14T10:37:26+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/il-gruppo-ebano-vince-la-3-edizione-del-best-managed-companies-di-deloitte-per-il-secondo-anno-consecutivo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/il-gruppo-ebano-vince-la-3-edizione-del-best-managed-companies-di-deloitte-per-il-secondo-anno-consecutivo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/il-gruppo-ebano-vince-la-3-edizione-del-best-managed-companies-di-deloitte-per-il-secondo-anno-consecutivo\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/05\/Schermata-2020-05-12-alle-12.38.12.png","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/05\/Schermata-2020-05-12-alle-12.38.12.png","width":681,"height":447},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/il-gruppo-ebano-vince-la-3-edizione-del-best-managed-companies-di-deloitte-per-il-secondo-anno-consecutivo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"Il Gruppo Ebano vince la 3\u00b0 edizione del \u201cBest Managed Companies\u201d di \u00a0Deloitte"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/4110"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=4110"}],"version-history":[{"count":3,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/4110\/revisions"}],"predecessor-version":[{"id":4113,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/4110\/revisions\/4113"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/3102"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=4110"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=4110"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=4110"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}