{"id":4114,"date":"2020-09-14T12:42:05","date_gmt":"2020-09-14T10:42:05","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=4114"},"modified":"2020-09-14T12:42:05","modified_gmt":"2020-09-14T10:42:05","slug":"coronavirus-la-commissione-da-il-via-ai-test-del-servizio-gateway-di-interoperabilita","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-la-commissione-da-il-via-ai-test-del-servizio-gateway-di-interoperabilita\/","title":{"rendered":"Coronavirus, la Commissione d\u00e0 il via ai test del servizio gateway di interoperabilit\u00e0"},"content":{"rendered":"<p><span class=\"dropcap dropcap3\">P<\/span>er sfruttare appieno il potenziale delle applicazioni mobili di tracciamento dei contatti di prossimit\u00e0 e allerta, al fine di spezzare la catena delle infezioni da coronavirus e salvare vite umane, la Commissione sta creando un servizio <a href=\"https:\/\/ec.europa.eu\/commission\/presscorner\/detail\/it\/ip_20_1043\"> gateway di interoperabilit\u00e0<\/a> che collega le applicazioni nazionali in tutta l&#8217;UE.<\/p>\n<p>Oggi \u00e8 stata completata una tappa importante con l&#8217;inizio dei primi test dell&#8217;infrastruttura in alcuni Stati membri. La Commissione ha dato il via alle prime prove di collegamento tra i server back-end delle applicazioni ufficiali di Cechia, Danimarca, Germania, Irlanda, Italia e Lettonia e un server gateway appena installato.<\/p>\n<p>Thierry <strong>Breton<\/strong>, Commissario per il Mercato interno, ha dichiarato: <em>&#8220;Molti Stati membri hanno introdotto applicazioni nazionali di tracciamento dei contatti e allerta. Ora \u00e8 giunto il momento di farle interagire. I viaggi e gli scambi personali sono al centro del progetto europeo e del mercato unico e in questi tempi segnati dalla pandemia il gateway contribuir\u00e0 ad agevolarli e a salvare vite umane.&#8221;<\/em><\/p>\n<p>Stella <strong>Kyriakides<\/strong>, Commissaria per la Salute e la Sicurezza alimentare, ha aggiunto<em>: &#8220;Applicazioni di tracciamento dei contatti e allerta per il coronavirus che funzionano al di l\u00e0 dei confini nazionali possono essere strumenti potenti per aiutarci a contenere la diffusione della COVID-19. Con il nuovo aumento dei contagi, queste applicazioni possono integrare altre misure, come un maggior numero di test e il tracciamento manuale dei contatti. Se diffuse a sufficienza possono aiutarci a spezzare la catena delle infezioni. Continueremo di lottare su ogni fronte contro la pandemia.&#8221;<\/em><\/p>\n<p>Nel contesto della lotta al coronavirus la maggior parte degli Stati membri ha lanciato un&#8217;applicazione nazionale di tracciamento dei contatti e allerta o prevede di farlo. L&#8217;istituzione del servizio gateway di interoperabilit\u00e0 da parte della Commissione d\u00e0 seguito all&#8217;<a href=\"https:\/\/ec.europa.eu\/commission\/presscorner\/detail\/it\/ip_20_1043\">accordo degli Stati membri sulle specifiche tecniche<\/a>, volto a fornire una soluzione europea per garantire lo scambio sicuro di informazioni tra i back-end delle applicazioni nazionali di tracciamento dei contatti e allerta basate su un&#8217;architettura decentrata. Ci\u00f2 riguarda pressoch\u00e9 tutte le applicazioni di tracciamento lanciate nell&#8217;UE.<\/p>\n<p>Il gateway, un&#8217;infrastruttura digitale che garantisce la trasmissione di informazioni tra i server back-end delle applicazioni nazionali, permetter\u00e0 a tali applicazioni di funzionare senza soluzione di continuit\u00e0 anche a livello transfrontaliero. In questo modo gli utenti dovranno installare solo un&#8217;applicazione e potranno comunque segnalare un test positivo all&#8217;infezione o ricevere un&#8217;allerta anche quando viaggiano all&#8217;estero.<\/p>\n<p>Il gateway far\u00e0 circolare in modo efficiente gli identificativi arbitrari tra le applicazioni nazionali, in modo da ridurre al minimo la quantit\u00e0 di dati scambiati e quindi il consumo di dati da parte degli utenti. Il gateway tratter\u00e0 esclusivamente le chiavi arbitrarie generate dalle applicazioni nazionali; le informazioni scambiate saranno pseudonimizzate, criptate, limitate al minimo indispensabile e conservate solo per il tempo necessario al tracciamento delle infezioni e non sar\u00e0 possibile l&#8217;identificazione di singole persone.<\/p>\n<p>Il gateway \u00e8 stato sviluppato e realizzato da T-Systems e SAP, sar\u00e0 gestito dal Data Centre della Commissione a Lussemburgo e sar\u00e0 operativo a partire da ottobre, al termine di una fase di test.<\/p>\n<p>&nbsp;<\/p>\n<p>Dall&#8217;inizio della pandemia di coronavirus gli Stati membri, sostenuti dalla Commissione, valutano le soluzioni digitali per affrontare la crisi sotto i seguenti profili: efficacia, sicurezza, tutela della vita privata e protezione dei dati. Le applicazioni di tracciamento dei contatti, se pienamente conformi alle norme dell&#8217;UE e ben coordinate, possono svolgere un ruolo importante in tutte le fasi di gestione della crisi e in particolare in quella attuale di graduale revoca delle misure di distanziamento sociale nella maggior parte dei paesi. Possono integrare il tracciamento manuale dei contatti gi\u00e0 in essere e contribuire a interrompere la catena di trasmissione del virus. In questo modo possono contribuire a salvare vite umane.<\/p>\n<p>&nbsp;<\/p>\n<p>Nell&#8217;ambito della rete di assistenza sanitaria online (eHealth) gli Stati membri hanno sviluppato, con il sostegno della Commissione, un <a href=\"https:\/\/ec.europa.eu\/health\/sites\/health\/files\/ehealth\/docs\/covid-19_apps_en.pdf\"> pacchetto di strumenti dell&#8217;UE per l&#8217;uso di applicazioni mobili di tracciamento dei contatti e allerta<\/a> in risposta alla pandemia di coronavirus, corredato degli <a href=\"https:\/\/ec.europa.eu\/commission\/presscorner\/detail\/it\/ip_20_669\">orientamenti sulla protezione dei dati<\/a> per le applicazioni mobili. Come <a href=\"https:\/\/ec.europa.eu\/commission\/presscorner\/detail\/it\/ip_20_626\">stabilito in una raccomandazione della Commissione<\/a>, questo pacchetto di strumenti rientra in un approccio comune coordinato a sostegno della revoca graduale delle misure di confinamento. Per garantire il funzionamento transfrontaliero delle applicazioni di tracciamento dei contatti e allerta, gli Stati membri, con il sostegno della Commissione, hanno concordato a maggio <a href=\"https:\/\/ec.europa.eu\/health\/sites\/health\/files\/ehealth\/docs\/contacttracing_mobileapps_guidelines_en.pdf\"> gli orientamenti sull&#8217;interoperabilit\u00e0<\/a> e successivamente a giugno una <a href=\"https:\/\/ec.europa.eu\/health\/ehealth\/key_documents_en#anchor0\"> serie di specifiche tecniche<\/a>, mentre la Commissione ha adottato una <a href=\"https:\/\/eur-lex.europa.eu\/legal-content\/IT\/TXT\/?uri=uriserv%3AOJ.LI.2020.227.01.0001.01.ITA\"> decisione di esecuzione<\/a> per fornire una base giuridica per l&#8217;istituzione del servizio gateway.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Per sfruttare appieno il potenziale delle applicazioni mobili di tracciamento dei contatti di prossimit\u00e0 e allerta, al fine di spezzare la catena delle infezioni da coronavirus e salvare vite umane, la Commissione sta creando un servizio gateway di interoperabilit\u00e0 che collega le applicazioni nazionali in tutta l&#8217;UE. Oggi \u00e8 stata completata una tappa importante con [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2783,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[56],"tags":[1030,877],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Coronavirus, la Commissione d\u00e0 il via ai test del servizio gateway di interoperabilit\u00e0 -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-la-commissione-da-il-via-ai-test-del-servizio-gateway-di-interoperabilita\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Coronavirus, la Commissione d\u00e0 il via ai test del servizio gateway di interoperabilit\u00e0 -\" \/>\n<meta property=\"og:description\" content=\"Per sfruttare appieno il potenziale delle applicazioni mobili di tracciamento dei contatti di prossimit\u00e0 e allerta, al fine di spezzare la catena delle infezioni da coronavirus e salvare vite umane, la Commissione sta creando un servizio gateway di interoperabilit\u00e0 che collega le applicazioni nazionali in tutta l&#8217;UE. Oggi \u00e8 stata completata una tappa importante con [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-la-commissione-da-il-via-ai-test-del-servizio-gateway-di-interoperabilita\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-14T10:42:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/03\/coronavirus.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-la-commissione-da-il-via-ai-test-del-servizio-gateway-di-interoperabilita\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-la-commissione-da-il-via-ai-test-del-servizio-gateway-di-interoperabilita\/\",\"name\":\"Coronavirus, la Commissione d\u00e0 il via ai test del servizio gateway di interoperabilit\u00e0 -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-la-commissione-da-il-via-ai-test-del-servizio-gateway-di-interoperabilita\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-la-commissione-da-il-via-ai-test-del-servizio-gateway-di-interoperabilita\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/03\/coronavirus.jpg\",\"datePublished\":\"2020-09-14T10:42:05+00:00\",\"dateModified\":\"2020-09-14T10:42:05+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-la-commissione-da-il-via-ai-test-del-servizio-gateway-di-interoperabilita\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-la-commissione-da-il-via-ai-test-del-servizio-gateway-di-interoperabilita\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-la-commissione-da-il-via-ai-test-del-servizio-gateway-di-interoperabilita\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/03\/coronavirus.jpg\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/03\/coronavirus.jpg\",\"width\":960,\"height\":640},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-la-commissione-da-il-via-ai-test-del-servizio-gateway-di-interoperabilita\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Coronavirus, la Commissione d\u00e0 il via ai test del servizio gateway di interoperabilit\u00e0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Coronavirus, la Commissione d\u00e0 il via ai test del servizio gateway di interoperabilit\u00e0 -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-la-commissione-da-il-via-ai-test-del-servizio-gateway-di-interoperabilita\/","og_locale":"it_IT","og_type":"article","og_title":"Coronavirus, la Commissione d\u00e0 il via ai test del servizio gateway di interoperabilit\u00e0 -","og_description":"Per sfruttare appieno il potenziale delle applicazioni mobili di tracciamento dei contatti di prossimit\u00e0 e allerta, al fine di spezzare la catena delle infezioni da coronavirus e salvare vite umane, la Commissione sta creando un servizio gateway di interoperabilit\u00e0 che collega le applicazioni nazionali in tutta l&#8217;UE. Oggi \u00e8 stata completata una tappa importante con [&hellip;]","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-la-commissione-da-il-via-ai-test-del-servizio-gateway-di-interoperabilita\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2020-09-14T10:42:05+00:00","og_image":[{"width":960,"height":640,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/03\/coronavirus.jpg","type":"image\/jpeg"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-la-commissione-da-il-via-ai-test-del-servizio-gateway-di-interoperabilita\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-la-commissione-da-il-via-ai-test-del-servizio-gateway-di-interoperabilita\/","name":"Coronavirus, la Commissione d\u00e0 il via ai test del servizio gateway di interoperabilit\u00e0 -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-la-commissione-da-il-via-ai-test-del-servizio-gateway-di-interoperabilita\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-la-commissione-da-il-via-ai-test-del-servizio-gateway-di-interoperabilita\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/03\/coronavirus.jpg","datePublished":"2020-09-14T10:42:05+00:00","dateModified":"2020-09-14T10:42:05+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-la-commissione-da-il-via-ai-test-del-servizio-gateway-di-interoperabilita\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-la-commissione-da-il-via-ai-test-del-servizio-gateway-di-interoperabilita\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-la-commissione-da-il-via-ai-test-del-servizio-gateway-di-interoperabilita\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/03\/coronavirus.jpg","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/03\/coronavirus.jpg","width":960,"height":640},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-la-commissione-da-il-via-ai-test-del-servizio-gateway-di-interoperabilita\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"Coronavirus, la Commissione d\u00e0 il via ai test del servizio gateway di interoperabilit\u00e0"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/4114"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=4114"}],"version-history":[{"count":1,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/4114\/revisions"}],"predecessor-version":[{"id":4115,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/4114\/revisions\/4115"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/2783"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=4114"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=4114"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=4114"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}