{"id":4127,"date":"2020-09-15T16:41:09","date_gmt":"2020-09-15T14:41:09","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=4127"},"modified":"2020-09-15T16:41:09","modified_gmt":"2020-09-15T14:41:09","slug":"marina-militare-e-inps-costituito-il-polo-nazionale-marina-militare","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/marina-militare-e-inps-costituito-il-polo-nazionale-marina-militare\/","title":{"rendered":"Marina militare e Inps: costituito il polo nazionale marina militare"},"content":{"rendered":"<p><span class=\"dropcap dropcap3\">I<\/span>l Presidente dell\u2019Inps prof. Pasquale Tridico e il Capo di Stato Maggiore della Marina Militare, Ammiraglio Giuseppe Cavo Dragone, hanno sottoscritto un protocollo d\u2019intesa per la costituzione del \u201cPolo nazionale della Marina Militare\u201d nel corso di una cerimonia tenutasi questa mattina presso la Sala dei Marmi di Palazzo Marina. L\u2019istituzione del Polo sancisce l\u2019avvio di un rapporto di collaborazione che ha lo scopo di migliorare i servizi offerti dall\u2019Istituto al personale militare della Marina.<\/p>\n<p>Il \u201cPolo nazionale Marina Militare\u201d sar\u00e0 operativo dal 1\u00b0 ottobre 2020 presso la Direzione provinciale Inps della Spezia e accentrer\u00e0 tutti gli adempimenti amministrativi di competenza dell\u2019Inps in materia di gestione della posizione assicurativa, prestazioni pensionistiche, posizioni previdenziali e gestione creditizia dei piccoli prestiti e dei prestiti pluriennali relativi al personale della Marina Militare dell\u2019intero territorio nazionale, consolidando cos\u00ec una gi\u00e0 rodata collaborazione tra le due istituzioni.<\/p>\n<p>La Marina Militare, al fine di uniformare le procedure interne e le tempistiche di erogazione del trattamento pensionistico a favore del proprio personale, ha provveduto gi\u00e0 da tempo a centralizzare la gestione delle relative pratiche presso il Reparto Trattamento Pensionistico della Marina Militare, operante alle dipendenze della Direzione di Intendenza di Roma<br \/>\nL\u2019assunzione delle competenze del Polo riguarder\u00e0 gli assicurati che, alla data del 1\u00b0 ottobre 2020, non risulteranno aver presentato all\u2019Inps domanda di prestazioni pensionistiche, ovvero transiteranno dalla posizione di ausiliaria a quella di riserva, o ai fini del trattamento di fine servizio cessino dal servizio o presentino domanda di riscatto ai fini TFS o di prestazioni creditizie dalla predetta data.<\/p>\n<p>L\u2019iniziativa, grazie all\u2019impegno di una progressiva sistemazione dei cassetti contributivi relativi alla platea interessata, favorir\u00e0 lo snellimento delle procedure e delle istruttorie per la definizione delle prestazioni richieste dagli utenti, con conseguenti risparmi dei costi di gestione delle Amministrazioni coinvolte.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Presidente dell\u2019Inps prof. Pasquale Tridico e il Capo di Stato Maggiore della Marina Militare, Ammiraglio Giuseppe Cavo Dragone, hanno sottoscritto un protocollo d\u2019intesa per la costituzione del \u201cPolo nazionale della Marina Militare\u201d nel corso di una cerimonia tenutasi questa mattina presso la Sala dei Marmi di Palazzo Marina. L\u2019istituzione del Polo sancisce l\u2019avvio di [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1600,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[490],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Marina militare e Inps: costituito il polo nazionale marina militare -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/marina-militare-e-inps-costituito-il-polo-nazionale-marina-militare\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Marina militare e Inps: costituito il polo nazionale marina militare -\" \/>\n<meta property=\"og:description\" content=\"Il Presidente dell\u2019Inps prof. Pasquale Tridico e il Capo di Stato Maggiore della Marina Militare, Ammiraglio Giuseppe Cavo Dragone, hanno sottoscritto un protocollo d\u2019intesa per la costituzione del \u201cPolo nazionale della Marina Militare\u201d nel corso di una cerimonia tenutasi questa mattina presso la Sala dei Marmi di Palazzo Marina. L\u2019istituzione del Polo sancisce l\u2019avvio di [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/marina-militare-e-inps-costituito-il-polo-nazionale-marina-militare\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-15T14:41:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/08\/Lavoro5.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"510\" \/>\n\t<meta property=\"og:image:height\" content=\"340\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/marina-militare-e-inps-costituito-il-polo-nazionale-marina-militare\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/marina-militare-e-inps-costituito-il-polo-nazionale-marina-militare\/\",\"name\":\"Marina militare e Inps: costituito il polo nazionale marina militare -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/marina-militare-e-inps-costituito-il-polo-nazionale-marina-militare\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/marina-militare-e-inps-costituito-il-polo-nazionale-marina-militare\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/08\/Lavoro5.jpg\",\"datePublished\":\"2020-09-15T14:41:09+00:00\",\"dateModified\":\"2020-09-15T14:41:09+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/marina-militare-e-inps-costituito-il-polo-nazionale-marina-militare\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/marina-militare-e-inps-costituito-il-polo-nazionale-marina-militare\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/marina-militare-e-inps-costituito-il-polo-nazionale-marina-militare\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/08\/Lavoro5.jpg\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/08\/Lavoro5.jpg\",\"width\":510,\"height\":340},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/marina-militare-e-inps-costituito-il-polo-nazionale-marina-militare\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Marina militare e Inps: costituito il polo nazionale marina militare\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Marina militare e Inps: costituito il polo nazionale marina militare -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/marina-militare-e-inps-costituito-il-polo-nazionale-marina-militare\/","og_locale":"it_IT","og_type":"article","og_title":"Marina militare e Inps: costituito il polo nazionale marina militare -","og_description":"Il Presidente dell\u2019Inps prof. Pasquale Tridico e il Capo di Stato Maggiore della Marina Militare, Ammiraglio Giuseppe Cavo Dragone, hanno sottoscritto un protocollo d\u2019intesa per la costituzione del \u201cPolo nazionale della Marina Militare\u201d nel corso di una cerimonia tenutasi questa mattina presso la Sala dei Marmi di Palazzo Marina. L\u2019istituzione del Polo sancisce l\u2019avvio di [&hellip;]","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/marina-militare-e-inps-costituito-il-polo-nazionale-marina-militare\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2020-09-15T14:41:09+00:00","og_image":[{"width":510,"height":340,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/08\/Lavoro5.jpg","type":"image\/jpeg"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/marina-militare-e-inps-costituito-il-polo-nazionale-marina-militare\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/marina-militare-e-inps-costituito-il-polo-nazionale-marina-militare\/","name":"Marina militare e Inps: costituito il polo nazionale marina militare -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/marina-militare-e-inps-costituito-il-polo-nazionale-marina-militare\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/marina-militare-e-inps-costituito-il-polo-nazionale-marina-militare\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/08\/Lavoro5.jpg","datePublished":"2020-09-15T14:41:09+00:00","dateModified":"2020-09-15T14:41:09+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/marina-militare-e-inps-costituito-il-polo-nazionale-marina-militare\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/marina-militare-e-inps-costituito-il-polo-nazionale-marina-militare\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/marina-militare-e-inps-costituito-il-polo-nazionale-marina-militare\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/08\/Lavoro5.jpg","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/08\/Lavoro5.jpg","width":510,"height":340},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/marina-militare-e-inps-costituito-il-polo-nazionale-marina-militare\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"Marina militare e Inps: costituito il polo nazionale marina militare"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/4127"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=4127"}],"version-history":[{"count":1,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/4127\/revisions"}],"predecessor-version":[{"id":4128,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/4127\/revisions\/4128"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/1600"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=4127"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=4127"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=4127"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}