{"id":4141,"date":"2020-09-18T10:41:17","date_gmt":"2020-09-18T08:41:17","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=4141"},"modified":"2020-09-18T10:42:42","modified_gmt":"2020-09-18T08:42:42","slug":"coronavirus-nellultima-settimana-26-di-ricoveri-41-di-terapie-intensive","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-nellultima-settimana-26-di-ricoveri-41-di-terapie-intensive\/","title":{"rendered":"Coronavirus, nell&#8217;ultima settimana +26% di ricoveri, +41% di terapie intensive"},"content":{"rendered":"<p><span class=\"dropcap dropcap3\">I<\/span>l monitoraggio indipendente della Fondazione GIMBE registra nella settimana 9-15 settembre, rispetto alla precedente, una stabilizzazione nell\u2019aumento dei nuovi casi (9.837 vs 9.964) a fronte di una riduzione dei casi testati (370.012 vs 421.897). Dal punto di vista epidemiologico aumentano i casi attualmente positivi (39.712 vs 33.789) e, sul fronte degli ospedali, i pazienti ricoverati con sintomi (2.222 vs 1.760) e in terapia intensiva (201 vs 143). Stabile il numero dei decessi (70 vs 72).<\/p>\n<p>In dettaglio, rispetto alla settimana precedente, si registrano le seguenti variazioni:<\/p>\n<p>Decessi: -2 (-2,8%)<br \/>\nTerapia intensiva: +58 (+40,6%)<br \/>\nRicoverati con sintomi: +462 (+26,3%)<br \/>\nNuovi casi: +9.837 (-1,3%)<br \/>\nCasi attualmente positivi: +5.923 (+17,5%)<br \/>\nCasi testati -51.885 (-12,3%)<br \/>\nTamponi totali: -58.573 (-9,2%)<\/p>\n<p>\u00abNell\u2019ultima settimana \u2013 afferma Nino Cartabellotta, Presidente della Fondazione GIMBE \u2013 l\u2019aumento dei nuovi casi appare stabilizzato, anche se \u00e8 verosimile che il numero sia sottostimato considerata la riduzione dei casi testati e l\u2019ulteriore aumento del rapporto positivi\/casi testati.<\/p>\n<p>Si conferma inoltre il trend in aumento dei pazienti ospedalizzati con sintomi e di quelli in terapia intensiva. Tutte spie rosse che impongono la consapevolezza pubblica sulle dinamiche dell\u2019epidemia, senza minimizzazioni o terrorismi di sorta, al fine di mantenere alta la guardia anche per l\u2019imprevedibile impatto della riapertura delle scuole sulla curva dei contagi\u00bb.<\/p>\n<p>Nel quadro di una circolazione endemica del virus l\u2019aumento progressivo dei focolai ha determinato la crescita dei nuovi casi settimanali. Infatti, dai 1.408 della settimana 15-21 luglio siamo passati a 9.837 nuovi casi di quella 9-15 settembre, con un incremento del rapporto positivi\/casi testati dallo 0,8% al 2,7%.<\/p>\n<p>Questa dinamica ha generato il progressivo aumento dei casi attualmente positivi che da fine luglio sono pi\u00f9 che triplicati: da 12.482 a 39.712 .<\/p>\n<p>L\u2019incremento dei casi attualmente positivi, espandendo il \u201cbacino\u201d dei contagi, si riflette progressivamente sull\u2019aumento dei pazienti ospedalizzati. Infatti, dal 21 luglio al 15 settembre i ricoverati con sintomi sono aumentati da 732 a 2.222 e i pazienti in terapia intensiva da 49 a 201 (figura 3).<\/p>\n<p>Circa 3\/4 dei pazienti ricoverati si concentrano in 7 Regioni (74,3%): Lazio (453), Campania (295), Lombardia (263), Puglia (204), Emilia-Romagna (168), Sicilia (141) e Liguria (128). Il 74,1% dei pazienti in terapia intensiva si distribuiscono in 8 Regioni: Lombardia (29), Lazio (18), Campania (18), Sardegna (18), Emilia-Romagna (17), Sicilia (17), Toscana (17), Veneto (15) .<\/p>\n<p>\u00abVero \u00e8 che si tratta di numeri ancora bassi \u2013 puntualizza il Presidente \u2013 e che al momento non risultano segnali di sovraccarico dei servizi ospedalieri, ma il trend in costante aumento impone di mantenere la guardia molto alta, soprattutto in alcune Regioni\u00bb. In particolare, rispetto ad una media nazionale di 4 ospedalizzazioni per 100.000 abitanti i tassi risultano pi\u00f9 elevati in Liguria (9), Lazio (8), Sardegna (6,3), Campania e Puglia (5,4).<\/p>\n<p>\u00abQueste dinamiche dell\u2019epidemia \u2013 conclude Cartabellotta \u2013 sono coerenti con quanto rilevato dalla sorveglianza epidemiologica dell\u2019Istituto Superiore di Sanit\u00e0 sull\u2019et\u00e0 mediana dei contagiati che si \u00e8 ridotta da oltre 60 anni dei primi due mesi dell\u2019epidemia sino a sotto i 30 nelle settimane centrali di agosto.<\/p>\n<p>Quindi, nelle ultime due settimane \u00e8 risalita a circa 40 anni, dimostrando che i giovani asintomatici, quando vengono a contatto in ambito familiare con persone adulte e anziane, contagiano soggetti fragili che sviluppano sintomi e possono necessitare di ricovero ospedaliero, o addirittura in terapia intensiva. Davanti a questo scenario epidemiologico e clinico, le Regioni devono potenziare senza indugi l\u2019attivit\u00e0 di testing e tracing, in evidente calo dopo il \u201cboom dei tamponi\u201d sui vacanzieri\u00bb.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il monitoraggio indipendente della Fondazione GIMBE registra nella settimana 9-15 settembre, rispetto alla precedente, una stabilizzazione nell\u2019aumento dei nuovi casi (9.837 vs 9.964) a fronte di una riduzione dei casi testati (370.012 vs 421.897). Dal punto di vista epidemiologico aumentano i casi attualmente positivi (39.712 vs 33.789) e, sul fronte degli ospedali, i pazienti ricoverati [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4144,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[128],"tags":[877,1260],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Coronavirus, nell&#039;ultima settimana +26% di ricoveri, +41% di terapie intensive -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-nellultima-settimana-26-di-ricoveri-41-di-terapie-intensive\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Coronavirus, nell&#039;ultima settimana +26% di ricoveri, +41% di terapie intensive -\" \/>\n<meta property=\"og:description\" content=\"Il monitoraggio indipendente della Fondazione GIMBE registra nella settimana 9-15 settembre, rispetto alla precedente, una stabilizzazione nell\u2019aumento dei nuovi casi (9.837 vs 9.964) a fronte di una riduzione dei casi testati (370.012 vs 421.897). Dal punto di vista epidemiologico aumentano i casi attualmente positivi (39.712 vs 33.789) e, sul fronte degli ospedali, i pazienti ricoverati [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-nellultima-settimana-26-di-ricoveri-41-di-terapie-intensive\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-18T08:41:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-09-18T08:42:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/09\/Schermata-2020-09-18-alle-10.40.28.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1230\" \/>\n\t<meta property=\"og:image:height\" content=\"718\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-nellultima-settimana-26-di-ricoveri-41-di-terapie-intensive\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-nellultima-settimana-26-di-ricoveri-41-di-terapie-intensive\/\",\"name\":\"Coronavirus, nell'ultima settimana +26% di ricoveri, +41% di terapie intensive -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-nellultima-settimana-26-di-ricoveri-41-di-terapie-intensive\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-nellultima-settimana-26-di-ricoveri-41-di-terapie-intensive\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/09\/Schermata-2020-09-18-alle-10.40.28.png\",\"datePublished\":\"2020-09-18T08:41:17+00:00\",\"dateModified\":\"2020-09-18T08:42:42+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-nellultima-settimana-26-di-ricoveri-41-di-terapie-intensive\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-nellultima-settimana-26-di-ricoveri-41-di-terapie-intensive\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-nellultima-settimana-26-di-ricoveri-41-di-terapie-intensive\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/09\/Schermata-2020-09-18-alle-10.40.28.png\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/09\/Schermata-2020-09-18-alle-10.40.28.png\",\"width\":1230,\"height\":718},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-nellultima-settimana-26-di-ricoveri-41-di-terapie-intensive\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Coronavirus, nell&#8217;ultima settimana +26% di ricoveri, +41% di terapie intensive\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Coronavirus, nell'ultima settimana +26% di ricoveri, +41% di terapie intensive -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-nellultima-settimana-26-di-ricoveri-41-di-terapie-intensive\/","og_locale":"it_IT","og_type":"article","og_title":"Coronavirus, nell'ultima settimana +26% di ricoveri, +41% di terapie intensive -","og_description":"Il monitoraggio indipendente della Fondazione GIMBE registra nella settimana 9-15 settembre, rispetto alla precedente, una stabilizzazione nell\u2019aumento dei nuovi casi (9.837 vs 9.964) a fronte di una riduzione dei casi testati (370.012 vs 421.897). Dal punto di vista epidemiologico aumentano i casi attualmente positivi (39.712 vs 33.789) e, sul fronte degli ospedali, i pazienti ricoverati [&hellip;]","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-nellultima-settimana-26-di-ricoveri-41-di-terapie-intensive\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2020-09-18T08:41:17+00:00","article_modified_time":"2020-09-18T08:42:42+00:00","og_image":[{"width":1230,"height":718,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/09\/Schermata-2020-09-18-alle-10.40.28.png","type":"image\/png"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-nellultima-settimana-26-di-ricoveri-41-di-terapie-intensive\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-nellultima-settimana-26-di-ricoveri-41-di-terapie-intensive\/","name":"Coronavirus, nell'ultima settimana +26% di ricoveri, +41% di terapie intensive -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-nellultima-settimana-26-di-ricoveri-41-di-terapie-intensive\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-nellultima-settimana-26-di-ricoveri-41-di-terapie-intensive\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/09\/Schermata-2020-09-18-alle-10.40.28.png","datePublished":"2020-09-18T08:41:17+00:00","dateModified":"2020-09-18T08:42:42+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-nellultima-settimana-26-di-ricoveri-41-di-terapie-intensive\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-nellultima-settimana-26-di-ricoveri-41-di-terapie-intensive\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-nellultima-settimana-26-di-ricoveri-41-di-terapie-intensive\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/09\/Schermata-2020-09-18-alle-10.40.28.png","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/09\/Schermata-2020-09-18-alle-10.40.28.png","width":1230,"height":718},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-nellultima-settimana-26-di-ricoveri-41-di-terapie-intensive\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"Coronavirus, nell&#8217;ultima settimana +26% di ricoveri, +41% di terapie intensive"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/4141"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=4141"}],"version-history":[{"count":1,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/4141\/revisions"}],"predecessor-version":[{"id":4142,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/4141\/revisions\/4142"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/4144"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=4141"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=4141"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=4141"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}