{"id":4168,"date":"2020-09-22T11:03:14","date_gmt":"2020-09-22T09:03:14","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=4168"},"modified":"2020-09-22T11:10:43","modified_gmt":"2020-09-22T09:10:43","slug":"in-circolazione-false-email-a-nome-dellagenzia-non-aprire-gli-allegati-e-cestinare-immediatamente","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/in-circolazione-false-email-a-nome-dellagenzia-non-aprire-gli-allegati-e-cestinare-immediatamente\/","title":{"rendered":"In circolazione false email a nome dell\u2019Agenzia delle entrate"},"content":{"rendered":"<p><span class=\"dropcap dropcap3\">S<\/span>ono in corso nuovi tentativi di phishing a danno degli utenti attraverso email che sembrano essere riconducibili all\u2019Agenzia.<\/p>\n<p>L\u2019Agenzia \u00e8 estranea a tali messaggi ed invita gli utenti a cestinare immediatamente messaggi di posta elettronica che riportano nell\u2019intestazione la dicitura \u201c<b>IL DIRETTORE DELL\u2019AGENZIA<\/b>\u201d o \u201c<b>GLI ORGANI DELL\u2019AGENZIA<\/b>\u201d e che, nel testo, invitano a prendere visione di documenti contenuti in un archivio allegato per verificare \u201c<b>alcune incoerenze<\/b>\u201d emerse \u201c<b>dall\u2019esame dei dati e dei saldi relativi alla Divulgazione delle eliminazioni periodiche Iva<\/b>\u201d.<\/p>\n<p>Le email, infatti, non provengono dall\u2019Agenzia, ma costituiscono il tentativo di installare un malware sui dispositivi dei destinatari anche allo scopo di acquisire successivamente informazioni riservate. Di seguito due esempi di questi messaggi:<\/p>\n<p align=\"center\"><img decoding=\"async\" src=\"https:\/\/www.agenziaentrate.gov.it\/portale\/documents\/20143\/2665953\/immgine1.jpg\/f359734a-1a8f-f38a-456b-e4cd63b51d81?t=1600764083808\" \/><\/p>\n<p align=\"center\"><a href=\"http:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/09\/Schermata-2020-09-22-alle-10.58.08.png\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-4169\" src=\"http:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/09\/Schermata-2020-09-22-alle-10.58.08.png\" alt=\"\" width=\"1606\" height=\"798\" srcset=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/09\/Schermata-2020-09-22-alle-10.58.08.png 1606w, https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/09\/Schermata-2020-09-22-alle-10.58.08-300x149.png 300w, https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/09\/Schermata-2020-09-22-alle-10.58.08-1024x509.png 1024w, https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/09\/Schermata-2020-09-22-alle-10.58.08-768x382.png 768w, https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/09\/Schermata-2020-09-22-alle-10.58.08-1536x763.png 1536w, https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/09\/Schermata-2020-09-22-alle-10.58.08-324x160.png 324w, https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/09\/Schermata-2020-09-22-alle-10.58.08-696x346.png 696w, https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/09\/Schermata-2020-09-22-alle-10.58.08-1068x531.png 1068w, https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/09\/Schermata-2020-09-22-alle-10.58.08-845x420.png 845w\" sizes=\"(max-width: 1606px) 100vw, 1606px\" \/><\/a><\/p>\n<p style=\"text-align: left;\" align=\"center\"><strong>L\u2019Agenzia raccomanda ai contribuenti di verificare sempre attentamente i messaggi ricevuti<\/strong> e, se questi appaiono sospetti, soprattutto se i mittenti sono sconosciuti, di non aprire gli allegati o seguire i collegamenti presenti nelle mail (anche per evitare danni ai propri pc, tablet e smartphone) e cestinarli. Inoltre, precisa che non vengono mai inviate per posta elettronica comunicazioni contenenti dati personali dei contribuenti. Le informazioni personali sono consultabili esclusivamente nel Cassetto fiscale, accessibile tramite l\u2019area riservata sul sito dell\u2019Agenzia delle Entrate.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sono in corso nuovi tentativi di phishing a danno degli utenti attraverso email che sembrano essere riconducibili all\u2019Agenzia. L\u2019Agenzia \u00e8 estranea a tali messaggi ed invita gli utenti a cestinare immediatamente messaggi di posta elettronica che riportano nell\u2019intestazione la dicitura \u201cIL DIRETTORE DELL\u2019AGENZIA\u201d o \u201cGLI ORGANI DELL\u2019AGENZIA\u201d e che, nel testo, invitano a prendere visione [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3865,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[632],"tags":[393,1100],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>In circolazione false email a nome dell\u2019Agenzia delle entrate -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/in-circolazione-false-email-a-nome-dellagenzia-non-aprire-gli-allegati-e-cestinare-immediatamente\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"In circolazione false email a nome dell\u2019Agenzia delle entrate -\" \/>\n<meta property=\"og:description\" content=\"Sono in corso nuovi tentativi di phishing a danno degli utenti attraverso email che sembrano essere riconducibili all\u2019Agenzia. L\u2019Agenzia \u00e8 estranea a tali messaggi ed invita gli utenti a cestinare immediatamente messaggi di posta elettronica che riportano nell\u2019intestazione la dicitura \u201cIL DIRETTORE DELL\u2019AGENZIA\u201d o \u201cGLI ORGANI DELL\u2019AGENZIA\u201d e che, nel testo, invitano a prendere visione [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/in-circolazione-false-email-a-nome-dellagenzia-non-aprire-gli-allegati-e-cestinare-immediatamente\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-22T09:03:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-09-22T09:10:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/08\/Schermata-2020-08-06-alle-11.47.35.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1486\" \/>\n\t<meta property=\"og:image:height\" content=\"956\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/in-circolazione-false-email-a-nome-dellagenzia-non-aprire-gli-allegati-e-cestinare-immediatamente\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/in-circolazione-false-email-a-nome-dellagenzia-non-aprire-gli-allegati-e-cestinare-immediatamente\/\",\"name\":\"In circolazione false email a nome dell\u2019Agenzia delle entrate -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/in-circolazione-false-email-a-nome-dellagenzia-non-aprire-gli-allegati-e-cestinare-immediatamente\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/in-circolazione-false-email-a-nome-dellagenzia-non-aprire-gli-allegati-e-cestinare-immediatamente\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/08\/Schermata-2020-08-06-alle-11.47.35.png\",\"datePublished\":\"2020-09-22T09:03:14+00:00\",\"dateModified\":\"2020-09-22T09:10:43+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/in-circolazione-false-email-a-nome-dellagenzia-non-aprire-gli-allegati-e-cestinare-immediatamente\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/in-circolazione-false-email-a-nome-dellagenzia-non-aprire-gli-allegati-e-cestinare-immediatamente\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/in-circolazione-false-email-a-nome-dellagenzia-non-aprire-gli-allegati-e-cestinare-immediatamente\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/08\/Schermata-2020-08-06-alle-11.47.35.png\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/08\/Schermata-2020-08-06-alle-11.47.35.png\",\"width\":1486,\"height\":956},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/in-circolazione-false-email-a-nome-dellagenzia-non-aprire-gli-allegati-e-cestinare-immediatamente\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"In circolazione false email a nome dell\u2019Agenzia delle entrate\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"In circolazione false email a nome dell\u2019Agenzia delle entrate -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/in-circolazione-false-email-a-nome-dellagenzia-non-aprire-gli-allegati-e-cestinare-immediatamente\/","og_locale":"it_IT","og_type":"article","og_title":"In circolazione false email a nome dell\u2019Agenzia delle entrate -","og_description":"Sono in corso nuovi tentativi di phishing a danno degli utenti attraverso email che sembrano essere riconducibili all\u2019Agenzia. L\u2019Agenzia \u00e8 estranea a tali messaggi ed invita gli utenti a cestinare immediatamente messaggi di posta elettronica che riportano nell\u2019intestazione la dicitura \u201cIL DIRETTORE DELL\u2019AGENZIA\u201d o \u201cGLI ORGANI DELL\u2019AGENZIA\u201d e che, nel testo, invitano a prendere visione [&hellip;]","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/in-circolazione-false-email-a-nome-dellagenzia-non-aprire-gli-allegati-e-cestinare-immediatamente\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2020-09-22T09:03:14+00:00","article_modified_time":"2020-09-22T09:10:43+00:00","og_image":[{"width":1486,"height":956,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/08\/Schermata-2020-08-06-alle-11.47.35.png","type":"image\/png"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/in-circolazione-false-email-a-nome-dellagenzia-non-aprire-gli-allegati-e-cestinare-immediatamente\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/in-circolazione-false-email-a-nome-dellagenzia-non-aprire-gli-allegati-e-cestinare-immediatamente\/","name":"In circolazione false email a nome dell\u2019Agenzia delle entrate -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/in-circolazione-false-email-a-nome-dellagenzia-non-aprire-gli-allegati-e-cestinare-immediatamente\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/in-circolazione-false-email-a-nome-dellagenzia-non-aprire-gli-allegati-e-cestinare-immediatamente\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/08\/Schermata-2020-08-06-alle-11.47.35.png","datePublished":"2020-09-22T09:03:14+00:00","dateModified":"2020-09-22T09:10:43+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/in-circolazione-false-email-a-nome-dellagenzia-non-aprire-gli-allegati-e-cestinare-immediatamente\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/in-circolazione-false-email-a-nome-dellagenzia-non-aprire-gli-allegati-e-cestinare-immediatamente\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/in-circolazione-false-email-a-nome-dellagenzia-non-aprire-gli-allegati-e-cestinare-immediatamente\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/08\/Schermata-2020-08-06-alle-11.47.35.png","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/08\/Schermata-2020-08-06-alle-11.47.35.png","width":1486,"height":956},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/in-circolazione-false-email-a-nome-dellagenzia-non-aprire-gli-allegati-e-cestinare-immediatamente\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"In circolazione false email a nome dell\u2019Agenzia delle entrate"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/4168"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=4168"}],"version-history":[{"count":2,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/4168\/revisions"}],"predecessor-version":[{"id":4171,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/4168\/revisions\/4171"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/3865"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=4168"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=4168"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=4168"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}