{"id":4189,"date":"2020-09-24T12:03:13","date_gmt":"2020-09-24T10:03:13","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=4189"},"modified":"2020-09-24T12:03:13","modified_gmt":"2020-09-24T10:03:13","slug":"coldiretti-mln-di-danni-in-citta-e-campagne","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/coldiretti-mln-di-danni-in-citta-e-campagne\/","title":{"rendered":"Coldiretti: MLN di danni in citt\u00e0 e campagne"},"content":{"rendered":"<p><span class=\"dropcap dropcap3\">L<\/span>\u2019ultima perturbazione fa salire ad oltre mille il conto degli eventi estremi che con nubifragi, tornado, bombe d\u2019acqua, grandinate e vento forte hanno colpito fino ad ora nel 2020 la Penisola per effetto dei cambiamenti climatici con una tendenza alla tropicalizzazione<\/p>\n<p>E\u2019 quanto emerge dl monitoraggio della Coldiretti sull\u2019ultima ondata di maltempo che da nord a sud ha devastato agrumi, ulivi, vigne, ortaggi e stalle. Dal Piemonte alla Puglia, dal Lazio fino alla Sicilia il maltempo ha colpito macchia di leopardo con manifestazioni violente che \u2013 sottolinea la Coldiretti &#8211; hanno provocato milioni di euro di danni nelle citt\u00e0 e nelle campagne.<\/p>\n<p>L\u2019evento pi\u00f9 distruttivo \u00e8 la grandine in grado di azzerare in una manciata di minuti il lavoro di un intero anno \u2013 spiega la Coldiretti \u2013 con chicchi diventati sempre pi\u00f9 grandi.<\/p>\n<p>Gli oltre mille eventi estremi che si sono verificati in questo 2020 \u2013 evidenzia la Coldiretti \u2013 sono il risultato dell\u2019enorme energia termica accumulata nell\u2019atmosfera in un anno che \u00e8 stato fino adesso di oltre un grado (+1,05 gradi) superiore alla media storica classificandosi in Italia al secondo posto tra i pi\u00f9 bollenti dal 1800, sulla base dell\u2019analisi Coldiretti su dati Isac Cnr relativi ai primi otto mesi dai quali si evidenzia anche la caduta di circa il 25% di pioggia in meno nonostante il moltiplicarsi di nubifragi e grandinate.<\/p>\n<p>Siamo di fronte \u2013 conclude la Coldiretti \u2013 alle conseguenze dei cambiamenti climatici con una tendenza alla tropicalizzazione che si manifesta con grandine di maggiori dimensioni, una pi\u00f9 elevata frequenza di manifestazioni violente, sfasamenti stagionali, precipitazioni brevi e intense ed il rapido passaggio dal sole al maltempo, con costi per oltre 14 miliardi di euro in un decennio, tra perdite della produzione agricola nazionale e danni alle strutture e alle infrastrutture nelle campagne con allagamenti, frane e smottamenti.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019ultima perturbazione fa salire ad oltre mille il conto degli eventi estremi che con nubifragi, tornado, bombe d\u2019acqua, grandinate e vento forte hanno colpito fino ad ora nel 2020 la Penisola per effetto dei cambiamenti climatici con una tendenza alla tropicalizzazione E\u2019 quanto emerge dl monitoraggio della Coldiretti sull\u2019ultima ondata di maltempo che da nord [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1988,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[795],"tags":[158,796],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Coldiretti: MLN di danni in citt\u00e0 e campagne -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/coldiretti-mln-di-danni-in-citta-e-campagne\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Coldiretti: MLN di danni in citt\u00e0 e campagne -\" \/>\n<meta property=\"og:description\" content=\"L\u2019ultima perturbazione fa salire ad oltre mille il conto degli eventi estremi che con nubifragi, tornado, bombe d\u2019acqua, grandinate e vento forte hanno colpito fino ad ora nel 2020 la Penisola per effetto dei cambiamenti climatici con una tendenza alla tropicalizzazione E\u2019 quanto emerge dl monitoraggio della Coldiretti sull\u2019ultima ondata di maltempo che da nord [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/coldiretti-mln-di-danni-in-citta-e-campagne\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-24T10:03:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/11\/temporale-maltempo-pioggia.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"540\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/coldiretti-mln-di-danni-in-citta-e-campagne\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/coldiretti-mln-di-danni-in-citta-e-campagne\/\",\"name\":\"Coldiretti: MLN di danni in citt\u00e0 e campagne -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/coldiretti-mln-di-danni-in-citta-e-campagne\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/coldiretti-mln-di-danni-in-citta-e-campagne\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/11\/temporale-maltempo-pioggia.jpg\",\"datePublished\":\"2020-09-24T10:03:13+00:00\",\"dateModified\":\"2020-09-24T10:03:13+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/coldiretti-mln-di-danni-in-citta-e-campagne\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/coldiretti-mln-di-danni-in-citta-e-campagne\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/coldiretti-mln-di-danni-in-citta-e-campagne\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/11\/temporale-maltempo-pioggia.jpg\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/11\/temporale-maltempo-pioggia.jpg\",\"width\":960,\"height\":540},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/coldiretti-mln-di-danni-in-citta-e-campagne\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Coldiretti: MLN di danni in citt\u00e0 e campagne\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Coldiretti: MLN di danni in citt\u00e0 e campagne -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/coldiretti-mln-di-danni-in-citta-e-campagne\/","og_locale":"it_IT","og_type":"article","og_title":"Coldiretti: MLN di danni in citt\u00e0 e campagne -","og_description":"L\u2019ultima perturbazione fa salire ad oltre mille il conto degli eventi estremi che con nubifragi, tornado, bombe d\u2019acqua, grandinate e vento forte hanno colpito fino ad ora nel 2020 la Penisola per effetto dei cambiamenti climatici con una tendenza alla tropicalizzazione E\u2019 quanto emerge dl monitoraggio della Coldiretti sull\u2019ultima ondata di maltempo che da nord [&hellip;]","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/coldiretti-mln-di-danni-in-citta-e-campagne\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2020-09-24T10:03:13+00:00","og_image":[{"width":960,"height":540,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/11\/temporale-maltempo-pioggia.jpg","type":"image\/jpeg"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/coldiretti-mln-di-danni-in-citta-e-campagne\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/coldiretti-mln-di-danni-in-citta-e-campagne\/","name":"Coldiretti: MLN di danni in citt\u00e0 e campagne -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/coldiretti-mln-di-danni-in-citta-e-campagne\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/coldiretti-mln-di-danni-in-citta-e-campagne\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/11\/temporale-maltempo-pioggia.jpg","datePublished":"2020-09-24T10:03:13+00:00","dateModified":"2020-09-24T10:03:13+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/coldiretti-mln-di-danni-in-citta-e-campagne\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/coldiretti-mln-di-danni-in-citta-e-campagne\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/coldiretti-mln-di-danni-in-citta-e-campagne\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/11\/temporale-maltempo-pioggia.jpg","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/11\/temporale-maltempo-pioggia.jpg","width":960,"height":540},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/coldiretti-mln-di-danni-in-citta-e-campagne\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"Coldiretti: MLN di danni in citt\u00e0 e campagne"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/4189"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=4189"}],"version-history":[{"count":1,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/4189\/revisions"}],"predecessor-version":[{"id":4190,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/4189\/revisions\/4190"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/1988"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=4189"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=4189"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=4189"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}