{"id":4302,"date":"2020-10-05T10:35:46","date_gmt":"2020-10-05T08:35:46","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=4302"},"modified":"2020-10-05T10:35:46","modified_gmt":"2020-10-05T08:35:46","slug":"con-tasse-europee-ogni-famiglia-italiana-risparmierebbe-1-500-euro-allanno","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/con-tasse-europee-ogni-famiglia-italiana-risparmierebbe-1-500-euro-allanno\/","title":{"rendered":"Con tasse Europee, ogni famiglia italiana risparmierebbe 1.500 euro all&#8217;anno"},"content":{"rendered":"<div class=\"page\" title=\"Page 1\">\n<div class=\"section\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p><span class=\"dropcap dropcap3\">S<\/span>e potessimo contare su una pressione fiscale pari a quella media europea, ogni famiglia italiana risparmierebbe 1.506 euro di tasse all\u2019anno. La CGIA e\u0300 giunta a questo risultato comparando la pressione fiscale di tutti i 28 paesi dell\u2019UE.<\/p>\n<p>Dopodiche\u0301, ha calcolato quanto pagherebbe in piu\u0300 o in meno di tasse una famiglia media italiana1 se subisse la pressione fiscale del paese europeo oggetto del confronto. Avendo registrato una pressione fiscale superiore di 2,2 punti percentuali rispetto al dato medio dell\u2019Unione, nel 2019 ogni famiglia italiana avrebbe risparmiato 1.506 euro.<\/p>\n<p>Nella manovra 2021 e\u0300 necessario un taglio da 20 miliardi Afferma il coordinatore dell\u2019Ufficio studi CGIA, Paolo Zabeo: \u201cCon la prossima legge di Bilancio e\u0300 necessario un intervento choc che nel giro di qualche anno riduca di almeno 3-4 punti percentuali la pressione fiscale.<\/p>\n<p>Chi ritiene che siano sufficienti solo 10 miliardi si sbaglia di grosso: questa cifra e\u0300 insufficiente. Per il 2021 e\u0300 necessaria una contrazione di almeno 20 miliardi di euro e questo obbiettivo potra\u0300 essere raggiunto solo se si riuscira\u0300 ad abbassare, di pari importo, la spesa pubblica improduttiva e una parte delle agevolazioni fiscali. Compiere questa operazione, comunque, non sara\u0300 per niente facile. Negli ultimi 10 anni, infatti, la spending review non ha prodotto risultati apprezzabili, mentre il numero delle deduzioni e delle detrazioni fiscali e\u0300 aumentato a dismisura, soprattutto in questo periodo di Covid\u201d.<\/p>\n<p>Secondo l\u2019Istat, nel 2019 era composta da 2,3 componenti<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"page\" title=\"Page 2\">\n<div class=\"section\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p>\uf0b7 Paghiamo tanto per avere pochi servizi<\/p>\n<p>Un peso tributario eccessivo come quello presente nel nostro Paese costituisce un problema sia perche\u0301 alleggerisce la disponibilita\u0300 economica di tante famiglie e di altrettante imprese sia perche\u0301 drena risorse che altrimenti potrebbero essere investite per favorire i consumi, gli investimenti e, quindi, lo sviluppo del sistema economico.<\/p>\n<p>Sottolinea il segretario della CGIA, Renato Mason: \u201cCon un carico fiscale cosi\u0300 eccessivo e una platea di servizi erogati dalla nostra Pubblica amministrazione che negli ultimi anni e\u0300 scesa sia in termini di qualita\u0300 che di quantita\u0300, questa situazione ha contribuito a determinare una contrazione della domanda interna e un crollo degli investimenti pubblici. Ma oltre a tagliare le tasse e\u0300 altrettanto importante semplificare il nostro sistema fiscale. Pagare le imposte e\u0300 diventato sempre piu\u0300 difficile: lo dicono gli esperti, come i commercialisti e i tecnici delle associazioni di categoria. Figuriamoci come la pensano i piccoli imprenditori che oltre a occuparsi della propria attivita\u0300, spesso sono chiamati a misurarsi con una burocrazia fiscale astrusa e scriteriata che non ha eguali nel resto d\u2019Europa\u201d.<\/p>\n<p>Quest\u2019anno il peso fiscale e\u0300 destinato a salire nuovamente Stando agli ultimi dati disponibili (media anno 2019), la pressione fiscale in Italia si e\u0300 fermata al 42,4 per cento del Pil, in aumento rispetto al 2018 di 0,7 punti percentuali. Questo incremento e\u0300 avvenuto dopo 5 anni di costante riduzione del carico fiscale. Dopo il picco massimo di tutti i tempi toccato nel 2013, il peso di tasse e contributi ha cominciato a scendere, in particolar modo con l\u2019esecutivo guidato da Renzi che, tra le altre cose, ha eliminato l\u2019Imu sulla prima casa e ha alleggerito il costo del lavoro dei neo assunti .<\/p>\n<p>Cosa succedera\u0300 quest\u2019anno ?<\/p>\n<p>Premesso che con la pubblicazione della Nota di aggiornamento al DEF prevista nei prossimi giorni avremo contezza della soglia ragiunta quest\u2019anno, abbiamo l\u2019impressione che la pressione fiscale sia destinata ad aumentare ulteriormente. Non tanto perche\u0301 sono state ritoccate all\u2019insu\u0300 le aliquote, cosa che infatti non e\u0300 avvenuta, ma perche\u0301 registreremo una caduta verticale del Pil piu\u0300 significativa della contrazione registrata dalle entrate. Ricordiamo, infatti, che la pressione fiscale e\u0300 data dalla somma delle entrate tributarie e di quelle contributive; il risultato di questa operazione deve poi essere rapportato al Pil e, successivamente, moltiplicato per 100.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"page\" title=\"Page 3\">\n<div class=\"section\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p>Per pressione fiscale siamo al 6\u00b0 posto in UE<br \/>\nTra i 28 paesi che nel 2019 costituivano l\u2019Unione europea, l\u2019Italia si e\u0300 classificata al sesto posto per quanto riguarda il peso della pressione fiscale in percentuale del Pil. La Danimarca presenta il carico fiscale piu\u0300 importante (47,6 per cento), seguono la Francia (47,3 per cento), il Belgio (45,5 per cento), la Svezia (43,5 per cento) e l\u2019Austria (42,9 per cento). Il sesto posto di questa particolare graduatoria e\u0300 occupato dall\u2019Italia che nel 2019 ha registrato una pressione fiscale del 42,4 per cento. Se tra i nostri principali competitor la Germania presenta un peso fiscale complessivo del 41,6 per cento, il Regno Unito e la Spagna, entrambe con un carico fiscale complessivo del 35,2 per cento, possono addirittura contare su un differenziale di 7,2 punti di tasse in meno rispetto al nostro Paese<\/p>\n<p>\uf0b7 Con le tasse di Spagna o Regno Unito, una famiglia italiana risparmierebbe quasi 5.000 euro all\u2019anno<\/p>\n<p>Se nel confronto con la pressione fiscale media dell\u2019UE riferita all\u2019anno scorso (40,2 per cento) una famiglia italiana avrebbe pagato 1.506 euro in meno di tasse, nella comparazione con il carico fiscale in capo alla Germania, invece, avrebbe risparmiato 548 euro, con quella dei Paesi Bassi il vantaggio sarebbe stato di 2.123 euro, con il Regno Unito e la Spagna avrebbe addirittura potuto beneficiare di una sforbiciata pari a 4.930 euro. Sempre tra i grandi paesi d\u2019Europa, spicca il risultato che emerge dal raffronto con la Francia. Se in Italia avessimo la stessa pressione fiscale di Parigi (47,3 per cento), la famiglia media italiana pagherebbe 3.355 euro di tasse in piu\u0300 e addirittura 3.561 euro se il confronto venisse effettuato con la Danimarca, che e\u0300 il paese con la pressione fiscale piu\u0300 alta di tutta Europa (47,6 per cento) Col Portogallo abbiamo il record di \u201coppressione\u201d fiscale<\/p>\n<p><a href=\"http:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/10\/Schermata-2020-10-05-alle-10.20.51.png\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-4303\" src=\"http:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/10\/Schermata-2020-10-05-alle-10.20.51.png\" alt=\"\" width=\"1040\" height=\"1400\" srcset=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/10\/Schermata-2020-10-05-alle-10.20.51.png 1040w, https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/10\/Schermata-2020-10-05-alle-10.20.51-223x300.png 223w, https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/10\/Schermata-2020-10-05-alle-10.20.51-761x1024.png 761w, https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/10\/Schermata-2020-10-05-alle-10.20.51-768x1034.png 768w, https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/10\/Schermata-2020-10-05-alle-10.20.51-696x937.png 696w, https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/10\/Schermata-2020-10-05-alle-10.20.51-312x420.png 312w\" sizes=\"(max-width: 1040px) 100vw, 1040px\" \/><\/a> <a href=\"http:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/10\/Schermata-2020-10-05-alle-10.25.04.png\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-4304\" src=\"http:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/10\/Schermata-2020-10-05-alle-10.25.04.png\" alt=\"\" width=\"1120\" height=\"1050\" srcset=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/10\/Schermata-2020-10-05-alle-10.25.04.png 1120w, https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/10\/Schermata-2020-10-05-alle-10.25.04-300x281.png 300w, https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/10\/Schermata-2020-10-05-alle-10.25.04-1024x960.png 1024w, https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/10\/Schermata-2020-10-05-alle-10.25.04-768x720.png 768w, https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/10\/Schermata-2020-10-05-alle-10.25.04-696x653.png 696w, https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/10\/Schermata-2020-10-05-alle-10.25.04-1068x1001.png 1068w, https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/10\/Schermata-2020-10-05-alle-10.25.04-448x420.png 448w\" sizes=\"(max-width: 1120px) 100vw, 1120px\" \/><\/a><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Se potessimo contare su una pressione fiscale pari a quella media europea, ogni famiglia italiana risparmierebbe 1.506 euro di tasse all\u2019anno. La CGIA e\u0300 giunta a questo risultato comparando la pressione fiscale di tutti i 28 paesi dell\u2019UE. Dopodiche\u0301, ha calcolato quanto pagherebbe in piu\u0300 o in meno di tasse una famiglia media italiana1 se [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1528,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41],"tags":[190,42,43],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Con tasse Europee, ogni famiglia italiana risparmierebbe 1.500 euro all&#039;anno -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/con-tasse-europee-ogni-famiglia-italiana-risparmierebbe-1-500-euro-allanno\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Con tasse Europee, ogni famiglia italiana risparmierebbe 1.500 euro all&#039;anno -\" \/>\n<meta property=\"og:description\" content=\"Se potessimo contare su una pressione fiscale pari a quella media europea, ogni famiglia italiana risparmierebbe 1.506 euro di tasse all\u2019anno. La CGIA e\u0300 giunta a questo risultato comparando la pressione fiscale di tutti i 28 paesi dell\u2019UE. Dopodiche\u0301, ha calcolato quanto pagherebbe in piu\u0300 o in meno di tasse una famiglia media italiana1 se [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/con-tasse-europee-ogni-famiglia-italiana-risparmierebbe-1-500-euro-allanno\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-05T08:35:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/08\/fisco-tasse.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"678\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/con-tasse-europee-ogni-famiglia-italiana-risparmierebbe-1-500-euro-allanno\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/con-tasse-europee-ogni-famiglia-italiana-risparmierebbe-1-500-euro-allanno\/\",\"name\":\"Con tasse Europee, ogni famiglia italiana risparmierebbe 1.500 euro all'anno -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/con-tasse-europee-ogni-famiglia-italiana-risparmierebbe-1-500-euro-allanno\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/con-tasse-europee-ogni-famiglia-italiana-risparmierebbe-1-500-euro-allanno\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/08\/fisco-tasse.jpg\",\"datePublished\":\"2020-10-05T08:35:46+00:00\",\"dateModified\":\"2020-10-05T08:35:46+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/con-tasse-europee-ogni-famiglia-italiana-risparmierebbe-1-500-euro-allanno\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/con-tasse-europee-ogni-famiglia-italiana-risparmierebbe-1-500-euro-allanno\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/con-tasse-europee-ogni-famiglia-italiana-risparmierebbe-1-500-euro-allanno\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/08\/fisco-tasse.jpg\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/08\/fisco-tasse.jpg\",\"width\":960,\"height\":678},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/con-tasse-europee-ogni-famiglia-italiana-risparmierebbe-1-500-euro-allanno\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Con tasse Europee, ogni famiglia italiana risparmierebbe 1.500 euro all&#8217;anno\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Con tasse Europee, ogni famiglia italiana risparmierebbe 1.500 euro all'anno -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/con-tasse-europee-ogni-famiglia-italiana-risparmierebbe-1-500-euro-allanno\/","og_locale":"it_IT","og_type":"article","og_title":"Con tasse Europee, ogni famiglia italiana risparmierebbe 1.500 euro all'anno -","og_description":"Se potessimo contare su una pressione fiscale pari a quella media europea, ogni famiglia italiana risparmierebbe 1.506 euro di tasse all\u2019anno. La CGIA e\u0300 giunta a questo risultato comparando la pressione fiscale di tutti i 28 paesi dell\u2019UE. Dopodiche\u0301, ha calcolato quanto pagherebbe in piu\u0300 o in meno di tasse una famiglia media italiana1 se [&hellip;]","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/con-tasse-europee-ogni-famiglia-italiana-risparmierebbe-1-500-euro-allanno\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2020-10-05T08:35:46+00:00","og_image":[{"width":960,"height":678,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/08\/fisco-tasse.jpg","type":"image\/jpeg"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/con-tasse-europee-ogni-famiglia-italiana-risparmierebbe-1-500-euro-allanno\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/con-tasse-europee-ogni-famiglia-italiana-risparmierebbe-1-500-euro-allanno\/","name":"Con tasse Europee, ogni famiglia italiana risparmierebbe 1.500 euro all'anno -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/con-tasse-europee-ogni-famiglia-italiana-risparmierebbe-1-500-euro-allanno\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/con-tasse-europee-ogni-famiglia-italiana-risparmierebbe-1-500-euro-allanno\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/08\/fisco-tasse.jpg","datePublished":"2020-10-05T08:35:46+00:00","dateModified":"2020-10-05T08:35:46+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/con-tasse-europee-ogni-famiglia-italiana-risparmierebbe-1-500-euro-allanno\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/con-tasse-europee-ogni-famiglia-italiana-risparmierebbe-1-500-euro-allanno\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/con-tasse-europee-ogni-famiglia-italiana-risparmierebbe-1-500-euro-allanno\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/08\/fisco-tasse.jpg","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/08\/fisco-tasse.jpg","width":960,"height":678},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/con-tasse-europee-ogni-famiglia-italiana-risparmierebbe-1-500-euro-allanno\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"Con tasse Europee, ogni famiglia italiana risparmierebbe 1.500 euro all&#8217;anno"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/4302"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=4302"}],"version-history":[{"count":1,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/4302\/revisions"}],"predecessor-version":[{"id":4305,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/4302\/revisions\/4305"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/1528"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=4302"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=4302"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=4302"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}