{"id":4340,"date":"2020-10-07T11:24:24","date_gmt":"2020-10-07T09:24:24","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=4340"},"modified":"2020-10-07T11:24:24","modified_gmt":"2020-10-07T09:24:24","slug":"istat-leconomia-a-livello-internazionale-i-ripresa-in-italia-ancora-incertezze","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/istat-leconomia-a-livello-internazionale-i-ripresa-in-italia-ancora-incertezze\/","title":{"rendered":"Istat, l&#8217;economia a livello internazionale i ripresa, in Italia ancora incertezze"},"content":{"rendered":"<p><span class=\"dropcap dropcap3\">N<\/span>ei mesi estivi, l\u2019<strong>attivit\u00e0 economica a livello internazionale<\/strong> ha evidenziato una decisa ripresa, diffusa in modo eterogeneo tra i paesi. Il quadro globale continua per\u00f2 a essere dominato dalle difficolt\u00e0 e incertezze derivanti dall\u2019evoluzione della pandemia, il cui recente riacutizzarsi potrebbe condizionare in misura significativa lo scenario a breve termine.<\/p>\n<p>In Italia, alla fase di recupero della produzione industriale si affiancano segnali confortanti per gli ordinativi e le esportazioni. Anche il settore delle costruzioni e il mercato immobiliare mostrano una certa dinamicit\u00e0.<\/p>\n<p>Ad agosto, l\u2019occupazione torna ad aumentare per il secondo mese consecutivo mentre si riducono marginalmente la disoccupazione e l\u2019inattivit\u00e0, quest\u2019ultima ancora su livelli pi\u00f9 elevati di quelli di gennaio.<\/p>\n<p>Debolezza della domanda assieme a effetti diretti e indiretti della caduta delle quotazioni dei prodotti energetici consolidano la fase deflativa dei prezzi al consumo. Si attenua ulteriormente l\u2019inflazione di fondo, risultata nulla a settembre per il calo dei prezzi nei servizi.<\/p>\n<p>A settembre, si registra un ulteriore miglioramento della fiducia dei consumatori e delle imprese che, nella manifattura, segnalano la presenza di ostacoli alle esportazioni e alla produzione, ancora condizionata, secondo i giudizi degli imprenditori, da insufficienza di domanda.<\/p>\n<p><strong>LA CONGIUNTURA ITALIANA<\/strong><br \/>\nImprese<br \/>\nLa revisione dei conti nazionali ha ampliato, seppure in misura marginale, il calo congiunturale senza precedenti registrato nel secondo trimestre dal prodotto interno lordo italiano (-13,0% rispetto al -12,8% diffuso precedentemente). Tuttavia, \u00e8 proseguita la fase di ripresa dei ritmi produttivi avviatasi a maggio.<\/p>\n<p>A luglio, l\u2019indice della produzione industriale ha continuato la fase di recupero congiunturale iniziata a maggio (+7,4% da +8,2% di giugno), pur rimanendo a un livello inferiore del 6,6% rispetto al dato di gennaio. La ripresa \u00e8 stata diffusa a tutti i raggruppamenti principali di industrie a eccezione di quello dei beni energetici, rimasti stazionari (+0,1% rispetto al mese precedente). Il settore dei beni strumentali ha fornito il maggiore contributo positivo (+11,8%).<\/p>\n<p>A seguito dell\u2019andamento positivo degli ultimi mesi, la produzione tra maggio e luglio \u00e8 aumentata del 15,0% rispetto ai tre mesi precedenti. Nello stesso trimestre, anche gli ordinativi dell\u2019industria hanno registrato una crescita di simile entit\u00e0 (+14,8%) spinti dal forte aumento di quelli sul mercato interno (+21,6%) e da quello minore della componente estera (+5,9%). A luglio, tuttavia, gli ordinativi totali hanno mostrato una dinamica meno vivace (+3,7%) rispetto a quella dei due mesi precedenti.<\/p>\n<p>A luglio, sia le esportazioni sia le importazioni di beni hanno segnato un nuovo incremento congiunturale (rispettivamente pari al +5,7% e +4,8%), confermando le tendenze positive osservate nei due mesi precedenti. L\u2019aumento delle esportazioni ha riguardato sia i mercati Ue sia, in misura pi\u00f9 accentuata, quelli extra Ue (rispettivamente +3,9% e +7,6%) e ha interessato tutte le principali categorie di prodotti, in particolare i beni di consumo non durevoli (+7,6%) e quelli strumentali (+5,6%).<\/p>\n<p>Rispetto a luglio 2019, le esportazioni sono diminuite complessivamente del -7,3%, registrando decise riduzioni verso tutti i maggiori mercati di destinazione dei prodotti italiani, in particolare verso la Francia (-6,1%), la Germania (-5,3%) e gli Stati Uniti (-5,4%) che congiuntamente rappresentano circa un terzo del valore complessivo delle vendite italiane all\u2019estero. Sono risultati invece in aumento i flussi diretti verso il Belgio (+15,6%) e la Cina (+14%).<\/p>\n<p>Il valore degli acquisti \u00e8 stato significativamente inferiore rispetto al 2019 (-14,2%) sia nel caso dei fornitori Ue (-11,5%) sia di quelli dell\u2019area extra Ue (-17,5%). Gli scambi verso i mercati extra Ue hanno segnalato, per agosto, un lieve rallentamento delle esportazioni (-0,3%) e un deciso aumento delle importazioni (+5,1%).<br \/>\nLa produzione del settore delle costruzioni ha registrato a luglio una decelerazione (+3,5%) dopo il forte recupero dei due mesi precedenti.<\/p>\n<p>Tra maggio e luglio, la variazione della produzione \u00e8 stata marcatamente positiva (+39,3% rispetto ai tre mesi precedenti) sebbene il livello rimanga ancora pi\u00f9 basso di quello di inizio 2020. Nella media dei primi sette mesi dell\u2019anno, l\u2019indice corretto per gli effetti di calendario \u00e8 risultato inferiore del 17,1% rispetto allo stesso periodo dell\u2019anno precedente. Il mercato immobiliare ha manifestato segnali di vivacit\u00e0: i prezzi delle abitazioni sono aumentati in T2 (+3,1% rispetto al trimestre precedente) a seguito di una pi\u00f9 forte crescita dei prezzi delle abitazioni esistenti (+3,3%) rispetto a quelli delle abitazioni nuove (+2,0%).<br \/>\nGli indicatori di fiducia delle imprese hanno continuato la loro fase di recupero anche a settembre con un aumento in tutti i settori, evidenziando un incremento di maggiore intensit\u00e0 nei servizi di mercato .<\/p>\n<p>Per le imprese manifatturiere si \u00e8 rilevato un miglioramento sia dei giudizi sugli ordini sia delle attese di produzione, con le scorte di prodotti finiti giudicate in riduzione rispetto ad agosto. Nel terzo trimestre, le imprese hanno confermato la presenza di decisi ostacoli sia alle esportazioni sia alla produzione, condizionata dalla insufficienza di domanda.<\/p>\n<p><strong>Famiglie e mercato del lavoro<\/strong><br \/>\nAnalogamente all\u2019area euro, nel secondo trimestre la caduta dei ritmi produttivi italiani ha avuto un impatto rilevante sul mercato del lavoro e sui redditi delle famiglie che hanno comunque beneficiato delle politiche di sostegno del governo. Gli effetti congiunti hanno comportato un deciso allontanamento degli aggregati economici di riferimento dai trend di medio periodo. In particolare, nel secondo trimestre la caduta congiunturale dei consumi delle famiglie (-11,5%) \u00e8 stata pi\u00f9 accentuata di quella del reddito disponibile (-5,8%), determinando un aumento anomalo della propensione al risparmio che ha raggiunto il 18,6%, in aumento di 5,3 punti rispetto al trimestre precedente.<\/p>\n<p>Da maggio, le vendite al dettaglio hanno evidenziato decisi segnali di recupero. Ad agosto il volume delle vendite ha segnato un marcato aumento congiunturale (+11,2%) sostenuto dagli acquisti in beni non alimentari (+19,2%) che hanno verosimilmente risentito del posticipo di un mese della data di inizio dei saldi rispetto al tradizionale inizio di luglio e di favorevoli condizioni di prezzo.<\/p>\n<p>L\u2019indice delle vendite ha quindi raggiunto livelli lievemente superiori a quelli medi del 2019 anche se la variazione tendenziale cumulata per il periodo gennaio-agosto \u00e8 risultata ancora inferiore a quella dello stesso periodo dell\u2019anno precedente (-8,3%). Sulla ripresa delle vendite ha inciso positivamente il deciso rialzo del commercio elettronico (+29,9% l\u2019aumento tendenziale nel periodo gennaio-agosto, +36,8% la crescita ad agosto).<\/p>\n<p>Anche il mercato del lavoro \u00e8 caratterizzato da alcuni segnali di miglioramento. Ad agosto si \u00e8 confermata la fase di aumento congiunturale dell\u2019occupazione (+0,4% pari a +83mila unit\u00e0) pi\u00f9 intensa tra gli uomini (+0,5% pari a +72mila unit\u00e0) rispetto alle donne (+0,1% pari a +11mila unit\u00e0) e tra i lavoratori indipendenti (+1,3% pari a 67mila unit\u00e0) rispetto ai dipendenti (+0,1% pari a 16mila unit\u00e0 . Da rilevare l\u2019aumento di occupati tra i giovani (+50mila tra le persone con meno di 35 anni, pari a una crescita congiunturale dell\u20191%). Nonostante la ripresa registrata nell\u2019ultimo bimestre, il livello complessivo di occupazione risulta ancora inferiore di oltre 350mila unit\u00e0 rispetto a febbraio 2020, mese immediatamente precedente l\u2019esplosione della crisi.<\/p>\n<p>La marginale riduzione del tasso di disoccupazione (9,7%, -0,1 punti percentuali rispetto al mese precedente) si \u00e8 accompagnata a un ulteriore calo del tasso di inattivit\u00e0 (35,5%, -0,1 p.p.). Nel confronto con gennaio, il tasso di disoccupazione rimane pi\u00f9 elevato (+0,2 p.p.) cos\u00ec come quello di inattivit\u00e0 (+0,8 p.p.).<\/p>\n<p>\u00c8 proseguita la ripresa delle ore pro capite effettivamente lavorate: il numero di ore lavorate settimanalmente nel mese di agosto, pari a 25,5, \u00e8 solo di 0,6 ore inferiore a quello registrato ad agosto 2019 e la differenza si riduce a 0,4 ore per i dipendenti.<br \/>\nLe informazioni sulla fiducia dei consumatori supportano l\u2019ipotesi di un proseguimento della fase di recupero. A settembre il clima di fiducia dei consumatori ha segnato una crescita diffusa a tutte le componenti, con un deciso miglioramento delle aspettative sulla disoccupazione che si associano ai giudizi di miglioramento dell\u2019occupazione segnalati dalle imprese. Allo stesso tempo, nel terzo trimestre si \u00e8 registrato un aumento delle intenzioni di realizzazione di interventi per la manutenzione delle abitazioni.<br \/>\nPrezzi<\/p>\n<p>A settembre si \u00e8 consolidata la tendenza deflattiva dei prezzi al consumo avviatasi a maggio. In base alla stima preliminare dell\u2019indice per l\u2019intera collettivit\u00e0, i prezzi al consumo sono risultati inferiori dello 0,5% rispetto a un anno prima (da -0,2% di maggio). La caduta tendenziale continua a risentire della fase deflativa della componente energetica, ma riflette anche l\u2019ulteriore rallentamento dell\u2019inflazione di fondo che, nell\u2019accezione che esclude energia, alimentari e tabacchi, \u00e8 risultata nulla. In particolare, accanto alla nuova decelerazione dei prezzi dei beni industriali non energetici (+0,2% rispetto a dodici mesi prima; +0,4% ad agosto), quelli dei servizi hanno registrato una variazione tendenziale negativa.<\/p>\n<p>Tale dinamica sconta, oltre alle usuali spinte deflative provenienti dalle comunicazioni, riduzioni dei prezzi nei servizi di trasporto e in quelli alla persona, ricreativi e culturali. In un contesto di bassa inflazione comune all\u2019intera area euro, la discesa dei prezzi nei servizi in Italia ha continuato a essere pi\u00f9 ampia rispetto a quella dei partner europei, contribuendo a mantenere negativo il nostro differenziale inflazionistico sia in termini di inflazione complessiva sia di componente core (-0,6 punti percentuali a settembre in entrambi i casi).<\/p>\n<p>Nei mesi estivi le pressioni al ribasso provenienti dagli stadi precedenti la distribuzione finale si sono attenuate. \u2028I prezzi all\u2019importazione sono diminuiti a luglio del 6,4% su base annua, mentre per quelli alla produzione dei prodotti industriali venduti sul mercato interno la caduta tendenziale \u00e8 stata pi\u00f9 contenuta (-4,0% in agosto). Per quanto riguarda i beni di consumo non alimentari, i prezzi all\u2019importazione evidenziano una lieve riduzione (-0,3%; -0,6% a giugno), mentre per i prezzi alla produzione si conferma la fase di stabilizzazione (+0,9% per il terzo mese consecutivo). Le riduzioni dei prezzi hanno interessato i comparti del tessile e delle calzature.<\/p>\n<p>A settembre, le attese di inflazione di imprese e consumatori si sono confermate ancora molto basse, dominate dalle incertezze sulle prospettive dell\u2019economia. Qualche differenza nelle tendenze \u00e8 per\u00f2 emersa. I consumatori hanno rivisto ulteriormente al ribasso le loro aspettative, con il saldo negativo pi\u00f9 ampio degli ultimi quattro anni circa. Nel quadro di politiche dei listini molto caute, tra i produttori di beni di consumo la prevalenza delle intenzioni di ribassi rispetto ad aumenti dei prezzi si \u00e8 invece notevolmente ridotta in confronto al picco negativo di maggio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nei mesi estivi, l\u2019attivit\u00e0 economica a livello internazionale ha evidenziato una decisa ripresa, diffusa in modo eterogeneo tra i paesi. Il quadro globale continua per\u00f2 a essere dominato dalle difficolt\u00e0 e incertezze derivanti dall\u2019evoluzione della pandemia, il cui recente riacutizzarsi potrebbe condizionare in misura significativa lo scenario a breve termine. In Italia, alla fase di [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1007,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[56],"tags":[1329,712,102],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Istat, l&#039;economia a livello internazionale i ripresa, in Italia ancora incertezze -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/istat-leconomia-a-livello-internazionale-i-ripresa-in-italia-ancora-incertezze\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Istat, l&#039;economia a livello internazionale i ripresa, in Italia ancora incertezze -\" \/>\n<meta property=\"og:description\" content=\"Nei mesi estivi, l\u2019attivit\u00e0 economica a livello internazionale ha evidenziato una decisa ripresa, diffusa in modo eterogeneo tra i paesi. Il quadro globale continua per\u00f2 a essere dominato dalle difficolt\u00e0 e incertezze derivanti dall\u2019evoluzione della pandemia, il cui recente riacutizzarsi potrebbe condizionare in misura significativa lo scenario a breve termine. In Italia, alla fase di [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/istat-leconomia-a-livello-internazionale-i-ripresa-in-italia-ancora-incertezze\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-07T09:24:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/06\/lavoro-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/istat-leconomia-a-livello-internazionale-i-ripresa-in-italia-ancora-incertezze\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/istat-leconomia-a-livello-internazionale-i-ripresa-in-italia-ancora-incertezze\/\",\"name\":\"Istat, l'economia a livello internazionale i ripresa, in Italia ancora incertezze -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/istat-leconomia-a-livello-internazionale-i-ripresa-in-italia-ancora-incertezze\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/istat-leconomia-a-livello-internazionale-i-ripresa-in-italia-ancora-incertezze\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/06\/lavoro-2.jpg\",\"datePublished\":\"2020-10-07T09:24:24+00:00\",\"dateModified\":\"2020-10-07T09:24:24+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/istat-leconomia-a-livello-internazionale-i-ripresa-in-italia-ancora-incertezze\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/istat-leconomia-a-livello-internazionale-i-ripresa-in-italia-ancora-incertezze\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/istat-leconomia-a-livello-internazionale-i-ripresa-in-italia-ancora-incertezze\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/06\/lavoro-2.jpg\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/06\/lavoro-2.jpg\",\"width\":960,\"height\":640},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/istat-leconomia-a-livello-internazionale-i-ripresa-in-italia-ancora-incertezze\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Istat, l&#8217;economia a livello internazionale i ripresa, in Italia ancora incertezze\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Istat, l'economia a livello internazionale i ripresa, in Italia ancora incertezze -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/istat-leconomia-a-livello-internazionale-i-ripresa-in-italia-ancora-incertezze\/","og_locale":"it_IT","og_type":"article","og_title":"Istat, l'economia a livello internazionale i ripresa, in Italia ancora incertezze -","og_description":"Nei mesi estivi, l\u2019attivit\u00e0 economica a livello internazionale ha evidenziato una decisa ripresa, diffusa in modo eterogeneo tra i paesi. Il quadro globale continua per\u00f2 a essere dominato dalle difficolt\u00e0 e incertezze derivanti dall\u2019evoluzione della pandemia, il cui recente riacutizzarsi potrebbe condizionare in misura significativa lo scenario a breve termine. In Italia, alla fase di [&hellip;]","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/istat-leconomia-a-livello-internazionale-i-ripresa-in-italia-ancora-incertezze\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2020-10-07T09:24:24+00:00","og_image":[{"width":960,"height":640,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/06\/lavoro-2.jpg","type":"image\/jpeg"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"8 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/istat-leconomia-a-livello-internazionale-i-ripresa-in-italia-ancora-incertezze\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/istat-leconomia-a-livello-internazionale-i-ripresa-in-italia-ancora-incertezze\/","name":"Istat, l'economia a livello internazionale i ripresa, in Italia ancora incertezze -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/istat-leconomia-a-livello-internazionale-i-ripresa-in-italia-ancora-incertezze\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/istat-leconomia-a-livello-internazionale-i-ripresa-in-italia-ancora-incertezze\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/06\/lavoro-2.jpg","datePublished":"2020-10-07T09:24:24+00:00","dateModified":"2020-10-07T09:24:24+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/istat-leconomia-a-livello-internazionale-i-ripresa-in-italia-ancora-incertezze\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/istat-leconomia-a-livello-internazionale-i-ripresa-in-italia-ancora-incertezze\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/istat-leconomia-a-livello-internazionale-i-ripresa-in-italia-ancora-incertezze\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/06\/lavoro-2.jpg","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/06\/lavoro-2.jpg","width":960,"height":640},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/istat-leconomia-a-livello-internazionale-i-ripresa-in-italia-ancora-incertezze\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"Istat, l&#8217;economia a livello internazionale i ripresa, in Italia ancora incertezze"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/4340"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=4340"}],"version-history":[{"count":1,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/4340\/revisions"}],"predecessor-version":[{"id":4341,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/4340\/revisions\/4341"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/1007"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=4340"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=4340"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=4340"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}