{"id":4393,"date":"2020-10-14T09:32:18","date_gmt":"2020-10-14T07:32:18","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=4393"},"modified":"2020-10-14T09:37:18","modified_gmt":"2020-10-14T07:37:18","slug":"l-sottosegretario-agli-esteri-di-stefano-e-il-direttore-generale-di-ice-agenzia-al-webinar-promosso-dalla-cna","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/l-sottosegretario-agli-esteri-di-stefano-e-il-direttore-generale-di-ice-agenzia-al-webinar-promosso-dalla-cna\/","title":{"rendered":"Il Sottosegretario agli Esteri Di Stefano e il Direttore Generale di Ice Agenzia al webinar promosso dalla CNA"},"content":{"rendered":"<p><span class=\"dropcap dropcap3\">L<\/span>\u2019export e l\u2019internazionalizzazione dell\u2019Artigianato e delle piccole imprese, analisi e proposte\u201d \u00e8 il titolo del webinar promosso dalla CNA al quale hanno partecipato il Presidente della Confederazione, <strong>Daniele Vaccarino<\/strong>, il Sottosegretario agli Esteri, <strong>Manlio Di Stefano<\/strong>, il Direttore generale di Ice Agenzia, <strong>Roberto Luongo<\/strong> e la Vicepresidente con delega all\u2019internazionalizzazione, <strong>Roberta Datteri.<\/strong><\/p>\n<p>Il Sottosegretario Di Stefano ha indicato di \u201ccondividere la mission di sostenere le piccole imprese sulla strada dell\u2019export. La sinergia tra il Ministero degli Affari Esteri e CNA ha visto come tassello determinante la partecipazione dell\u2019associazione di categoria nei numerosi tavoli di confronto. L\u2019obiettivo prioritario per tutti rimane il raccordo costante tra istituzioni e imprese in virt\u00f9 di una rinnovata semplificazione anche attraverso nuovi strumenti di digitalizzazione\u201d.<\/p>\n<p>\u201cAbbiamo toccato con mano quanto il periodo sia stato difficile \u2013 ha dichiarato il Presidente Vaccarino &#8211; e quanto le imprese abbiano avuto bisogno di punti di riferimento. Adesso dobbiamo preoccuparci del futuro, avanzando ipotesi e strategie per rafforzare l\u2019internazionalizzazione delle micro e piccole imprese. Questo \u00e8 lo sforzo che sta compiendo il nostro sistema associativo insieme a tutti gli altri attori, continuando ad infondere fiducia nelle imprese per percorrere questo cammino insieme.\u201d<\/p>\n<p>Il Direttore generale di Ice Agenzia Luongo ha evidenziato che &#8220;in questa delicata e complessa fase congiunturale, l&#8217;Agenzia Ice, attraverso\u00a0una vasta offerta di strumenti promozionali e di assistenza &#8211; per la maggior parte &#8211; gratuiti, si pone al fianco di micro e piccole imprese italiane, soprattutto artigiane. \u00a0Stiamo, inoltre, potenziando la collaborazione con piattaforme digitali di e-commerce, come quella Ice-Agenzia &#8220;365&#8221; dedicata\u00a0in particolar modo all&#8217;organizzazione di incontri\u00a0B2B virtuali, particolarmente utili in questi mesi.&#8221;<\/p>\n<p>La Vicepresidente CNA Datteri ha sottolineato che \u201cCNA collaborer\u00e0 come sempre nella definizione di progetti e proposte per sostenere il difficile percorso di consolidamento dell\u2019export e di internazionalizzazione per le micro e piccole imprese. Siamo impegnati nell\u2019 individuazione di un nuovo modello di Made in Italy che coniughi ambiente, economia circolare, sostenibilit\u00e0 economica delle filiere produttive, etica e connessione sociale con l\u2019auspicio di un nuovo Rinascimento che non potr\u00e0 che essere anche artigiano.\u201d<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019export e l\u2019internazionalizzazione dell\u2019Artigianato e delle piccole imprese, analisi e proposte\u201d \u00e8 il titolo del webinar promosso dalla CNA al quale hanno partecipato il Presidente della Confederazione, Daniele Vaccarino, il Sottosegretario agli Esteri, Manlio Di Stefano, il Direttore generale di Ice Agenzia, Roberto Luongo e la Vicepresidente con delega all\u2019internazionalizzazione, Roberta Datteri. Il Sottosegretario Di [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":703,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[56],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Il Sottosegretario agli Esteri Di Stefano e il Direttore Generale di Ice Agenzia al webinar promosso dalla CNA -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/l-sottosegretario-agli-esteri-di-stefano-e-il-direttore-generale-di-ice-agenzia-al-webinar-promosso-dalla-cna\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il Sottosegretario agli Esteri Di Stefano e il Direttore Generale di Ice Agenzia al webinar promosso dalla CNA -\" \/>\n<meta property=\"og:description\" content=\"L\u2019export e l\u2019internazionalizzazione dell\u2019Artigianato e delle piccole imprese, analisi e proposte\u201d \u00e8 il titolo del webinar promosso dalla CNA al quale hanno partecipato il Presidente della Confederazione, Daniele Vaccarino, il Sottosegretario agli Esteri, Manlio Di Stefano, il Direttore generale di Ice Agenzia, Roberto Luongo e la Vicepresidente con delega all\u2019internazionalizzazione, Roberta Datteri. Il Sottosegretario Di [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/l-sottosegretario-agli-esteri-di-stefano-e-il-direttore-generale-di-ice-agenzia-al-webinar-promosso-dalla-cna\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-14T07:32:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-10-14T07:37:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/05\/lavoro.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"606\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/l-sottosegretario-agli-esteri-di-stefano-e-il-direttore-generale-di-ice-agenzia-al-webinar-promosso-dalla-cna\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/l-sottosegretario-agli-esteri-di-stefano-e-il-direttore-generale-di-ice-agenzia-al-webinar-promosso-dalla-cna\/\",\"name\":\"Il Sottosegretario agli Esteri Di Stefano e il Direttore Generale di Ice Agenzia al webinar promosso dalla CNA -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/l-sottosegretario-agli-esteri-di-stefano-e-il-direttore-generale-di-ice-agenzia-al-webinar-promosso-dalla-cna\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/l-sottosegretario-agli-esteri-di-stefano-e-il-direttore-generale-di-ice-agenzia-al-webinar-promosso-dalla-cna\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/05\/lavoro.jpg\",\"datePublished\":\"2020-10-14T07:32:18+00:00\",\"dateModified\":\"2020-10-14T07:37:18+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/l-sottosegretario-agli-esteri-di-stefano-e-il-direttore-generale-di-ice-agenzia-al-webinar-promosso-dalla-cna\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/l-sottosegretario-agli-esteri-di-stefano-e-il-direttore-generale-di-ice-agenzia-al-webinar-promosso-dalla-cna\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/l-sottosegretario-agli-esteri-di-stefano-e-il-direttore-generale-di-ice-agenzia-al-webinar-promosso-dalla-cna\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/05\/lavoro.jpg\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/05\/lavoro.jpg\",\"width\":960,\"height\":606},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/l-sottosegretario-agli-esteri-di-stefano-e-il-direttore-generale-di-ice-agenzia-al-webinar-promosso-dalla-cna\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il Sottosegretario agli Esteri Di Stefano e il Direttore Generale di Ice Agenzia al webinar promosso dalla CNA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il Sottosegretario agli Esteri Di Stefano e il Direttore Generale di Ice Agenzia al webinar promosso dalla CNA -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/l-sottosegretario-agli-esteri-di-stefano-e-il-direttore-generale-di-ice-agenzia-al-webinar-promosso-dalla-cna\/","og_locale":"it_IT","og_type":"article","og_title":"Il Sottosegretario agli Esteri Di Stefano e il Direttore Generale di Ice Agenzia al webinar promosso dalla CNA -","og_description":"L\u2019export e l\u2019internazionalizzazione dell\u2019Artigianato e delle piccole imprese, analisi e proposte\u201d \u00e8 il titolo del webinar promosso dalla CNA al quale hanno partecipato il Presidente della Confederazione, Daniele Vaccarino, il Sottosegretario agli Esteri, Manlio Di Stefano, il Direttore generale di Ice Agenzia, Roberto Luongo e la Vicepresidente con delega all\u2019internazionalizzazione, Roberta Datteri. Il Sottosegretario Di [&hellip;]","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/l-sottosegretario-agli-esteri-di-stefano-e-il-direttore-generale-di-ice-agenzia-al-webinar-promosso-dalla-cna\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2020-10-14T07:32:18+00:00","article_modified_time":"2020-10-14T07:37:18+00:00","og_image":[{"width":960,"height":606,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/05\/lavoro.jpg","type":"image\/jpeg"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/l-sottosegretario-agli-esteri-di-stefano-e-il-direttore-generale-di-ice-agenzia-al-webinar-promosso-dalla-cna\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/l-sottosegretario-agli-esteri-di-stefano-e-il-direttore-generale-di-ice-agenzia-al-webinar-promosso-dalla-cna\/","name":"Il Sottosegretario agli Esteri Di Stefano e il Direttore Generale di Ice Agenzia al webinar promosso dalla CNA -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/l-sottosegretario-agli-esteri-di-stefano-e-il-direttore-generale-di-ice-agenzia-al-webinar-promosso-dalla-cna\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/l-sottosegretario-agli-esteri-di-stefano-e-il-direttore-generale-di-ice-agenzia-al-webinar-promosso-dalla-cna\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/05\/lavoro.jpg","datePublished":"2020-10-14T07:32:18+00:00","dateModified":"2020-10-14T07:37:18+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/l-sottosegretario-agli-esteri-di-stefano-e-il-direttore-generale-di-ice-agenzia-al-webinar-promosso-dalla-cna\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/l-sottosegretario-agli-esteri-di-stefano-e-il-direttore-generale-di-ice-agenzia-al-webinar-promosso-dalla-cna\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/l-sottosegretario-agli-esteri-di-stefano-e-il-direttore-generale-di-ice-agenzia-al-webinar-promosso-dalla-cna\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/05\/lavoro.jpg","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/05\/lavoro.jpg","width":960,"height":606},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/l-sottosegretario-agli-esteri-di-stefano-e-il-direttore-generale-di-ice-agenzia-al-webinar-promosso-dalla-cna\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"Il Sottosegretario agli Esteri Di Stefano e il Direttore Generale di Ice Agenzia al webinar promosso dalla CNA"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/4393"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=4393"}],"version-history":[{"count":2,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/4393\/revisions"}],"predecessor-version":[{"id":4397,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/4393\/revisions\/4397"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/703"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=4393"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=4393"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=4393"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}