{"id":4427,"date":"2020-10-16T12:24:03","date_gmt":"2020-10-16T10:24:03","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=4427"},"modified":"2020-10-16T12:24:03","modified_gmt":"2020-10-16T10:24:03","slug":"inflazione-coldiretti-con-102-frutta-salgono-prezzi-carrello","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/inflazione-coldiretti-con-102-frutta-salgono-prezzi-carrello\/","title":{"rendered":"Inflazione, Coldiretti: con +10,2% frutta salgono prezzi carrello"},"content":{"rendered":"<p><span class=\"dropcap dropcap3\">I<\/span>n controtendenza alla deflazione generale salgono i prezzi al consumo nel carrello della spesa con un rincaro record del 10,2% per la frutta.<\/p>\n<p>E\u2019 quanto emerge da una analisi della Coldiretti sui dati Istat relativi all\u2019inflazione a settembre che registra una diminuzione dello 0,6% su base annua ma una spinta al rialzo dei prezzi dell\u20191,1% per gli alimentari.<\/p>\n<p>&nbsp;<\/p>\n<p>E\u2019 il risultato &#8211; spiega la Coldiretti &#8211; di aumenti che vanno dai salumi (+2,6%) alla pasta (+1,7%), dai formaggi (+1,1%) (alla carne (+2%) ma anche per il pesce surgelato (+3,5%) mentre sono in atto tentativi di speculazione al ribasso nei compensi riconosciuti agli agricoltori.<\/p>\n<p>&nbsp;<\/p>\n<p>Una situazione paradossale poich\u00e9 mentre i prezzi al consumo per cibi e bevande aumentano quelli pagati agli agricoltori e agli allevatori spesso diminuiscono con le quotazioni riconosciute ai produttori che in molti settori \u2013 sottolinea la Coldiretti \u2013 non coprono pi\u00f9 neanche i costi e mettono a rischio il sistema agroalimentare nazionale.<\/p>\n<p>&nbsp;<\/p>\n<p>Alle speculazioni si sommano peraltro gli effetti del clima impazzito \u2013 rileva la Coldiretti \u2013 con il moltiplicarsi di eventi estremi come caldo torrido, nubifragi e grandine che hanno compromesso le produzioni di frutta e verdura provocando la perdita del lavoro di un intero anno in molte aziende agricole.<\/p>\n<p>&nbsp;<\/p>\n<p>Occorre dunque evitare che i comportamenti scorretti di pochi compromettano il lavoro della maggioranza degli operatori della filiera che si dimostra determinante per garantire le forniture alimentari alle famiglie in un momento in cui la pandemia ha messo a rischio gli scambi commerciali internazionali. In un momento difficile per l\u2019economia e l\u2019occupazione nazionale il consiglio della Coldiretti \u00e8 di acquistare prodotto italiano e sostenere la campagna #mangiaitaliano, verificando sempre, laddove possibile, l\u2019origine nazionale in etichetta.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>In controtendenza alla deflazione generale salgono i prezzi al consumo nel carrello della spesa con un rincaro record del 10,2% per la frutta. E\u2019 quanto emerge da una analisi della Coldiretti sui dati Istat relativi all\u2019inflazione a settembre che registra una diminuzione dello 0,6% su base annua ma una spinta al rialzo dei prezzi dell\u20191,1% [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":173,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[56],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Inflazione, Coldiretti: con +10,2% frutta salgono prezzi carrello -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.italiaeconomiaonline.it\/web\/inflazione-coldiretti-con-102-frutta-salgono-prezzi-carrello\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Inflazione, Coldiretti: con +10,2% frutta salgono prezzi carrello -\" \/>\n<meta property=\"og:description\" content=\"In controtendenza alla deflazione generale salgono i prezzi al consumo nel carrello della spesa con un rincaro record del 10,2% per la frutta. E\u2019 quanto emerge da una analisi della Coldiretti sui dati Istat relativi all\u2019inflazione a settembre che registra una diminuzione dello 0,6% su base annua ma una spinta al rialzo dei prezzi dell\u20191,1% [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.italiaeconomiaonline.it\/web\/inflazione-coldiretti-con-102-frutta-salgono-prezzi-carrello\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-16T10:24:03+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/07\/istat_tasse_famiglie-696x522.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"696\" \/>\n\t<meta property=\"og:image:height\" content=\"522\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"http:\/\/www.italiaeconomiaonline.it\/web\/inflazione-coldiretti-con-102-frutta-salgono-prezzi-carrello\/\",\"url\":\"http:\/\/www.italiaeconomiaonline.it\/web\/inflazione-coldiretti-con-102-frutta-salgono-prezzi-carrello\/\",\"name\":\"Inflazione, Coldiretti: con +10,2% frutta salgono prezzi carrello -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/www.italiaeconomiaonline.it\/web\/inflazione-coldiretti-con-102-frutta-salgono-prezzi-carrello\/#primaryimage\"},\"image\":{\"@id\":\"http:\/\/www.italiaeconomiaonline.it\/web\/inflazione-coldiretti-con-102-frutta-salgono-prezzi-carrello\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/07\/istat_tasse_famiglie-696x522.jpg\",\"datePublished\":\"2020-10-16T10:24:03+00:00\",\"dateModified\":\"2020-10-16T10:24:03+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"http:\/\/www.italiaeconomiaonline.it\/web\/inflazione-coldiretti-con-102-frutta-salgono-prezzi-carrello\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/www.italiaeconomiaonline.it\/web\/inflazione-coldiretti-con-102-frutta-salgono-prezzi-carrello\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"http:\/\/www.italiaeconomiaonline.it\/web\/inflazione-coldiretti-con-102-frutta-salgono-prezzi-carrello\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/07\/istat_tasse_famiglie-696x522.jpg\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/07\/istat_tasse_famiglie-696x522.jpg\",\"width\":696,\"height\":522},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/www.italiaeconomiaonline.it\/web\/inflazione-coldiretti-con-102-frutta-salgono-prezzi-carrello\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Inflazione, Coldiretti: con +10,2% frutta salgono prezzi carrello\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Inflazione, Coldiretti: con +10,2% frutta salgono prezzi carrello -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.italiaeconomiaonline.it\/web\/inflazione-coldiretti-con-102-frutta-salgono-prezzi-carrello\/","og_locale":"it_IT","og_type":"article","og_title":"Inflazione, Coldiretti: con +10,2% frutta salgono prezzi carrello -","og_description":"In controtendenza alla deflazione generale salgono i prezzi al consumo nel carrello della spesa con un rincaro record del 10,2% per la frutta. E\u2019 quanto emerge da una analisi della Coldiretti sui dati Istat relativi all\u2019inflazione a settembre che registra una diminuzione dello 0,6% su base annua ma una spinta al rialzo dei prezzi dell\u20191,1% [&hellip;]","og_url":"http:\/\/www.italiaeconomiaonline.it\/web\/inflazione-coldiretti-con-102-frutta-salgono-prezzi-carrello\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2020-10-16T10:24:03+00:00","og_image":[{"width":696,"height":522,"url":"http:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/07\/istat_tasse_famiglie-696x522.jpg","type":"image\/jpeg"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"http:\/\/www.italiaeconomiaonline.it\/web\/inflazione-coldiretti-con-102-frutta-salgono-prezzi-carrello\/","url":"http:\/\/www.italiaeconomiaonline.it\/web\/inflazione-coldiretti-con-102-frutta-salgono-prezzi-carrello\/","name":"Inflazione, Coldiretti: con +10,2% frutta salgono prezzi carrello -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"http:\/\/www.italiaeconomiaonline.it\/web\/inflazione-coldiretti-con-102-frutta-salgono-prezzi-carrello\/#primaryimage"},"image":{"@id":"http:\/\/www.italiaeconomiaonline.it\/web\/inflazione-coldiretti-con-102-frutta-salgono-prezzi-carrello\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/07\/istat_tasse_famiglie-696x522.jpg","datePublished":"2020-10-16T10:24:03+00:00","dateModified":"2020-10-16T10:24:03+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"http:\/\/www.italiaeconomiaonline.it\/web\/inflazione-coldiretti-con-102-frutta-salgono-prezzi-carrello\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.italiaeconomiaonline.it\/web\/inflazione-coldiretti-con-102-frutta-salgono-prezzi-carrello\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"http:\/\/www.italiaeconomiaonline.it\/web\/inflazione-coldiretti-con-102-frutta-salgono-prezzi-carrello\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/07\/istat_tasse_famiglie-696x522.jpg","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/07\/istat_tasse_famiglie-696x522.jpg","width":696,"height":522},{"@type":"BreadcrumbList","@id":"http:\/\/www.italiaeconomiaonline.it\/web\/inflazione-coldiretti-con-102-frutta-salgono-prezzi-carrello\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"Inflazione, Coldiretti: con +10,2% frutta salgono prezzi carrello"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/4427"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=4427"}],"version-history":[{"count":1,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/4427\/revisions"}],"predecessor-version":[{"id":4428,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/4427\/revisions\/4428"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/173"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=4427"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=4427"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=4427"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}