{"id":4442,"date":"2020-10-19T17:00:17","date_gmt":"2020-10-19T15:00:17","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=4442"},"modified":"2020-10-19T17:08:12","modified_gmt":"2020-10-19T15:08:12","slug":"coronavirus-il-gateway-di-interoperabilita-dellue-entra-in-funzione","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-il-gateway-di-interoperabilita-dellue-entra-in-funzione\/","title":{"rendered":"Coronavirus, il gateway di interoperabilit\u00e0 dell&#8217;UE entra in funzione."},"content":{"rendered":"<p><span class=\"dropcap dropcap3\">P<\/span>er sfruttare appieno il potenziale delle app di tracciamento dei contatti e allerta, volte a spezzare la catena dei contagi da coronavirus a livello transfrontaliero e salvare vite, la Commissione, su richiesta degli Stati membri dell&#8217;Unione, ha creato un sistema a livello dell&#8217;UE per garantirne l&#8217;interoperabilit\u00e0: un cosiddetto &#8220;gateway&#8221;.<\/p>\n<p>Al termine di una <a href=\"https:\/\/ec.europa.eu\/commission\/presscorner\/detail\/it\/ip_20_1606\">fase pilota<\/a> che ha dato esito positivo, oggi il sistema entra in funzione con una prima serie di app nazionali collegate attraverso questo servizio: la tedesca <em>Corona-Warn-App<\/em>, l&#8217;irlandese <em>COVID Tracker<\/em> e l&#8217;italiana <em>Immuni<\/em>.<\/p>\n<p>Complessivamente queste app sono state scaricate da circa 30 milioni di persone, corrispondenti ai due terzi di tutti i download di app nell&#8217;UE.<\/p>\n<p>Thierry <strong>Breton<\/strong>, Commissario per il Mercato interno, ha dichiarato: <em>&#8220;Molti Stati membri hanno lanciato app volontarie di tracciamento dei contatti e allerta e la Commissione li ha aiutati a fare in modo che queste app interagiscano tra loro in sicurezza. La libera circolazione \u00e8 parte integrante del mercato unico: il gateway la facilita, aiutandoci inoltre a salvare vite.&#8221;<\/em><\/p>\n<p>Stella <strong>Kyriakides<\/strong>, Commissaria per la Salute e la Sicurezza alimentare, ha aggiunto<em>: &#8220;La app di tracciamento e allerta per il coronavirus possono integrare efficacemente altre misure, quali l&#8217;aumento dei test e il tracciamento manuale dei contatti. Con i casi nuovamente in aumento, possono svolgere un ruolo importante nell&#8217;aiutarci a spezzare le catene di trasmissione. Il fatto di funzionare a livello transfrontaliero rende queste app strumenti ancora pi\u00f9 efficaci. Il sistema gateway che entra in funzione oggi \u00e8 un passo importante nel nostro lavoro e invito i cittadini a utilizzare queste app per contribuire a proteggerci l&#8217;un l&#8217;altro.&#8221;<\/em><\/p>\n<p>Jens <strong>Spahn<\/strong>, Ministro federale della Salute tedesco, ha dichiarato:<em> &#8220;Ovunque in Europa le infezioni sono nuovamente in aumento. In questo momento le app nazionali di allerta fanno davvero la differenza, perch\u00e9 ogni catena del contagio che l&#8217;app consente di spezzare pi\u00f9 rapidamente contribuisce a contenere la pandemia. Con il nuovo servizio gateway colleghiamo le app di tutta Europa, in questo modo i contatti saranno allertati anche durante o dopo un viaggio all&#8217;estero.&#8221;<\/em><\/p>\n<p>Nel contesto della lotta al coronavirus, la maggior parte degli Stati membri ha deciso di lanciare un&#8217;app di tracciamento dei contatti e allerta. Il servizio gateway consente l&#8217;interoperabilit\u00e0 di un totale di 18 app basate su sistemi decentralizzati, che possono essere collegate al gateway dopo aver seguito un protocollo che prevede diverse prove e controlli, e il rilascio di un aggiornamento per ciascuna app. Il secondo gruppo di app sar\u00e0 collegato la prossima settimana, quando dovrebbero aderire le app <em>eRou\u0161ka<\/em> della Cechia, <em>Smitte|stop<\/em> della Danimarca, <em>Apturi Covid<\/em> della Lettonia e <em>Radar COVID<\/em> della Spagna, mentre altre app saranno collegate al sistema a novembre. La panoramica degli Stati membri partecipanti \u00e8 disponibile su una <a href=\"https:\/\/ec.europa.eu\/info\/live-work-travel-eu\/health\/coronavirus-response\/digital-solutions\/tracing-warning-apps-coronavirus-crisis_it\">pagina web <\/a>dedicata.<\/p>\n<p>Il gateway garantisce che le app funzionino senza soluzione di continuit\u00e0 a livello transfrontaliero. Per gli utenti sar\u00e0 quindi sufficiente installare una sola app e, quando viaggeranno in un altro paese europeo che partecipa all&#8217;iniziativa, potranno continuare a beneficiare del tracciamento dei contatti e a ricevere messaggi di allerta, indipendentemente dal fatto che si trovino all&#8217;estero o nel loro paese di origine. Il server del gateway riduce al minimo la quantit\u00e0 di dati scambiati, provvedendo allo scambio efficiente degli identificatori arbitrari tra le app nazionali. Il gateway tratter\u00e0 esclusivamente le chiavi arbitrarie generate dalle app; le informazioni sono pseudonimizzate, criptate, limitate al minimo e conservate solo per il tempo necessario al tracciamento delle infezioni. Non sar\u00e0 possibile identificare singole persone n\u00e9 localizzare dispositivi o tracciarne gli spostamenti.<\/p>\n<p>L&#8217;istituzione del gateway d\u00e0 seguito all&#8217;accordo degli Stati membri sulle<a href=\"https:\/\/ec.europa.eu\/commission\/presscorner\/detail\/it\/ip_20_1043\">specifiche tecniche<\/a>, volto a garantire lo scambio sicuro di informazioni tra i server di back-end delle app nazionali di tracciamento dei contatti e allerta basate su un&#8217;architettura decentrata. Il sistema \u00e8 stato sviluppato e realizzato in meno di due mesi da T-Systems e SAP e sar\u00e0 gestito dal centro dati della Commissione a Lussemburgo.<\/p>\n<p>Le app di tracciamento dei contatti, se pienamente conformi alle norme dell&#8217;UE e ben coordinate, possono svolgere un ruolo importante in tutte le fasi di gestione della crisi. Possono integrare il tracciamento manuale dei contatti gi\u00e0 in essere e contribuire a interrompere la catena di trasmissione del virus, contribuendo cos\u00ec a salvare vite.<\/p>\n<p>Dall&#8217;inizio della pandemia di coronavirus gli Stati membri, con il sostegno della Commissione, valutano le soluzioni digitali per affrontare la crisi sotto i profili dell&#8217;efficacia, della sicurezza, della tutela della privacy e della protezione dei dati, e hanno sviluppato un <a href=\"https:\/\/ec.europa.eu\/health\/sites\/health\/files\/ehealth\/docs\/covid-19_apps_en.pdf\">pacchetto di strumenti dell&#8217;UE<\/a> per le app di tracciamento dei contatti e allerta, corredato di <a href=\"https:\/\/ec.europa.eu\/commission\/presscorner\/detail\/it\/ip_20_669\">orientamenti sulla protezione dei dati<\/a>. Come stabilito in una <a href=\"https:\/\/ec.europa.eu\/commission\/presscorner\/detail\/it\/ip_20_626\">raccomandazione della Commissione<\/a>, questo pacchetto di strumenti rientra in un approccio comune coordinato a sostegno della revoca graduale delle misure di confinamento. Per garantire il funzionamento transfrontaliero delle app di tracciamento e allerta gli Stati membri, con il sostegno della Commissione, hanno concordato a maggio gli <a href=\"https:\/\/ec.europa.eu\/health\/sites\/health\/files\/ehealth\/docs\/contacttracing_mobileapps_guidelines_en.pdf\">orientamenti sull&#8217;interoperabilit\u00e0<\/a> e successivamente a giugno una <a href=\"https:\/\/ec.europa.eu\/health\/ehealth\/key_documents_en#anchor0\">serie di specifiche tecniche<\/a>, mentre la Commissione ha adottato una <a href=\"https:\/\/eur-lex.europa.eu\/legal-content\/IT\/TXT\/?uri=uriserv%3AOJ.LI.2020.227.01.0001.01.ITA\">decisione di esecuzione<\/a> per fornire una base giuridica per il servizio gateway. A settembre il sistema \u00e8 stato testato nell&#8217;ambito di una <a href=\"https:\/\/ec.europa.eu\/commission\/presscorner\/detail\/it\/ip_20_1606\">fase pilota<\/a>.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Per sfruttare appieno il potenziale delle app di tracciamento dei contatti e allerta, volte a spezzare la catena dei contagi da coronavirus a livello transfrontaliero e salvare vite, la Commissione, su richiesta degli Stati membri dell&#8217;Unione, ha creato un sistema a livello dell&#8217;UE per garantirne l&#8217;interoperabilit\u00e0: un cosiddetto &#8220;gateway&#8221;. Al termine di una fase pilota [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2273,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[309],"tags":[1353],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Coronavirus, il gateway di interoperabilit\u00e0 dell&#039;UE entra in funzione. -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-il-gateway-di-interoperabilita-dellue-entra-in-funzione\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Coronavirus, il gateway di interoperabilit\u00e0 dell&#039;UE entra in funzione. -\" \/>\n<meta property=\"og:description\" content=\"Per sfruttare appieno il potenziale delle app di tracciamento dei contatti e allerta, volte a spezzare la catena dei contagi da coronavirus a livello transfrontaliero e salvare vite, la Commissione, su richiesta degli Stati membri dell&#8217;Unione, ha creato un sistema a livello dell&#8217;UE per garantirne l&#8217;interoperabilit\u00e0: un cosiddetto &#8220;gateway&#8221;. Al termine di una fase pilota [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-il-gateway-di-interoperabilita-dellue-entra-in-funzione\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-19T15:00:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-10-19T15:08:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/01\/Internet1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-il-gateway-di-interoperabilita-dellue-entra-in-funzione\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-il-gateway-di-interoperabilita-dellue-entra-in-funzione\/\",\"name\":\"Coronavirus, il gateway di interoperabilit\u00e0 dell'UE entra in funzione. -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-il-gateway-di-interoperabilita-dellue-entra-in-funzione\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-il-gateway-di-interoperabilita-dellue-entra-in-funzione\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/01\/Internet1.jpg\",\"datePublished\":\"2020-10-19T15:00:17+00:00\",\"dateModified\":\"2020-10-19T15:08:12+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-il-gateway-di-interoperabilita-dellue-entra-in-funzione\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-il-gateway-di-interoperabilita-dellue-entra-in-funzione\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-il-gateway-di-interoperabilita-dellue-entra-in-funzione\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/01\/Internet1.jpg\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/01\/Internet1.jpg\",\"width\":800,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-il-gateway-di-interoperabilita-dellue-entra-in-funzione\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Coronavirus, il gateway di interoperabilit\u00e0 dell&#8217;UE entra in funzione.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Coronavirus, il gateway di interoperabilit\u00e0 dell'UE entra in funzione. -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-il-gateway-di-interoperabilita-dellue-entra-in-funzione\/","og_locale":"it_IT","og_type":"article","og_title":"Coronavirus, il gateway di interoperabilit\u00e0 dell'UE entra in funzione. -","og_description":"Per sfruttare appieno il potenziale delle app di tracciamento dei contatti e allerta, volte a spezzare la catena dei contagi da coronavirus a livello transfrontaliero e salvare vite, la Commissione, su richiesta degli Stati membri dell&#8217;Unione, ha creato un sistema a livello dell&#8217;UE per garantirne l&#8217;interoperabilit\u00e0: un cosiddetto &#8220;gateway&#8221;. Al termine di una fase pilota [&hellip;]","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-il-gateway-di-interoperabilita-dellue-entra-in-funzione\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2020-10-19T15:00:17+00:00","article_modified_time":"2020-10-19T15:08:12+00:00","og_image":[{"width":800,"height":600,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/01\/Internet1.jpg","type":"image\/jpeg"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-il-gateway-di-interoperabilita-dellue-entra-in-funzione\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-il-gateway-di-interoperabilita-dellue-entra-in-funzione\/","name":"Coronavirus, il gateway di interoperabilit\u00e0 dell'UE entra in funzione. -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-il-gateway-di-interoperabilita-dellue-entra-in-funzione\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-il-gateway-di-interoperabilita-dellue-entra-in-funzione\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/01\/Internet1.jpg","datePublished":"2020-10-19T15:00:17+00:00","dateModified":"2020-10-19T15:08:12+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-il-gateway-di-interoperabilita-dellue-entra-in-funzione\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-il-gateway-di-interoperabilita-dellue-entra-in-funzione\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-il-gateway-di-interoperabilita-dellue-entra-in-funzione\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/01\/Internet1.jpg","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/01\/Internet1.jpg","width":800,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-il-gateway-di-interoperabilita-dellue-entra-in-funzione\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"Coronavirus, il gateway di interoperabilit\u00e0 dell&#8217;UE entra in funzione."}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/4442"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=4442"}],"version-history":[{"count":2,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/4442\/revisions"}],"predecessor-version":[{"id":4444,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/4442\/revisions\/4444"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/2273"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=4442"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=4442"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=4442"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}