{"id":4464,"date":"2020-10-22T10:10:35","date_gmt":"2020-10-22T08:10:35","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=4464"},"modified":"2020-10-22T10:10:35","modified_gmt":"2020-10-22T08:10:35","slug":"online-le-faq-dellagenzia-di-riscossione-su-stop-cartelle-fino-al-31-dicembre","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/online-le-faq-dellagenzia-di-riscossione-su-stop-cartelle-fino-al-31-dicembre\/","title":{"rendered":"Online le faq dell&#8217;agenzia di riscossione su stop cartelle fino al 31 dicembre"},"content":{"rendered":"<p><span class=\"dropcap dropcap3\">A<\/span>genzia delle entrate-Riscossione ha aggiornato sul proprio sito internet le risposte alle domande pi\u00f9 frequenti (Faq) con le novit\u00e0 introdotte dal Decreto Legge n. 129\/2020, pubblicato nella Gazzetta Ufficiale n. 260 del 20 ottobre 2020, recante \u201cDisposizioni urgenti in materia di riscossione esattoriale\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>Tra le misure del nuovo provvedimento, \u00e8 previsto il differimento al 31 dicembre 2020 del termine di sospensione per la notifica e il pagamento delle cartelle, precedentemente fissato al 15 ottobre 2020 dal &#8220;Decreto Agosto&#8221;, lasciando invariata la sola scadenza riferita al pagamento delle rate 2020 della Definizione Agevolata. Inoltre, viene prorogata l\u2019agevolazione relativa al maggior termine di decadenza delle rateizzazioni presentate entro il 31 dicembre 2020, consistente nel mancato pagamento di dieci rate, anche non consecutive, invece delle cinque rate ordinariamente previste.<\/p>\n<p>&nbsp;<\/p>\n<p>In considerazione del protrarsi della situazione di emergenza epidemiologica da Covid-19, i cittadini possono utilizzare i servizi online presenti sul <a href=\"http:\/\/www.agenziaentrateriscossione.gov.it\">sito<\/a> \u00a0e sull\u2019app Equiclick, e ricevere assistenza rivolgendosi al Contact Center al numero 060101. Inoltre rimangono disponibili gli indirizzi di posta elettronica\u00a0attivati dall\u2019Agenzia appositamente per le situazioni urgenti e ai quali \u00e8 possibile inviare la richiesta semplicemente allegando un documento di riconoscimento. Tali canali di assistenza, con il perdurare dell\u2019emergenza sanitaria, sono preferibili rispetto agli sportelli che rimangono comunque aperti su appuntamento.<\/p>\n<p>&nbsp;<\/p>\n<p>Vediamo nel dettaglio alcuni chiarimenti contenuti nelle Faq relative alle misure introdotte in materia di riscossione dai provvedimenti normativi emanati nel periodo di emergenza sanitaria.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>SOSPESI I PAGAMENTI DI CARTELLE E AVVISI<\/strong>. Il Decreto Legge n. 129\/2020 estende l\u2019arco temporale degli interventi agevolativi gi\u00e0 contenuti nel Decreto \u201cCura Italia\u201d (DL n. 18\/2020) e nei successivi Decreto Rilancio (DL n. 34\/2020) e Decreto Agosto (DL n. 104\/2020). \u00c8 stata quindi disposta la sospensione fino al 31 dicembre 2020 del versamento\u00a0di tutte le entrate tributarie e non tributarie derivanti da\u00a0cartelle di pagamento, avvisi di addebito e avvisi di accertamento affidati all\u2019Agente della riscossione dall\u20198 marzo. I pagamenti dovranno essere effettuati entro il mese successivo alla scadenza del periodo di sospensione e, dunque, entro il 31 gennaio 2021.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>STOP A NOTIFICHE E PIGNORAMENTI. <\/strong>\u00c8 stata estesa fino al 31 dicembre 2020 anche la sospensione delle attivit\u00e0 di notifica di nuove cartelle, degli altri atti di riscossione nonch\u00e9 degli obblighi derivanti dai pignoramenti presso terzi effettuati prima della data di entrata in vigore del decreto Rilancio (19\/5\/2020), su stipendi, salari, altre indennit\u00e0 relative al rapporto di lavoro o impiego, nonch\u00e9 a titolo di pensioni e trattamenti assimilati. Fino al 31 dicembre 2020, le somme oggetto di pignoramento non devono essere sottoposte ad alcun vincolo di indisponibilit\u00e0 e il soggetto terzo pignorato (ad esempio il datore di lavoro) deve renderle fruibili al debitore (ci\u00f2 anche in presenza di assegnazione gi\u00e0 disposta dal giudice dell\u2019esecuzione). Cessati gli effetti della sospensione, e quindi a decorrere dal 1\u00b0 gennaio 2021, riprenderanno a operare gli obblighi imposti al soggetto terzo debitore (e quindi la necessit\u00e0 di rendere indisponibili le somme oggetto di pignoramento e di versamento all\u2019Agente della riscossione fino alla copertura del debito).<\/p>\n<p>&nbsp;<\/p>\n<p><strong>RATEIZZAZIONI, DECADENZA A 10 RATE. <\/strong>Per i piani di dilazione gi\u00e0 in essere alla data dell\u20198 marzo 2020 e per i provvedimenti di accoglimento delle richieste presentate fino al 31 dicembre 2020, la decadenza del debitore dalle rateizzazioni accordate viene determinata nel caso di mancato pagamento di dieci rate, anche non consecutive, invece delle cinque rate ordinariamente previste. Per i contribuenti decaduti dai benefici della Definizione agevolata (\u201c<a href=\"https:\/\/www.agenziaentrateriscossione.gov.it\/it\/Per-saperne-di-piu\/definizione-agevolata\/definizione-agevolata-2018-\/dopopresentazionedomanda\/\">Rottamazione-ter<\/a>\u201d, \u201c<a href=\"https:\/\/www.agenziaentrateriscossione.gov.it\/it\/Per-saperne-di-piu\/definizione-agevolata\/saldo-e-stralcio\/cosasuccededopoaverpresentatodomanda\/\">Saldo e stralcio<\/a>\u201d e \u201c<a href=\"https:\/\/www.agenziaentrateriscossione.gov.it\/it\/Per-saperne-di-piu\/definizione-agevolata\/definizione-agevolata-per-le-risorse-proprie-ue\/le-prossime-rate-in-scadenza\/\">Definizione agevolata delle risorse UE<\/a>\u201d), per mancato, insufficiente o tardivo versamento delle rate scadute nel 2019, rimane in vigore la possibilit\u00e0, introdotta dal DL 34\/2020, di chiedere la dilazione del pagamento per le somme ancora dovute.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>CREDITI PA, PAGAMENTI SENZA VERIFICHE.<\/strong> Rimarranno sospese fino al 31 dicembre 2020 anche le verifiche di inadempienza delle Pubbliche Amministrazioni e delle societ\u00e0 a prevalente partecipazione pubblica, da effettuarsi, ai sensi dell\u2019art. 48 bis del DPR 602\/1973, prima di disporre pagamenti di importo superiore a cinquemila euro. Tutte le verifiche eventualmente gi\u00e0 effettuate, anche prima dell\u2019inizio del periodo di sospensione, restano prive di qualunque effetto se l\u2019Agente della riscossione non ha notificato l\u2019atto di pignoramento e le Amministrazioni pubbliche possono quindi procedere con il pagamento in favore del beneficiario.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>ROTTAMAZIONE E \u201cSALDO E STRALCIO\u201d.<\/strong> Il Decreto Legge n. 129\/2020 non \u00e8 intervenuto sui termini di scadenza della &#8220;Rottamazione-ter\u201d e del \u201cSaldo e stralcio\u201d, gi\u00e0 oggetto di modifica normativa con il DL 34\/2020 (\u201c<a href=\"https:\/\/www.agenziaentrateriscossione.gov.it\/it\/Per-saperne-di-piu\/covid-19\/il-decreto-rilancio-dl-34-2020\/\">Decreto Rilancio<\/a>\u201d). Resta pertanto confermato il termine \u201cultimo\u201d del 10 dicembre 2020 entro il quale i contribuenti in regola con il pagamento delle rate scadute nell\u2019anno 2019, possono effettuare i pagamenti delle rate in scadenza nel 2020 senza perdere i benefici delle misure agevolative.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Agenzia delle entrate-Riscossione ha aggiornato sul proprio sito internet le risposte alle domande pi\u00f9 frequenti (Faq) con le novit\u00e0 introdotte dal Decreto Legge n. 129\/2020, pubblicato nella Gazzetta Ufficiale n. 260 del 20 ottobre 2020, recante \u201cDisposizioni urgenti in materia di riscossione esattoriale\u201d. &nbsp; Tra le misure del nuovo provvedimento, \u00e8 previsto il differimento al [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3737,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41],"tags":[393,239,1361,42],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Online le faq dell&#039;agenzia di riscossione su stop cartelle fino al 31 dicembre -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/online-le-faq-dellagenzia-di-riscossione-su-stop-cartelle-fino-al-31-dicembre\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Online le faq dell&#039;agenzia di riscossione su stop cartelle fino al 31 dicembre -\" \/>\n<meta property=\"og:description\" content=\"Agenzia delle entrate-Riscossione ha aggiornato sul proprio sito internet le risposte alle domande pi\u00f9 frequenti (Faq) con le novit\u00e0 introdotte dal Decreto Legge n. 129\/2020, pubblicato nella Gazzetta Ufficiale n. 260 del 20 ottobre 2020, recante \u201cDisposizioni urgenti in materia di riscossione esattoriale\u201d. &nbsp; Tra le misure del nuovo provvedimento, \u00e8 previsto il differimento al [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/online-le-faq-dellagenzia-di-riscossione-su-stop-cartelle-fino-al-31-dicembre\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-22T08:10:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/07\/Schermata-2020-07-22-alle-08.58.23.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1408\" \/>\n\t<meta property=\"og:image:height\" content=\"920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/online-le-faq-dellagenzia-di-riscossione-su-stop-cartelle-fino-al-31-dicembre\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/online-le-faq-dellagenzia-di-riscossione-su-stop-cartelle-fino-al-31-dicembre\/\",\"name\":\"Online le faq dell'agenzia di riscossione su stop cartelle fino al 31 dicembre -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/online-le-faq-dellagenzia-di-riscossione-su-stop-cartelle-fino-al-31-dicembre\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/online-le-faq-dellagenzia-di-riscossione-su-stop-cartelle-fino-al-31-dicembre\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/07\/Schermata-2020-07-22-alle-08.58.23.png\",\"datePublished\":\"2020-10-22T08:10:35+00:00\",\"dateModified\":\"2020-10-22T08:10:35+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/online-le-faq-dellagenzia-di-riscossione-su-stop-cartelle-fino-al-31-dicembre\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/online-le-faq-dellagenzia-di-riscossione-su-stop-cartelle-fino-al-31-dicembre\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/online-le-faq-dellagenzia-di-riscossione-su-stop-cartelle-fino-al-31-dicembre\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/07\/Schermata-2020-07-22-alle-08.58.23.png\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/07\/Schermata-2020-07-22-alle-08.58.23.png\",\"width\":1408,\"height\":920},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/online-le-faq-dellagenzia-di-riscossione-su-stop-cartelle-fino-al-31-dicembre\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Online le faq dell&#8217;agenzia di riscossione su stop cartelle fino al 31 dicembre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Online le faq dell'agenzia di riscossione su stop cartelle fino al 31 dicembre -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/online-le-faq-dellagenzia-di-riscossione-su-stop-cartelle-fino-al-31-dicembre\/","og_locale":"it_IT","og_type":"article","og_title":"Online le faq dell'agenzia di riscossione su stop cartelle fino al 31 dicembre -","og_description":"Agenzia delle entrate-Riscossione ha aggiornato sul proprio sito internet le risposte alle domande pi\u00f9 frequenti (Faq) con le novit\u00e0 introdotte dal Decreto Legge n. 129\/2020, pubblicato nella Gazzetta Ufficiale n. 260 del 20 ottobre 2020, recante \u201cDisposizioni urgenti in materia di riscossione esattoriale\u201d. &nbsp; Tra le misure del nuovo provvedimento, \u00e8 previsto il differimento al [&hellip;]","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/online-le-faq-dellagenzia-di-riscossione-su-stop-cartelle-fino-al-31-dicembre\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2020-10-22T08:10:35+00:00","og_image":[{"width":1408,"height":920,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/07\/Schermata-2020-07-22-alle-08.58.23.png","type":"image\/png"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/online-le-faq-dellagenzia-di-riscossione-su-stop-cartelle-fino-al-31-dicembre\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/online-le-faq-dellagenzia-di-riscossione-su-stop-cartelle-fino-al-31-dicembre\/","name":"Online le faq dell'agenzia di riscossione su stop cartelle fino al 31 dicembre -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/online-le-faq-dellagenzia-di-riscossione-su-stop-cartelle-fino-al-31-dicembre\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/online-le-faq-dellagenzia-di-riscossione-su-stop-cartelle-fino-al-31-dicembre\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/07\/Schermata-2020-07-22-alle-08.58.23.png","datePublished":"2020-10-22T08:10:35+00:00","dateModified":"2020-10-22T08:10:35+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/online-le-faq-dellagenzia-di-riscossione-su-stop-cartelle-fino-al-31-dicembre\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/online-le-faq-dellagenzia-di-riscossione-su-stop-cartelle-fino-al-31-dicembre\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/online-le-faq-dellagenzia-di-riscossione-su-stop-cartelle-fino-al-31-dicembre\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/07\/Schermata-2020-07-22-alle-08.58.23.png","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/07\/Schermata-2020-07-22-alle-08.58.23.png","width":1408,"height":920},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/online-le-faq-dellagenzia-di-riscossione-su-stop-cartelle-fino-al-31-dicembre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"Online le faq dell&#8217;agenzia di riscossione su stop cartelle fino al 31 dicembre"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/4464"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=4464"}],"version-history":[{"count":1,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/4464\/revisions"}],"predecessor-version":[{"id":4465,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/4464\/revisions\/4465"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/3737"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=4464"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=4464"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=4464"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}