{"id":4507,"date":"2020-10-28T15:49:41","date_gmt":"2020-10-28T14:49:41","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=4507"},"modified":"2020-10-28T15:49:41","modified_gmt":"2020-10-28T14:49:41","slug":"passa-al-senato-emendamento-che-esclude-gli-oli-di-palma-e-di-soia-dai-sussidi-per-uso-energetico","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/passa-al-senato-emendamento-che-esclude-gli-oli-di-palma-e-di-soia-dai-sussidi-per-uso-energetico\/","title":{"rendered":"Passa al Senato emendamento che esclude gli oli di palma e di soia dai sussidi per uso energetico"},"content":{"rendered":"<p><span class=\"dropcap dropcap3\">L<\/span>o stop ai sussidi per gli oli di palma e di soia per usi energetici si avvicina; l\u2019Italia potrebbe essere il terzo Paese europeo a fermarli prima del 2030. \u00c8 passato, infatti, ieri al Senato l\u2019emendamento alla proposta di \u201cLegge di delegazione europea\u201d che accelera la fine degli usi energetici dei due oli alimentari (palma e soia), causa primaria di deforestazione nel mondo.<\/p>\n<p>Se la proposta passer\u00e0 alla Camera, l\u2019olio di palma, di soia e i loro derivati, in Italia, saranno esclusi dal conteggio delle energie rinnovabili e dai sussidi di mercato oggi previsti dalla legge, a partire dal 1 gennaio 2023.<\/p>\n<p>Nella nuova direttiva sulle energie rinnovabili, l\u2019Ue ne impone la fine prima del 2030, ma gli Stati membri possono anticiparla. In Francia, l\u2019esclusione avverr\u00e0 dal 1 gennaio 2020; in Norvegia dal 2021.<\/p>\n<p>Un\u2019occasione da non perdere, secondo Legambiente, ma che la soddisfa solo in parte. La battaglia sui tempi della fine dei sussidi all\u2019olio di palma \u00e8, infatti, aperta da tempo e Legambiente chiede da un anno di cessare i sussidi dal 1 gennaio 2021, anche attraverso la petizione #unpienodipalle che ha raccolto 65 mila firme (<a href=\"http:\/\/www.change.org\/unpienodipalle\">www.change.org\/unpienodipalle<\/a>).<\/p>\n<p>L\u2019Eni, dopo essere stata condannata dall\u2019Autorit\u00e0 Garante della Concorrenza e del Mercato a gennaio 2020, ha promesso di eliminare l\u2019olio di palma dal proprio biodiesel Enidiesel+ entro il 2023.<\/p>\n<p>\u201cIl 2023 &#8211; commenta Andrea Poggio, responsabile mobilit\u00e0 di Legambiente &#8211; sembra essere la mediazione possibile tra gli interessi di petrolieri e lobbisti nella lotta alla deforestazione e alle emissioni climalteranti. Una mediazione che ci soddisfa solo in parte, perch\u00e9 sovvenzioneremo ancora per due anni la combustione di olio di palma e di soia a spese dei cittadini. Secondo le nostre stime sui report del Gestore dei Servizi Energetici, parliamo di quasi un miliardo di euro all\u2019anno pagato dalle famiglie attraverso le bollette elettriche e l\u2019acquisto di carburante. Alla luce delle ricerche commissionate dalla Commissione Europea, la combustione di olio di palma e di soia comporta emissioni di CO2 doppie o triple rispetto a quella del gasolio fossile. Ecco perch\u00e9 \u00e8 sbagliato usare e sovvenzionare l\u2019uso di alimenti per produrre energia, specie se prodotti in piantagioni che hanno sostituito foreste e torbiere nel mondo\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lo stop ai sussidi per gli oli di palma e di soia per usi energetici si avvicina; l\u2019Italia potrebbe essere il terzo Paese europeo a fermarli prima del 2030. \u00c8 passato, infatti, ieri al Senato l\u2019emendamento alla proposta di \u201cLegge di delegazione europea\u201d che accelera la fine degli usi energetici dei due oli alimentari (palma [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":187,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[1127,1128],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Passa al Senato emendamento che esclude gli oli di palma e di soia dai sussidi per uso energetico -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/passa-al-senato-emendamento-che-esclude-gli-oli-di-palma-e-di-soia-dai-sussidi-per-uso-energetico\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Passa al Senato emendamento che esclude gli oli di palma e di soia dai sussidi per uso energetico -\" \/>\n<meta property=\"og:description\" content=\"Lo stop ai sussidi per gli oli di palma e di soia per usi energetici si avvicina; l\u2019Italia potrebbe essere il terzo Paese europeo a fermarli prima del 2030. \u00c8 passato, infatti, ieri al Senato l\u2019emendamento alla proposta di \u201cLegge di delegazione europea\u201d che accelera la fine degli usi energetici dei due oli alimentari (palma [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/passa-al-senato-emendamento-che-esclude-gli-oli-di-palma-e-di-soia-dai-sussidi-per-uso-energetico\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-28T14:49:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/08\/olio_di_oliva.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/passa-al-senato-emendamento-che-esclude-gli-oli-di-palma-e-di-soia-dai-sussidi-per-uso-energetico\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/passa-al-senato-emendamento-che-esclude-gli-oli-di-palma-e-di-soia-dai-sussidi-per-uso-energetico\/\",\"name\":\"Passa al Senato emendamento che esclude gli oli di palma e di soia dai sussidi per uso energetico -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/passa-al-senato-emendamento-che-esclude-gli-oli-di-palma-e-di-soia-dai-sussidi-per-uso-energetico\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/passa-al-senato-emendamento-che-esclude-gli-oli-di-palma-e-di-soia-dai-sussidi-per-uso-energetico\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/08\/olio_di_oliva.jpg\",\"datePublished\":\"2020-10-28T14:49:41+00:00\",\"dateModified\":\"2020-10-28T14:49:41+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/passa-al-senato-emendamento-che-esclude-gli-oli-di-palma-e-di-soia-dai-sussidi-per-uso-energetico\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/passa-al-senato-emendamento-che-esclude-gli-oli-di-palma-e-di-soia-dai-sussidi-per-uso-energetico\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/passa-al-senato-emendamento-che-esclude-gli-oli-di-palma-e-di-soia-dai-sussidi-per-uso-energetico\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/08\/olio_di_oliva.jpg\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/08\/olio_di_oliva.jpg\",\"width\":960,\"height\":640},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/passa-al-senato-emendamento-che-esclude-gli-oli-di-palma-e-di-soia-dai-sussidi-per-uso-energetico\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Passa al Senato emendamento che esclude gli oli di palma e di soia dai sussidi per uso energetico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Passa al Senato emendamento che esclude gli oli di palma e di soia dai sussidi per uso energetico -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/passa-al-senato-emendamento-che-esclude-gli-oli-di-palma-e-di-soia-dai-sussidi-per-uso-energetico\/","og_locale":"it_IT","og_type":"article","og_title":"Passa al Senato emendamento che esclude gli oli di palma e di soia dai sussidi per uso energetico -","og_description":"Lo stop ai sussidi per gli oli di palma e di soia per usi energetici si avvicina; l\u2019Italia potrebbe essere il terzo Paese europeo a fermarli prima del 2030. \u00c8 passato, infatti, ieri al Senato l\u2019emendamento alla proposta di \u201cLegge di delegazione europea\u201d che accelera la fine degli usi energetici dei due oli alimentari (palma [&hellip;]","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/passa-al-senato-emendamento-che-esclude-gli-oli-di-palma-e-di-soia-dai-sussidi-per-uso-energetico\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2020-10-28T14:49:41+00:00","og_image":[{"width":960,"height":640,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/08\/olio_di_oliva.jpg","type":"image\/jpeg"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/passa-al-senato-emendamento-che-esclude-gli-oli-di-palma-e-di-soia-dai-sussidi-per-uso-energetico\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/passa-al-senato-emendamento-che-esclude-gli-oli-di-palma-e-di-soia-dai-sussidi-per-uso-energetico\/","name":"Passa al Senato emendamento che esclude gli oli di palma e di soia dai sussidi per uso energetico -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/passa-al-senato-emendamento-che-esclude-gli-oli-di-palma-e-di-soia-dai-sussidi-per-uso-energetico\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/passa-al-senato-emendamento-che-esclude-gli-oli-di-palma-e-di-soia-dai-sussidi-per-uso-energetico\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/08\/olio_di_oliva.jpg","datePublished":"2020-10-28T14:49:41+00:00","dateModified":"2020-10-28T14:49:41+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/passa-al-senato-emendamento-che-esclude-gli-oli-di-palma-e-di-soia-dai-sussidi-per-uso-energetico\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/passa-al-senato-emendamento-che-esclude-gli-oli-di-palma-e-di-soia-dai-sussidi-per-uso-energetico\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/passa-al-senato-emendamento-che-esclude-gli-oli-di-palma-e-di-soia-dai-sussidi-per-uso-energetico\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/08\/olio_di_oliva.jpg","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/08\/olio_di_oliva.jpg","width":960,"height":640},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/passa-al-senato-emendamento-che-esclude-gli-oli-di-palma-e-di-soia-dai-sussidi-per-uso-energetico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"Passa al Senato emendamento che esclude gli oli di palma e di soia dai sussidi per uso energetico"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/4507"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=4507"}],"version-history":[{"count":1,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/4507\/revisions"}],"predecessor-version":[{"id":4508,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/4507\/revisions\/4508"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/187"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=4507"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=4507"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=4507"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}