{"id":4517,"date":"2020-10-30T09:04:56","date_gmt":"2020-10-30T08:04:56","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=4517"},"modified":"2020-10-30T09:04:56","modified_gmt":"2020-10-30T08:04:56","slug":"fondazione-gimbe-epidemia-fuori-controllo","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/fondazione-gimbe-epidemia-fuori-controllo\/","title":{"rendered":"Fondazione Gimbe: epidemia fuori controllo"},"content":{"rendered":"<p><span class=\"dropcap dropcap3\">I<\/span>l monitoraggio indipendente della Fondazione GIMBE conferma nella settimana 21-27 ottobre, rispetto alla precedente, l\u2019incremento esponenziale nel trend dei nuovi casi (130.329 vs 68.982), in parte per l\u2019aumento dei casi testati (722.570 vs 630.929), ma soprattutto per il netto incremento del rapporto positivi\/casi testati (18% vs 10,9%) .<\/p>\n<p>Crescono di oltre 112.000 i casi attualmente positivi (255.090 vs 142.739) e, sul fronte degli ospedali, si rileva un costante aumento dei pazienti ricoverati con sintomi (13.955 vs 8.454) e in terapia intensiva (1.411 vs 870). Pi\u00f9 che raddoppiati i decessi (995 vs 459) .<\/p>\n<p>In dettaglio, rispetto alla settimana precedente, si registrano le seguenti variazioni:<br \/>\nDecessi: 955 (+108,1%)<br \/>\nTerapia intensiva: +541 (+62,2%)<br \/>\nRicoverati con sintomi: +5.501 (+65,1%)<br \/>\nNuovi casi: 130.329 (+88,9%)<br \/>\nCasi attualmente positivi: +112.351 (+78,7%)<br \/>\nCasi testati +91.641 (+14,5%)<br \/>\nTamponi totali: +147.423 (+14,4%)<\/p>\n<p>\u00abI dati dell\u2019ultima settimana \u2013 afferma Nino Cartabellotta, Presidente della Fondazione GIMBE \u2013 documentano il crollo definitivo dell\u2019argine territoriale del testing &amp; tracing, confermano un incremento di oltre il 60% dei pazienti ricoverati con sintomi e in terapia intensiva e fanno registrare un raddoppio dei decessi. In alcune aree del Paese non \u00e8 pi\u00f9 procrastinabile il lockdown totale per arginare il contagio diffuso e ridurre la pressione sugli ospedali\u00bb. In generale, i principali indicatori peggiorano in tutte le Regioni, fatta eccezione per il modesto incremento dei casi testati .<\/p>\n<p>\u00abAl di l\u00e0 dei numeri assoluti \u2013 spiega il Presidente \u2013 preoccupano i trend esponenziali con cui aumentano i pazienti ospedalizzati e in terapia intensiva, con un tempo di raddoppiamento di circa 10 giorni da 3 settimane consecutive\u00bb. Secondo Enrico Bucci, professore aggiunto SHRO, Temple University \u00abmantenendo questi trend di crescita, all\u20198 novembre si stimano 31.400 (IC 95%: 30.000-33.000) ricoverati con sintomi e 3.310 (IC 95%: 3.200-3.400) in terapia intensiva; numeri che potrebbero ridursi per l\u2019eccesso di letalit\u00e0 da sovraccarico ospedaliero\u00bb.<\/p>\n<p>Infatti, superando il limite del 30% dei posti letto occupati da pazienti COVID-19, dopo la cancellazione di interventi chirurgici programmati e prestazioni sanitarie differibili, si assister\u00e0 inevitabilmente all\u2019incremento della mortalit\u00e0, non solo COVID-19 correlata.<\/p>\n<p>\u00abVero \u00e8 \u2013 continua Cartabellotta \u2013 che sono state introdotte progressive restrizioni da parte di Governo e Regioni, ma il loro effetto sulla flessione della curva dei contagi sar\u00e0 minimo, sia perch\u00e9 le misure non sono state \u201ctarate\u201d su modelli predittivi a 2 settimane, sia perch\u00e9 le blande misure dei primi due DPCM sono gi\u00e0 state neutralizzate dalla crescita esponenziale della curva epidemica\u00bb.<\/p>\n<p>L\u2019impatto dell\u2019introduzione di differenti misure di contenimento sul valore di Rt \u00e8 oggetto di un recente studio &#8211; pubblicato su Lancet Infectious Diseases da ricercatori dell\u2019Universit\u00e0 di Edimburgo &#8211; che ha analizzato dati da 131 Paesi. \u00abIn relazione ai risultati ottenuti dall\u2019introduzione di ciascuna misura di contenimento \u2013 spiega Renata Gili, responsabile della Ricerca sui Servizi Sanitari della Fondazione GIMBE \u2013 \u00e8 stata stimata l\u2019efficacia sul valore di Rt di quattro possibili gruppi di interventi a 7, 14 e 28 giorni. Se da un lato gli effetti dipendono dal numero e dalla tipologia di restrizioni, dall\u2019altro non sono affatto immediati. Infatti, per dimezzare il valore di Rt servono 28 giorni di lockdown totale, tempi che in Italia potrebbero dilatarsi ulteriormente per il ritardo sempre maggiore nella notifica dei casi\u00bb.<\/p>\n<p>Considerato che le misure introdotte con il DPCM del 24 ottobre includono divieto di eventi pubblici e assembramenti, invito allo smart working e didattica a distanza nelle scuole secondarie di secondo grado per almeno al 75% delle attivit\u00e0, \u00e8 possibile stimare a 14 giorni una riduzione del valore di Rt di circa il 20-25%, totalmente insufficiente per piegare la curva dei contagi e arginare il sovraccarico degli ospedali.<\/p>\n<p>\u00abPeraltro \u2013 spiega Cartabellotta \u2013 l\u2019indice Rt oggi sottostima ampiamente la velocit\u00e0 di diffusione del virus perch\u00e9, oltre ad essere calcolato solo sui casi sintomatici (circa 1\/3 del totale dei contagiati), si basa su dati relativi a due settimane prima e pubblicati dopo circa 10 giorni. In altri termini, le decisioni vengono prese sulla base di un Rt che riflette contagi di circa un mese fa\u00bb. Secondo quanto pubblicato dall\u2019Istituto Superiore di Sanit\u00e0 il 23 ottobre, infatti, l\u2019indice Rt medio di 1,50 (IC 95%: 1,09-1,75) \u00e8 calcolato al 20 ottobre su dati riferiti al periodo 1-14 ottobre.<\/p>\n<p>\u00abL\u2019epidemia gi\u00e0 fuori controllo in diverse aree del Paese da oltre 3 settimane \u2013 conclude Cartabellotta \u2013 insieme al continuo tentennamento di Sindaci e Presidenti di Regioni nell\u2019attuare lockdown locali stanno spingendo l\u2019Italia verso la chiusura totale. Senza immediate chiusure in tutte le zone pi\u00f9 a rischio, serviranno a breve almeno 4 settimane di lockdown nazionale per abbattere la curva dei contagi e permettere di assistere i pazienti in ospedale, al fine di evitare una catastrofe sanitaria peggiore della prima ondata. Perch\u00e9 questa volta, oltre al dilagare dei contagi anche nelle regioni del Sud, meno attrezzate dal punto di vista sanitario, abbiamo davanti quasi 5 mesi di stagione invernale con l\u2019influenza in arrivo\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il monitoraggio indipendente della Fondazione GIMBE conferma nella settimana 21-27 ottobre, rispetto alla precedente, l\u2019incremento esponenziale nel trend dei nuovi casi (130.329 vs 68.982), in parte per l\u2019aumento dei casi testati (722.570 vs 630.929), ma soprattutto per il netto incremento del rapporto positivi\/casi testati (18% vs 10,9%) . Crescono di oltre 112.000 i casi attualmente [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2645,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[128],"tags":[877,880],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Fondazione Gimbe: epidemia fuori controllo -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/fondazione-gimbe-epidemia-fuori-controllo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fondazione Gimbe: epidemia fuori controllo -\" \/>\n<meta property=\"og:description\" content=\"Il monitoraggio indipendente della Fondazione GIMBE conferma nella settimana 21-27 ottobre, rispetto alla precedente, l\u2019incremento esponenziale nel trend dei nuovi casi (130.329 vs 68.982), in parte per l\u2019aumento dei casi testati (722.570 vs 630.929), ma soprattutto per il netto incremento del rapporto positivi\/casi testati (18% vs 10,9%) . Crescono di oltre 112.000 i casi attualmente [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/fondazione-gimbe-epidemia-fuori-controllo\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-30T08:04:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/03\/Schermata-2020-03-06-alle-17.58.41.png\" \/>\n\t<meta property=\"og:image:width\" content=\"854\" \/>\n\t<meta property=\"og:image:height\" content=\"542\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/fondazione-gimbe-epidemia-fuori-controllo\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/fondazione-gimbe-epidemia-fuori-controllo\/\",\"name\":\"Fondazione Gimbe: epidemia fuori controllo -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/fondazione-gimbe-epidemia-fuori-controllo\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/fondazione-gimbe-epidemia-fuori-controllo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/03\/Schermata-2020-03-06-alle-17.58.41.png\",\"datePublished\":\"2020-10-30T08:04:56+00:00\",\"dateModified\":\"2020-10-30T08:04:56+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/fondazione-gimbe-epidemia-fuori-controllo\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/fondazione-gimbe-epidemia-fuori-controllo\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/fondazione-gimbe-epidemia-fuori-controllo\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/03\/Schermata-2020-03-06-alle-17.58.41.png\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/03\/Schermata-2020-03-06-alle-17.58.41.png\",\"width\":854,\"height\":542},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/fondazione-gimbe-epidemia-fuori-controllo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fondazione Gimbe: epidemia fuori controllo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fondazione Gimbe: epidemia fuori controllo -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/fondazione-gimbe-epidemia-fuori-controllo\/","og_locale":"it_IT","og_type":"article","og_title":"Fondazione Gimbe: epidemia fuori controllo -","og_description":"Il monitoraggio indipendente della Fondazione GIMBE conferma nella settimana 21-27 ottobre, rispetto alla precedente, l\u2019incremento esponenziale nel trend dei nuovi casi (130.329 vs 68.982), in parte per l\u2019aumento dei casi testati (722.570 vs 630.929), ma soprattutto per il netto incremento del rapporto positivi\/casi testati (18% vs 10,9%) . Crescono di oltre 112.000 i casi attualmente [&hellip;]","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/fondazione-gimbe-epidemia-fuori-controllo\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2020-10-30T08:04:56+00:00","og_image":[{"width":854,"height":542,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/03\/Schermata-2020-03-06-alle-17.58.41.png","type":"image\/png"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/fondazione-gimbe-epidemia-fuori-controllo\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/fondazione-gimbe-epidemia-fuori-controllo\/","name":"Fondazione Gimbe: epidemia fuori controllo -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/fondazione-gimbe-epidemia-fuori-controllo\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/fondazione-gimbe-epidemia-fuori-controllo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/03\/Schermata-2020-03-06-alle-17.58.41.png","datePublished":"2020-10-30T08:04:56+00:00","dateModified":"2020-10-30T08:04:56+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/fondazione-gimbe-epidemia-fuori-controllo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/fondazione-gimbe-epidemia-fuori-controllo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/fondazione-gimbe-epidemia-fuori-controllo\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/03\/Schermata-2020-03-06-alle-17.58.41.png","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/03\/Schermata-2020-03-06-alle-17.58.41.png","width":854,"height":542},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/fondazione-gimbe-epidemia-fuori-controllo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"Fondazione Gimbe: epidemia fuori controllo"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/4517"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=4517"}],"version-history":[{"count":1,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/4517\/revisions"}],"predecessor-version":[{"id":4518,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/4517\/revisions\/4518"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/2645"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=4517"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=4517"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=4517"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}