{"id":4545,"date":"2020-11-03T12:29:05","date_gmt":"2020-11-03T11:29:05","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=4545"},"modified":"2020-11-03T12:29:05","modified_gmt":"2020-11-03T11:29:05","slug":"osservatorio-cna-a-settembre-tiene-loccupazione-nelle-pi-ma-aumenta-lincertezza-per-lultimo-trimestre","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/osservatorio-cna-a-settembre-tiene-loccupazione-nelle-pi-ma-aumenta-lincertezza-per-lultimo-trimestre\/","title":{"rendered":"Osservatorio CNA: \u201cA settembre tiene l\u2019occupazione nelle PI ma aumenta l\u2019incertezza per l\u2019ultimo trimestre\u201d"},"content":{"rendered":"<p><span class=\"dropcap dropcap3\">O<\/span>ccupazione stabile a settembre per le imprese artigiane, micro e piccole rispetto a un anno fa anche per effetto del blocco dei licenziamenti. In termini congiunturali invece il numero di occupati registra una contrazione dello 0,7% nei confronti di agosto, una dinamica legata alla chiusura della stagione estiva.<\/p>\n<p>E\u2019 quanto emerge dall\u2019Osservatorio lavoro CNA, curato dal Centro Studi della Confederazione che analizza mensilmente le tendenze dell\u2019occupazione dal dicembre 2014. Con la ripresa dei contagi e le conseguenti misure di contenimento, tuttavia, cresce l\u2019incertezza sulle prospettive dell\u2019ultimo trimestre dell\u2019anno.<\/p>\n<p>&nbsp;<\/p>\n<p>Anche a settembre si conferma il trend dello stesso mese del 2019, le assunzioni e le cessazioni sono diminuite su base tendenziale e l\u2019occupazione si \u00e8 ridotta a causa della domanda di lavoro da parte delle imprese, in flessione rispetto a un anno fa.<\/p>\n<p>Le assunzioni mostrano un calo del 15,8% rispetto al settembre 2019 mentre le cessazioni sono diminuite del 3,8% in termini tendenziali. Questa variazione, in linea con quelle osservate nel mese di settembre degli ultimi anni, interrompe una serie di cinque diminuzioni molto ampie determinate con ogni probabilit\u00e0 dagli ammortizzatori sociali.<\/p>\n<p>&nbsp;<\/p>\n<p>In maniera simile a quanto osservato negli altri mesi della stagione estiva, l\u2019esigenza delle micro e piccole imprese a gestire la manodopera in maniera flessibile si riflette in un aumento dell\u2019occupazione inquadrata con tipologie contrattuali non permanenti. Rispetto a un anno fa, infatti, \u00e8 aumentata l\u2019occupazione a tempo di determinato e di apprendistato (rispettivamente +8,8% e +8,0%) nonch\u00e9 di lavoro intermittente (+2,9%).<\/p>\n<p>In diminuzione invece le posizioni a tempo indeterminato (-5,5%) il cui calo nel mese di settembre \u00e8 ormai una costante degli ultimi sei anni. Questa diminuzione si \u00e8 riflessa, come in passato, in una erosione della quota di lavoratori a tempo indeterminato che in sei anni sono passati dall\u201985,4% al 55,6% del totale.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Occupazione stabile a settembre per le imprese artigiane, micro e piccole rispetto a un anno fa anche per effetto del blocco dei licenziamenti. In termini congiunturali invece il numero di occupati registra una contrazione dello 0,7% nei confronti di agosto, una dinamica legata alla chiusura della stagione estiva. E\u2019 quanto emerge dall\u2019Osservatorio lavoro CNA, curato [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4546,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28],"tags":[1374,1375],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Osservatorio CNA: \u201cA settembre tiene l\u2019occupazione nelle PI ma aumenta l\u2019incertezza per l\u2019ultimo trimestre\u201d -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/osservatorio-cna-a-settembre-tiene-loccupazione-nelle-pi-ma-aumenta-lincertezza-per-lultimo-trimestre\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Osservatorio CNA: \u201cA settembre tiene l\u2019occupazione nelle PI ma aumenta l\u2019incertezza per l\u2019ultimo trimestre\u201d -\" \/>\n<meta property=\"og:description\" content=\"Occupazione stabile a settembre per le imprese artigiane, micro e piccole rispetto a un anno fa anche per effetto del blocco dei licenziamenti. In termini congiunturali invece il numero di occupati registra una contrazione dello 0,7% nei confronti di agosto, una dinamica legata alla chiusura della stagione estiva. E\u2019 quanto emerge dall\u2019Osservatorio lavoro CNA, curato [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/osservatorio-cna-a-settembre-tiene-loccupazione-nelle-pi-ma-aumenta-lincertezza-per-lultimo-trimestre\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-03T11:29:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/11\/Schermata-2020-11-03-alle-12.28.30.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1372\" \/>\n\t<meta property=\"og:image:height\" content=\"914\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/osservatorio-cna-a-settembre-tiene-loccupazione-nelle-pi-ma-aumenta-lincertezza-per-lultimo-trimestre\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/osservatorio-cna-a-settembre-tiene-loccupazione-nelle-pi-ma-aumenta-lincertezza-per-lultimo-trimestre\/\",\"name\":\"Osservatorio CNA: \u201cA settembre tiene l\u2019occupazione nelle PI ma aumenta l\u2019incertezza per l\u2019ultimo trimestre\u201d -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/osservatorio-cna-a-settembre-tiene-loccupazione-nelle-pi-ma-aumenta-lincertezza-per-lultimo-trimestre\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/osservatorio-cna-a-settembre-tiene-loccupazione-nelle-pi-ma-aumenta-lincertezza-per-lultimo-trimestre\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/11\/Schermata-2020-11-03-alle-12.28.30.png\",\"datePublished\":\"2020-11-03T11:29:05+00:00\",\"dateModified\":\"2020-11-03T11:29:05+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/osservatorio-cna-a-settembre-tiene-loccupazione-nelle-pi-ma-aumenta-lincertezza-per-lultimo-trimestre\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/osservatorio-cna-a-settembre-tiene-loccupazione-nelle-pi-ma-aumenta-lincertezza-per-lultimo-trimestre\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/osservatorio-cna-a-settembre-tiene-loccupazione-nelle-pi-ma-aumenta-lincertezza-per-lultimo-trimestre\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/11\/Schermata-2020-11-03-alle-12.28.30.png\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/11\/Schermata-2020-11-03-alle-12.28.30.png\",\"width\":1372,\"height\":914},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/osservatorio-cna-a-settembre-tiene-loccupazione-nelle-pi-ma-aumenta-lincertezza-per-lultimo-trimestre\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Osservatorio CNA: \u201cA settembre tiene l\u2019occupazione nelle PI ma aumenta l\u2019incertezza per l\u2019ultimo trimestre\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Osservatorio CNA: \u201cA settembre tiene l\u2019occupazione nelle PI ma aumenta l\u2019incertezza per l\u2019ultimo trimestre\u201d -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/osservatorio-cna-a-settembre-tiene-loccupazione-nelle-pi-ma-aumenta-lincertezza-per-lultimo-trimestre\/","og_locale":"it_IT","og_type":"article","og_title":"Osservatorio CNA: \u201cA settembre tiene l\u2019occupazione nelle PI ma aumenta l\u2019incertezza per l\u2019ultimo trimestre\u201d -","og_description":"Occupazione stabile a settembre per le imprese artigiane, micro e piccole rispetto a un anno fa anche per effetto del blocco dei licenziamenti. In termini congiunturali invece il numero di occupati registra una contrazione dello 0,7% nei confronti di agosto, una dinamica legata alla chiusura della stagione estiva. E\u2019 quanto emerge dall\u2019Osservatorio lavoro CNA, curato [&hellip;]","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/osservatorio-cna-a-settembre-tiene-loccupazione-nelle-pi-ma-aumenta-lincertezza-per-lultimo-trimestre\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2020-11-03T11:29:05+00:00","og_image":[{"width":1372,"height":914,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/11\/Schermata-2020-11-03-alle-12.28.30.png","type":"image\/png"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/osservatorio-cna-a-settembre-tiene-loccupazione-nelle-pi-ma-aumenta-lincertezza-per-lultimo-trimestre\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/osservatorio-cna-a-settembre-tiene-loccupazione-nelle-pi-ma-aumenta-lincertezza-per-lultimo-trimestre\/","name":"Osservatorio CNA: \u201cA settembre tiene l\u2019occupazione nelle PI ma aumenta l\u2019incertezza per l\u2019ultimo trimestre\u201d -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/osservatorio-cna-a-settembre-tiene-loccupazione-nelle-pi-ma-aumenta-lincertezza-per-lultimo-trimestre\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/osservatorio-cna-a-settembre-tiene-loccupazione-nelle-pi-ma-aumenta-lincertezza-per-lultimo-trimestre\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/11\/Schermata-2020-11-03-alle-12.28.30.png","datePublished":"2020-11-03T11:29:05+00:00","dateModified":"2020-11-03T11:29:05+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/osservatorio-cna-a-settembre-tiene-loccupazione-nelle-pi-ma-aumenta-lincertezza-per-lultimo-trimestre\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/osservatorio-cna-a-settembre-tiene-loccupazione-nelle-pi-ma-aumenta-lincertezza-per-lultimo-trimestre\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/osservatorio-cna-a-settembre-tiene-loccupazione-nelle-pi-ma-aumenta-lincertezza-per-lultimo-trimestre\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/11\/Schermata-2020-11-03-alle-12.28.30.png","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/11\/Schermata-2020-11-03-alle-12.28.30.png","width":1372,"height":914},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/osservatorio-cna-a-settembre-tiene-loccupazione-nelle-pi-ma-aumenta-lincertezza-per-lultimo-trimestre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"Osservatorio CNA: \u201cA settembre tiene l\u2019occupazione nelle PI ma aumenta l\u2019incertezza per l\u2019ultimo trimestre\u201d"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/4545"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=4545"}],"version-history":[{"count":1,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/4545\/revisions"}],"predecessor-version":[{"id":4547,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/4545\/revisions\/4547"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/4546"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=4545"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=4545"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=4545"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}