{"id":4577,"date":"2020-11-09T12:10:51","date_gmt":"2020-11-09T11:10:51","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=4577"},"modified":"2020-11-09T12:10:51","modified_gmt":"2020-11-09T11:10:51","slug":"usa-2020-confagricoltura-ripartiamo-dal-dialogo-per-porre-fine-alla-guerra-dei-dazi","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/usa-2020-confagricoltura-ripartiamo-dal-dialogo-per-porre-fine-alla-guerra-dei-dazi\/","title":{"rendered":"USA 2020, Confagricoltura: ripartiamo dal dialogo per porre fine alla guerra dei dazi"},"content":{"rendered":"<p><span class=\"dropcap dropcap3\">A<\/span>ll\u2019indomani dell\u2019esito elettorale negli Stati Uniti, le relazioni commerciali tra UE e USA sono all\u2019ordine del giorno dell\u2019odierna videoconferenza del Consiglio dei ministri degli Affari Esteri (Commercio) dell\u2019Unione.<\/p>\n<p>\u201cPrima di tutto \u2013 dichiara il presidente di Confagricoltura, <strong>Massimiliano Giansanti<\/strong> \u2013 dovrebbe essere chiuso il contenzioso ultradecennale sugli aiuti pubblici ai gruppi Airbus e Boeing. Sarebbero cos\u00ec soppressi i dazi aggiuntivi \u2013 pari al 25% del valore \u2013 che gli Stati Uniti applicano sulle nostre esportazioni di formaggi, salumi, agrumi e liquori\u201d.<\/p>\n<p>Gli Stati Uniti, evidenzia Confagricoltura, sono il primo mercato di sbocco fuori dalla UE per il Made in Italy agroalimentare. Nel 2019 le esportazioni di prodotti agroalimentari sono ammontate a 4,7 miliardi di euro.<\/p>\n<p>Secondo i dati della Commissione europea, per effetto dei dazi aggiuntivi, le esportazioni di prodotti agroalimentari dell\u2019Unione sul mercato statunitense si sono ridotte di 400 milioni di euro nei primi sei mesi di quest\u2019anno sullo stesso periodo del 2019.<\/p>\n<p>\u201cIn prospettiva \u2013 aggiunge Giansanti \u2013 va rilanciato il sistema multilaterale di gestione degli scambi commerciali a livello mondiale. Le tensioni tra Unione europea e Stati Uniti hanno anche paralizzato il funzionamento dell\u2019Organizzazione mondiale del commercio (WTO). La nomina del nuovo direttore generale \u00e8 bloccata e manca il numero legale per la convocazione dell\u2019organo di risoluzione delle controversie\u201d.<\/p>\n<p>\u201cIl sistema agroalimentare italiano ha bisogno di mercati aperti e di regole condivise, per far ripartire la crescita delle esportazioni che ha caratterizzato gli ultimi dieci anni, con un balzo in avanti delle vendite all\u2019estero nell\u2019ordine del 90%\u201d.<\/p>\n<p>\u201cUna riforma del WTO \u00e8 per\u00f2 necessaria \u2013 sottolinea il presidente di Confagricoltura &#8211; e una ritrovata intesa tra Unione europea e Stati Uniti sarebbe fondamentale, anche per la ripresa del commercio internazionale dopo la pandemia\u201d.<\/p>\n<p>\u201cIl processo di globalizzazione &#8211; conclude Giansanti &#8211; ha imposto nuove esigenze di armonizzazione e reciprocit\u00e0 delle regole in termini di protezione dei consumatori, tutela dell\u2019ambiente e protezione delle risorse naturali\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>All\u2019indomani dell\u2019esito elettorale negli Stati Uniti, le relazioni commerciali tra UE e USA sono all\u2019ordine del giorno dell\u2019odierna videoconferenza del Consiglio dei ministri degli Affari Esteri (Commercio) dell\u2019Unione. \u201cPrima di tutto \u2013 dichiara il presidente di Confagricoltura, Massimiliano Giansanti \u2013 dovrebbe essere chiuso il contenzioso ultradecennale sugli aiuti pubblici ai gruppi Airbus e Boeing. Sarebbero [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4311,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[537],"tags":[20,1384],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>USA 2020, Confagricoltura: ripartiamo dal dialogo per porre fine alla guerra dei dazi -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/usa-2020-confagricoltura-ripartiamo-dal-dialogo-per-porre-fine-alla-guerra-dei-dazi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"USA 2020, Confagricoltura: ripartiamo dal dialogo per porre fine alla guerra dei dazi -\" \/>\n<meta property=\"og:description\" content=\"All\u2019indomani dell\u2019esito elettorale negli Stati Uniti, le relazioni commerciali tra UE e USA sono all\u2019ordine del giorno dell\u2019odierna videoconferenza del Consiglio dei ministri degli Affari Esteri (Commercio) dell\u2019Unione. \u201cPrima di tutto \u2013 dichiara il presidente di Confagricoltura, Massimiliano Giansanti \u2013 dovrebbe essere chiuso il contenzioso ultradecennale sugli aiuti pubblici ai gruppi Airbus e Boeing. Sarebbero [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/usa-2020-confagricoltura-ripartiamo-dal-dialogo-per-porre-fine-alla-guerra-dei-dazi\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-09T11:10:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/10\/Schermata-2020-10-05-alle-12.14.06.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1668\" \/>\n\t<meta property=\"og:image:height\" content=\"764\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/usa-2020-confagricoltura-ripartiamo-dal-dialogo-per-porre-fine-alla-guerra-dei-dazi\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/usa-2020-confagricoltura-ripartiamo-dal-dialogo-per-porre-fine-alla-guerra-dei-dazi\/\",\"name\":\"USA 2020, Confagricoltura: ripartiamo dal dialogo per porre fine alla guerra dei dazi -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/usa-2020-confagricoltura-ripartiamo-dal-dialogo-per-porre-fine-alla-guerra-dei-dazi\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/usa-2020-confagricoltura-ripartiamo-dal-dialogo-per-porre-fine-alla-guerra-dei-dazi\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/10\/Schermata-2020-10-05-alle-12.14.06.png\",\"datePublished\":\"2020-11-09T11:10:51+00:00\",\"dateModified\":\"2020-11-09T11:10:51+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/usa-2020-confagricoltura-ripartiamo-dal-dialogo-per-porre-fine-alla-guerra-dei-dazi\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/usa-2020-confagricoltura-ripartiamo-dal-dialogo-per-porre-fine-alla-guerra-dei-dazi\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/usa-2020-confagricoltura-ripartiamo-dal-dialogo-per-porre-fine-alla-guerra-dei-dazi\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/10\/Schermata-2020-10-05-alle-12.14.06.png\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/10\/Schermata-2020-10-05-alle-12.14.06.png\",\"width\":1668,\"height\":764},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/usa-2020-confagricoltura-ripartiamo-dal-dialogo-per-porre-fine-alla-guerra-dei-dazi\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"USA 2020, Confagricoltura: ripartiamo dal dialogo per porre fine alla guerra dei dazi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"USA 2020, Confagricoltura: ripartiamo dal dialogo per porre fine alla guerra dei dazi -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/usa-2020-confagricoltura-ripartiamo-dal-dialogo-per-porre-fine-alla-guerra-dei-dazi\/","og_locale":"it_IT","og_type":"article","og_title":"USA 2020, Confagricoltura: ripartiamo dal dialogo per porre fine alla guerra dei dazi -","og_description":"All\u2019indomani dell\u2019esito elettorale negli Stati Uniti, le relazioni commerciali tra UE e USA sono all\u2019ordine del giorno dell\u2019odierna videoconferenza del Consiglio dei ministri degli Affari Esteri (Commercio) dell\u2019Unione. \u201cPrima di tutto \u2013 dichiara il presidente di Confagricoltura, Massimiliano Giansanti \u2013 dovrebbe essere chiuso il contenzioso ultradecennale sugli aiuti pubblici ai gruppi Airbus e Boeing. Sarebbero [&hellip;]","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/usa-2020-confagricoltura-ripartiamo-dal-dialogo-per-porre-fine-alla-guerra-dei-dazi\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2020-11-09T11:10:51+00:00","og_image":[{"width":1668,"height":764,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/10\/Schermata-2020-10-05-alle-12.14.06.png","type":"image\/png"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/usa-2020-confagricoltura-ripartiamo-dal-dialogo-per-porre-fine-alla-guerra-dei-dazi\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/usa-2020-confagricoltura-ripartiamo-dal-dialogo-per-porre-fine-alla-guerra-dei-dazi\/","name":"USA 2020, Confagricoltura: ripartiamo dal dialogo per porre fine alla guerra dei dazi -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/usa-2020-confagricoltura-ripartiamo-dal-dialogo-per-porre-fine-alla-guerra-dei-dazi\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/usa-2020-confagricoltura-ripartiamo-dal-dialogo-per-porre-fine-alla-guerra-dei-dazi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/10\/Schermata-2020-10-05-alle-12.14.06.png","datePublished":"2020-11-09T11:10:51+00:00","dateModified":"2020-11-09T11:10:51+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/usa-2020-confagricoltura-ripartiamo-dal-dialogo-per-porre-fine-alla-guerra-dei-dazi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/usa-2020-confagricoltura-ripartiamo-dal-dialogo-per-porre-fine-alla-guerra-dei-dazi\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/usa-2020-confagricoltura-ripartiamo-dal-dialogo-per-porre-fine-alla-guerra-dei-dazi\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/10\/Schermata-2020-10-05-alle-12.14.06.png","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/10\/Schermata-2020-10-05-alle-12.14.06.png","width":1668,"height":764},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/usa-2020-confagricoltura-ripartiamo-dal-dialogo-per-porre-fine-alla-guerra-dei-dazi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"USA 2020, Confagricoltura: ripartiamo dal dialogo per porre fine alla guerra dei dazi"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/4577"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=4577"}],"version-history":[{"count":1,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/4577\/revisions"}],"predecessor-version":[{"id":4578,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/4577\/revisions\/4578"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/4311"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=4577"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=4577"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=4577"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}