{"id":4671,"date":"2020-11-19T13:01:41","date_gmt":"2020-11-19T12:01:41","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=4671"},"modified":"2020-11-19T13:01:41","modified_gmt":"2020-11-19T12:01:41","slug":"brexit-giansanti-confagricoltura-un-accordo-e-ancora-possibile","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/brexit-giansanti-confagricoltura-un-accordo-e-ancora-possibile\/","title":{"rendered":"Brexit, Giansanti (Confagricoltura): un accordo \u00e8 ancora possibile&#8221;"},"content":{"rendered":"<p><span class=\"dropcap dropcap3\">I<\/span> negoziati proseguono e un\u2019intesa \u00e8 ancora possibile, ma dobbiamo essere preparati a tutti gli scenari, compreso il fallimento del negoziato sulle future relazioni commerciali tra Unione europea e Regno Unito. E\u2019 perci\u00f2 necessaria e urgente la messa a punto di un piano di emergenza, per limitare i contraccolpi del mancato accordo. Mancano poche settimane al 31 dicembre 2020, data di scadenza del periodo transitorio.<\/p>\n<p>&nbsp;<\/p>\n<p>La richiesta \u00e8 stata avanzata dal presidente di Confagricoltura, Massimiliano Giansanti: \u201cIl piano dovrebbe prevedere un rafforzamento del personale della nostra amministrazione doganale, che ha gi\u00e0 svolto una rilevante attivit\u00e0 di preparazione e informazione nei confronti degli operatori, per supportare le imprese che saranno chiamate, dal 1\u00b0 gennaio prossimo, a presentare una dichiarazione per le singole partite di esportazione sul mercato britannico\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>Confagricoltura ricorda che l\u2019export agroalimentare della UE sul mercato britannico supera i 40 miliardi di euro l\u2019anno.<\/p>\n<p>&nbsp;<\/p>\n<p>\u201cSenza un accordo \u2013 rileva il presidente della Confagricoltura \u2013 il prevedibile blocco o rallentamento dei flussi commerciali provocherebbe una situazione di instabilit\u00e0 sui mercati agricoli europei, in aggiunta a quella innescata dalla pandemia. La Commissione Ue dovrebbe attivare le misure di gestione previste dalla normativa europea, anche con il ricorso alla dotazione del fondo per le conseguenze del recesso del Regno Unito, previsto nel quadro dell\u2019accordo di luglio del Consiglio europeo sul bilancio dell\u2019Unione per il periodo 2021-2027 e sul Next Generation UE\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>Confagricoltura sottolinea che il governo di Londra ha avviato una serie di negoziati per la conclusione di accordi commerciali con i Paesi terzi. La concorrenza ai nostri prodotti \u00e8 destinata ad aumentare.<\/p>\n<p>&nbsp;<\/p>\n<p>\u201cAndrebbero, quindi, ulteriormente rafforzate le iniziative promozionali per aprire nuovi mercati di sbocco per le nostre produzioni pi\u00f9 presenti sul mercato britannico\u201d conclude Giansanti. Si tratta, in dettaglio, di vini, ortofrutta fresca e trasformata, riso e prodotti del settore lattiero-caseario.<\/p>\n<p>&nbsp;<\/p>\n<p>Nel complesso, le esportazioni del &#8216;Made in Italy&#8217; agroalimentare verso il Regno Unito ammontano a 3,4 miliardi di euro. I prodotti a indicazione geografica protetta incidono per oltre il 30% sul totale.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>I negoziati proseguono e un\u2019intesa \u00e8 ancora possibile, ma dobbiamo essere preparati a tutti gli scenari, compreso il fallimento del negoziato sulle future relazioni commerciali tra Unione europea e Regno Unito. E\u2019 perci\u00f2 necessaria e urgente la messa a punto di un piano di emergenza, per limitare i contraccolpi del mancato accordo. Mancano poche settimane [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4311,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Brexit, Giansanti (Confagricoltura): un accordo \u00e8 ancora possibile&quot; -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/brexit-giansanti-confagricoltura-un-accordo-e-ancora-possibile\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Brexit, Giansanti (Confagricoltura): un accordo \u00e8 ancora possibile&quot; -\" \/>\n<meta property=\"og:description\" content=\"I negoziati proseguono e un\u2019intesa \u00e8 ancora possibile, ma dobbiamo essere preparati a tutti gli scenari, compreso il fallimento del negoziato sulle future relazioni commerciali tra Unione europea e Regno Unito. E\u2019 perci\u00f2 necessaria e urgente la messa a punto di un piano di emergenza, per limitare i contraccolpi del mancato accordo. Mancano poche settimane [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/brexit-giansanti-confagricoltura-un-accordo-e-ancora-possibile\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-19T12:01:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/10\/Schermata-2020-10-05-alle-12.14.06.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1668\" \/>\n\t<meta property=\"og:image:height\" content=\"764\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/brexit-giansanti-confagricoltura-un-accordo-e-ancora-possibile\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/brexit-giansanti-confagricoltura-un-accordo-e-ancora-possibile\/\",\"name\":\"Brexit, Giansanti (Confagricoltura): un accordo \u00e8 ancora possibile\\\" -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/brexit-giansanti-confagricoltura-un-accordo-e-ancora-possibile\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/brexit-giansanti-confagricoltura-un-accordo-e-ancora-possibile\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/10\/Schermata-2020-10-05-alle-12.14.06.png\",\"datePublished\":\"2020-11-19T12:01:41+00:00\",\"dateModified\":\"2020-11-19T12:01:41+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/brexit-giansanti-confagricoltura-un-accordo-e-ancora-possibile\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/brexit-giansanti-confagricoltura-un-accordo-e-ancora-possibile\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/brexit-giansanti-confagricoltura-un-accordo-e-ancora-possibile\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/10\/Schermata-2020-10-05-alle-12.14.06.png\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/10\/Schermata-2020-10-05-alle-12.14.06.png\",\"width\":1668,\"height\":764},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/brexit-giansanti-confagricoltura-un-accordo-e-ancora-possibile\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Brexit, Giansanti (Confagricoltura): un accordo \u00e8 ancora possibile&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Brexit, Giansanti (Confagricoltura): un accordo \u00e8 ancora possibile\" -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/brexit-giansanti-confagricoltura-un-accordo-e-ancora-possibile\/","og_locale":"it_IT","og_type":"article","og_title":"Brexit, Giansanti (Confagricoltura): un accordo \u00e8 ancora possibile\" -","og_description":"I negoziati proseguono e un\u2019intesa \u00e8 ancora possibile, ma dobbiamo essere preparati a tutti gli scenari, compreso il fallimento del negoziato sulle future relazioni commerciali tra Unione europea e Regno Unito. E\u2019 perci\u00f2 necessaria e urgente la messa a punto di un piano di emergenza, per limitare i contraccolpi del mancato accordo. Mancano poche settimane [&hellip;]","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/brexit-giansanti-confagricoltura-un-accordo-e-ancora-possibile\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2020-11-19T12:01:41+00:00","og_image":[{"width":1668,"height":764,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/10\/Schermata-2020-10-05-alle-12.14.06.png","type":"image\/png"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/brexit-giansanti-confagricoltura-un-accordo-e-ancora-possibile\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/brexit-giansanti-confagricoltura-un-accordo-e-ancora-possibile\/","name":"Brexit, Giansanti (Confagricoltura): un accordo \u00e8 ancora possibile\" -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/brexit-giansanti-confagricoltura-un-accordo-e-ancora-possibile\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/brexit-giansanti-confagricoltura-un-accordo-e-ancora-possibile\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/10\/Schermata-2020-10-05-alle-12.14.06.png","datePublished":"2020-11-19T12:01:41+00:00","dateModified":"2020-11-19T12:01:41+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/brexit-giansanti-confagricoltura-un-accordo-e-ancora-possibile\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/brexit-giansanti-confagricoltura-un-accordo-e-ancora-possibile\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/brexit-giansanti-confagricoltura-un-accordo-e-ancora-possibile\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/10\/Schermata-2020-10-05-alle-12.14.06.png","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/10\/Schermata-2020-10-05-alle-12.14.06.png","width":1668,"height":764},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/brexit-giansanti-confagricoltura-un-accordo-e-ancora-possibile\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"Brexit, Giansanti (Confagricoltura): un accordo \u00e8 ancora possibile&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/4671"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=4671"}],"version-history":[{"count":1,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/4671\/revisions"}],"predecessor-version":[{"id":4672,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/4671\/revisions\/4672"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/4311"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=4671"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=4671"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=4671"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}