{"id":4673,"date":"2020-11-19T15:02:47","date_gmt":"2020-11-19T14:02:47","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=4673"},"modified":"2020-11-19T15:02:47","modified_gmt":"2020-11-19T14:02:47","slug":"ristorazione-fiepet-confesercenti-per-bonus-filiera-serve-piu-tempo","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/ristorazione-fiepet-confesercenti-per-bonus-filiera-serve-piu-tempo\/","title":{"rendered":"Ristorazione, Fiepet Confesercenti: &#8220;per bonus filiera serve pi\u00f9 tempo&#8221;"},"content":{"rendered":"<p><span class=\"dropcap dropcap3\">A<\/span>lle imprese serve pi\u00f9 tempo per accedere al bonus filiera: il termine di scadenza per la presentazione delle domande, attualmente fissato al prossimo 28, \u00e8 troppo vicino. Molte attivit\u00e0 non riusciranno ad accedere\u201d.<\/p>\n<p>Cos\u00ec <strong>Giancarlo Banchieri<\/strong>, Presidente di Fiepet Confesercenti, sul bonus filiera \u2018Made in Italy\u2019, il contributo a fondo perduto da spendere per prodotti di filiere agricole ed alimentari del territorio riservata ai ristoratori che abbiano registrato da marzo a giugno 2020 un fatturato medio inferiore di almeno il 25% rispetto a quello dello stesso periodo del 2019.<br \/>\n\u201cL\u2019impostazione dell\u2019istruttoria per accedere alla misura \u00e8 macchinosa, e sta mettendo in difficolt\u00e0 non solo le imprese ma anche i commercialisti. Ad essere particolarmente laborioso \u00e8 soprattutto il processo di analisi delle forniture, che prevede il monitoraggio di tutte le fatture e i documenti di trasporto per individuare le spese che corrispondono ai requisiti tecnici previsti. Un lungo lavoro, difficile da ultimare in pochi giorni: per questo chiediamo che il termine ultimo per la presentazione delle domande venga spostato di almeno 15 giorni\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Alle imprese serve pi\u00f9 tempo per accedere al bonus filiera: il termine di scadenza per la presentazione delle domande, attualmente fissato al prossimo 28, \u00e8 troppo vicino. Molte attivit\u00e0 non riusciranno ad accedere\u201d. Cos\u00ec Giancarlo Banchieri, Presidente di Fiepet Confesercenti, sul bonus filiera \u2018Made in Italy\u2019, il contributo a fondo perduto da spendere per prodotti [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2054,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[56],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ristorazione, Fiepet Confesercenti: &quot;per bonus filiera serve pi\u00f9 tempo&quot; -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/ristorazione-fiepet-confesercenti-per-bonus-filiera-serve-piu-tempo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ristorazione, Fiepet Confesercenti: &quot;per bonus filiera serve pi\u00f9 tempo&quot; -\" \/>\n<meta property=\"og:description\" content=\"Alle imprese serve pi\u00f9 tempo per accedere al bonus filiera: il termine di scadenza per la presentazione delle domande, attualmente fissato al prossimo 28, \u00e8 troppo vicino. Molte attivit\u00e0 non riusciranno ad accedere\u201d. Cos\u00ec Giancarlo Banchieri, Presidente di Fiepet Confesercenti, sul bonus filiera \u2018Made in Italy\u2019, il contributo a fondo perduto da spendere per prodotti [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/ristorazione-fiepet-confesercenti-per-bonus-filiera-serve-piu-tempo\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-19T14:02:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/11\/piatto-ristorante-cibo-alimenti.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/ristorazione-fiepet-confesercenti-per-bonus-filiera-serve-piu-tempo\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/ristorazione-fiepet-confesercenti-per-bonus-filiera-serve-piu-tempo\/\",\"name\":\"Ristorazione, Fiepet Confesercenti: \\\"per bonus filiera serve pi\u00f9 tempo\\\" -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/ristorazione-fiepet-confesercenti-per-bonus-filiera-serve-piu-tempo\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/ristorazione-fiepet-confesercenti-per-bonus-filiera-serve-piu-tempo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/11\/piatto-ristorante-cibo-alimenti.jpg\",\"datePublished\":\"2020-11-19T14:02:47+00:00\",\"dateModified\":\"2020-11-19T14:02:47+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/ristorazione-fiepet-confesercenti-per-bonus-filiera-serve-piu-tempo\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/ristorazione-fiepet-confesercenti-per-bonus-filiera-serve-piu-tempo\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/ristorazione-fiepet-confesercenti-per-bonus-filiera-serve-piu-tempo\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/11\/piatto-ristorante-cibo-alimenti.jpg\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/11\/piatto-ristorante-cibo-alimenti.jpg\",\"width\":960,\"height\":640},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/ristorazione-fiepet-confesercenti-per-bonus-filiera-serve-piu-tempo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ristorazione, Fiepet Confesercenti: &#8220;per bonus filiera serve pi\u00f9 tempo&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ristorazione, Fiepet Confesercenti: \"per bonus filiera serve pi\u00f9 tempo\" -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/ristorazione-fiepet-confesercenti-per-bonus-filiera-serve-piu-tempo\/","og_locale":"it_IT","og_type":"article","og_title":"Ristorazione, Fiepet Confesercenti: \"per bonus filiera serve pi\u00f9 tempo\" -","og_description":"Alle imprese serve pi\u00f9 tempo per accedere al bonus filiera: il termine di scadenza per la presentazione delle domande, attualmente fissato al prossimo 28, \u00e8 troppo vicino. Molte attivit\u00e0 non riusciranno ad accedere\u201d. Cos\u00ec Giancarlo Banchieri, Presidente di Fiepet Confesercenti, sul bonus filiera \u2018Made in Italy\u2019, il contributo a fondo perduto da spendere per prodotti [&hellip;]","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/ristorazione-fiepet-confesercenti-per-bonus-filiera-serve-piu-tempo\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2020-11-19T14:02:47+00:00","og_image":[{"width":960,"height":640,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/11\/piatto-ristorante-cibo-alimenti.jpg","type":"image\/jpeg"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/ristorazione-fiepet-confesercenti-per-bonus-filiera-serve-piu-tempo\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/ristorazione-fiepet-confesercenti-per-bonus-filiera-serve-piu-tempo\/","name":"Ristorazione, Fiepet Confesercenti: \"per bonus filiera serve pi\u00f9 tempo\" -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/ristorazione-fiepet-confesercenti-per-bonus-filiera-serve-piu-tempo\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/ristorazione-fiepet-confesercenti-per-bonus-filiera-serve-piu-tempo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/11\/piatto-ristorante-cibo-alimenti.jpg","datePublished":"2020-11-19T14:02:47+00:00","dateModified":"2020-11-19T14:02:47+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/ristorazione-fiepet-confesercenti-per-bonus-filiera-serve-piu-tempo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/ristorazione-fiepet-confesercenti-per-bonus-filiera-serve-piu-tempo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/ristorazione-fiepet-confesercenti-per-bonus-filiera-serve-piu-tempo\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/11\/piatto-ristorante-cibo-alimenti.jpg","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/11\/piatto-ristorante-cibo-alimenti.jpg","width":960,"height":640},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/ristorazione-fiepet-confesercenti-per-bonus-filiera-serve-piu-tempo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"Ristorazione, Fiepet Confesercenti: &#8220;per bonus filiera serve pi\u00f9 tempo&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/4673"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=4673"}],"version-history":[{"count":1,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/4673\/revisions"}],"predecessor-version":[{"id":4674,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/4673\/revisions\/4674"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/2054"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=4673"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=4673"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=4673"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}