{"id":4735,"date":"2020-11-24T15:45:12","date_gmt":"2020-11-24T14:45:12","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=4735"},"modified":"2020-11-24T15:45:12","modified_gmt":"2020-11-24T14:45:12","slug":"avviata-la-consultazione-pubblica-della-strategia-nazionale-sullidrogeno","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/avviata-la-consultazione-pubblica-della-strategia-nazionale-sullidrogeno\/","title":{"rendered":"Avviata la consultazione pubblica della Strategia nazionale sull\u2019idrogeno"},"content":{"rendered":"<p><span class=\"dropcap dropcap3\">A<\/span>l via oggi la consultazione pubblica sulle Linee Guida per la Strategia nazionale sull\u2019idrogeno, elaborate dal Ministero dello Sviluppo Economico, che mirano a individuare i settori in cui si ritiene che questo vettore energetico possa diventare competitivo in tempi brevi ma anche verificare le aree d\u2019intervento che meglio si adattano a sviluppare e implementare l\u2019utilizzo dell\u2019idrogeno.<\/p>\n<p>Durante il periodo di consultazione pubblica, dal 24 novembre al 21 dicembre 2020, i soggetti interessati e gli stakeholders potranno inviare osservazioni o presentare ulteriori elementi in merito alle Linee Guida Preliminari della Strategia, scrivendo all\u2019indirizzo email:\u00a0consultazione.idrogeno@mise.gov.it<\/p>\n<p>\u201cL\u2019Italia \u00e8 tra i primi Paesi che hanno creduto nell\u2019idrogeno come vettore energetico pulito del futuro, in grado di accelerare il processo di decarbonizzazione verso un modello di sviluppo ecosostenibile\u201d, dichiara il Ministro dello Sviluppo Economico Stefano Patuanelli.\u00a0 \u201cQuesto ha permesso ai ricercatori e alle aziende italiane di acquisire un vantaggio in termini di capacit\u00e0 e conoscenze sull\u2019idrogeno, che oggi consente al nostro Paese di avere un ruolo centrale nella definizione dei piani europei di investimento previsti per lo sviluppo e l\u2019implementazione della produzione e utilizzo dell\u2019idrogeno. Inoltre, l\u2019Italia si candida a diventare l\u2019hub del Mediterraneo per la produzione, il trasporto e lo stoccaggio di idrogeno verde\u201d, conclude Patuanelli.<\/p>\n<p>\u201cAbbattere l&#8217;inquinamento &#8211; dichiara il Vice Ministro Stefano Buffagni &#8211; \u00e8 una priorit\u00e0 della nostra agenda politica. L\u2019idrogeno, oltre alla sua importanza dal punto di vista economico, \u00e8 un pilastro delle future strategie ambientali ed energetiche globali e rappresenta il futuro green che vogliamo lasciare ai nostri figli. Grazie a queste prime linee guida per la realizzazione della Strategia Nazionale Idrogeno, l\u2019Italia si sta ritagliando un ruolo centrale in questa sfida, insieme con i Paesi europei maggiormente avanzati su questo tema. Il nostro Paese pu\u00f2 sfruttare la sua posizione geografica, il suo solido know-how progettuale e scientifico e la sua rete infrastrutturale\u201d, conclude Buffagni.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>La strategia <\/strong><\/p>\n<p>La Strategia Nazionale sull\u2019idrogeno consentir\u00e0 all\u2019Italia di accelerare il raggiungimento degli obiettivi fissati dal PNIEC, favorendo la transizione energetica verso una economia green, sostenibile e tecnologicamente avanzata, che rappresenta uno dei punti centrali dell\u2019azione portata avanti dal Governo e in particolare dal Ministero dello Sviluppo Economico.<\/p>\n<p>Una prima fase della strategia con obiettivo al 2030, sar\u00e0 focalizzata sui settori in cui \u00e8 possibile produrre e utilizzare l\u2019idrogeno localmente, a partire dagli impianti esistenti, e facilitare l\u2019utilizzo del vettore in nuove applicazioni come, per esempio, nel trasporto ferroviario grazie alla sostituzione dei treni diesel nelle tratte non elettrificabili.<\/p>\n<p>Verso il 2050 si prevede che l&#8217;idrogeno rinnovabile raggiunger\u00e0 una maturit\u00e0 tale da consentirne l\u2019utilizzo pi\u00f9 deciso anche in altri settori dell\u2019industria e dei trasporti.<\/p>\n<p>La realizzazione della strategia porter\u00e0 benefici in termini di filiera in nuovi settori industriali e tecnologici (in particolare elettrolizzatori, celle a combustibile e componentistica) determinando importanti effetti positivi sulla crescita dell\u2019economia, con impatti positivi anche dal punto di vista occupazionale nelle diverse fasi di progettazione, costruzione e operativit\u00e0 degli impianti.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Al via oggi la consultazione pubblica sulle Linee Guida per la Strategia nazionale sull\u2019idrogeno, elaborate dal Ministero dello Sviluppo Economico, che mirano a individuare i settori in cui si ritiene che questo vettore energetico possa diventare competitivo in tempi brevi ma anche verificare le aree d\u2019intervento che meglio si adattano a sviluppare e implementare l\u2019utilizzo [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3600,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[127],"tags":[233,1414,31],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Avviata la consultazione pubblica della Strategia nazionale sull\u2019idrogeno -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/avviata-la-consultazione-pubblica-della-strategia-nazionale-sullidrogeno\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Avviata la consultazione pubblica della Strategia nazionale sull\u2019idrogeno -\" \/>\n<meta property=\"og:description\" content=\"Al via oggi la consultazione pubblica sulle Linee Guida per la Strategia nazionale sull\u2019idrogeno, elaborate dal Ministero dello Sviluppo Economico, che mirano a individuare i settori in cui si ritiene che questo vettore energetico possa diventare competitivo in tempi brevi ma anche verificare le aree d\u2019intervento che meglio si adattano a sviluppare e implementare l\u2019utilizzo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/avviata-la-consultazione-pubblica-della-strategia-nazionale-sullidrogeno\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-24T14:45:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/07\/Schermata-2020-07-07-alle-11.16.46.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1444\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/avviata-la-consultazione-pubblica-della-strategia-nazionale-sullidrogeno\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/avviata-la-consultazione-pubblica-della-strategia-nazionale-sullidrogeno\/\",\"name\":\"Avviata la consultazione pubblica della Strategia nazionale sull\u2019idrogeno -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/avviata-la-consultazione-pubblica-della-strategia-nazionale-sullidrogeno\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/avviata-la-consultazione-pubblica-della-strategia-nazionale-sullidrogeno\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/07\/Schermata-2020-07-07-alle-11.16.46.png\",\"datePublished\":\"2020-11-24T14:45:12+00:00\",\"dateModified\":\"2020-11-24T14:45:12+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/avviata-la-consultazione-pubblica-della-strategia-nazionale-sullidrogeno\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/avviata-la-consultazione-pubblica-della-strategia-nazionale-sullidrogeno\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/avviata-la-consultazione-pubblica-della-strategia-nazionale-sullidrogeno\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/07\/Schermata-2020-07-07-alle-11.16.46.png\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/07\/Schermata-2020-07-07-alle-11.16.46.png\",\"width\":1444,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/avviata-la-consultazione-pubblica-della-strategia-nazionale-sullidrogeno\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Avviata la consultazione pubblica della Strategia nazionale sull\u2019idrogeno\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Avviata la consultazione pubblica della Strategia nazionale sull\u2019idrogeno -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/avviata-la-consultazione-pubblica-della-strategia-nazionale-sullidrogeno\/","og_locale":"it_IT","og_type":"article","og_title":"Avviata la consultazione pubblica della Strategia nazionale sull\u2019idrogeno -","og_description":"Al via oggi la consultazione pubblica sulle Linee Guida per la Strategia nazionale sull\u2019idrogeno, elaborate dal Ministero dello Sviluppo Economico, che mirano a individuare i settori in cui si ritiene che questo vettore energetico possa diventare competitivo in tempi brevi ma anche verificare le aree d\u2019intervento che meglio si adattano a sviluppare e implementare l\u2019utilizzo [&hellip;]","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/avviata-la-consultazione-pubblica-della-strategia-nazionale-sullidrogeno\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2020-11-24T14:45:12+00:00","og_image":[{"width":1444,"height":900,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/07\/Schermata-2020-07-07-alle-11.16.46.png","type":"image\/png"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/avviata-la-consultazione-pubblica-della-strategia-nazionale-sullidrogeno\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/avviata-la-consultazione-pubblica-della-strategia-nazionale-sullidrogeno\/","name":"Avviata la consultazione pubblica della Strategia nazionale sull\u2019idrogeno -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/avviata-la-consultazione-pubblica-della-strategia-nazionale-sullidrogeno\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/avviata-la-consultazione-pubblica-della-strategia-nazionale-sullidrogeno\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/07\/Schermata-2020-07-07-alle-11.16.46.png","datePublished":"2020-11-24T14:45:12+00:00","dateModified":"2020-11-24T14:45:12+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/avviata-la-consultazione-pubblica-della-strategia-nazionale-sullidrogeno\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/avviata-la-consultazione-pubblica-della-strategia-nazionale-sullidrogeno\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/avviata-la-consultazione-pubblica-della-strategia-nazionale-sullidrogeno\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/07\/Schermata-2020-07-07-alle-11.16.46.png","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/07\/Schermata-2020-07-07-alle-11.16.46.png","width":1444,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/avviata-la-consultazione-pubblica-della-strategia-nazionale-sullidrogeno\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"Avviata la consultazione pubblica della Strategia nazionale sull\u2019idrogeno"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/4735"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=4735"}],"version-history":[{"count":1,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/4735\/revisions"}],"predecessor-version":[{"id":4736,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/4735\/revisions\/4736"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/3600"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=4735"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=4735"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=4735"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}