{"id":4745,"date":"2020-11-25T17:05:37","date_gmt":"2020-11-25T16:05:37","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=4745"},"modified":"2020-11-25T17:05:37","modified_gmt":"2020-11-25T16:05:37","slug":"agrinsieme-canapa-dopo-sentenza-cgue-accelerare-convocazione-tavolo-filiera","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/agrinsieme-canapa-dopo-sentenza-cgue-accelerare-convocazione-tavolo-filiera\/","title":{"rendered":"Agrinsieme: canapa dopo sentenza CGUE, accelerare convocazione tavolo filiera"},"content":{"rendered":"<p><span class=\"dropcap dropcap3\">L<\/span>a valorizzazione delle infiorescenze di <strong>canapa<\/strong> <strong>industriale<\/strong> \u00e8 strategica per le imprese agricole in termini di diversificazione del reddito e di bioeconomia: nei fiori di canapa, infatti, sono presenti elementi non stupefacenti, quali cannabinoidi e terpeni, di notevole rilevanza per i nuovi mercati della bioeconomia, quali le produzioni alimentari, la nutraceutica e la biocosmetica, senza contare le implicazioni legate alle altre filiere della canapa, come la bioedilizia, le bioplastiche e il biotessile\u201d.<\/p>\n<p>Lo sottolinea il coordinamento di <strong>Agrinsieme<\/strong>, che riunisce <strong>Cia-Agricoltori italiani<\/strong>, <strong>Confagricoltura<\/strong>, <strong>Copagri<\/strong> e <strong>Alleanza delle Cooperative Agroalimentari<\/strong>, esprimendo soddisfazione per la sentenza della Corte di Giustizia dell\u2019UE, la quale ha stabilito che uno Stato Membro non pu\u00f2 vietare la commercializzazione del cannabidiolo (CBD), molecola appartenente alla famiglia dei cannabinoidi, nel mercato comunitario.<\/p>\n<p>\u201cLa CGUE, inoltre, sulla base delle attuali conoscenze scientifiche, stabilisce che il cannabidiolo \u2018non pu\u00f2 essere considerato come uno stupefacente\u2019, andando finalmente a fare chiarezza sui suoi presunti effetti psicotropi o nocivi per la salute umana\u201d, aggiunge il Coordinamento.<\/p>\n<p>\u201cAlla luce di tale sentenza diventa ancora pi\u00f9 urgente convocare il Tavolo di filiera interministeriale, del quale abbiamo ripetutamente sollecitato l\u2019istituzione, coinvolgendo i ministeri della Salute, dell\u2019Agricoltura, dell\u2019Interno, della Giustizia e dello Sviluppo Economico e tutti gli attori del comparto, cos\u00ec da andare a implementare il quadro normativo della canapicoltura, settore che negli ultimi anni ha fatto registrare un aumento importante delle superfici coltivate e i cui margini di crescita sono molto pi\u00f9 ampi\u201d, prosegue Agrinsieme.<\/p>\n<p>\u201cIn tale contesto, nell\u2019alveo di un percorso di revisione della Legge 242\/2016, occorrer\u00e0 esplicitare la valorizzazione di tutte le parti della pianta, e dunque anche delle infiorescenze, inserendo un esplicito riferimento alle coltivazioni in ambienti protetti oltre che in pieno campo, legittimando i produttori agricoli alla prima trasformazione dei prodotti di canapa e dando nuovo impulso alla ricerca; in un\u2019ottica di pi\u00f9 ampio respiro, servir\u00e0 poi dare maggiori certezze agli operatori della filiera in termini di controlli e di qualit\u00e0, prevedendo appositi sistemi di tracciabilit\u00e0\u201d, suggerisce il Coordinamento.<\/p>\n<p>\u201cAllo stesso tempo, bisogner\u00e0 lavorare per inserire le infiorescenze di canapa, cos\u00ec come i semi, nell\u2019elenco delle parti di piante officinali previste dal Testo unico in materia di coltivazione, raccolta e prima trasformazione delle piante officinali\u201d, aggiunge Agrinsieme.<\/p>\n<p>\u201cRibadiamo che senza tale Tavolo di confronto sar\u00e0 molto complicato definire un piano di settore che favorisca lo sviluppo del comparto e andare a dipanare tutte le incertezze normative legate alle singole destinazioni d\u2019uso della canapa industriale, che stanno frenando la crescita di una coltura che pu\u00f2 rappresentare un\u2019importante opportunit\u00e0 di integrazione del reddito delle imprese e delle cooperative agricole\u201d, conclude il Coordinamento.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La valorizzazione delle infiorescenze di canapa industriale \u00e8 strategica per le imprese agricole in termini di diversificazione del reddito e di bioeconomia: nei fiori di canapa, infatti, sono presenti elementi non stupefacenti, quali cannabinoidi e terpeni, di notevole rilevanza per i nuovi mercati della bioeconomia, quali le produzioni alimentari, la nutraceutica e la biocosmetica, senza [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":268,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Agrinsieme: canapa dopo sentenza CGUE, accelerare convocazione tavolo filiera -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/agrinsieme-canapa-dopo-sentenza-cgue-accelerare-convocazione-tavolo-filiera\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Agrinsieme: canapa dopo sentenza CGUE, accelerare convocazione tavolo filiera -\" \/>\n<meta property=\"og:description\" content=\"La valorizzazione delle infiorescenze di canapa industriale \u00e8 strategica per le imprese agricole in termini di diversificazione del reddito e di bioeconomia: nei fiori di canapa, infatti, sono presenti elementi non stupefacenti, quali cannabinoidi e terpeni, di notevole rilevanza per i nuovi mercati della bioeconomia, quali le produzioni alimentari, la nutraceutica e la biocosmetica, senza [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/agrinsieme-canapa-dopo-sentenza-cgue-accelerare-convocazione-tavolo-filiera\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-25T16:05:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/09\/agricoltura-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"571\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/agrinsieme-canapa-dopo-sentenza-cgue-accelerare-convocazione-tavolo-filiera\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/agrinsieme-canapa-dopo-sentenza-cgue-accelerare-convocazione-tavolo-filiera\/\",\"name\":\"Agrinsieme: canapa dopo sentenza CGUE, accelerare convocazione tavolo filiera -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/agrinsieme-canapa-dopo-sentenza-cgue-accelerare-convocazione-tavolo-filiera\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/agrinsieme-canapa-dopo-sentenza-cgue-accelerare-convocazione-tavolo-filiera\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/09\/agricoltura-1.jpg\",\"datePublished\":\"2020-11-25T16:05:37+00:00\",\"dateModified\":\"2020-11-25T16:05:37+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/agrinsieme-canapa-dopo-sentenza-cgue-accelerare-convocazione-tavolo-filiera\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/agrinsieme-canapa-dopo-sentenza-cgue-accelerare-convocazione-tavolo-filiera\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/agrinsieme-canapa-dopo-sentenza-cgue-accelerare-convocazione-tavolo-filiera\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/09\/agricoltura-1.jpg\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/09\/agricoltura-1.jpg\",\"width\":960,\"height\":571},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/agrinsieme-canapa-dopo-sentenza-cgue-accelerare-convocazione-tavolo-filiera\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Agrinsieme: canapa dopo sentenza CGUE, accelerare convocazione tavolo filiera\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Agrinsieme: canapa dopo sentenza CGUE, accelerare convocazione tavolo filiera -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/agrinsieme-canapa-dopo-sentenza-cgue-accelerare-convocazione-tavolo-filiera\/","og_locale":"it_IT","og_type":"article","og_title":"Agrinsieme: canapa dopo sentenza CGUE, accelerare convocazione tavolo filiera -","og_description":"La valorizzazione delle infiorescenze di canapa industriale \u00e8 strategica per le imprese agricole in termini di diversificazione del reddito e di bioeconomia: nei fiori di canapa, infatti, sono presenti elementi non stupefacenti, quali cannabinoidi e terpeni, di notevole rilevanza per i nuovi mercati della bioeconomia, quali le produzioni alimentari, la nutraceutica e la biocosmetica, senza [&hellip;]","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/agrinsieme-canapa-dopo-sentenza-cgue-accelerare-convocazione-tavolo-filiera\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2020-11-25T16:05:37+00:00","og_image":[{"width":960,"height":571,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/09\/agricoltura-1.jpg","type":"image\/jpeg"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/agrinsieme-canapa-dopo-sentenza-cgue-accelerare-convocazione-tavolo-filiera\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/agrinsieme-canapa-dopo-sentenza-cgue-accelerare-convocazione-tavolo-filiera\/","name":"Agrinsieme: canapa dopo sentenza CGUE, accelerare convocazione tavolo filiera -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/agrinsieme-canapa-dopo-sentenza-cgue-accelerare-convocazione-tavolo-filiera\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/agrinsieme-canapa-dopo-sentenza-cgue-accelerare-convocazione-tavolo-filiera\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/09\/agricoltura-1.jpg","datePublished":"2020-11-25T16:05:37+00:00","dateModified":"2020-11-25T16:05:37+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/agrinsieme-canapa-dopo-sentenza-cgue-accelerare-convocazione-tavolo-filiera\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/agrinsieme-canapa-dopo-sentenza-cgue-accelerare-convocazione-tavolo-filiera\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/agrinsieme-canapa-dopo-sentenza-cgue-accelerare-convocazione-tavolo-filiera\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/09\/agricoltura-1.jpg","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/09\/agricoltura-1.jpg","width":960,"height":571},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/agrinsieme-canapa-dopo-sentenza-cgue-accelerare-convocazione-tavolo-filiera\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"Agrinsieme: canapa dopo sentenza CGUE, accelerare convocazione tavolo filiera"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/4745"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=4745"}],"version-history":[{"count":1,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/4745\/revisions"}],"predecessor-version":[{"id":4746,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/4745\/revisions\/4746"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/268"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=4745"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=4745"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=4745"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}