{"id":4747,"date":"2020-11-25T17:07:03","date_gmt":"2020-11-25T16:07:03","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=4747"},"modified":"2020-11-25T17:07:03","modified_gmt":"2020-11-25T16:07:03","slug":"coldiretti-attacco-ue-a-cibo-made-in-italy-costa-446mld","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/coldiretti-attacco-ue-a-cibo-made-in-italy-costa-446mld\/","title":{"rendered":"Coldiretti: attacco UE a cibo Made in Italy costa 44,6MLD"},"content":{"rendered":"<p><span class=\"dropcap dropcap3\">E\u2019<\/span> necessario intervenire con urgenza per fermare l\u2019attacco al prodotti alimentari nazionali con il rischio del via libera all\u2019etichetta nutrizionale a colori dell\u2019Unione Europea che boccia ingiustamente quasi l\u201985% in valore del Made in Italy a denominazione di origine (Dop\/Igp) che la stessa UE dovrebbe invece tutelare e valorizzare soprattutto nel tempo del Covid.<\/p>\n<p>E\u2019 quanto afferma il presidente della Coldiretti Ettore Prandini che chiede al Governo di intervenire per fermare la pericolosa deriva in atto nell\u2019Unione su etichettatura nutrizionale, profili nutrizionali e etichettatura d\u2019origine in vista del Consiglio Agricoltura Ue il 15\/16 dicembre.<\/p>\n<p>&nbsp;<\/p>\n<p>Un sistema che \u2013 sottolinea la Coldiretti &#8211; rischia di espandersi a livello globale dove in gioco ci sono 44,6 miliardi di esportazioni agroalimentari tricolori nel mondo tra i quali si conta una rilevante presenza di prodotti, dai formaggi all\u2019olio fino ai salumi ingiustamente penalizzati dal nuovo sistema. La manovra degli altri Paesi punta a fermare la crescita del Made in Italy agroalimentare che nel tempo del Covid, insieme alle medicine, \u00e8 l\u2019unico settore a crescere all\u2019estero (+2,9%) nei primi nove mesi del 2020 e pu\u00f2 essere l\u2019elemento di traino per l\u2019intero tessuto economico del Paese.<\/p>\n<p>&nbsp;<\/p>\n<p>Nell\u2019ambito della definizione della proposta di conclusioni finali da approvare al Consiglio di met\u00e0 dicembre, \u00e8 fondamentale evitare che venga portato avanti un documento poco ambizioso sull\u2019obbligo di indicazione di origine obbligatoria che cita come priorit\u00e0 solamente il latte e le carni mentre l\u2019obiettivo della trasparenza sulla provenienza degli alimenti riguarda tutti i prodotti. Ma preoccupa anche l\u2019apertura sull\u2019 etichetta nutrizionale all\u2019utilizzo dei colori o l\u2019eccessiva semplificazione proposta che metterebbe fuori gioco la proposta italiana dell\u2019etichetta a batteria.<\/p>\n<p>&nbsp;<\/p>\n<p>L\u2019etichettatura nutriscore francese come quello a semaforo adottato in Gran Bretagna influenzano il consumatore, con un bel verde, a scegliere prodotti con ingredienti di sintesi e a basso costo spacciandoli per pi\u00f9 salutari. Un sistema fuorviante, discriminatorio ed incompleto e \u2013 sostiene la Coldiretti \u2013 finisce per escludere paradossalmente dalla dieta alimenti sani e naturali che da secoli sono presenti sulle tavole per favorire prodotti artificiali di cui in alcuni casi non \u00e8 nota neanche la ricetta. Si rischia \u2013 precisa la Coldiretti \u2013 di promuovere cibi spazzatura con edulcoranti al posto dello zucchero e di sfavorire elisir di lunga vita come l\u2019olio extravergine di oliva considerato il simbolo della dieta mediterranea, ma anche specialit\u00e0 come il Grana Padano, il Parmigiano Reggiano ed il prosciutto di Parma le cui semplici ricette non possono essere certo modificate.<\/p>\n<p>&nbsp;<\/p>\n<p>In un momento difficile per l\u2019economia &#8211; continua Prandini &#8211; dobbiamo portare sul mercato il valore aggiunto della trasparenza contrastando le indicazioni fuorvianti ed estendendo l\u2019obbligo di indicare in etichetta il Paese d\u2019origine di tutti gli alimenti per combattere la concorrenza sleale al Made in Italy. L\u2019Italia grazie ai primati nella qualit\u00e0 e nella sicurezza alimentare conquistati a livello europeo \u2013 conclude Prandini &#8211; ha la responsabilit\u00e0 di svolgere un ruolo di leadership in Europa.<\/p>\n<p><em>\u00a0<\/em><\/p>\n<p><em>\u00a0<\/em><\/p>\n<p><em>\u00a0<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>E\u2019 necessario intervenire con urgenza per fermare l\u2019attacco al prodotti alimentari nazionali con il rischio del via libera all\u2019etichetta nutrizionale a colori dell\u2019Unione Europea che boccia ingiustamente quasi l\u201985% in valore del Made in Italy a denominazione di origine (Dop\/Igp) che la stessa UE dovrebbe invece tutelare e valorizzare soprattutto nel tempo del Covid. E\u2019 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2330,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Coldiretti: attacco UE a cibo Made in Italy costa 44,6MLD -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/coldiretti-attacco-ue-a-cibo-made-in-italy-costa-446mld\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Coldiretti: attacco UE a cibo Made in Italy costa 44,6MLD -\" \/>\n<meta property=\"og:description\" content=\"E\u2019 necessario intervenire con urgenza per fermare l\u2019attacco al prodotti alimentari nazionali con il rischio del via libera all\u2019etichetta nutrizionale a colori dell\u2019Unione Europea che boccia ingiustamente quasi l\u201985% in valore del Made in Italy a denominazione di origine (Dop\/Igp) che la stessa UE dovrebbe invece tutelare e valorizzare soprattutto nel tempo del Covid. E\u2019 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/coldiretti-attacco-ue-a-cibo-made-in-italy-costa-446mld\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-25T16:07:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/01\/Schermata-2020-01-16-alle-17.59.06.png\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"496\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/coldiretti-attacco-ue-a-cibo-made-in-italy-costa-446mld\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/coldiretti-attacco-ue-a-cibo-made-in-italy-costa-446mld\/\",\"name\":\"Coldiretti: attacco UE a cibo Made in Italy costa 44,6MLD -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/coldiretti-attacco-ue-a-cibo-made-in-italy-costa-446mld\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/coldiretti-attacco-ue-a-cibo-made-in-italy-costa-446mld\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/01\/Schermata-2020-01-16-alle-17.59.06.png\",\"datePublished\":\"2020-11-25T16:07:03+00:00\",\"dateModified\":\"2020-11-25T16:07:03+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/coldiretti-attacco-ue-a-cibo-made-in-italy-costa-446mld\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/coldiretti-attacco-ue-a-cibo-made-in-italy-costa-446mld\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/coldiretti-attacco-ue-a-cibo-made-in-italy-costa-446mld\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/01\/Schermata-2020-01-16-alle-17.59.06.png\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/01\/Schermata-2020-01-16-alle-17.59.06.png\",\"width\":700,\"height\":496},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/coldiretti-attacco-ue-a-cibo-made-in-italy-costa-446mld\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Coldiretti: attacco UE a cibo Made in Italy costa 44,6MLD\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Coldiretti: attacco UE a cibo Made in Italy costa 44,6MLD -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/coldiretti-attacco-ue-a-cibo-made-in-italy-costa-446mld\/","og_locale":"it_IT","og_type":"article","og_title":"Coldiretti: attacco UE a cibo Made in Italy costa 44,6MLD -","og_description":"E\u2019 necessario intervenire con urgenza per fermare l\u2019attacco al prodotti alimentari nazionali con il rischio del via libera all\u2019etichetta nutrizionale a colori dell\u2019Unione Europea che boccia ingiustamente quasi l\u201985% in valore del Made in Italy a denominazione di origine (Dop\/Igp) che la stessa UE dovrebbe invece tutelare e valorizzare soprattutto nel tempo del Covid. E\u2019 [&hellip;]","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/coldiretti-attacco-ue-a-cibo-made-in-italy-costa-446mld\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2020-11-25T16:07:03+00:00","og_image":[{"width":700,"height":496,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/01\/Schermata-2020-01-16-alle-17.59.06.png","type":"image\/png"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/coldiretti-attacco-ue-a-cibo-made-in-italy-costa-446mld\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/coldiretti-attacco-ue-a-cibo-made-in-italy-costa-446mld\/","name":"Coldiretti: attacco UE a cibo Made in Italy costa 44,6MLD -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/coldiretti-attacco-ue-a-cibo-made-in-italy-costa-446mld\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/coldiretti-attacco-ue-a-cibo-made-in-italy-costa-446mld\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/01\/Schermata-2020-01-16-alle-17.59.06.png","datePublished":"2020-11-25T16:07:03+00:00","dateModified":"2020-11-25T16:07:03+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/coldiretti-attacco-ue-a-cibo-made-in-italy-costa-446mld\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/coldiretti-attacco-ue-a-cibo-made-in-italy-costa-446mld\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/coldiretti-attacco-ue-a-cibo-made-in-italy-costa-446mld\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/01\/Schermata-2020-01-16-alle-17.59.06.png","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/01\/Schermata-2020-01-16-alle-17.59.06.png","width":700,"height":496},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/coldiretti-attacco-ue-a-cibo-made-in-italy-costa-446mld\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"Coldiretti: attacco UE a cibo Made in Italy costa 44,6MLD"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/4747"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=4747"}],"version-history":[{"count":1,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/4747\/revisions"}],"predecessor-version":[{"id":4748,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/4747\/revisions\/4748"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/2330"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=4747"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=4747"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=4747"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}