{"id":4817,"date":"2020-12-06T16:12:04","date_gmt":"2020-12-06T15:12:04","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=4817"},"modified":"2020-12-06T16:12:33","modified_gmt":"2020-12-06T15:12:33","slug":"a-novembre-continua-il-calo-delle-richieste-di-prestiti-da-parte-degli-italiani","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/a-novembre-continua-il-calo-delle-richieste-di-prestiti-da-parte-degli-italiani\/","title":{"rendered":"A novembre continua il calo delle richieste di prestiti da parte degli italiani"},"content":{"rendered":"<p><span class=\"dropcap dropcap3\">D<\/span>opo le costanti flessioni che perdurano ininterrottamente dal mese di marzo, con la brusca frenata coincisa con l\u2019introduzione delle prime misure restrittive per limitare la diffusione della pandemia di Covid-19, anche a novembre si registra una pesante contrazione del numero di richieste di finanziamenti da parte delle famiglie italiane (vere e proprie istruttorie formali contribuite sul Sistema di Informazioni Creditizie gestito da CRIF), con la componente dei prestiti finalizzati all\u2019acquisto di beni e servizi che si caratterizza per un calo del -22,4% rispetto al corrispondente mese del 2019, a fronte di un ancor pi\u00f9 marcato -27,4% fatto segnare dai prestiti personali.<\/p>\n<p>Nemmeno le iniziative promosse nelle settimane subito prima e dopo il Black Friday sono riuscite a stimolare pi\u00f9 di tanto i consumatori in questa fase di incertezza, sebbene quasi la met\u00e0 delle richieste di prestiti finalizzati si sia concentrata nell\u2019ultima settimana del mese, che ha fatto segnare un incremento del +13% rispetto alla media delle settimane precedenti.<\/p>\n<p>Un altro aspetto da sottolineare che emerge dall\u2019ultimo aggiornamento prodotto da CRIF \u00e8 rappresentato dalla crescente tendenza da parte dei consumatori a privilegiare gli acquisti online, tanto che le richieste di credito riconducibili alle piattaforme di e-commerce hanno fatto registrare una crescita del +19% rispetto alla media delle settimane precedenti.<br \/>\nUn\u2019ulteriore evidenza che emerge dallo studio di CRIF riguarda la contrazione del valore medio dei finanziamenti richiesti, che nell\u2019aggregato di prestiti personali e finalizzati nell\u2019ultimo mese di osservazione si \u00e8 attestato a 8.644 Euro (-3,4% rispetto al dato di novembre 2019).<\/p>\n<p>Entrando, nel dettaglio, per quanto riguarda i prestiti finalizzati l\u2019importo medio richiesto si \u00e8 attestato a 5.934 Euro (-3,7%), mentre per i prestiti personali \u00e8 risultato pari a 12.765 Euro (-1,1%). Relativamente ai prestiti finalizzati, il 61% delle richieste riguarda importi al di sotto dei 5.000 Euro, in virt\u00f9 della componente maggioritaria del credito al consumo. Anche per i prestiti personali la quota al di sotto dei 5.000 Euro \u00e8 quella maggioritaria, con il 30,8% del totale.<\/p>\n<p>In merito alla durata dei contratti di finanziamento, per quanto riguarda i prestiti finalizzati le richieste privilegiano piani di rimborso inferiori ai 12 mesi (con il 22,9% del totale) mentre per i prestiti personali le preferenze si stanno indirizzando sempre di pi\u00f9 su durate superiori ai 5 anni, che arrivano a spiegare il 45,2% del totale.<\/p>\n<p>L\u2019ANDAMENTO DELLE RICHIESTE DI MUTUI E SURROGHE<br \/>\nDopo la battuta d\u2019arresto fatta segnare a ottobre, anche a novembre le richieste di mutui e surroghe restano in territorio negativo, facendo segnare una flessione del -11,4% rispetto al corrispondente mese del 2019.<\/p>\n<p>Nel complesso, dopo la fase di lockdown della scorsa primavera, caratterizzata sia dalla contrazione della domanda delle famiglie sia dalla limitata operativit\u00e0 da parte degli istituti di credito, le richieste di mutuo erano tornate a crescere in modo solido a partire dal mese di giugno (+26,7% nel III trimestre dell\u2019anno), riassestandosi su volumi persino superiori a quelli pre crisi. Con la seconda ondata di contagi che ha investito il Paese a partire dall\u2019inizio di ottobre si \u00e8 per\u00f2 assistito a una improvvisa inversione di tendenza che ha nuovamente frenato la domanda.<\/p>\n<p>In questo momento gli italiani non trovano stimolo nemmeno da condizioni di offerta particolarmente vantaggiose, con la media dei migliori spread online per mutui a tasso variabile che nel III trimestre dell\u2019anno risultava stabile allo 0,8% mentre quella per i mutui a tasso fisso si attestava allo 0,4%.<\/p>\n<p>Le preoccupazioni delle famiglie trovano conferma anche nell\u2019analisi delle moratorie per la sospensione delle rate, tanto che quasi la met\u00e0 dei contratti di finanziamento che hanno beneficiato della sospensione del pagamento delle rate riguarda infatti un mutuo immobiliare.<\/p>\n<p>In compenso a novembre risulta in crescita (+1,5%) l\u2019importo medio, che si \u00e8 attestato a 134.599 Euro; nel complesso, il 72,1% delle richieste presenta un valore inferiore ai 150.000 Euro.<\/p>\n<p>Per quanto riguarda la distribuzione per classe di durata dei mutui, invece, anche il mese di novembre ha visto gli italiani orientarsi verso piani di rimborso pi\u00f9 lunghi, con pi\u00f9 del 75% delle richieste che prevede una durata superiore ai 15 anni.<\/p>\n<p>\u201cCon l\u2019arrivo della seconda ondata di contagi gli italiani hanno ridotto in modo significativo le richieste di credito per sostenere i propri progetti di spesa e gli acquisti di servizi e beni durevoli. Ma l\u2019atteggiamento attendista sta frenando anche i mutui, con le famiglie che sembrano aver tirato il freno a mano in attesa che l\u2019emergenza sanitaria venga superata e si torni ad una situazione di normalit\u00e0\u201d \u2013 commenta Simone Capecchi, Executive Director di CRIF \u2013. In questa fase \u00e8 estremamente difficile fare previsioni sull\u2019evoluzione del comparto nei prossimi mesi ma, indubbiamente, per la ripartenza sar\u00e0 fondamentale che gli Istituti di credito possano sostenere famiglie e imprese anche attraverso processi agili e veloci, ad esempio sfruttando le nuove tecnologie per accelerare sul fronte della digitalizzazione. Al contempo saranno fondamentali le iniziative di sostegno da parte del Governo, come nel caso degli incentivi al settore auto o il Superbonus 110% varato per stimolare la riqualificazione del patrimonio immobiliare italiano\u201d- conclude Capecchi.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dopo le costanti flessioni che perdurano ininterrottamente dal mese di marzo, con la brusca frenata coincisa con l\u2019introduzione delle prime misure restrittive per limitare la diffusione della pandemia di Covid-19, anche a novembre si registra una pesante contrazione del numero di richieste di finanziamenti da parte delle famiglie italiane (vere e proprie istruttorie formali contribuite [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3378,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[162],"tags":[713,1431],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>A novembre continua il calo delle richieste di prestiti da parte degli italiani -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/a-novembre-continua-il-calo-delle-richieste-di-prestiti-da-parte-degli-italiani\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A novembre continua il calo delle richieste di prestiti da parte degli italiani -\" \/>\n<meta property=\"og:description\" content=\"Dopo le costanti flessioni che perdurano ininterrottamente dal mese di marzo, con la brusca frenata coincisa con l\u2019introduzione delle prime misure restrittive per limitare la diffusione della pandemia di Covid-19, anche a novembre si registra una pesante contrazione del numero di richieste di finanziamenti da parte delle famiglie italiane (vere e proprie istruttorie formali contribuite [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/a-novembre-continua-il-calo-delle-richieste-di-prestiti-da-parte-degli-italiani\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-06T15:12:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-12-06T15:12:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/06\/Schermata-2020-06-17-alle-15.57.33.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1396\" \/>\n\t<meta property=\"og:image:height\" content=\"942\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/a-novembre-continua-il-calo-delle-richieste-di-prestiti-da-parte-degli-italiani\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/a-novembre-continua-il-calo-delle-richieste-di-prestiti-da-parte-degli-italiani\/\",\"name\":\"A novembre continua il calo delle richieste di prestiti da parte degli italiani -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/a-novembre-continua-il-calo-delle-richieste-di-prestiti-da-parte-degli-italiani\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/a-novembre-continua-il-calo-delle-richieste-di-prestiti-da-parte-degli-italiani\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/06\/Schermata-2020-06-17-alle-15.57.33.png\",\"datePublished\":\"2020-12-06T15:12:04+00:00\",\"dateModified\":\"2020-12-06T15:12:33+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/a-novembre-continua-il-calo-delle-richieste-di-prestiti-da-parte-degli-italiani\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/a-novembre-continua-il-calo-delle-richieste-di-prestiti-da-parte-degli-italiani\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/a-novembre-continua-il-calo-delle-richieste-di-prestiti-da-parte-degli-italiani\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/06\/Schermata-2020-06-17-alle-15.57.33.png\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/06\/Schermata-2020-06-17-alle-15.57.33.png\",\"width\":1396,\"height\":942},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/a-novembre-continua-il-calo-delle-richieste-di-prestiti-da-parte-degli-italiani\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A novembre continua il calo delle richieste di prestiti da parte degli italiani\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A novembre continua il calo delle richieste di prestiti da parte degli italiani -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/a-novembre-continua-il-calo-delle-richieste-di-prestiti-da-parte-degli-italiani\/","og_locale":"it_IT","og_type":"article","og_title":"A novembre continua il calo delle richieste di prestiti da parte degli italiani -","og_description":"Dopo le costanti flessioni che perdurano ininterrottamente dal mese di marzo, con la brusca frenata coincisa con l\u2019introduzione delle prime misure restrittive per limitare la diffusione della pandemia di Covid-19, anche a novembre si registra una pesante contrazione del numero di richieste di finanziamenti da parte delle famiglie italiane (vere e proprie istruttorie formali contribuite [&hellip;]","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/a-novembre-continua-il-calo-delle-richieste-di-prestiti-da-parte-degli-italiani\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2020-12-06T15:12:04+00:00","article_modified_time":"2020-12-06T15:12:33+00:00","og_image":[{"width":1396,"height":942,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/06\/Schermata-2020-06-17-alle-15.57.33.png","type":"image\/png"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/a-novembre-continua-il-calo-delle-richieste-di-prestiti-da-parte-degli-italiani\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/a-novembre-continua-il-calo-delle-richieste-di-prestiti-da-parte-degli-italiani\/","name":"A novembre continua il calo delle richieste di prestiti da parte degli italiani -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/a-novembre-continua-il-calo-delle-richieste-di-prestiti-da-parte-degli-italiani\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/a-novembre-continua-il-calo-delle-richieste-di-prestiti-da-parte-degli-italiani\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/06\/Schermata-2020-06-17-alle-15.57.33.png","datePublished":"2020-12-06T15:12:04+00:00","dateModified":"2020-12-06T15:12:33+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/a-novembre-continua-il-calo-delle-richieste-di-prestiti-da-parte-degli-italiani\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/a-novembre-continua-il-calo-delle-richieste-di-prestiti-da-parte-degli-italiani\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/a-novembre-continua-il-calo-delle-richieste-di-prestiti-da-parte-degli-italiani\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/06\/Schermata-2020-06-17-alle-15.57.33.png","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/06\/Schermata-2020-06-17-alle-15.57.33.png","width":1396,"height":942},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/a-novembre-continua-il-calo-delle-richieste-di-prestiti-da-parte-degli-italiani\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"A novembre continua il calo delle richieste di prestiti da parte degli italiani"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/4817"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=4817"}],"version-history":[{"count":2,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/4817\/revisions"}],"predecessor-version":[{"id":4819,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/4817\/revisions\/4819"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/3378"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=4817"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=4817"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=4817"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}