{"id":4820,"date":"2020-12-06T16:17:17","date_gmt":"2020-12-06T15:17:17","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=4820"},"modified":"2020-12-06T16:19:15","modified_gmt":"2020-12-06T15:19:15","slug":"legambiente-i-reflui-zootecnici-non-devono-finire-sui-campi-ma-nei-digestori-anaerobici-per-produrre-biometano","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/legambiente-i-reflui-zootecnici-non-devono-finire-sui-campi-ma-nei-digestori-anaerobici-per-produrre-biometano\/","title":{"rendered":"Legambiente: \u201cI reflui zootecnici non devono finire sui campi ma nei digestori anaerobici per produrre biometano&#8221;"},"content":{"rendered":"<p><span class=\"dropcap dropcap3\">L<\/span>a nuova messa in mora del nostro Paese da parte dell\u2019Unione europea non arriva inaspettata, di sicuro non per noi che abbiamo segnalato queste condotte a Bruxelles. E pone ancora una volta all\u2019attenzione del Governo italiano il problema strutturale riguardante, in particolar modo, la gestione dei reflui zootecnici in Pianura Padana (e non solo) che presenta livelli di carico ambientale incompatibili con la qualit\u00e0 delle acque definita a livello comunitario.<\/p>\n<p>Lo spandimento di liquami nel periodo invernale deve restare vietato ed \u00e8 grave che le condotte da noi denunciate, in aperta violazione delle normative europee, siano state messe in atto dalle Regioni con il formale benestare del Ministero dell&#8217;Agricoltura.<\/p>\n<p>I reflui zootecnici devono diventare l&#8217;alimentazione dei digestori anaerobici per la produzione di biometano con cui alimentare i trattori agricoli di nuova generazione e i mezzi pesanti che trasportano i prodotti dell&#8217;agroalimentare dal terreno agricolo ai punti vendita. Solo cos\u00ec si potr\u00e0 trasformare il problema dei reflui della zootecnia in una grande opportunit\u00e0 per decarbonizzare la filiera agricola del nostro Paese\u201d.<\/p>\n<p>Cos\u00ec\u00a0<strong>il presidente di Legambiente, Stefano Ciafani<\/strong>, a commento della seconda procedura d\u2019infrazione appena notificata dalla Commissione europea all\u2019Italia per il mancato rispetto della direttiva che mira a prevenire l\u2019inquinamento idrico da nitrati di origine agricola.<\/p>\n<p>Gi\u00e0 nel 2018 la Commissione europea aveva chiesto all\u2019Italia di garantire la stabilit\u00e0 della rete di monitoraggio delle proprie acque, nonch\u00e9 di riesaminare e designare nuove \u201czone vulnerabili\u201d ai nitrati, istituendo adeguati programmi di azione con misure obbligatorie per gli agricoltori e adottando, ove necessario, misure aggiuntive o azioni rafforzate per raggiungere gli obiettivi fissati dalla 91\/676\/Cee. Misure che, tuttavia, il nostro Paese ha attuato\u00a0solo in parte, aggiungendo anzi altri due elementi che motivano questa seconda messa in mora: la mancata revisione di alcuni programmi d\u2019azione regionali e la riduzione del periodo annuale di chiusura continua durante il quale \u00e8 vietato l\u2019uso dei fertilizzanti.<\/p>\n<p>Su quest\u2019ultimo punto Legambiente si era pronunciata all&#8217;inizio del 2020, denunciando proprio alla Commissione europea l\u2019infrazione delle norme comunitarie, come ricorda\u00a0<strong>Damiano Di Simine, coordinatore della presidenza del comitato scientifico nazionale di Legambiente<\/strong>.<\/p>\n<p>\u201cGi\u00e0 lo scorso inverno avevamo contestato la circolare del MIPAAF che per venire incontro agli allevatori del Nord aveva autorizzato l\u2019impiego di liquami anche nei mesi in cui vige il divieto di spandimento, denunciando inoltre alla Commissione europea la supposta violazione di ben quattro direttive comunitarie, in materia di acque, aria, rifiuti e inquinamento da nitrati, e rilevando in Lombardia il picco di inquinamento\u00a0da ammoniaca e polveri sottili\u00a0proprio nei giorni in cui la Regione ha disposto la possibilit\u00e0 di spandimento di reflui zootecnici\u201d.<\/p>\n<p>\u201c\u00c8 evidente \u2013 prosegue\u00a0<strong>Di Simine<\/strong>\u00a0\u2013 come si sia autorizzata una pratica che equivale ad uno smaltimento su superfici agricole, al di fuori delle regole comunitarie e che non pu\u00f2 essere spacciato per fertilizzazione,\u00a0dal momento che in inverno non ci sono coltivazioni in grado di utilizzare i nutrienti delle deiezioni. Le aziende che affogano nei liquami e che non dispongono n\u00e9 di superfici agricole sufficienti per gestirne lo spandimento, n\u00e9 di volumi adeguati ad assicurarne lo stoccaggio nella stagione del riposo vegetativo, devono attrezzarsi diversamente con le soluzioni tecnologiche oggi disponibili sul mercato. L\u2019Europa ha preso sul serio le nostre denunce, ampiamente documentate anche dai nostri attivisti sui territori, che hanno rilevato estesi e persistenti impaludamenti su terreni saturi di liquami, formazione di schiuma, ristagni e colature in corsi d\u2019acqua dalle colorazioni anomale. Ci aspettiamo che ora anche il Governo e le regioni intervengano per risanare le vaste aree in cui i reflui e le immissioni zootecniche sono ormai la pi\u00f9 preoccupante fonte di inquinamento per acque, aria e suolo\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La nuova messa in mora del nostro Paese da parte dell\u2019Unione europea non arriva inaspettata, di sicuro non per noi che abbiamo segnalato queste condotte a Bruxelles. E pone ancora una volta all\u2019attenzione del Governo italiano il problema strutturale riguardante, in particolar modo, la gestione dei reflui zootecnici in Pianura Padana (e non solo) che [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4822,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[127],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Legambiente: \u201cI reflui zootecnici non devono finire sui campi ma nei digestori anaerobici per produrre biometano&quot; -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/legambiente-i-reflui-zootecnici-non-devono-finire-sui-campi-ma-nei-digestori-anaerobici-per-produrre-biometano\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Legambiente: \u201cI reflui zootecnici non devono finire sui campi ma nei digestori anaerobici per produrre biometano&quot; -\" \/>\n<meta property=\"og:description\" content=\"La nuova messa in mora del nostro Paese da parte dell\u2019Unione europea non arriva inaspettata, di sicuro non per noi che abbiamo segnalato queste condotte a Bruxelles. E pone ancora una volta all\u2019attenzione del Governo italiano il problema strutturale riguardante, in particolar modo, la gestione dei reflui zootecnici in Pianura Padana (e non solo) che [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/legambiente-i-reflui-zootecnici-non-devono-finire-sui-campi-ma-nei-digestori-anaerobici-per-produrre-biometano\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-06T15:17:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-12-06T15:19:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/12\/Schermata-2020-12-06-alle-16.18.04.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1186\" \/>\n\t<meta property=\"og:image:height\" content=\"606\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/legambiente-i-reflui-zootecnici-non-devono-finire-sui-campi-ma-nei-digestori-anaerobici-per-produrre-biometano\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/legambiente-i-reflui-zootecnici-non-devono-finire-sui-campi-ma-nei-digestori-anaerobici-per-produrre-biometano\/\",\"name\":\"Legambiente: \u201cI reflui zootecnici non devono finire sui campi ma nei digestori anaerobici per produrre biometano\\\" -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/legambiente-i-reflui-zootecnici-non-devono-finire-sui-campi-ma-nei-digestori-anaerobici-per-produrre-biometano\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/legambiente-i-reflui-zootecnici-non-devono-finire-sui-campi-ma-nei-digestori-anaerobici-per-produrre-biometano\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/12\/Schermata-2020-12-06-alle-16.18.04.png\",\"datePublished\":\"2020-12-06T15:17:17+00:00\",\"dateModified\":\"2020-12-06T15:19:15+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/legambiente-i-reflui-zootecnici-non-devono-finire-sui-campi-ma-nei-digestori-anaerobici-per-produrre-biometano\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/legambiente-i-reflui-zootecnici-non-devono-finire-sui-campi-ma-nei-digestori-anaerobici-per-produrre-biometano\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/legambiente-i-reflui-zootecnici-non-devono-finire-sui-campi-ma-nei-digestori-anaerobici-per-produrre-biometano\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/12\/Schermata-2020-12-06-alle-16.18.04.png\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/12\/Schermata-2020-12-06-alle-16.18.04.png\",\"width\":1186,\"height\":606},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/legambiente-i-reflui-zootecnici-non-devono-finire-sui-campi-ma-nei-digestori-anaerobici-per-produrre-biometano\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Legambiente: \u201cI reflui zootecnici non devono finire sui campi ma nei digestori anaerobici per produrre biometano&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Legambiente: \u201cI reflui zootecnici non devono finire sui campi ma nei digestori anaerobici per produrre biometano\" -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/legambiente-i-reflui-zootecnici-non-devono-finire-sui-campi-ma-nei-digestori-anaerobici-per-produrre-biometano\/","og_locale":"it_IT","og_type":"article","og_title":"Legambiente: \u201cI reflui zootecnici non devono finire sui campi ma nei digestori anaerobici per produrre biometano\" -","og_description":"La nuova messa in mora del nostro Paese da parte dell\u2019Unione europea non arriva inaspettata, di sicuro non per noi che abbiamo segnalato queste condotte a Bruxelles. E pone ancora una volta all\u2019attenzione del Governo italiano il problema strutturale riguardante, in particolar modo, la gestione dei reflui zootecnici in Pianura Padana (e non solo) che [&hellip;]","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/legambiente-i-reflui-zootecnici-non-devono-finire-sui-campi-ma-nei-digestori-anaerobici-per-produrre-biometano\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2020-12-06T15:17:17+00:00","article_modified_time":"2020-12-06T15:19:15+00:00","og_image":[{"width":1186,"height":606,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/12\/Schermata-2020-12-06-alle-16.18.04.png","type":"image\/png"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/legambiente-i-reflui-zootecnici-non-devono-finire-sui-campi-ma-nei-digestori-anaerobici-per-produrre-biometano\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/legambiente-i-reflui-zootecnici-non-devono-finire-sui-campi-ma-nei-digestori-anaerobici-per-produrre-biometano\/","name":"Legambiente: \u201cI reflui zootecnici non devono finire sui campi ma nei digestori anaerobici per produrre biometano\" -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/legambiente-i-reflui-zootecnici-non-devono-finire-sui-campi-ma-nei-digestori-anaerobici-per-produrre-biometano\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/legambiente-i-reflui-zootecnici-non-devono-finire-sui-campi-ma-nei-digestori-anaerobici-per-produrre-biometano\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/12\/Schermata-2020-12-06-alle-16.18.04.png","datePublished":"2020-12-06T15:17:17+00:00","dateModified":"2020-12-06T15:19:15+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/legambiente-i-reflui-zootecnici-non-devono-finire-sui-campi-ma-nei-digestori-anaerobici-per-produrre-biometano\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/legambiente-i-reflui-zootecnici-non-devono-finire-sui-campi-ma-nei-digestori-anaerobici-per-produrre-biometano\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/legambiente-i-reflui-zootecnici-non-devono-finire-sui-campi-ma-nei-digestori-anaerobici-per-produrre-biometano\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/12\/Schermata-2020-12-06-alle-16.18.04.png","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/12\/Schermata-2020-12-06-alle-16.18.04.png","width":1186,"height":606},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/legambiente-i-reflui-zootecnici-non-devono-finire-sui-campi-ma-nei-digestori-anaerobici-per-produrre-biometano\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"Legambiente: \u201cI reflui zootecnici non devono finire sui campi ma nei digestori anaerobici per produrre biometano&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/4820"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=4820"}],"version-history":[{"count":1,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/4820\/revisions"}],"predecessor-version":[{"id":4821,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/4820\/revisions\/4821"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/4822"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=4820"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=4820"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=4820"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}