{"id":4824,"date":"2020-12-07T12:35:28","date_gmt":"2020-12-07T11:35:28","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=4824"},"modified":"2020-12-07T12:35:28","modified_gmt":"2020-12-07T11:35:28","slug":"confagricoltura-per-un-natale-ecologico-scegliere-alberi-veri-stelle-e-ciclamini","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/confagricoltura-per-un-natale-ecologico-scegliere-alberi-veri-stelle-e-ciclamini\/","title":{"rendered":"Confagricoltura: per un Natale ecologico scegliere alberi veri, stelle e ciclamini"},"content":{"rendered":"<p><span class=\"dropcap dropcap3\">I<\/span>l 2020 ha radicalmente cambiato abitudini e consuetudini, ma nonostante le tante rinunce, tutti aspettiamo l\u2019atmosfera e il calore di Natale. Confagricoltura invita, per queste feste diverse dal solito, a riconnettersi con la natura portandola a casa propria.<\/p>\n<p>Comprare un abete vero e decorare la propria abitazione con ciclamini e Stelle di Natale \u00e8 un comportamento all\u2019insegna della sostenibilit\u00e0.<\/p>\n<p>\u201cMai come quest\u2019anno \u2013 rimarca Francesco Mati, presidente della Federazione florovivaistica di Confagricoltura \u2013 c\u2019\u00e8 bisogno che le prossime festivit\u00e0 ci portino buonumore, calore e speranza. Un albero di Natale vero \u00e8 l\u2019unico che fa atmosfera. Ed \u00e8 coltivato esclusivamente per l\u2019uso natalizio, senza l\u2019utilizzo di prodotti nocivi per l\u2019ambiente\u201d.<\/p>\n<p>Come ci dice la ricerca di settore, nel ciclo di produzione dell\u2019abete, l\u2019impronta del carbonio \u2013 la cosiddetta carbon footprint \u2013 \u00e8 ampiamente positiva, mentre non lo \u00e8 affatto, anzi \u00e8 alquanto impattante, nella produzione di alberi di Natale di plastica.<\/p>\n<p>\u201cAnche a Natale \u2013 conclude Mati \u2013 conta ogni azione per contribuire a migliorare la qualit\u00e0 della vita, la nostra salute e sostenere un comparto essenziale per l\u2019economia italiana\u201d.<\/p>\n<p>Il florovivaismo ha un fatturato che supera i 2 miliardi e mezzo di euro e un export che sfiora il miliardo. Particolarmente provato dalla pandemia, il settore conta sul periodo natalizio, che rappresenta circa il 15% degli affari delle imprese del settore.<\/p>\n<p>Quest\u2019anno i vivaisti di Confagricoltura consigliano l\u2019Abete Normandiano o\u2028l\u2019Excelsa (abete rosso). Per quanto riguarda le Stelle di Natale, oltre al rosso e il bianco, i floricoltori propongono l\u2019arancione, colore simbolo di allegria e\u00a0felicit\u00e0.<br \/>\nAnche l\u2019acquisto in un vivaio o garden center pu\u00f2 diventare sostenibile \u2013 conclude il presidente della federazione florovivaistica di Confagricoltura \u2013 se si sceglie di farlo non lontano da casa, alimentando cos\u00ec l\u2019economia locale\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il 2020 ha radicalmente cambiato abitudini e consuetudini, ma nonostante le tante rinunce, tutti aspettiamo l\u2019atmosfera e il calore di Natale. Confagricoltura invita, per queste feste diverse dal solito, a riconnettersi con la natura portandola a casa propria. Comprare un abete vero e decorare la propria abitazione con ciclamini e Stelle di Natale \u00e8 un [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4825,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[127],"tags":[158,1432],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Confagricoltura: per un Natale ecologico scegliere alberi veri, stelle e ciclamini -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/confagricoltura-per-un-natale-ecologico-scegliere-alberi-veri-stelle-e-ciclamini\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Confagricoltura: per un Natale ecologico scegliere alberi veri, stelle e ciclamini -\" \/>\n<meta property=\"og:description\" content=\"Il 2020 ha radicalmente cambiato abitudini e consuetudini, ma nonostante le tante rinunce, tutti aspettiamo l\u2019atmosfera e il calore di Natale. Confagricoltura invita, per queste feste diverse dal solito, a riconnettersi con la natura portandola a casa propria. Comprare un abete vero e decorare la propria abitazione con ciclamini e Stelle di Natale \u00e8 un [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/confagricoltura-per-un-natale-ecologico-scegliere-alberi-veri-stelle-e-ciclamini\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-07T11:35:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/12\/Schermata-2020-12-07-alle-12.34.27.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1228\" \/>\n\t<meta property=\"og:image:height\" content=\"756\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/confagricoltura-per-un-natale-ecologico-scegliere-alberi-veri-stelle-e-ciclamini\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/confagricoltura-per-un-natale-ecologico-scegliere-alberi-veri-stelle-e-ciclamini\/\",\"name\":\"Confagricoltura: per un Natale ecologico scegliere alberi veri, stelle e ciclamini -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/confagricoltura-per-un-natale-ecologico-scegliere-alberi-veri-stelle-e-ciclamini\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/confagricoltura-per-un-natale-ecologico-scegliere-alberi-veri-stelle-e-ciclamini\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/12\/Schermata-2020-12-07-alle-12.34.27.png\",\"datePublished\":\"2020-12-07T11:35:28+00:00\",\"dateModified\":\"2020-12-07T11:35:28+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/confagricoltura-per-un-natale-ecologico-scegliere-alberi-veri-stelle-e-ciclamini\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/confagricoltura-per-un-natale-ecologico-scegliere-alberi-veri-stelle-e-ciclamini\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/confagricoltura-per-un-natale-ecologico-scegliere-alberi-veri-stelle-e-ciclamini\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/12\/Schermata-2020-12-07-alle-12.34.27.png\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/12\/Schermata-2020-12-07-alle-12.34.27.png\",\"width\":1228,\"height\":756},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/confagricoltura-per-un-natale-ecologico-scegliere-alberi-veri-stelle-e-ciclamini\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Confagricoltura: per un Natale ecologico scegliere alberi veri, stelle e ciclamini\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Confagricoltura: per un Natale ecologico scegliere alberi veri, stelle e ciclamini -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/confagricoltura-per-un-natale-ecologico-scegliere-alberi-veri-stelle-e-ciclamini\/","og_locale":"it_IT","og_type":"article","og_title":"Confagricoltura: per un Natale ecologico scegliere alberi veri, stelle e ciclamini -","og_description":"Il 2020 ha radicalmente cambiato abitudini e consuetudini, ma nonostante le tante rinunce, tutti aspettiamo l\u2019atmosfera e il calore di Natale. Confagricoltura invita, per queste feste diverse dal solito, a riconnettersi con la natura portandola a casa propria. Comprare un abete vero e decorare la propria abitazione con ciclamini e Stelle di Natale \u00e8 un [&hellip;]","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/confagricoltura-per-un-natale-ecologico-scegliere-alberi-veri-stelle-e-ciclamini\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2020-12-07T11:35:28+00:00","og_image":[{"width":1228,"height":756,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/12\/Schermata-2020-12-07-alle-12.34.27.png","type":"image\/png"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/confagricoltura-per-un-natale-ecologico-scegliere-alberi-veri-stelle-e-ciclamini\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/confagricoltura-per-un-natale-ecologico-scegliere-alberi-veri-stelle-e-ciclamini\/","name":"Confagricoltura: per un Natale ecologico scegliere alberi veri, stelle e ciclamini -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/confagricoltura-per-un-natale-ecologico-scegliere-alberi-veri-stelle-e-ciclamini\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/confagricoltura-per-un-natale-ecologico-scegliere-alberi-veri-stelle-e-ciclamini\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/12\/Schermata-2020-12-07-alle-12.34.27.png","datePublished":"2020-12-07T11:35:28+00:00","dateModified":"2020-12-07T11:35:28+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/confagricoltura-per-un-natale-ecologico-scegliere-alberi-veri-stelle-e-ciclamini\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/confagricoltura-per-un-natale-ecologico-scegliere-alberi-veri-stelle-e-ciclamini\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/confagricoltura-per-un-natale-ecologico-scegliere-alberi-veri-stelle-e-ciclamini\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/12\/Schermata-2020-12-07-alle-12.34.27.png","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/12\/Schermata-2020-12-07-alle-12.34.27.png","width":1228,"height":756},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/confagricoltura-per-un-natale-ecologico-scegliere-alberi-veri-stelle-e-ciclamini\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"Confagricoltura: per un Natale ecologico scegliere alberi veri, stelle e ciclamini"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/4824"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=4824"}],"version-history":[{"count":1,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/4824\/revisions"}],"predecessor-version":[{"id":4826,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/4824\/revisions\/4826"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/4825"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=4824"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=4824"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=4824"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}