{"id":4844,"date":"2020-12-09T15:34:18","date_gmt":"2020-12-09T14:34:18","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=4844"},"modified":"2020-12-09T15:34:39","modified_gmt":"2020-12-09T14:34:39","slug":"caschback-di-stato-superbonus-ai-maggiori-utilizzatori-cioe-ai-ricchi","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/caschback-di-stato-superbonus-ai-maggiori-utilizzatori-cioe-ai-ricchi\/","title":{"rendered":"Caschback di Stato: superbonus ai maggiori utilizzatori, cio\u00e8 ai ricchi"},"content":{"rendered":"<p><span class=\"dropcap dropcap3\">C<\/span>om&#8217;\u00e8 stato pensato il caschback di Stato premia pochi a danno di troppi. Federcontribuenti: &#8221;100 mila cittadini che effettueranno il <strong>maggior numero di transazioni<\/strong> a semestre verranno premiati con un super cashback da 1500 euro.<\/p>\n<p>Un <strong>premio ai ricchi,<\/strong> solo per i possessori di una carta di credito oro, come i politici ad esempio! Nessun pensionato, nessun cassaintegrato, nessun precario o disoccupato (insomma le fasce che necessitano di aiuto ) potr\u00e0 concorrere al super bonus qual \u00e8 il senso di questa lotteria?&#8221;.<\/p>\n<p>Torniamo alla realt\u00e0 raccontando una storia tra un milione di storie ingiuste: &#8221; Moglie e marito, entrambi cassaintegrati a zero ore, due bambini di 7 e 9 anni, non percepiscono un euro da agosto e hanno dato fondo a tutti i risparmi, compreso un piccolo fondo di emergenza per le spese mediche&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<p>In questi giorni alla Federcontribuenti \u00e8 giunto l&#8217;ennesimo sfogo di una famiglia come tante che vive nel ricco (leggenda) Veneto: &#8221; come molti altri veneti avevamo creduto alle rassicurazioni di una politica assolutamente inadeguata, cialtrona, parolaia, iniziando da chi governa e arrivando a chi dovrebbe fare un&#8217;opposizione intelligente e invece vegeta scaldando la poltrona nella speranza di essere eletto.<\/p>\n<p>Dove sono i ristori promessi? Quelli che dovevano arrivare direttamente in conto corrente in un biz? Ma soprattutto dov&#8217;\u00e8 la cassa integrazione? Perch\u00e9 la cassa integrazione per alcuni \u00e8 questione di sopravvivenza. Affitto, bollette da pagare, i figli da mandare a scuola con tutto quello che comporta.<\/p>\n<p>La <strong>banca ha chiamato quattro volte <\/strong>per uno <strong>sconfinamento di ben 7 euro<\/strong> e 61 centesimi, una di quelle <strong>banche salvate <\/strong>pi\u00f9 volte da uno Stato che per farlo ha usato i soldi dei contribuenti. I nostri soldi. Vi risparmio la via crucis telefonica per avere informazioni, richieste affondate in un mare di &#8220;non sappiamo&#8221;, &#8220;deve chiamare un altro numero&#8221;, &#8220;non siamo competenti per il caso specifico&#8221;, in sintesi il nulla assoluto che fa il paio con la politica italiana che \u00e8 da sempre il nulla assoluto&#8221;.<\/p>\n<p><strong>Federcontribuenti:<\/strong> &#8221;non vi accalcate nel chiederci un contatto con questa dignitosissima famiglia, non vogliono essere l&#8217;ennesimo carosello di lacrime in nessuna trasmissione. Questa famiglia non aveva alcun problema economico prima della pandemia; riusciva tranquillamente a vivere con il proprio reddito anche se non gli permetteva grandi risparmi o spese da pazzi. Queste storie tolgono, a chi le riceve, la voglia di credere e di sperare in una classe politica seria, laboriosa, consapevole del vivere quotidiano di milioni di famiglie italiane umiliate, di nuovo, con la lotteria a premi ideata da questo governo!<strong> Volevate aiutare in qualche modo i consumi<\/strong>?<\/p>\n<p>Perch\u00e9 non<strong> scalare l&#8217;IVA<\/strong> per gli acquisti con<strong> bancomat<\/strong>? Invece no: scarica l&#8217;app, iscriviti e usa l&#8217;infernale SPID che se paghi una piattaforma l&#8217;hai subito ma, se vuoi farlo gratis devi perderti nei gironi infernali o ingaggiare un ingegnere aereospaziale! Questa e altre famiglie verranno aiutate da altri miserabili cittadini e dalle associazioni \u2013 a cui s<strong>tate per chiedere di aprire una partita iva<\/strong>, cose da pazzi -&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<table>\n<tbody>\n<tr>\n<td>\n<table width=\"100%\">\n<tbody>\n<tr>\n<td><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Com&#8217;\u00e8 stato pensato il caschback di Stato premia pochi a danno di troppi. Federcontribuenti: &#8221;100 mila cittadini che effettueranno il maggior numero di transazioni a semestre verranno premiati con un super cashback da 1500 euro. Un premio ai ricchi, solo per i possessori di una carta di credito oro, come i politici ad esempio! Nessun [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4845,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[162],"tags":[1436],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Caschback di Stato: superbonus ai maggiori utilizzatori, cio\u00e8 ai ricchi -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/caschback-di-stato-superbonus-ai-maggiori-utilizzatori-cioe-ai-ricchi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Caschback di Stato: superbonus ai maggiori utilizzatori, cio\u00e8 ai ricchi -\" \/>\n<meta property=\"og:description\" content=\"Com&#8217;\u00e8 stato pensato il caschback di Stato premia pochi a danno di troppi. Federcontribuenti: &#8221;100 mila cittadini che effettueranno il maggior numero di transazioni a semestre verranno premiati con un super cashback da 1500 euro. Un premio ai ricchi, solo per i possessori di una carta di credito oro, come i politici ad esempio! Nessun [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/caschback-di-stato-superbonus-ai-maggiori-utilizzatori-cioe-ai-ricchi\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-09T14:34:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-12-09T14:34:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/12\/Schermata-2020-12-09-alle-15.23.21.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1120\" \/>\n\t<meta property=\"og:image:height\" content=\"508\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/caschback-di-stato-superbonus-ai-maggiori-utilizzatori-cioe-ai-ricchi\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/caschback-di-stato-superbonus-ai-maggiori-utilizzatori-cioe-ai-ricchi\/\",\"name\":\"Caschback di Stato: superbonus ai maggiori utilizzatori, cio\u00e8 ai ricchi -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/caschback-di-stato-superbonus-ai-maggiori-utilizzatori-cioe-ai-ricchi\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/caschback-di-stato-superbonus-ai-maggiori-utilizzatori-cioe-ai-ricchi\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/12\/Schermata-2020-12-09-alle-15.23.21.png\",\"datePublished\":\"2020-12-09T14:34:18+00:00\",\"dateModified\":\"2020-12-09T14:34:39+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/caschback-di-stato-superbonus-ai-maggiori-utilizzatori-cioe-ai-ricchi\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/caschback-di-stato-superbonus-ai-maggiori-utilizzatori-cioe-ai-ricchi\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/caschback-di-stato-superbonus-ai-maggiori-utilizzatori-cioe-ai-ricchi\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/12\/Schermata-2020-12-09-alle-15.23.21.png\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/12\/Schermata-2020-12-09-alle-15.23.21.png\",\"width\":1120,\"height\":508},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/caschback-di-stato-superbonus-ai-maggiori-utilizzatori-cioe-ai-ricchi\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Caschback di Stato: superbonus ai maggiori utilizzatori, cio\u00e8 ai ricchi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Caschback di Stato: superbonus ai maggiori utilizzatori, cio\u00e8 ai ricchi -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/caschback-di-stato-superbonus-ai-maggiori-utilizzatori-cioe-ai-ricchi\/","og_locale":"it_IT","og_type":"article","og_title":"Caschback di Stato: superbonus ai maggiori utilizzatori, cio\u00e8 ai ricchi -","og_description":"Com&#8217;\u00e8 stato pensato il caschback di Stato premia pochi a danno di troppi. Federcontribuenti: &#8221;100 mila cittadini che effettueranno il maggior numero di transazioni a semestre verranno premiati con un super cashback da 1500 euro. Un premio ai ricchi, solo per i possessori di una carta di credito oro, come i politici ad esempio! Nessun [&hellip;]","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/caschback-di-stato-superbonus-ai-maggiori-utilizzatori-cioe-ai-ricchi\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2020-12-09T14:34:18+00:00","article_modified_time":"2020-12-09T14:34:39+00:00","og_image":[{"width":1120,"height":508,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/12\/Schermata-2020-12-09-alle-15.23.21.png","type":"image\/png"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/caschback-di-stato-superbonus-ai-maggiori-utilizzatori-cioe-ai-ricchi\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/caschback-di-stato-superbonus-ai-maggiori-utilizzatori-cioe-ai-ricchi\/","name":"Caschback di Stato: superbonus ai maggiori utilizzatori, cio\u00e8 ai ricchi -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/caschback-di-stato-superbonus-ai-maggiori-utilizzatori-cioe-ai-ricchi\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/caschback-di-stato-superbonus-ai-maggiori-utilizzatori-cioe-ai-ricchi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/12\/Schermata-2020-12-09-alle-15.23.21.png","datePublished":"2020-12-09T14:34:18+00:00","dateModified":"2020-12-09T14:34:39+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/caschback-di-stato-superbonus-ai-maggiori-utilizzatori-cioe-ai-ricchi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/caschback-di-stato-superbonus-ai-maggiori-utilizzatori-cioe-ai-ricchi\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/caschback-di-stato-superbonus-ai-maggiori-utilizzatori-cioe-ai-ricchi\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/12\/Schermata-2020-12-09-alle-15.23.21.png","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/12\/Schermata-2020-12-09-alle-15.23.21.png","width":1120,"height":508},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/caschback-di-stato-superbonus-ai-maggiori-utilizzatori-cioe-ai-ricchi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"Caschback di Stato: superbonus ai maggiori utilizzatori, cio\u00e8 ai ricchi"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/4844"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=4844"}],"version-history":[{"count":1,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/4844\/revisions"}],"predecessor-version":[{"id":4846,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/4844\/revisions\/4846"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/4845"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=4844"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=4844"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=4844"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}