{"id":4888,"date":"2020-12-15T11:31:26","date_gmt":"2020-12-15T10:31:26","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=4888"},"modified":"2020-12-15T11:31:26","modified_gmt":"2020-12-15T10:31:26","slug":"rinnovato-laccordo-a-n-c-o-t-adiconsum","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/rinnovato-laccordo-a-n-c-o-t-adiconsum\/","title":{"rendered":"Rinnovato l&#8217;accordo A.N.C.O.T. &#8211; Adiconsum"},"content":{"rendered":"<p><span class=\"dropcap dropcap3\"> L<\/span>&#8216;<strong>A.N.CO.T.<\/strong> \u2013 Associazione Nazionale Consulenti Tributari e l&#8217;<strong>Adiconsum<\/strong> hanno deciso di rinnovare l&#8217;accordo paritetico volto a migliorare la trasparenza informativa e l&#8217;individuazione di buone pratiche nel settore della consulenza tributaria.<\/p>\n<p>&nbsp;<\/p>\n<p>L&#8217;obiettivo primario dell&#8217;accordo, sottoscritto dal presidente dell&#8217;<strong>A.N.CO.T.<\/strong> Celestino Bottoni e dal presidente Adiconsum Carlo de Masi, \u00e8 l&#8217;implementazione della tutela dei consumatori, quali utenti dei servizi erogati dagli associati all&#8217;<strong>A.N.CO.T.<\/strong>. Realizzabile attraverso la promozione di attivit\u00e0 congiunte volte a migliorare l&#8217;informazione, la consapevolezza e la qualit\u00e0 dei servizi offerti dagli stessi, anche ai sensi della Legge 4\/2013.<\/p>\n<p>&nbsp;<\/p>\n<p>L&#8217;accordo prevede, inoltre, la costituzione di un <strong>Osservatorio Paritetico Nazionale<\/strong>, per il monitoraggio del comparto della consulenza tributaria e per la promozione e la realizzazione congiunta di tutte le iniziative e le attivit\u00e0 condivise. L&#8217;Osservatorio avr\u00e0 il compito di rilevare le eventuali criticit\u00e0 al fine di predisporre soluzioni migliorative e implementare i diritti e le tutele dei consumatori, attraverso l&#8217;individuazione di buone pratiche.<\/p>\n<p>&nbsp;<\/p>\n<p>L\u2019intento dell&#8217;<strong>A.N.CO.T.<\/strong> e di <strong>Adiconsum<\/strong> \u00e8 quello di ampliare sempre pi\u00f9 la tutela del consumatore andando a confrontarsi con tutte le realt\u00e0 con cui viene in contatto il consumatore per scrivere delle regole che possano essere condivise dai consumatori e da tutti quegli operatori corretti che pongono al centro della loro attivit\u00e0 il consumatore.<\/p>\n<p>&nbsp;<\/p>\n<p>L\u2019associazione <strong>A.N.C.O.T.<\/strong> promuove forme di garanzia a tutela dell\u2019utenza, tra cui l\u2019attivazione di uno sportello di riferimento del cittadino consumatore, presso il quale i committenti delle prestazioni professionali possono rivolgersi in caso di contenzioso con i singoli professionisti, ai sensi dell\u2019art. 27 ter del <strong>Codice del Consumo<\/strong>, di cui al decreto legislativo 206\/2005, nonch\u00e9 ottenere informazioni relative all\u2019attivit\u00e0 professionale in generale e agli standard qualitativi da esse richiesti agli iscritti.<\/p>\n<p>&nbsp;<\/p>\n<p>\u201c<em>Abbiamo voluto rinnovare l&#8217;importante accordo con Adiconsum<\/em> \u2013 ha detto il <strong>Presidente nazionale<\/strong> dell&#8217;<strong>A.N.CO.T. Celestino Bottoni<\/strong> \u2013 consapevoli che era giunto il momento di adeguarlo alle mutate esigenze dell&#8217;utenza e quindi anche dei nostri iscritti. Il progetto, curato dalla vicepresidente della nostra associazione Anna Bonelli, prevede anche la predisposizione di un&#8217;adeguata informativa. Sui temi riguardanti l&#8217;attivit\u00e0 del Tributarista e anche i requisiti e modalit\u00e0 di iscrizione alla nostra associazione e per avviare le pratiche di conciliazione\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p><em>&#8220;Il rinnovo dell\u2019accordo con A.N.CO.T.<\/em> \u2013 dichiara <strong>Carlo De Masi, Presidente di Adiconsum nazionale<\/strong> \u2013 <em>\u00e8 molto importante, perch\u00e9 ci permette di proseguire un lavoro che ci vede impegnati ad assicurare una maggiore tutela a favore dei consumatori, grazie anche alle attivit\u00e0 di formazione dei consulenti tributari di A.N.CO.T per offrire un corretto servizio. Come Adiconsum siamo convinti che il dialogo e il confronto siano gli strumenti giusti per superare le difficolt\u00e0 che possano insorgere. Alla luce della nostra esperienza, possiamo testimoniare che la procedura della conciliazione paritetica sia di estremo aiuto per risolvere in maniera economica e rapida, ma soprattutto soddisfacente per entrambe le parti, un\u2019eventuale controversia. Utili a tal proposito sia la costituzione dell\u2019Osservatorio Paritetico Nazionale che lo \u201cSportello del cittadino<\/em>\u201d&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<p>Gli interessati potranno farlo telefonando al numero <strong>06 44170210<\/strong> dove sar\u00e0 possibile ottenere anche le informazioni per completare la procedura di conciliazione.<\/p>\n<p>Inoltre, \u00e8 possibile visitare i siti internet: <a href=\"http:\/\/www.ancot.it\">Ancot<\/a> &#8211;\u00a0<a href=\"https:\/\/www.adiconsum.it\/\" target=\"_blank\" rel=\"noopener noreferrer\">Adiconsum<\/a> <strong><br \/>\n<\/strong><\/p>\n<table width=\"100%\">\n<tbody>\n<tr>\n<td>\n<table width=\"100%\">\n<tbody>\n<tr>\n<td><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>L&#8216;A.N.CO.T. \u2013 Associazione Nazionale Consulenti Tributari e l&#8217;Adiconsum hanno deciso di rinnovare l&#8217;accordo paritetico volto a migliorare la trasparenza informativa e l&#8217;individuazione di buone pratiche nel settore della consulenza tributaria. &nbsp; L&#8217;obiettivo primario dell&#8217;accordo, sottoscritto dal presidente dell&#8217;A.N.CO.T. Celestino Bottoni e dal presidente Adiconsum Carlo de Masi, \u00e8 l&#8217;implementazione della tutela dei consumatori, quali utenti [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1123,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[56],"tags":[442,1445],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Rinnovato l&#039;accordo A.N.C.O.T. - Adiconsum -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/rinnovato-laccordo-a-n-c-o-t-adiconsum\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rinnovato l&#039;accordo A.N.C.O.T. - Adiconsum -\" \/>\n<meta property=\"og:description\" content=\"L&#8216;A.N.CO.T. \u2013 Associazione Nazionale Consulenti Tributari e l&#8217;Adiconsum hanno deciso di rinnovare l&#8217;accordo paritetico volto a migliorare la trasparenza informativa e l&#8217;individuazione di buone pratiche nel settore della consulenza tributaria. &nbsp; L&#8217;obiettivo primario dell&#8217;accordo, sottoscritto dal presidente dell&#8217;A.N.CO.T. Celestino Bottoni e dal presidente Adiconsum Carlo de Masi, \u00e8 l&#8217;implementazione della tutela dei consumatori, quali utenti [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/rinnovato-laccordo-a-n-c-o-t-adiconsum\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-15T10:31:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/06\/lavoro-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/rinnovato-laccordo-a-n-c-o-t-adiconsum\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/rinnovato-laccordo-a-n-c-o-t-adiconsum\/\",\"name\":\"Rinnovato l'accordo A.N.C.O.T. - Adiconsum -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/rinnovato-laccordo-a-n-c-o-t-adiconsum\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/rinnovato-laccordo-a-n-c-o-t-adiconsum\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/06\/lavoro-3.jpg\",\"datePublished\":\"2020-12-15T10:31:26+00:00\",\"dateModified\":\"2020-12-15T10:31:26+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/rinnovato-laccordo-a-n-c-o-t-adiconsum\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/rinnovato-laccordo-a-n-c-o-t-adiconsum\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/rinnovato-laccordo-a-n-c-o-t-adiconsum\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/06\/lavoro-3.jpg\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/06\/lavoro-3.jpg\",\"width\":960,\"height\":640},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/rinnovato-laccordo-a-n-c-o-t-adiconsum\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rinnovato l&#8217;accordo A.N.C.O.T. &#8211; Adiconsum\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rinnovato l'accordo A.N.C.O.T. - Adiconsum -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/rinnovato-laccordo-a-n-c-o-t-adiconsum\/","og_locale":"it_IT","og_type":"article","og_title":"Rinnovato l'accordo A.N.C.O.T. - Adiconsum -","og_description":"L&#8216;A.N.CO.T. \u2013 Associazione Nazionale Consulenti Tributari e l&#8217;Adiconsum hanno deciso di rinnovare l&#8217;accordo paritetico volto a migliorare la trasparenza informativa e l&#8217;individuazione di buone pratiche nel settore della consulenza tributaria. &nbsp; L&#8217;obiettivo primario dell&#8217;accordo, sottoscritto dal presidente dell&#8217;A.N.CO.T. Celestino Bottoni e dal presidente Adiconsum Carlo de Masi, \u00e8 l&#8217;implementazione della tutela dei consumatori, quali utenti [&hellip;]","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/rinnovato-laccordo-a-n-c-o-t-adiconsum\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2020-12-15T10:31:26+00:00","og_image":[{"width":960,"height":640,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/06\/lavoro-3.jpg","type":"image\/jpeg"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/rinnovato-laccordo-a-n-c-o-t-adiconsum\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/rinnovato-laccordo-a-n-c-o-t-adiconsum\/","name":"Rinnovato l'accordo A.N.C.O.T. - Adiconsum -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/rinnovato-laccordo-a-n-c-o-t-adiconsum\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/rinnovato-laccordo-a-n-c-o-t-adiconsum\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/06\/lavoro-3.jpg","datePublished":"2020-12-15T10:31:26+00:00","dateModified":"2020-12-15T10:31:26+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/rinnovato-laccordo-a-n-c-o-t-adiconsum\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/rinnovato-laccordo-a-n-c-o-t-adiconsum\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/rinnovato-laccordo-a-n-c-o-t-adiconsum\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/06\/lavoro-3.jpg","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/06\/lavoro-3.jpg","width":960,"height":640},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/rinnovato-laccordo-a-n-c-o-t-adiconsum\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"Rinnovato l&#8217;accordo A.N.C.O.T. &#8211; Adiconsum"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/4888"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=4888"}],"version-history":[{"count":1,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/4888\/revisions"}],"predecessor-version":[{"id":4889,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/4888\/revisions\/4889"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/1123"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=4888"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=4888"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=4888"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}