{"id":4893,"date":"2020-12-15T12:07:16","date_gmt":"2020-12-15T11:07:16","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=4893"},"modified":"2020-12-15T12:07:16","modified_gmt":"2020-12-15T11:07:16","slug":"istat-uecoop-con-15-anziani-in-italia-e-sfida-servizi","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/istat-uecoop-con-15-anziani-in-italia-e-sfida-servizi\/","title":{"rendered":"Istat, UECOOP: con +1,5 anziani in Italia \u00e8 sfida servizi"},"content":{"rendered":"<p><span class=\"dropcap dropcap3\">C<\/span>on quasi 1,5 milioni di anziani over 65 in pi\u00f9 in Italia \u00e8 necessario aumentare i servizi e l\u2019assistenza sul territorio nazionale anche nelle aree pi\u00f9 svantaggiate e isolate.<\/p>\n<p>E\u2019 quanto emerge da una analisi dell\u2019Unione europea delle cooperative (Uecoop) in riferimento agli ultimi dati Istat sul censimento della popolazione italiana con l\u2019emergenza Covid che sta colpendo gli anziani in famiglia e nelle case di riposo.<\/p>\n<p>&nbsp;<\/p>\n<p>La percentuale di popolazione con oltre 65 anni \u00e8 passata dal 20,8% (12.384.972 persone) del 2011 al 23,2% (13.859.090) nel 2019 \u2013 sottolinea Uecoop \u2013 e un aumento sensibile si registra anche per le et\u00e0 pi\u00f9 avanzate con gli ultrasettantacinquenni, passati dal 10,4% del 2011 (6.152.413) all\u201911,9% del 2019 (7.063.716), e gli ultra 85enni, che passano dal 2,8 al 3,7% sul totale della popolazione. In pratica \u2013 evidenzia Uecoop \u2013 ci sono 5 anziani per ogni bambino in Italia.<\/p>\n<p>&nbsp;<\/p>\n<p>In una realt\u00e0 come quella italiana dove gli anziani sono sempre pi\u00f9 al centro dello scenario sociale \u2013 spiega Uecoop \u2013 serve un continuo miglioramento dei servizi di welfare che vedono con in prima linea 350mila operatori di cooperative sociali e di assistenza che seguono 7 milioni di famiglie affiancando il lavoro dei servizi pubblici. L\u2019allungamento della vita \u2013 evidenzia Uecoop \u2013 sta cambiando le metodologie di cura in relazione ai nuovi bisogni della popolazione. Si sta delineando \u2013 sottolinea Uecoop \u2013 una societ\u00e0 dove gli anziani cresceranno ancora di numero insieme al bisogno di assistenza e servizi sia nelle citt\u00e0 che nei piccoli centri urbani a fronte di network familiari con minor capacit\u00e0 di seguire i parenti pi\u00f9 avanti negli anni.<\/p>\n<p>&nbsp;<\/p>\n<p>E nonostante le quasi 8mila case di riposo italiane abbiano in media un buon livello di qualit\u00e0 dell\u2019assistenza e siano cresciute del 30% in dieci anni \u2013 spiega un\u2019analisi di Uecoop \u2013 la disponibilit\u00e0 media a livello nazionale \u00e8 solo di 1 posto letto ogni 41 anziani con richieste in aumento nonostante rette che vanno dai 1.000 ai 3.000 euro al mese a seconda della posizione della struttura, dai servizi offerti e dalla possibilit\u00e0 di ospitare anche a persone non autosufficienti.<\/p>\n<p>&nbsp;<\/p>\n<p>Proprio gli anziani non autosufficienti \u2013 sottolinea Uecoop \u2013 raddoppieranno fino a quasi 5 milioni entro il 2030. In base agli ultimi dati disponibili \u2013 spiega Uecoop \u20131 anziano su 3 ha gravi difficolt\u00e0 a prepararsi da mangiare, fare la spesa, prendere le medicine, pulire la casa, mentre addirittura pi\u00f9 dell\u201911% ha problemi a prendersi cura di se stesso: dal fare il bagno o la doccia a sdraiarsi o sedersi sul letto fino a indossare abiti o svestirsi. Una situazione \u2013 conclude Uecoop \u2013 che impone di organizzare un sistema di welfare in grado di soddisfare la domanda di assistenza e servizi delle famiglie italiane potenziando la collaborazione fra il settore pubblico e quello privato.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con quasi 1,5 milioni di anziani over 65 in pi\u00f9 in Italia \u00e8 necessario aumentare i servizi e l\u2019assistenza sul territorio nazionale anche nelle aree pi\u00f9 svantaggiate e isolate. E\u2019 quanto emerge da una analisi dell\u2019Unione europea delle cooperative (Uecoop) in riferimento agli ultimi dati Istat sul censimento della popolazione italiana con l\u2019emergenza Covid che [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2460,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[56],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Istat, UECOOP: con +1,5 anziani in Italia \u00e8 sfida servizi -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/istat-uecoop-con-15-anziani-in-italia-e-sfida-servizi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Istat, UECOOP: con +1,5 anziani in Italia \u00e8 sfida servizi -\" \/>\n<meta property=\"og:description\" content=\"Con quasi 1,5 milioni di anziani over 65 in pi\u00f9 in Italia \u00e8 necessario aumentare i servizi e l\u2019assistenza sul territorio nazionale anche nelle aree pi\u00f9 svantaggiate e isolate. E\u2019 quanto emerge da una analisi dell\u2019Unione europea delle cooperative (Uecoop) in riferimento agli ultimi dati Istat sul censimento della popolazione italiana con l\u2019emergenza Covid che [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/istat-uecoop-con-15-anziani-in-italia-e-sfida-servizi\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-15T11:07:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/02\/hands-981400_1280.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"853\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/istat-uecoop-con-15-anziani-in-italia-e-sfida-servizi\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/istat-uecoop-con-15-anziani-in-italia-e-sfida-servizi\/\",\"name\":\"Istat, UECOOP: con +1,5 anziani in Italia \u00e8 sfida servizi -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/istat-uecoop-con-15-anziani-in-italia-e-sfida-servizi\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/istat-uecoop-con-15-anziani-in-italia-e-sfida-servizi\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/02\/hands-981400_1280.jpg\",\"datePublished\":\"2020-12-15T11:07:16+00:00\",\"dateModified\":\"2020-12-15T11:07:16+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/istat-uecoop-con-15-anziani-in-italia-e-sfida-servizi\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/istat-uecoop-con-15-anziani-in-italia-e-sfida-servizi\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/istat-uecoop-con-15-anziani-in-italia-e-sfida-servizi\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/02\/hands-981400_1280.jpg\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/02\/hands-981400_1280.jpg\",\"width\":1280,\"height\":853},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/istat-uecoop-con-15-anziani-in-italia-e-sfida-servizi\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Istat, UECOOP: con +1,5 anziani in Italia \u00e8 sfida servizi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Istat, UECOOP: con +1,5 anziani in Italia \u00e8 sfida servizi -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/istat-uecoop-con-15-anziani-in-italia-e-sfida-servizi\/","og_locale":"it_IT","og_type":"article","og_title":"Istat, UECOOP: con +1,5 anziani in Italia \u00e8 sfida servizi -","og_description":"Con quasi 1,5 milioni di anziani over 65 in pi\u00f9 in Italia \u00e8 necessario aumentare i servizi e l\u2019assistenza sul territorio nazionale anche nelle aree pi\u00f9 svantaggiate e isolate. E\u2019 quanto emerge da una analisi dell\u2019Unione europea delle cooperative (Uecoop) in riferimento agli ultimi dati Istat sul censimento della popolazione italiana con l\u2019emergenza Covid che [&hellip;]","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/istat-uecoop-con-15-anziani-in-italia-e-sfida-servizi\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2020-12-15T11:07:16+00:00","og_image":[{"width":1280,"height":853,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/02\/hands-981400_1280.jpg","type":"image\/jpeg"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/istat-uecoop-con-15-anziani-in-italia-e-sfida-servizi\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/istat-uecoop-con-15-anziani-in-italia-e-sfida-servizi\/","name":"Istat, UECOOP: con +1,5 anziani in Italia \u00e8 sfida servizi -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/istat-uecoop-con-15-anziani-in-italia-e-sfida-servizi\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/istat-uecoop-con-15-anziani-in-italia-e-sfida-servizi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/02\/hands-981400_1280.jpg","datePublished":"2020-12-15T11:07:16+00:00","dateModified":"2020-12-15T11:07:16+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/istat-uecoop-con-15-anziani-in-italia-e-sfida-servizi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/istat-uecoop-con-15-anziani-in-italia-e-sfida-servizi\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/istat-uecoop-con-15-anziani-in-italia-e-sfida-servizi\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/02\/hands-981400_1280.jpg","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/02\/hands-981400_1280.jpg","width":1280,"height":853},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/istat-uecoop-con-15-anziani-in-italia-e-sfida-servizi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"Istat, UECOOP: con +1,5 anziani in Italia \u00e8 sfida servizi"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/4893"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=4893"}],"version-history":[{"count":1,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/4893\/revisions"}],"predecessor-version":[{"id":4894,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/4893\/revisions\/4894"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/2460"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=4893"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=4893"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=4893"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}