{"id":4904,"date":"2020-12-16T10:23:50","date_gmt":"2020-12-16T09:23:50","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=4904"},"modified":"2020-12-16T10:23:50","modified_gmt":"2020-12-16T09:23:50","slug":"475-miliardi-di-euro-alle-regioni-per-affrontare-le-conseguenze-immediate-del-covid-19","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/475-miliardi-di-euro-alle-regioni-per-affrontare-le-conseguenze-immediate-del-covid-19\/","title":{"rendered":"47,5 miliardi di euro alle regioni per affrontare le conseguenze immediate del COVID-19"},"content":{"rendered":"<div class=\"ep_gridcolumn ep-m_product\" data-view1200=\"6\" data-view1020=\"6\" data-view750=\"10\" data-view640=\"6\" data-view480=\"8\" data-view320=\"4\">\n<div class=\"ep_gridcolumn-content\">\n<div class=\"ep-a_text ep-layout_chapo\">\n<p><span class=\"dropcap dropcap3\">I<\/span> deputati hanno dato il via libera a aiuti UE extra per le regioni, in risposta alla pandemia di COVID-19 e alle sue conseguenze sociali e sanitarie.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"ep_gridcolumn ep-m_product\" data-view1200=\"6\" data-view1020=\"6\" data-view750=\"10\" data-view640=\"6\" data-view480=\"8\" data-view320=\"4\">\n<div class=\"ep_gridcolumn-content\">\n<div class=\"ep-a_text\">\n<p class=\"ep-wysiwig_paragraph\">Il Parlamento ha approvato REACT-EU, un pacchetto da 47,5 miliardi di euro per contribuire a mitigare gli effetti immediati della crisi di COVID-19 nelle regioni dell&#8217;UE. L&#8217;iniziativa \u00e8 stata approvata con 654 voti favorevoli, 23 contrari e 17 astensioni.<\/p>\n<p class=\"ep-wysiwig_paragraph\">\nGli aiuti saranno erogati attraverso i Fondi strutturali dell&#8217;UE. Sono stati stanziati 37,5 miliardi di euro per il 2021 e 10 miliardi di euro per il 2022. Le operazioni di REACT-EU sono ammissibili al finanziamento dal 1\u00b0 febbraio 2020, con effetto retroattivo. Le risorse possono essere spese fino alla fine del 2023.<\/p>\n<p class=\"ep-wysiwig_paragraph\">\nI paesi UE potranno destinare parte delle risorse al Fondo sociale europeo, al Fondo per gli aiuti europei agli indigenti (FEAD), all&#8217;Iniziativa a favore dell&#8217;occupazione giovanile e ai programmi transfrontalieri (Interreg). Gli investimenti si concentreranno sui settori pi\u00f9 colpiti dalle ripercussioni economiche della pandemia.<\/p>\n<p class=\"ep-wysiwig_paragraph\">REACT-EU \u00e8 una proposta della Commissione europea per affrontare l&#8217;impatto economico e sociale della pandemia di COVID-19. Si tratta di una modifica del <a href=\"https:\/\/eur-lex.europa.eu\/legal-content\/IT\/TXT\/?uri=CELEX%3A02013R1303-20200718\" target=\"_blank\" rel=\"noopener noreferrer\">regolamento sulle disposizioni comuni<\/a>, che disciplina il periodo di programmazione della politica di coesione 2014-2020.<\/p>\n<p class=\"ep-wysiwig_paragraph\">\nFa seguito a due precedenti proposte relative alla politica di coesione: l&#8217;<a href=\"https:\/\/eur-lex.europa.eu\/legal-content\/IT\/TXT\/?qid=1607688003272&amp;uri=CELEX%3A32020R0460\" target=\"_blank\" rel=\"noopener noreferrer\">Iniziativa di investimento in risposta al coronavirus (CRII)<\/a> e l&#8217;<a href=\"https:\/\/eur-lex.europa.eu\/legal-content\/IT\/TXT\/?qid=1607688174925&amp;uri=CELEX%3A32020R0558\" target=\"_blank\" rel=\"noopener noreferrer\">Iniziativa di investimento in risposta al coronavirus Plus (CRII+)<\/a>, che hanno entrambe modificato le norme sulla spesa regionale per agevolare la ripresa. Le risorse per REACT-EU verranno da Next Generation EU, lo <a href=\"https:\/\/oeil.secure.europarl.europa.eu\/oeil\/popups\/ficheprocedure.do?reference=COM(2020)0441&amp;l=en\" target=\"_blank\" rel=\"noopener noreferrer\">strumento dell&#8217;Unione europea per la ripresa<\/a>.<\/p>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>I deputati hanno dato il via libera a aiuti UE extra per le regioni, in risposta alla pandemia di COVID-19 e alle sue conseguenze sociali e sanitarie. Il Parlamento ha approvato REACT-EU, un pacchetto da 47,5 miliardi di euro per contribuire a mitigare gli effetti immediati della crisi di COVID-19 nelle regioni dell&#8217;UE. L&#8217;iniziativa \u00e8 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1724,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[970],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>47,5 miliardi di euro alle regioni per affrontare le conseguenze immediate del COVID-19 -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/475-miliardi-di-euro-alle-regioni-per-affrontare-le-conseguenze-immediate-del-covid-19\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"47,5 miliardi di euro alle regioni per affrontare le conseguenze immediate del COVID-19 -\" \/>\n<meta property=\"og:description\" content=\"I deputati hanno dato il via libera a aiuti UE extra per le regioni, in risposta alla pandemia di COVID-19 e alle sue conseguenze sociali e sanitarie. Il Parlamento ha approvato REACT-EU, un pacchetto da 47,5 miliardi di euro per contribuire a mitigare gli effetti immediati della crisi di COVID-19 nelle regioni dell&#8217;UE. L&#8217;iniziativa \u00e8 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/475-miliardi-di-euro-alle-regioni-per-affrontare-le-conseguenze-immediate-del-covid-19\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-16T09:23:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/09\/soldi.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"486\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/475-miliardi-di-euro-alle-regioni-per-affrontare-le-conseguenze-immediate-del-covid-19\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/475-miliardi-di-euro-alle-regioni-per-affrontare-le-conseguenze-immediate-del-covid-19\/\",\"name\":\"47,5 miliardi di euro alle regioni per affrontare le conseguenze immediate del COVID-19 -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/475-miliardi-di-euro-alle-regioni-per-affrontare-le-conseguenze-immediate-del-covid-19\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/475-miliardi-di-euro-alle-regioni-per-affrontare-le-conseguenze-immediate-del-covid-19\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/09\/soldi.jpg\",\"datePublished\":\"2020-12-16T09:23:50+00:00\",\"dateModified\":\"2020-12-16T09:23:50+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/475-miliardi-di-euro-alle-regioni-per-affrontare-le-conseguenze-immediate-del-covid-19\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/475-miliardi-di-euro-alle-regioni-per-affrontare-le-conseguenze-immediate-del-covid-19\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/475-miliardi-di-euro-alle-regioni-per-affrontare-le-conseguenze-immediate-del-covid-19\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/09\/soldi.jpg\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/09\/soldi.jpg\",\"width\":960,\"height\":486},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/475-miliardi-di-euro-alle-regioni-per-affrontare-le-conseguenze-immediate-del-covid-19\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"47,5 miliardi di euro alle regioni per affrontare le conseguenze immediate del COVID-19\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"47,5 miliardi di euro alle regioni per affrontare le conseguenze immediate del COVID-19 -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/475-miliardi-di-euro-alle-regioni-per-affrontare-le-conseguenze-immediate-del-covid-19\/","og_locale":"it_IT","og_type":"article","og_title":"47,5 miliardi di euro alle regioni per affrontare le conseguenze immediate del COVID-19 -","og_description":"I deputati hanno dato il via libera a aiuti UE extra per le regioni, in risposta alla pandemia di COVID-19 e alle sue conseguenze sociali e sanitarie. Il Parlamento ha approvato REACT-EU, un pacchetto da 47,5 miliardi di euro per contribuire a mitigare gli effetti immediati della crisi di COVID-19 nelle regioni dell&#8217;UE. L&#8217;iniziativa \u00e8 [&hellip;]","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/475-miliardi-di-euro-alle-regioni-per-affrontare-le-conseguenze-immediate-del-covid-19\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2020-12-16T09:23:50+00:00","og_image":[{"width":960,"height":486,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/09\/soldi.jpg","type":"image\/jpeg"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/475-miliardi-di-euro-alle-regioni-per-affrontare-le-conseguenze-immediate-del-covid-19\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/475-miliardi-di-euro-alle-regioni-per-affrontare-le-conseguenze-immediate-del-covid-19\/","name":"47,5 miliardi di euro alle regioni per affrontare le conseguenze immediate del COVID-19 -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/475-miliardi-di-euro-alle-regioni-per-affrontare-le-conseguenze-immediate-del-covid-19\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/475-miliardi-di-euro-alle-regioni-per-affrontare-le-conseguenze-immediate-del-covid-19\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/09\/soldi.jpg","datePublished":"2020-12-16T09:23:50+00:00","dateModified":"2020-12-16T09:23:50+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/475-miliardi-di-euro-alle-regioni-per-affrontare-le-conseguenze-immediate-del-covid-19\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/475-miliardi-di-euro-alle-regioni-per-affrontare-le-conseguenze-immediate-del-covid-19\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/475-miliardi-di-euro-alle-regioni-per-affrontare-le-conseguenze-immediate-del-covid-19\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/09\/soldi.jpg","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/09\/soldi.jpg","width":960,"height":486},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/475-miliardi-di-euro-alle-regioni-per-affrontare-le-conseguenze-immediate-del-covid-19\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"47,5 miliardi di euro alle regioni per affrontare le conseguenze immediate del COVID-19"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/4904"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=4904"}],"version-history":[{"count":1,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/4904\/revisions"}],"predecessor-version":[{"id":4905,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/4904\/revisions\/4905"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/1724"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=4904"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=4904"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=4904"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}