{"id":4978,"date":"2020-12-28T14:39:37","date_gmt":"2020-12-28T13:39:37","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=4978"},"modified":"2020-12-28T14:39:37","modified_gmt":"2020-12-28T13:39:37","slug":"con-la-pandemia-a-rischio-oltre-il-10-dei-posti-di-lavoro-nelle-pmi","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/con-la-pandemia-a-rischio-oltre-il-10-dei-posti-di-lavoro-nelle-pmi\/","title":{"rendered":"Con la pandemia a rischio oltre il 10% dei posti di lavoro nelle PMI"},"content":{"rendered":"<p><span class=\"dropcap dropcap3\">M<\/span>igliora la fiducia sul futuro della ripresa economica. Ma per l\u2019occupazione lo scenario resta critico.<\/p>\n<p>Con lo sblocco dei licenziamenti, si rischia di vedere sfumare pi\u00f9 del 10% dei posti di lavoro delle PMI da inizio 2020. Va peggio, per\u00f2, nel lavoro autonomo, dove l\u2019urto della crisi sembra aver inciso fino ad oggi in maniera pi\u00f9 incisiva. Il comparto potrebbe arrivare a perdere fino al 14% della base occupazionale per effetto della pandemia.<\/p>\n<p>\u00c8 quanto emerge dal Secondo Rapporto di monitoraggio sulla crisi da Covid-19 elaborato dallaFondazione Studi Consulenti del Lavoroa partire dalle risposte di una base di oltre 3mila iscritti all\u2019Ordine, che dall\u2019inizio dell\u2019emergenza stanno assistendo imprese per lo pi\u00f9 di medie e piccole dimensioni e lavoratori nelle loro attivit\u00e0, a partire dal supporto nell\u2019accesso agli strumenti di sostegno al reddito.<\/p>\n<p>Il monitoraggio, condotto nella prima met\u00e0 del mese di dicembre, a distanza di due mesi dalla precedente rilevazione, per le PMI evidenzia in particolare che: le imprese ritorneranno ai livelli di fatturato pre-crisi entro il 2022 (la pensa cosi il 69,2% contro il 53,2% degli intervistati ad ottobre); gli organici delle PMI potrebbero ridursi mediamente dell\u201911,7% (anche se il 22,2% degli intervistati pensa che la riduzione sar\u00e0 tra il 10% e il 14% mentre il 6,8% di loro individua un valore uguale o superiore al 25%).<\/p>\n<p>Stando alle risposte dei Consulenti del Lavoro, il grosso delle perdite si registrer\u00e0 nel settore degli alloggi e della ristorazione, che secondo la met\u00e0 degli intervistati (49,3%) subir\u00e0 una riduzione degli organici aziendali superiore al 15% mentre per il 26,7% compresa tra il 10% e 15%, seguito, a distanza, dal commercio, con organici previsti in fortissima (pi\u00f9 del 15%) e forte (tra 10% e 15%) riduzione rispettivamente dal 25,9% e 29,2% degli intervistati e infine i servizi ricreativi, culturali e sportivi, per cui le previsioni oscillano tra la fortissima (27,7%) e forte (25,4%) contrazione. Un capitolo a parte merita lo scenario di peggioramento delle previsioni sul lavoro autonomo.<\/p>\n<p>Un universo \u2013composto da imprenditori, artigiani, commercianti, professionisti e partite Iva -che in questi mesi ha pagato un prezzo pesante per effetto della crisi, ma che rischia in prospettiva di vedere assottigliarsi ancora di pi\u00f9 le proprie fila: rispetto ad inizio anno, i Consulenti del Lavoro stimano che la riduzione media delle attivit\u00e0 in proprio prodotta dalla pandemia sar\u00e0 del 14,6%, mentre ad ottobre il dato si collocava al 13,6%.<\/p>\n<p>Con il nuovo anno e l\u2019orizzonte di un ritorno graduale alla normalit\u00e0, grazie alle prospettive aperte dai vaccini, le aziende avranno come principale obiettivo il recupero e l\u2019innalzamento dei livelli di produttivit\u00e0, e la ricostruzione di un clima di lavoro sereno all\u2019interno dellestrutture. Cos\u00ec la pensa pi\u00f9 della met\u00e0 degli interpellati, che individua come prioritari i due obiettivi (li giudica a priorit\u00e0 elevata e molto elevata rispettivamente il 62,4% e 55,6% dei rispondenti); ma anche la riorganizzazione interna dei processi lavorativi rivestir\u00e0 un ruolo importante nell\u2019orientare le strategie aziendali sulle risorse umane (51,9%). \u201cAccanto a questi problemi e alle previsioni strutturali, ci sono poi da considerare le difficolt\u00e0 di gestione delle risorse umane causate dalla pandemia e dal ricorso agli strumenti di integrazione salariale\u201d, commenta il Presidente della Fondazione Studi Consulenti del Lavoro, Rosario De Luca.<\/p>\n<p>\u201cLe criticit\u00e0 legate all\u2019eccezionalit\u00e0 della fase economica e sanitaria, derivanti dal clima di incertezza, dalla difficolt\u00e0 di programmazione, dalla gestione del lavoro a distanza, dallo stress dei lavoratori, finiscono per affossare le organizzazioni e, assieme ad esse, il clima e la qualit\u00e0 di lavoro\u201d, ha aggiunto. E, infatti, secondo il 46,8% dei colleghi ilmaggiore affanno \u00e8 quello legato alla gestione del personale, accanto agli adempimenti per la Cig, naturalmente, indicati da ben il 48,3% di loro, mentre il 7% dei dipendenti \u00e8 in attesa da oltre due mesi del pagamento della cassa. Con effetti sulla stessa produttivit\u00e0 aziendale, indicata al terzo posto (42,7%) quale principale problema che le aziende stanno affrontando in questa fase, con riferimento alla gestione delle risorse umane<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Migliora la fiducia sul futuro della ripresa economica. Ma per l\u2019occupazione lo scenario resta critico. Con lo sblocco dei licenziamenti, si rischia di vedere sfumare pi\u00f9 del 10% dei posti di lavoro delle PMI da inizio 2020. Va peggio, per\u00f2, nel lavoro autonomo, dove l\u2019urto della crisi sembra aver inciso fino ad oggi in maniera [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4979,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[56],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Con la pandemia a rischio oltre il 10% dei posti di lavoro nelle PMI -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/con-la-pandemia-a-rischio-oltre-il-10-dei-posti-di-lavoro-nelle-pmi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Con la pandemia a rischio oltre il 10% dei posti di lavoro nelle PMI -\" \/>\n<meta property=\"og:description\" content=\"Migliora la fiducia sul futuro della ripresa economica. Ma per l\u2019occupazione lo scenario resta critico. Con lo sblocco dei licenziamenti, si rischia di vedere sfumare pi\u00f9 del 10% dei posti di lavoro delle PMI da inizio 2020. Va peggio, per\u00f2, nel lavoro autonomo, dove l\u2019urto della crisi sembra aver inciso fino ad oggi in maniera [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/con-la-pandemia-a-rischio-oltre-il-10-dei-posti-di-lavoro-nelle-pmi\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-28T13:39:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/12\/Schermata-2020-12-28-alle-14.38.49.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1538\" \/>\n\t<meta property=\"og:image:height\" content=\"948\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/con-la-pandemia-a-rischio-oltre-il-10-dei-posti-di-lavoro-nelle-pmi\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/con-la-pandemia-a-rischio-oltre-il-10-dei-posti-di-lavoro-nelle-pmi\/\",\"name\":\"Con la pandemia a rischio oltre il 10% dei posti di lavoro nelle PMI -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/con-la-pandemia-a-rischio-oltre-il-10-dei-posti-di-lavoro-nelle-pmi\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/con-la-pandemia-a-rischio-oltre-il-10-dei-posti-di-lavoro-nelle-pmi\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/12\/Schermata-2020-12-28-alle-14.38.49.png\",\"datePublished\":\"2020-12-28T13:39:37+00:00\",\"dateModified\":\"2020-12-28T13:39:37+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/con-la-pandemia-a-rischio-oltre-il-10-dei-posti-di-lavoro-nelle-pmi\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/con-la-pandemia-a-rischio-oltre-il-10-dei-posti-di-lavoro-nelle-pmi\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/con-la-pandemia-a-rischio-oltre-il-10-dei-posti-di-lavoro-nelle-pmi\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/12\/Schermata-2020-12-28-alle-14.38.49.png\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/12\/Schermata-2020-12-28-alle-14.38.49.png\",\"width\":1538,\"height\":948},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/con-la-pandemia-a-rischio-oltre-il-10-dei-posti-di-lavoro-nelle-pmi\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Con la pandemia a rischio oltre il 10% dei posti di lavoro nelle PMI\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Con la pandemia a rischio oltre il 10% dei posti di lavoro nelle PMI -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/con-la-pandemia-a-rischio-oltre-il-10-dei-posti-di-lavoro-nelle-pmi\/","og_locale":"it_IT","og_type":"article","og_title":"Con la pandemia a rischio oltre il 10% dei posti di lavoro nelle PMI -","og_description":"Migliora la fiducia sul futuro della ripresa economica. Ma per l\u2019occupazione lo scenario resta critico. Con lo sblocco dei licenziamenti, si rischia di vedere sfumare pi\u00f9 del 10% dei posti di lavoro delle PMI da inizio 2020. Va peggio, per\u00f2, nel lavoro autonomo, dove l\u2019urto della crisi sembra aver inciso fino ad oggi in maniera [&hellip;]","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/con-la-pandemia-a-rischio-oltre-il-10-dei-posti-di-lavoro-nelle-pmi\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2020-12-28T13:39:37+00:00","og_image":[{"width":1538,"height":948,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/12\/Schermata-2020-12-28-alle-14.38.49.png","type":"image\/png"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/con-la-pandemia-a-rischio-oltre-il-10-dei-posti-di-lavoro-nelle-pmi\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/con-la-pandemia-a-rischio-oltre-il-10-dei-posti-di-lavoro-nelle-pmi\/","name":"Con la pandemia a rischio oltre il 10% dei posti di lavoro nelle PMI -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/con-la-pandemia-a-rischio-oltre-il-10-dei-posti-di-lavoro-nelle-pmi\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/con-la-pandemia-a-rischio-oltre-il-10-dei-posti-di-lavoro-nelle-pmi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/12\/Schermata-2020-12-28-alle-14.38.49.png","datePublished":"2020-12-28T13:39:37+00:00","dateModified":"2020-12-28T13:39:37+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/con-la-pandemia-a-rischio-oltre-il-10-dei-posti-di-lavoro-nelle-pmi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/con-la-pandemia-a-rischio-oltre-il-10-dei-posti-di-lavoro-nelle-pmi\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/con-la-pandemia-a-rischio-oltre-il-10-dei-posti-di-lavoro-nelle-pmi\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/12\/Schermata-2020-12-28-alle-14.38.49.png","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/12\/Schermata-2020-12-28-alle-14.38.49.png","width":1538,"height":948},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/con-la-pandemia-a-rischio-oltre-il-10-dei-posti-di-lavoro-nelle-pmi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"Con la pandemia a rischio oltre il 10% dei posti di lavoro nelle PMI"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/4978"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=4978"}],"version-history":[{"count":1,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/4978\/revisions"}],"predecessor-version":[{"id":4980,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/4978\/revisions\/4980"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/4979"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=4978"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=4978"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=4978"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}