{"id":4986,"date":"2020-12-30T10:34:36","date_gmt":"2020-12-30T09:34:36","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=4986"},"modified":"2020-12-30T10:34:36","modified_gmt":"2020-12-30T09:34:36","slug":"transazione-fiscale-nelle-crisi-di-impresa-una-circolare-dellagenzia-delle-entrate-illustra-le-nuove-procedure","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/transazione-fiscale-nelle-crisi-di-impresa-una-circolare-dellagenzia-delle-entrate-illustra-le-nuove-procedure\/","title":{"rendered":"Transazione fiscale nelle crisi di impresa. Una circolare dell\u2019Agenzia delle Entrate illustra le nuove procedure"},"content":{"rendered":"<p><span class=\"dropcap dropcap3\">A<\/span>rrivano le istruzioni delle Entrate ai propri uffici per garantire una tempestiva gestione delle procedure di composizione delle crisi di impresa e per fornire supporto agli operatori che si trovano ad affrontare l\u2019attuale congiuntura economica.Con la circolare n. 34\/E firmata oggi dal direttore delle Entrate, Ernesto Maria Ruffini, sulla base delle modifiche normative introdotte dalla legge n. 159\/2020, sono delineate le regole per la valutazione delle proposte di trattamento del credito tributario presentate dai contribuenti, nell\u2019ottica di favorire la ripresa produttiva e la conservazione dei posti di lavoro.<\/p>\n<p>Considerato il crescente ricorso alla transazione fiscale nelle crisi di impresa, e tenuto conto anche delle ripercussioni finanziarie sugli operatori economici determinate dall\u2019emergenza Covid-19, la circolare intende rappresentare un utile vademecum per orientare e uniformare il comportamento degli Uffici su tutto il territorio nazionale. Dopo un breve excursus normativo, il documento fornisce infatti indicazioni agli Uffici sulla valutazione delle proposte di trattamento del credito tributario presentate dai contribuenti, sul rapporto con i rappresentanti dell\u2019imprenditore in stato di crisi e con il Commissario giudiziale.<\/p>\n<p>Le due vie percorribili-La circolare si sofferma anche sull\u2019accordo di ristrutturazione dei debiti e sul concordato preventivo, ossia le due procedure cui il debitore pu\u00f2 far ricorso, a seconda dei casi, ai fini della composizione della crisi d\u2019impresa, descrivendone la disciplina normativa, i requisiti di ammissibilit\u00e0, gli oneri a carico dei soggetti interessati e gli effetti.<\/p>\n<p>Il ruolo dei professionisti \u2013 L\u2019Agenzia ricorda nel documento che gliinterventi legislativi in materia di composizione della crisi di impresa hanno, progressivamente, assegnato ai professionisti che attestano la veridicit\u00e0 dei dati aziendali e l\u2019attuabilit\u00e0 dell\u2019accordo un ruolo sempre pi\u00f9 rilevante, da assolvere con rigore, competenza e trasparenza per assicurare la corretta riuscita della procedura.<\/p>\n<p>La circolare illustra quindi anchegli elementi che devono essere necessariamente riportati nella relazione del professionista, che rappresenta il supporto su cui si fondano le valutazioni dei creditoriin merito alle proposte di soddisfacimento dei crediti.<\/p>\n<p>Le indicazioni agli Uffici \u2013Con la circolare vengono, quindi, impartite le indicazioni operative alle strutture territorialidelle Entrate,finalizzate a garantire un approccio uniforme, su tutto il territorio nazionale, all\u2019attivit\u00e0 di valutazione delle proposte di trattamento dei crediti tributari.L\u2019Agenzia evidenzia che perritenere accoglibile una proposta di trattamento del credito tributario occorre sostanzialmente valutare la maggiore, o minore, convenienza economica della stessa rispetto all\u2019alternativa liquidatoria, anche in considerazione della relazione di attestazione del professionista.<\/p>\n<div class=\"page\" data-page-number=\"1\" data-loaded=\"true\">\n<div class=\"annotationLayer\"><\/div>\n<\/div>\n<div class=\"page\" data-page-number=\"2\" data-loaded=\"true\">\n<div class=\"canvasWrapper\"><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Arrivano le istruzioni delle Entrate ai propri uffici per garantire una tempestiva gestione delle procedure di composizione delle crisi di impresa e per fornire supporto agli operatori che si trovano ad affrontare l\u2019attuale congiuntura economica.Con la circolare n. 34\/E firmata oggi dal direttore delle Entrate, Ernesto Maria Ruffini, sulla base delle modifiche normative introdotte dalla [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1528,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41],"tags":[393],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Transazione fiscale nelle crisi di impresa. Una circolare dell\u2019Agenzia delle Entrate illustra le nuove procedure -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/transazione-fiscale-nelle-crisi-di-impresa-una-circolare-dellagenzia-delle-entrate-illustra-le-nuove-procedure\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Transazione fiscale nelle crisi di impresa. Una circolare dell\u2019Agenzia delle Entrate illustra le nuove procedure -\" \/>\n<meta property=\"og:description\" content=\"Arrivano le istruzioni delle Entrate ai propri uffici per garantire una tempestiva gestione delle procedure di composizione delle crisi di impresa e per fornire supporto agli operatori che si trovano ad affrontare l\u2019attuale congiuntura economica.Con la circolare n. 34\/E firmata oggi dal direttore delle Entrate, Ernesto Maria Ruffini, sulla base delle modifiche normative introdotte dalla [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/transazione-fiscale-nelle-crisi-di-impresa-una-circolare-dellagenzia-delle-entrate-illustra-le-nuove-procedure\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-30T09:34:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/08\/fisco-tasse.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"678\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/transazione-fiscale-nelle-crisi-di-impresa-una-circolare-dellagenzia-delle-entrate-illustra-le-nuove-procedure\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/transazione-fiscale-nelle-crisi-di-impresa-una-circolare-dellagenzia-delle-entrate-illustra-le-nuove-procedure\/\",\"name\":\"Transazione fiscale nelle crisi di impresa. Una circolare dell\u2019Agenzia delle Entrate illustra le nuove procedure -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/transazione-fiscale-nelle-crisi-di-impresa-una-circolare-dellagenzia-delle-entrate-illustra-le-nuove-procedure\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/transazione-fiscale-nelle-crisi-di-impresa-una-circolare-dellagenzia-delle-entrate-illustra-le-nuove-procedure\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/08\/fisco-tasse.jpg\",\"datePublished\":\"2020-12-30T09:34:36+00:00\",\"dateModified\":\"2020-12-30T09:34:36+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/transazione-fiscale-nelle-crisi-di-impresa-una-circolare-dellagenzia-delle-entrate-illustra-le-nuove-procedure\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/transazione-fiscale-nelle-crisi-di-impresa-una-circolare-dellagenzia-delle-entrate-illustra-le-nuove-procedure\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/transazione-fiscale-nelle-crisi-di-impresa-una-circolare-dellagenzia-delle-entrate-illustra-le-nuove-procedure\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/08\/fisco-tasse.jpg\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/08\/fisco-tasse.jpg\",\"width\":960,\"height\":678},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/transazione-fiscale-nelle-crisi-di-impresa-una-circolare-dellagenzia-delle-entrate-illustra-le-nuove-procedure\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Transazione fiscale nelle crisi di impresa. Una circolare dell\u2019Agenzia delle Entrate illustra le nuove procedure\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Transazione fiscale nelle crisi di impresa. Una circolare dell\u2019Agenzia delle Entrate illustra le nuove procedure -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/transazione-fiscale-nelle-crisi-di-impresa-una-circolare-dellagenzia-delle-entrate-illustra-le-nuove-procedure\/","og_locale":"it_IT","og_type":"article","og_title":"Transazione fiscale nelle crisi di impresa. Una circolare dell\u2019Agenzia delle Entrate illustra le nuove procedure -","og_description":"Arrivano le istruzioni delle Entrate ai propri uffici per garantire una tempestiva gestione delle procedure di composizione delle crisi di impresa e per fornire supporto agli operatori che si trovano ad affrontare l\u2019attuale congiuntura economica.Con la circolare n. 34\/E firmata oggi dal direttore delle Entrate, Ernesto Maria Ruffini, sulla base delle modifiche normative introdotte dalla [&hellip;]","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/transazione-fiscale-nelle-crisi-di-impresa-una-circolare-dellagenzia-delle-entrate-illustra-le-nuove-procedure\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2020-12-30T09:34:36+00:00","og_image":[{"width":960,"height":678,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/08\/fisco-tasse.jpg","type":"image\/jpeg"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/transazione-fiscale-nelle-crisi-di-impresa-una-circolare-dellagenzia-delle-entrate-illustra-le-nuove-procedure\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/transazione-fiscale-nelle-crisi-di-impresa-una-circolare-dellagenzia-delle-entrate-illustra-le-nuove-procedure\/","name":"Transazione fiscale nelle crisi di impresa. Una circolare dell\u2019Agenzia delle Entrate illustra le nuove procedure -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/transazione-fiscale-nelle-crisi-di-impresa-una-circolare-dellagenzia-delle-entrate-illustra-le-nuove-procedure\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/transazione-fiscale-nelle-crisi-di-impresa-una-circolare-dellagenzia-delle-entrate-illustra-le-nuove-procedure\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/08\/fisco-tasse.jpg","datePublished":"2020-12-30T09:34:36+00:00","dateModified":"2020-12-30T09:34:36+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/transazione-fiscale-nelle-crisi-di-impresa-una-circolare-dellagenzia-delle-entrate-illustra-le-nuove-procedure\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/transazione-fiscale-nelle-crisi-di-impresa-una-circolare-dellagenzia-delle-entrate-illustra-le-nuove-procedure\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/transazione-fiscale-nelle-crisi-di-impresa-una-circolare-dellagenzia-delle-entrate-illustra-le-nuove-procedure\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/08\/fisco-tasse.jpg","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/08\/fisco-tasse.jpg","width":960,"height":678},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/transazione-fiscale-nelle-crisi-di-impresa-una-circolare-dellagenzia-delle-entrate-illustra-le-nuove-procedure\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"Transazione fiscale nelle crisi di impresa. Una circolare dell\u2019Agenzia delle Entrate illustra le nuove procedure"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/4986"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=4986"}],"version-history":[{"count":1,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/4986\/revisions"}],"predecessor-version":[{"id":4987,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/4986\/revisions\/4987"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/1528"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=4986"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=4986"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=4986"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}