{"id":5092,"date":"2021-01-14T10:06:33","date_gmt":"2021-01-14T09:06:33","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=5092"},"modified":"2021-01-14T10:19:54","modified_gmt":"2021-01-14T09:19:54","slug":"superbonus-de-lise-commercialisti-banche-non-orientino-scelte-dei-clienti","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/superbonus-de-lise-commercialisti-banche-non-orientino-scelte-dei-clienti\/","title":{"rendered":"Superbonus, De Lise (commercialisti): banche non orientino scelte dei clienti"},"content":{"rendered":"<p><span class=\"dropcap dropcap3\">I<\/span>n tema di Superbonus, arrivano numerose segnalazioni dai colleghi che ci obbligano a una presa di posizione presso l&#8217;Abi (Associazione Bancari Italiani), la Banca d&#8217;Italia e le Autorit\u00e0 competenti Agcm (Autorit\u00e0 Garante della Concorrenza del Mercato) e la Consob (Commissione nazionale per le societ\u00e0 e la Borsa).<\/p>\n<p>Troppo spesso, infatti, si verificano situazioni in cui alcuni istituti di credito, a seguito della sottoscrizione di Convenzioni con societ\u00e0 di revisione, agiscano e insistano &#8211; per non dire \u2018obblighino\u2019 &#8211; affinch\u00e9 il visto di conformit\u00e0 previsto dal comma 11 dell\u2019art. 119 del Decreto Rilancio (detrazioni fiscali per il Superbonus) sia rilasciato esclusivamente dalle stesse societ\u00e0\u201d.<\/p>\n<p>Lo afferma <strong>Matteo De Lise<\/strong>, presidente dell\u2019Unione nazionale giovani dottori commercialisti.<\/p>\n<p>\u201cQuesta scelta \u2018consigliata\u2019 sarebbe una condizione necessaria al prosieguo della pratica di acquisizione del credito da parte dell\u2019istituto oppure, in casi meno gravi, farebbe proseguire la pratica con tempistiche notevolmente ridotte. Al contrario, se il visto di conformit\u00e0 fosse rilasciato da un professionista, la pratica non sarebbe presa in carico oppure lavorata con tempistiche lunghe sino ai 5 mesi. Tale comportamento \u00e8 censurabile poich\u00e9 viola principi fondamentali sui quali \u00e8 basata la nostra professione e il libero mercato\u201d.<\/p>\n<p>\u201cLa libert\u00e0 di scelta del cliente &#8211; spiega De Lise &#8211; viene cos\u00ec calpestata. Il cliente \u00e8 infatti costretto ad annullare il rapporto di fiducia che \u00e8 intrinseco nel mandato professionale, essendo obbligato ad accettare un nominativo imposto senza averlo visto n\u00e9 conosciuto. In seconda battuta, viene lesa la concorrenza di mercato: imponendo una scelta, si ottiene come risultato l\u2019esclusione di tutti i colleghi che non appartengono a determinate strutture\u201d.<\/p>\n<p>\u201cInoltre, il comportamento degli istituti bancari sarebbe da censurare per una evidente violazione della libert\u00e0 di scelta della clientela che, con queste modalit\u00e0, non potrebbe avvalersi dei propri consulenti di fiducia per la gestione delle proprie pratiche e per la tutela dei propri interessi. Al di l\u00e0 delle convenzioni, \u00e8 il cliente che sceglie i suoi professionisti di fiducia (ingegnere, architetto, commercialista, avvocato) nonch\u00e9 l&#8217;impresa per eseguire i lavori relativi. Alle banche &#8211; conclude il numero uno dei giovani commercialisti italiani &#8211; non chiediamo altro che fare le banche\u201d.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>In tema di Superbonus, arrivano numerose segnalazioni dai colleghi che ci obbligano a una presa di posizione presso l&#8217;Abi (Associazione Bancari Italiani), la Banca d&#8217;Italia e le Autorit\u00e0 competenti Agcm (Autorit\u00e0 Garante della Concorrenza del Mercato) e la Consob (Commissione nazionale per le societ\u00e0 e la Borsa). Troppo spesso, infatti, si verificano situazioni in cui [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5095,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[162],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Superbonus, De Lise (commercialisti): banche non orientino scelte dei clienti -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/superbonus-de-lise-commercialisti-banche-non-orientino-scelte-dei-clienti\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Superbonus, De Lise (commercialisti): banche non orientino scelte dei clienti -\" \/>\n<meta property=\"og:description\" content=\"In tema di Superbonus, arrivano numerose segnalazioni dai colleghi che ci obbligano a una presa di posizione presso l&#8217;Abi (Associazione Bancari Italiani), la Banca d&#8217;Italia e le Autorit\u00e0 competenti Agcm (Autorit\u00e0 Garante della Concorrenza del Mercato) e la Consob (Commissione nazionale per le societ\u00e0 e la Borsa). Troppo spesso, infatti, si verificano situazioni in cui [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/superbonus-de-lise-commercialisti-banche-non-orientino-scelte-dei-clienti\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-14T09:06:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-01-14T09:19:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2021\/01\/Matteo-De-Lise-Presidente-Ungdcec-e1610615879342.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"501\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/superbonus-de-lise-commercialisti-banche-non-orientino-scelte-dei-clienti\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/superbonus-de-lise-commercialisti-banche-non-orientino-scelte-dei-clienti\/\",\"name\":\"Superbonus, De Lise (commercialisti): banche non orientino scelte dei clienti -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/superbonus-de-lise-commercialisti-banche-non-orientino-scelte-dei-clienti\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/superbonus-de-lise-commercialisti-banche-non-orientino-scelte-dei-clienti\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2021\/01\/Matteo-De-Lise-Presidente-Ungdcec-e1610615879342.jpg\",\"datePublished\":\"2021-01-14T09:06:33+00:00\",\"dateModified\":\"2021-01-14T09:19:54+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/superbonus-de-lise-commercialisti-banche-non-orientino-scelte-dei-clienti\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/superbonus-de-lise-commercialisti-banche-non-orientino-scelte-dei-clienti\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/superbonus-de-lise-commercialisti-banche-non-orientino-scelte-dei-clienti\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2021\/01\/Matteo-De-Lise-Presidente-Ungdcec-e1610615879342.jpg\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2021\/01\/Matteo-De-Lise-Presidente-Ungdcec-e1610615879342.jpg\",\"width\":720,\"height\":501},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/superbonus-de-lise-commercialisti-banche-non-orientino-scelte-dei-clienti\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Superbonus, De Lise (commercialisti): banche non orientino scelte dei clienti\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Superbonus, De Lise (commercialisti): banche non orientino scelte dei clienti -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/superbonus-de-lise-commercialisti-banche-non-orientino-scelte-dei-clienti\/","og_locale":"it_IT","og_type":"article","og_title":"Superbonus, De Lise (commercialisti): banche non orientino scelte dei clienti -","og_description":"In tema di Superbonus, arrivano numerose segnalazioni dai colleghi che ci obbligano a una presa di posizione presso l&#8217;Abi (Associazione Bancari Italiani), la Banca d&#8217;Italia e le Autorit\u00e0 competenti Agcm (Autorit\u00e0 Garante della Concorrenza del Mercato) e la Consob (Commissione nazionale per le societ\u00e0 e la Borsa). Troppo spesso, infatti, si verificano situazioni in cui [&hellip;]","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/superbonus-de-lise-commercialisti-banche-non-orientino-scelte-dei-clienti\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2021-01-14T09:06:33+00:00","article_modified_time":"2021-01-14T09:19:54+00:00","og_image":[{"width":720,"height":501,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2021\/01\/Matteo-De-Lise-Presidente-Ungdcec-e1610615879342.jpg","type":"image\/jpeg"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/superbonus-de-lise-commercialisti-banche-non-orientino-scelte-dei-clienti\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/superbonus-de-lise-commercialisti-banche-non-orientino-scelte-dei-clienti\/","name":"Superbonus, De Lise (commercialisti): banche non orientino scelte dei clienti -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/superbonus-de-lise-commercialisti-banche-non-orientino-scelte-dei-clienti\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/superbonus-de-lise-commercialisti-banche-non-orientino-scelte-dei-clienti\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2021\/01\/Matteo-De-Lise-Presidente-Ungdcec-e1610615879342.jpg","datePublished":"2021-01-14T09:06:33+00:00","dateModified":"2021-01-14T09:19:54+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/superbonus-de-lise-commercialisti-banche-non-orientino-scelte-dei-clienti\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/superbonus-de-lise-commercialisti-banche-non-orientino-scelte-dei-clienti\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/superbonus-de-lise-commercialisti-banche-non-orientino-scelte-dei-clienti\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2021\/01\/Matteo-De-Lise-Presidente-Ungdcec-e1610615879342.jpg","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2021\/01\/Matteo-De-Lise-Presidente-Ungdcec-e1610615879342.jpg","width":720,"height":501},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/superbonus-de-lise-commercialisti-banche-non-orientino-scelte-dei-clienti\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"Superbonus, De Lise (commercialisti): banche non orientino scelte dei clienti"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/5092"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=5092"}],"version-history":[{"count":2,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/5092\/revisions"}],"predecessor-version":[{"id":5096,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/5092\/revisions\/5096"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/5095"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=5092"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=5092"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=5092"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}