{"id":5104,"date":"2021-01-15T10:38:42","date_gmt":"2021-01-15T09:38:42","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=5104"},"modified":"2021-01-15T10:38:42","modified_gmt":"2021-01-15T09:38:42","slug":"a-milano-per-i-bar-ulteriore-perdita-del-50-con-lo-stop-allasporto-alle-18","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/a-milano-per-i-bar-ulteriore-perdita-del-50-con-lo-stop-allasporto-alle-18\/","title":{"rendered":"A Milano per i bar ulteriore perdita del 50% con lo stop all\u2019asporto alle 18"},"content":{"rendered":"<p><span class=\"dropcap dropcap3\">L<\/span>o stop all\u2019asporto nei bar alle 18 &#8211; che sta per essere introdotto dal Governo con le nuove misure anti-Covid in vigore da <a class=\"matchTooltip\">domani<\/a> &#8211; colpisce duramente i pubblici esercizi, in particolare a Milano citt\u00e0. Il dato emerge dal sondaggio (risposte da 407 imprese del settore) realizzato fra mercoled\u00ec e gioved\u00ec da Confcommercio Milano, Lodi, Monza e Brianza con Epam (l\u2019Associazione dei pubblici esercizi) e i risultati elaborati dall\u2019Ufficio Studi.<\/p>\n<p>Per i bar la perdita media ulteriore di fatturato sar\u00e0 del 46%. Pi\u00f9 alta a Milano, del 50%, rispetto a Lodi (45%), hinterland milanese (40%) e Monza Brianza (38%). Dalle risposte per tipologia d\u2019esercizio, la perdita ulteriore di fatturato con lo stop all\u2019asporto alle 18, sale al 59% per i locali pi\u00f9 attivi nelle ore serali.<\/p>\n<p><strong>CROLLO DEL FATTURATO DI OLTRE IL 70%<\/strong> &#8211; La restrizione sull\u2019asporto arriva in una situazione drammatica per tutti i pubblici esercizi: nel dicembre 2020 il fatturato scende del 71% in tutte le attivit\u00e0 rispetto al dicembre del 2019. Le perdite maggiori le indicano i bar-locali pi\u00f9 attivi la sera e i ristoranti: -77 e -76%.<\/p>\n<p>A Milano citt\u00e0 i pubblici esercizi hanno perso a dicembre il 75% del volume di affari (Lodi il 69%, hinterland milanese il 66%, Monza Brianza il 64%).<\/p>\n<p><strong>RISCHIO CHIUSURA PER L\u201986% DELLE IMPRESE<\/strong> &#8211; Nei pubblici esercizi si alza notevolmente, dal 67 all\u201986%, la quota di operatori che ritiene la propria attivit\u00e0 a rischio chiusura (il confronto \u00e8 con le risposte della categoria date in un sondaggio effettuato a settembre): il 91% a Milano citt\u00e0 (Lodi 86%, hinterland milanese e Monza Brianza l\u201981%).<\/p>\n<p><strong>CONTRIBUTI: IL 27% LI ATTENDE ANCORA<\/strong> &#8211; Infine il dato sui contributi, dei decreti Natale e Ristori, giunti al 73% delle imprese. Il 27% non li ha ancora ricevuti (29% per ristoranti e pizzerie).<\/p>\n<p>&#8220;<i>I dati<\/i> \u2013 afferma <b>Lino Stoppani<\/b>, presidente di Epam (Associazione pubblici esercizi Confcommercio Milano, Lodi, Monza e Brianza) e Fipe (Federazione italiana pubblici esercizi Confcommercio) &#8211; <i>evidenziano ancora una volta le grandi difficolt\u00e0 del settore, danneggiato dall&#8217;evoluzione della pandemia che trasferisce danni aggiuntivi ad un comparto letteralmente al collasso, mettendo a rischio il modello del pubblico esercizio italiano, diffuso e qualificato. In aggiunta, questo \u2018accanimento normativo\u2019 crea confusione, ha scarsa efficacia sanitaria e impedisce qualsiasi programmazione sul futuro delle imprese, alimentando, oltre ai danni economici, preoccupazione, disagi, disperazione, che hanno effetti anche sulla coesione sociale del Paese<\/i>&#8220;.<\/p>\n<p>*<i>Al sondaggio hanno risposto in le imprese di pubblico esercizio della Citt\u00e0 Metropolitana di Milano e delle Province di Lodi e Monza Brianza. Quelle di Milano citt\u00e0 e hinterland rappresentano il 67% del totale, quelle fino a 5 addetti il 70% del totale.<\/i><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lo stop all\u2019asporto nei bar alle 18 &#8211; che sta per essere introdotto dal Governo con le nuove misure anti-Covid in vigore da domani &#8211; colpisce duramente i pubblici esercizi, in particolare a Milano citt\u00e0. Il dato emerge dal sondaggio (risposte da 407 imprese del settore) realizzato fra mercoled\u00ec e gioved\u00ec da Confcommercio Milano, Lodi, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5105,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[56],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>A Milano per i bar ulteriore perdita del 50% con lo stop all\u2019asporto alle 18 -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/a-milano-per-i-bar-ulteriore-perdita-del-50-con-lo-stop-allasporto-alle-18\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A Milano per i bar ulteriore perdita del 50% con lo stop all\u2019asporto alle 18 -\" \/>\n<meta property=\"og:description\" content=\"Lo stop all\u2019asporto nei bar alle 18 &#8211; che sta per essere introdotto dal Governo con le nuove misure anti-Covid in vigore da domani &#8211; colpisce duramente i pubblici esercizi, in particolare a Milano citt\u00e0. Il dato emerge dal sondaggio (risposte da 407 imprese del settore) realizzato fra mercoled\u00ec e gioved\u00ec da Confcommercio Milano, Lodi, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/a-milano-per-i-bar-ulteriore-perdita-del-50-con-lo-stop-allasporto-alle-18\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-15T09:38:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2021\/01\/Schermata-2021-01-15-alle-10.37.14.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1194\" \/>\n\t<meta property=\"og:image:height\" content=\"776\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/a-milano-per-i-bar-ulteriore-perdita-del-50-con-lo-stop-allasporto-alle-18\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/a-milano-per-i-bar-ulteriore-perdita-del-50-con-lo-stop-allasporto-alle-18\/\",\"name\":\"A Milano per i bar ulteriore perdita del 50% con lo stop all\u2019asporto alle 18 -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/a-milano-per-i-bar-ulteriore-perdita-del-50-con-lo-stop-allasporto-alle-18\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/a-milano-per-i-bar-ulteriore-perdita-del-50-con-lo-stop-allasporto-alle-18\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2021\/01\/Schermata-2021-01-15-alle-10.37.14.png\",\"datePublished\":\"2021-01-15T09:38:42+00:00\",\"dateModified\":\"2021-01-15T09:38:42+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/a-milano-per-i-bar-ulteriore-perdita-del-50-con-lo-stop-allasporto-alle-18\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/a-milano-per-i-bar-ulteriore-perdita-del-50-con-lo-stop-allasporto-alle-18\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/a-milano-per-i-bar-ulteriore-perdita-del-50-con-lo-stop-allasporto-alle-18\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2021\/01\/Schermata-2021-01-15-alle-10.37.14.png\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2021\/01\/Schermata-2021-01-15-alle-10.37.14.png\",\"width\":1194,\"height\":776},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/a-milano-per-i-bar-ulteriore-perdita-del-50-con-lo-stop-allasporto-alle-18\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A Milano per i bar ulteriore perdita del 50% con lo stop all\u2019asporto alle 18\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A Milano per i bar ulteriore perdita del 50% con lo stop all\u2019asporto alle 18 -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/a-milano-per-i-bar-ulteriore-perdita-del-50-con-lo-stop-allasporto-alle-18\/","og_locale":"it_IT","og_type":"article","og_title":"A Milano per i bar ulteriore perdita del 50% con lo stop all\u2019asporto alle 18 -","og_description":"Lo stop all\u2019asporto nei bar alle 18 &#8211; che sta per essere introdotto dal Governo con le nuove misure anti-Covid in vigore da domani &#8211; colpisce duramente i pubblici esercizi, in particolare a Milano citt\u00e0. Il dato emerge dal sondaggio (risposte da 407 imprese del settore) realizzato fra mercoled\u00ec e gioved\u00ec da Confcommercio Milano, Lodi, [&hellip;]","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/a-milano-per-i-bar-ulteriore-perdita-del-50-con-lo-stop-allasporto-alle-18\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2021-01-15T09:38:42+00:00","og_image":[{"width":1194,"height":776,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2021\/01\/Schermata-2021-01-15-alle-10.37.14.png","type":"image\/png"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/a-milano-per-i-bar-ulteriore-perdita-del-50-con-lo-stop-allasporto-alle-18\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/a-milano-per-i-bar-ulteriore-perdita-del-50-con-lo-stop-allasporto-alle-18\/","name":"A Milano per i bar ulteriore perdita del 50% con lo stop all\u2019asporto alle 18 -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/a-milano-per-i-bar-ulteriore-perdita-del-50-con-lo-stop-allasporto-alle-18\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/a-milano-per-i-bar-ulteriore-perdita-del-50-con-lo-stop-allasporto-alle-18\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2021\/01\/Schermata-2021-01-15-alle-10.37.14.png","datePublished":"2021-01-15T09:38:42+00:00","dateModified":"2021-01-15T09:38:42+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/a-milano-per-i-bar-ulteriore-perdita-del-50-con-lo-stop-allasporto-alle-18\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/a-milano-per-i-bar-ulteriore-perdita-del-50-con-lo-stop-allasporto-alle-18\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/a-milano-per-i-bar-ulteriore-perdita-del-50-con-lo-stop-allasporto-alle-18\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2021\/01\/Schermata-2021-01-15-alle-10.37.14.png","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2021\/01\/Schermata-2021-01-15-alle-10.37.14.png","width":1194,"height":776},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/a-milano-per-i-bar-ulteriore-perdita-del-50-con-lo-stop-allasporto-alle-18\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"A Milano per i bar ulteriore perdita del 50% con lo stop all\u2019asporto alle 18"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/5104"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=5104"}],"version-history":[{"count":1,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/5104\/revisions"}],"predecessor-version":[{"id":5106,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/5104\/revisions\/5106"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/5105"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=5104"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=5104"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=5104"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}