{"id":5160,"date":"2021-01-21T11:53:36","date_gmt":"2021-01-21T10:53:36","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=5160"},"modified":"2021-01-21T11:53:36","modified_gmt":"2021-01-21T10:53:36","slug":"covid-coldiretti-scrive-a-conte-crack-stalle-da-17-mld","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/covid-coldiretti-scrive-a-conte-crack-stalle-da-17-mld\/","title":{"rendered":"Covid, Coldiretti scrive a Conte. Crack stalle da 1,7 MLD"},"content":{"rendered":"<p><span class=\"dropcap dropcap3\">L<\/span>\u2019emergenza Covid \u00e8 costata sino ad oggi alle stalle italiane 1,7 miliardi di euro tra il blocco delle vendite, con la chiusura del canale della ristorazione, le fake news e il crollo dei prezzi, mettendo a rischio la sopravvivenza della Fattoria Italia.<\/p>\n<p>E\u2019 l\u2019allarme lanciato dal presidente della Coldiretti Ettore Prandini che ha scritto una lettera al Presidente del Consiglio Giuseppe Conte, che ha assunto l\u2019interim di Ministro delle politiche agricole, chiedendo un intervento immediato per dare garanzie alle imprese e salvaguardare una filiera che \u00e8 strategica e centrale per tutto il sistema agroalimentare nazionale.<\/p>\n<p>&nbsp;<\/p>\n<p>Le misure di contenimento e la chiusura parziale o totale del canale della ristorazione e dell\u2019Horeca \u2013 scrive Prandini &#8211; stanno penalizzando tutto il settore agroalimentare, che in quelle attivit\u00e0 vede lo sbocco del 30% della produzione, con un impatto particolarmente pesante per il settore della zootecnia da carne dove quasi 2 aIlevamenti su tre (63,6%) hanno avuto un impatto economico negativo dalla pandemia.<\/p>\n<p>&nbsp;<\/p>\n<p>Complice anche il diffondersi di fake news sugli allevamenti \u2013 ricorda Prandini -, le macellazioni di bovini sono diminuite in un anno del 17,8%, quelle dei suini del 20,2% secondo un\u2019analisi Coldiretti su dati Istat. Il calo della domanda ha causato il crollo dei prezzi di vendita, mandando in sofferenza soprattutto le razze storiche italiane, come Piemontese, Marchigiana e Romagnola, e gli interi territori ad esse legati.<\/p>\n<p>&nbsp;<\/p>\n<p>Da qui la richiesta del presidente della Coldiretti al premier Conte che vengano individuati quanto prima strumenti di sostegno, aiuti diretti alle imprese e ristori concreti. Riteniamo indispensabile \u2013 spiega Prandini &#8211; un confronto attraverso un tavolo nazionale di filiera per poter costruire le risposte che servono ai nostri allevatori.<\/p>\n<p>&nbsp;<\/p>\n<p>Coldiretti e Filiera Italia stanno gi\u00e0 lavorando \u2013 sottolinea Prandini &#8211; su nuovi progetti di investimento per la zootecnica sostenibile che potranno contribuire al grande sforzo di ripresa del Paese attraverso le risorse europee di Next generation EU e il Recovery Plan. L\u2019emergenza di oggi \u2013 conclude il presidente della Coldiretti &#8211; per\u00f2 mette a rischio troppi allevatori per attendere l\u2019orizzonte temporale del Recovery.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019emergenza Covid \u00e8 costata sino ad oggi alle stalle italiane 1,7 miliardi di euro tra il blocco delle vendite, con la chiusura del canale della ristorazione, le fake news e il crollo dei prezzi, mettendo a rischio la sopravvivenza della Fattoria Italia. E\u2019 l\u2019allarme lanciato dal presidente della Coldiretti Ettore Prandini che ha scritto una [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5070,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[56],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Covid, Coldiretti scrive a Conte. Crack stalle da 1,7 MLD -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/covid-coldiretti-scrive-a-conte-crack-stalle-da-17-mld\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Covid, Coldiretti scrive a Conte. Crack stalle da 1,7 MLD -\" \/>\n<meta property=\"og:description\" content=\"L\u2019emergenza Covid \u00e8 costata sino ad oggi alle stalle italiane 1,7 miliardi di euro tra il blocco delle vendite, con la chiusura del canale della ristorazione, le fake news e il crollo dei prezzi, mettendo a rischio la sopravvivenza della Fattoria Italia. E\u2019 l\u2019allarme lanciato dal presidente della Coldiretti Ettore Prandini che ha scritto una [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/covid-coldiretti-scrive-a-conte-crack-stalle-da-17-mld\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-21T10:53:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2021\/01\/Schermata-2021-01-12-alle-09.25.36.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1238\" \/>\n\t<meta property=\"og:image:height\" content=\"608\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/covid-coldiretti-scrive-a-conte-crack-stalle-da-17-mld\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/covid-coldiretti-scrive-a-conte-crack-stalle-da-17-mld\/\",\"name\":\"Covid, Coldiretti scrive a Conte. Crack stalle da 1,7 MLD -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/covid-coldiretti-scrive-a-conte-crack-stalle-da-17-mld\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/covid-coldiretti-scrive-a-conte-crack-stalle-da-17-mld\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2021\/01\/Schermata-2021-01-12-alle-09.25.36.png\",\"datePublished\":\"2021-01-21T10:53:36+00:00\",\"dateModified\":\"2021-01-21T10:53:36+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/covid-coldiretti-scrive-a-conte-crack-stalle-da-17-mld\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/covid-coldiretti-scrive-a-conte-crack-stalle-da-17-mld\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/covid-coldiretti-scrive-a-conte-crack-stalle-da-17-mld\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2021\/01\/Schermata-2021-01-12-alle-09.25.36.png\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2021\/01\/Schermata-2021-01-12-alle-09.25.36.png\",\"width\":1238,\"height\":608},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/covid-coldiretti-scrive-a-conte-crack-stalle-da-17-mld\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Covid, Coldiretti scrive a Conte. Crack stalle da 1,7 MLD\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Covid, Coldiretti scrive a Conte. Crack stalle da 1,7 MLD -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/covid-coldiretti-scrive-a-conte-crack-stalle-da-17-mld\/","og_locale":"it_IT","og_type":"article","og_title":"Covid, Coldiretti scrive a Conte. Crack stalle da 1,7 MLD -","og_description":"L\u2019emergenza Covid \u00e8 costata sino ad oggi alle stalle italiane 1,7 miliardi di euro tra il blocco delle vendite, con la chiusura del canale della ristorazione, le fake news e il crollo dei prezzi, mettendo a rischio la sopravvivenza della Fattoria Italia. E\u2019 l\u2019allarme lanciato dal presidente della Coldiretti Ettore Prandini che ha scritto una [&hellip;]","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/covid-coldiretti-scrive-a-conte-crack-stalle-da-17-mld\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2021-01-21T10:53:36+00:00","og_image":[{"width":1238,"height":608,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2021\/01\/Schermata-2021-01-12-alle-09.25.36.png","type":"image\/png"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/covid-coldiretti-scrive-a-conte-crack-stalle-da-17-mld\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/covid-coldiretti-scrive-a-conte-crack-stalle-da-17-mld\/","name":"Covid, Coldiretti scrive a Conte. Crack stalle da 1,7 MLD -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/covid-coldiretti-scrive-a-conte-crack-stalle-da-17-mld\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/covid-coldiretti-scrive-a-conte-crack-stalle-da-17-mld\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2021\/01\/Schermata-2021-01-12-alle-09.25.36.png","datePublished":"2021-01-21T10:53:36+00:00","dateModified":"2021-01-21T10:53:36+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/covid-coldiretti-scrive-a-conte-crack-stalle-da-17-mld\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/covid-coldiretti-scrive-a-conte-crack-stalle-da-17-mld\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/covid-coldiretti-scrive-a-conte-crack-stalle-da-17-mld\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2021\/01\/Schermata-2021-01-12-alle-09.25.36.png","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2021\/01\/Schermata-2021-01-12-alle-09.25.36.png","width":1238,"height":608},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/covid-coldiretti-scrive-a-conte-crack-stalle-da-17-mld\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"Covid, Coldiretti scrive a Conte. Crack stalle da 1,7 MLD"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/5160"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=5160"}],"version-history":[{"count":1,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/5160\/revisions"}],"predecessor-version":[{"id":5161,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/5160\/revisions\/5161"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/5070"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=5160"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=5160"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=5160"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}