{"id":5180,"date":"2021-01-22T12:15:41","date_gmt":"2021-01-22T11:15:41","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=5180"},"modified":"2021-01-22T12:15:41","modified_gmt":"2021-01-22T11:15:41","slug":"crea-lagro-alimentare-italiano-settore-chiave-delleconomia","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/crea-lagro-alimentare-italiano-settore-chiave-delleconomia\/","title":{"rendered":"CREA: L\u2019agro-alimentare italiano settore chiave dell\u2019economia \u00a0"},"content":{"rendered":"<div>\n<p class=\"x_MsoNormal\"><span class=\"dropcap dropcap3\">C<\/span>on oltre 522 miliardi di euro, il sistema agroalimentare italiano rappresenta il 15% del PIL nazionale: primi in Europa per valore aggiunto agricolo.<\/p>\n<p class=\"x_MsoNormal\">\u00c8 su questo che dobbiamo lavorare per creare reddito e posti di lavoro in grado di traghettarci oltre la crisi dovuta alla pandemia &#8211; dichiara &#8211; Con il nuovo corso alla guida del Crea, stiamo analizzando i fabbisogni delle diverse realt\u00e0 locali e sono certo che potremo dare presto risposte, raggiungendo risultati concreti ed efficaci per le nostre imprese.<\/p>\n<p class=\"x_MsoNormal\">Cos\u00ec <b>Giuseppe L&#8217;Abbate, Sottosegretario alle Politiche Agricole<\/b> intervenendo <a class=\"matchTooltip\">oggi<\/a> alla <b>presentazione dell\u2019Annuario dell\u2019Agricoltura italiana 2019<\/b>, la fonte pi\u00f9 autorevole e completa per comprendere lo stato del settore in Italia, realizzato dal CREA con il suo Centro Politiche e Bioeconomia \u00a0e corredato quest\u2019anno anche dal <b><i>Rapporto sul commercio estero dei prodotti agroalimentari 2019 con anticipazioni 2020 e dal Rapporto L\u2019emergenza Covid-19 e il settore ittico italiano: impatto e risposte.<\/i><\/b><\/p>\n<p>ll sistema agro\u00adalimentare, inteso complessivamente come agricoltura, silvicoltura e pesca, si conferma settore chiave della nostra economia, <strong>in tutte le sue componenti (agricoltura, agroindustria e <\/strong>commercio all\u2019ingrosso e al dettaglio e ristorazione<strong>)<\/strong>, raggiunge un peso del<b> 15% del PIL italiano, come media stabile degli ultimi anni. <\/b>Messo alla prova dalla pandemia, il sistema ha saputo essere resiliente rispetto alla media generale dell\u2019economia (stime ISTAT).<\/p>\n<p class=\"x_MsoNormal\">Nonostante la superficie nazionale sia circa la met\u00e0 di quella spagnola e francese, <b>l\u2019agricoltura italiana conferma la sua leadership europea: \u00e8 la prima agricoltura d\u2019Europa per valore aggiunto e la terza per produzione lorda vendibile.<\/b> <b>L\u2019Italia \u00e8 primo produttore mondiale di vino in volume e primo produttore europeo in valore nella produzione di ortaggi.<\/b> <b>Nel 2019 il valore della produzione agricola \u00e8 stato di 57,3 miliardi di euro<\/b>, in linea con l\u2019anno precedente, di cui oltre il 50% dovuto alle coltivazioni, il 29% circa agli allevamenti e la restante parte alle attivit\u00e0 di supporto e secondarie.<\/p>\n<p class=\"x_MsoNormal\">Crescita significativa nell\u2019ultimo decennio per <b>l\u2019industria alimentare <\/b>con +12% di valore aggiunto (circa il doppio rispetto a quello del manifatturiero) e +8% dell\u2019indice della produzione, a fronte di una diminuzione generale.<\/p>\n<p class=\"x_MsoNormal\">Indiscusso il contributo dell\u2019agricoltura e dell\u2019industria alimentare (incidenza sul settore del 64%) alla <b>bioeconomia<\/b>, che, con un\u00a0<b>fatturato <\/b>in crescita (+1,3%) <b>di oltre 324 miliardi di euro,<\/b> costituisce ormai uno degli elementi di forza dell\u2019economia italiana.<\/p>\n<p class=\"x_MsoNormal\"><b>Le produzioni di qualit\u00e0 certificata<\/b> (DOP-IGP) che, meglio di altre, hanno fatto fronte alle difficolt\u00e0 legate alla pandemia, si confermano tra le pi\u00f9 dinamiche dell\u2019agroalimentare italiano, con un valore che raggiunge i <b>17 miliardi di euro<\/b> (+oltre il 4%), tra componente alimentare e vinicola, circa il 19% del totale dell\u2019agro-alimentare italiano.<\/p>\n<p class=\"x_MsoNormal\">Sempre pi\u00f9 significativa \u00e8 la crescita delle attivit\u00e0 connesse all\u2019agricoltura, ormai oltre un quinto del valore complessivo della produzione agricola realizzata: <b>l\u2019agriturismo con +3,3% in valore e +4,1% di aziende nel solo 2019<\/b>, (brusca flessione nel 2020 per le restrizioni conseguenti alla pandemia) e il <b>contoterzismo (+1,7% in valore),<\/b> particolarmente attivo in termini di maggiore diffusione di innovazioni tecnologiche, di ricorso alle pratiche dell\u2019agricoltura 4.0, di facilitazioni nel rispetto di alcune prescrizioni ambientali, di riduzione del digital divide.<\/p>\n<p class=\"x_MsoNormal\">Dal punto di vista strutturale sono <b>oltre 1,5 milioni le aziende agricole<\/b>, di cui il <b>27% sono imprese <\/b><b>che intrattengono rapporti stabili di mercato<\/b>, ricoprono<b> il 65% della SAU<\/b> (superficie media di 21 ha, superiore alla media nazionale) e rappresentano il <b>75% della produzione standard complessiva<\/b>.\u00a0Le <b>imprese non specificamente orientate al mercato<\/b>, invece, sono <b>circa il 66% del totale <\/b>(di cui il 36% ha rapporti solo saltuari e il 30% dedito al solo autoconsumo)<b> <\/b>e<b><\/b>occupano complessivamente <b>circa il 29% della SAU totale<\/b>.<\/p>\n<p class=\"x_MsoNormal\">Si conferma rilevante il <b>sostegno pubblico<\/b> al settore agricolo, <b>circa 11,9 miliardi di euro<\/b> nel 2019, ma in calo rispetto agli anni precedenti: dal 2015 al 2019, infatti, si \u00e8 verificata una riduzione oltre 1,3 miliardi di euro (-10%), quasi totalmente derivante da minori agevolazioni nazionali.<\/p>\n<p class=\"x_MsoNormal\">Sul fronte degli scambi commerciali, come evidenziato dal\u00a0<i>Rapporto sul commercio estero 2019, <\/i>netta \u00e8 stata la <b>riduzione del deficit della bilancia agroalimentare italiana<\/b>, sceso largamente al di sotto di 1 miliardo di euro<b> nel 2019<\/b>, a fronte dei 5 miliardi del 2015 e degli oltre 9 miliardi del 2011. Si tratta di un dato straordinario, confermato dai <b>primi 9 mesi del 2020<\/b>, in cui, addirittura, si verifica <b> un cambio di segno nel saldo<\/b>, <b>per la prima volta positivo<\/b> dall\u2019inizio della serie storica<b>,<\/b> grazie alla crescita tendenziale delle esportazioni (+0,8%) a fronte di un importante calo delle importazioni (-4,4%).<\/p>\n<p class=\"x_MsoNormal\">In particolare, l\u2019export, dopo un\u2019ottima performance <b>nei primi tre mesi dell\u2019anno (+6,3%)<\/b> e un <b>calo nel secondo trimestre (-4,6%)<\/b> soprattutto a maggio, ha visto una ripresa dei flussi, confermata al termine del <b>terzo trimestre 2020 (+0,8%).<\/b> I settori dell\u2019export pi\u00f9 colpiti dagli effetti del Covid-19, nel secondo trimestre 2020, sono stati il florovivaismo, le carni, i prodotti dolciari e il vino, parzialmente compensati dalla crescita di altri importanti prodotti del <i>Made in Italy<\/i>, come la pasta, le conserve di pomodoro e l\u2019olio di oliva.<\/p>\n<p>Verr\u00e0 infine presentato il <i>Rapporto L\u2019emergenza Covid-19 e il settore ittico italiano: impatto e risposte,<\/i> realizzato dal CREA, in collaborazione con NISEA, dedicato al settore della <b>pesca e dell\u2019acquacoltura<\/b>, che ha ampiamente risentito della crisi pandemica, con un <b>calo della domanda di prodotto fresco (-29% in valore a marzo e -17% ad aprile)<\/b>. In termini di scambi commerciali con l\u2019estero, il settore e\u0300 tra i pi\u00f9 colpiti dagli effetti delle misure di contenimento del Covid-19 e dalla conseguente crisi economica <b>(-16% in valore le importazioni nel I semestre 2020)<\/b>.<\/p>\n<p>Le imprese di acquacoltura hanno sub\u00ecto una forte riduzione nelle vendite, soprattutto tra marzo e aprile, ad eccezione del canale della grande distribuzione. Le attivit\u00e0 di pesca hanno cercato di adattarsi alle richieste del consumo domestico, anche attraverso il ricorso a nuove modalit\u00e0 di commercializzazione, quali la vendita diretta, le prenotazioni a distanza, gli acquisti on-line e le consegne a domicilio.<\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<div>\n<div><\/div>\n<div id=\"x_Signature\">\n<div>\n<div>\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Con oltre 522 miliardi di euro, il sistema agroalimentare italiano rappresenta il 15% del PIL nazionale: primi in Europa per valore aggiunto agricolo. \u00c8 su questo che dobbiamo lavorare per creare reddito e posti di lavoro in grado di traghettarci oltre la crisi dovuta alla pandemia &#8211; dichiara &#8211; Con il nuovo corso alla guida [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":146,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[379,368],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>CREA: L\u2019agro-alimentare italiano settore chiave dell\u2019economia \u00a0 -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/crea-lagro-alimentare-italiano-settore-chiave-delleconomia\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CREA: L\u2019agro-alimentare italiano settore chiave dell\u2019economia \u00a0 -\" \/>\n<meta property=\"og:description\" content=\"Con oltre 522 miliardi di euro, il sistema agroalimentare italiano rappresenta il 15% del PIL nazionale: primi in Europa per valore aggiunto agricolo. \u00c8 su questo che dobbiamo lavorare per creare reddito e posti di lavoro in grado di traghettarci oltre la crisi dovuta alla pandemia &#8211; dichiara &#8211; Con il nuovo corso alla guida [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/crea-lagro-alimentare-italiano-settore-chiave-delleconomia\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-22T11:15:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/07\/frutta_verdura.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"844\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/crea-lagro-alimentare-italiano-settore-chiave-delleconomia\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/crea-lagro-alimentare-italiano-settore-chiave-delleconomia\/\",\"name\":\"CREA: L\u2019agro-alimentare italiano settore chiave dell\u2019economia \u00a0 -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/crea-lagro-alimentare-italiano-settore-chiave-delleconomia\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/crea-lagro-alimentare-italiano-settore-chiave-delleconomia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/07\/frutta_verdura.jpg\",\"datePublished\":\"2021-01-22T11:15:41+00:00\",\"dateModified\":\"2021-01-22T11:15:41+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/crea-lagro-alimentare-italiano-settore-chiave-delleconomia\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/crea-lagro-alimentare-italiano-settore-chiave-delleconomia\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/crea-lagro-alimentare-italiano-settore-chiave-delleconomia\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/07\/frutta_verdura.jpg\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/07\/frutta_verdura.jpg\",\"width\":844,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/crea-lagro-alimentare-italiano-settore-chiave-delleconomia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CREA: L\u2019agro-alimentare italiano settore chiave dell\u2019economia \u00a0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CREA: L\u2019agro-alimentare italiano settore chiave dell\u2019economia \u00a0 -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/crea-lagro-alimentare-italiano-settore-chiave-delleconomia\/","og_locale":"it_IT","og_type":"article","og_title":"CREA: L\u2019agro-alimentare italiano settore chiave dell\u2019economia \u00a0 -","og_description":"Con oltre 522 miliardi di euro, il sistema agroalimentare italiano rappresenta il 15% del PIL nazionale: primi in Europa per valore aggiunto agricolo. \u00c8 su questo che dobbiamo lavorare per creare reddito e posti di lavoro in grado di traghettarci oltre la crisi dovuta alla pandemia &#8211; dichiara &#8211; Con il nuovo corso alla guida [&hellip;]","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/crea-lagro-alimentare-italiano-settore-chiave-delleconomia\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2021-01-22T11:15:41+00:00","og_image":[{"width":844,"height":720,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/07\/frutta_verdura.jpg","type":"image\/jpeg"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/crea-lagro-alimentare-italiano-settore-chiave-delleconomia\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/crea-lagro-alimentare-italiano-settore-chiave-delleconomia\/","name":"CREA: L\u2019agro-alimentare italiano settore chiave dell\u2019economia \u00a0 -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/crea-lagro-alimentare-italiano-settore-chiave-delleconomia\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/crea-lagro-alimentare-italiano-settore-chiave-delleconomia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/07\/frutta_verdura.jpg","datePublished":"2021-01-22T11:15:41+00:00","dateModified":"2021-01-22T11:15:41+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/crea-lagro-alimentare-italiano-settore-chiave-delleconomia\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/crea-lagro-alimentare-italiano-settore-chiave-delleconomia\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/crea-lagro-alimentare-italiano-settore-chiave-delleconomia\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/07\/frutta_verdura.jpg","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/07\/frutta_verdura.jpg","width":844,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/crea-lagro-alimentare-italiano-settore-chiave-delleconomia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"CREA: L\u2019agro-alimentare italiano settore chiave dell\u2019economia \u00a0"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/5180"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=5180"}],"version-history":[{"count":1,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/5180\/revisions"}],"predecessor-version":[{"id":5181,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/5180\/revisions\/5181"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/146"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=5180"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=5180"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=5180"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}