{"id":5252,"date":"2021-01-29T12:01:21","date_gmt":"2021-01-29T11:01:21","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=5252"},"modified":"2021-01-29T12:01:21","modified_gmt":"2021-01-29T11:01:21","slug":"aiuti-di-stato-cna-apprezza-la-proroga-al-31-dicembre-decisa-dalla-commissione-ue","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/aiuti-di-stato-cna-apprezza-la-proroga-al-31-dicembre-decisa-dalla-commissione-ue\/","title":{"rendered":"Aiuti di Stato,  CNA apprezza la proroga al 31 dicembre decisa dalla Commissione UE"},"content":{"rendered":"<p><span class=\"dropcap dropcap3\">C<\/span>NA apprezza la decisione della Commissione Europea di prorogare fino al 31 dicembre il quadro temporaneo sugli aiuti di Stato accogliendo le richieste di artigiani e piccole imprese di estendere la deroga alla luce del permanere della crisi economica provocata dalla pandemia e dell\u2019incertezza sui tempi per superare gli effetti pesanti su imprese e cittadini.<\/p>\n<p>La proroga decisa dalla Commissione Europea riflette l\u2019esigenza di continuare ad assicurare il sostegno alle attivit\u00e0 economiche attraverso moratorie e garanzie sui prestiti. Per essere operativa il Governo dovr\u00e0 quanto prima recepire la disposizione della Commissione.<\/p>\n<p>Coerentemente alla proroga, CNA rileva che fino a quando non sar\u00e0 rientrata l\u2019emergenza sanitaria \u00e8 necessario garantire la massima flessibilit\u00e0 delle norme e della regolamentazione bancaria per scongiurare ripercussioni negative sui flussi di credito alle imprese oltre a minare la solidit\u00e0 del sistema bancario. In quest\u2019ottica CNA ribadisce l\u2019esigenza di sospendere le nuove definizioni di default e di rivedere la normativa sulla copertura dei crediti deteriorati.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CNA apprezza la decisione della Commissione Europea di prorogare fino al 31 dicembre il quadro temporaneo sugli aiuti di Stato accogliendo le richieste di artigiani e piccole imprese di estendere la deroga alla luce del permanere della crisi economica provocata dalla pandemia e dell\u2019incertezza sui tempi per superare gli effetti pesanti su imprese e cittadini. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2513,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[162],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Aiuti di Stato, CNA apprezza la proroga al 31 dicembre decisa dalla Commissione UE -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/aiuti-di-stato-cna-apprezza-la-proroga-al-31-dicembre-decisa-dalla-commissione-ue\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aiuti di Stato, CNA apprezza la proroga al 31 dicembre decisa dalla Commissione UE -\" \/>\n<meta property=\"og:description\" content=\"CNA apprezza la decisione della Commissione Europea di prorogare fino al 31 dicembre il quadro temporaneo sugli aiuti di Stato accogliendo le richieste di artigiani e piccole imprese di estendere la deroga alla luce del permanere della crisi economica provocata dalla pandemia e dell\u2019incertezza sui tempi per superare gli effetti pesanti su imprese e cittadini. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/aiuti-di-stato-cna-apprezza-la-proroga-al-31-dicembre-decisa-dalla-commissione-ue\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-29T11:01:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/02\/Schermata-2020-02-13-alle-10.24.47.png\" \/>\n\t<meta property=\"og:image:width\" content=\"744\" \/>\n\t<meta property=\"og:image:height\" content=\"424\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/aiuti-di-stato-cna-apprezza-la-proroga-al-31-dicembre-decisa-dalla-commissione-ue\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/aiuti-di-stato-cna-apprezza-la-proroga-al-31-dicembre-decisa-dalla-commissione-ue\/\",\"name\":\"Aiuti di Stato, CNA apprezza la proroga al 31 dicembre decisa dalla Commissione UE -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/aiuti-di-stato-cna-apprezza-la-proroga-al-31-dicembre-decisa-dalla-commissione-ue\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/aiuti-di-stato-cna-apprezza-la-proroga-al-31-dicembre-decisa-dalla-commissione-ue\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/02\/Schermata-2020-02-13-alle-10.24.47.png\",\"datePublished\":\"2021-01-29T11:01:21+00:00\",\"dateModified\":\"2021-01-29T11:01:21+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/aiuti-di-stato-cna-apprezza-la-proroga-al-31-dicembre-decisa-dalla-commissione-ue\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/aiuti-di-stato-cna-apprezza-la-proroga-al-31-dicembre-decisa-dalla-commissione-ue\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/aiuti-di-stato-cna-apprezza-la-proroga-al-31-dicembre-decisa-dalla-commissione-ue\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/02\/Schermata-2020-02-13-alle-10.24.47.png\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/02\/Schermata-2020-02-13-alle-10.24.47.png\",\"width\":744,\"height\":424,\"caption\":\"europa parlamento\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/aiuti-di-stato-cna-apprezza-la-proroga-al-31-dicembre-decisa-dalla-commissione-ue\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aiuti di Stato, CNA apprezza la proroga al 31 dicembre decisa dalla Commissione UE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aiuti di Stato, CNA apprezza la proroga al 31 dicembre decisa dalla Commissione UE -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/aiuti-di-stato-cna-apprezza-la-proroga-al-31-dicembre-decisa-dalla-commissione-ue\/","og_locale":"it_IT","og_type":"article","og_title":"Aiuti di Stato, CNA apprezza la proroga al 31 dicembre decisa dalla Commissione UE -","og_description":"CNA apprezza la decisione della Commissione Europea di prorogare fino al 31 dicembre il quadro temporaneo sugli aiuti di Stato accogliendo le richieste di artigiani e piccole imprese di estendere la deroga alla luce del permanere della crisi economica provocata dalla pandemia e dell\u2019incertezza sui tempi per superare gli effetti pesanti su imprese e cittadini. [&hellip;]","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/aiuti-di-stato-cna-apprezza-la-proroga-al-31-dicembre-decisa-dalla-commissione-ue\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2021-01-29T11:01:21+00:00","og_image":[{"width":744,"height":424,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/02\/Schermata-2020-02-13-alle-10.24.47.png","type":"image\/png"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/aiuti-di-stato-cna-apprezza-la-proroga-al-31-dicembre-decisa-dalla-commissione-ue\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/aiuti-di-stato-cna-apprezza-la-proroga-al-31-dicembre-decisa-dalla-commissione-ue\/","name":"Aiuti di Stato, CNA apprezza la proroga al 31 dicembre decisa dalla Commissione UE -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/aiuti-di-stato-cna-apprezza-la-proroga-al-31-dicembre-decisa-dalla-commissione-ue\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/aiuti-di-stato-cna-apprezza-la-proroga-al-31-dicembre-decisa-dalla-commissione-ue\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/02\/Schermata-2020-02-13-alle-10.24.47.png","datePublished":"2021-01-29T11:01:21+00:00","dateModified":"2021-01-29T11:01:21+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/aiuti-di-stato-cna-apprezza-la-proroga-al-31-dicembre-decisa-dalla-commissione-ue\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/aiuti-di-stato-cna-apprezza-la-proroga-al-31-dicembre-decisa-dalla-commissione-ue\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/aiuti-di-stato-cna-apprezza-la-proroga-al-31-dicembre-decisa-dalla-commissione-ue\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/02\/Schermata-2020-02-13-alle-10.24.47.png","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/02\/Schermata-2020-02-13-alle-10.24.47.png","width":744,"height":424,"caption":"europa parlamento"},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/aiuti-di-stato-cna-apprezza-la-proroga-al-31-dicembre-decisa-dalla-commissione-ue\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"Aiuti di Stato, CNA apprezza la proroga al 31 dicembre decisa dalla Commissione UE"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/5252"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=5252"}],"version-history":[{"count":1,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/5252\/revisions"}],"predecessor-version":[{"id":5253,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/5252\/revisions\/5253"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/2513"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=5252"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=5252"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=5252"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}