{"id":5269,"date":"2021-02-01T09:38:21","date_gmt":"2021-02-01T08:38:21","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=5269"},"modified":"2021-02-01T09:38:21","modified_gmt":"2021-02-01T08:38:21","slug":"vaccini-pubblicato-il-contratto-tra-la-commissione-europea-e-astrazeneca","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/vaccini-pubblicato-il-contratto-tra-la-commissione-europea-e-astrazeneca\/","title":{"rendered":"Vaccini, pubblicato il contratto tra la Commissione europea e AstraZeneca"},"content":{"rendered":"<p><span class=\"dropcap dropcap3\">A<\/span> seguito della rinnovata richiesta della Commissione europea, il 27 gennaio 2021 la societ\u00e0 farmaceutica AstraZeneca ha accettato di pubblicare la versione espunta delle informazioni riservate del contratto preliminare di acquisto <a href=\"https:\/\/ec.europa.eu\/commission\/presscorner\/detail\/it\/ip_20_1524\">firmato<\/a> tra le due parti il 27 agosto 2020.<\/p>\n<p>La Commissione accoglie con favore l&#8217;impegno di AstraZeneca per una maggiore trasparenza nell&#8217;ambito della sua partecipazione all&#8217;attuazione della strategia dell&#8217;UE sui vaccini.<\/p>\n<p>Trasparenza e responsabilit\u00e0 sono importanti per il rafforzamento della fiducia dei cittadini europei e per l&#8217;efficacia e la sicurezza dei vaccini per essi acquistati a livello di UE.<\/p>\n<p>La Commissione spera di poter pubblicare nel prossimo futuro tutti i contratti stipulati nel quadro degli accordi preliminari di acquisto.<\/p>\n<p>Il contratto pubblicato oggi contiene parti espunte relative a informazioni riservate, quali i dettagli delle fatture. Il contratto con AstraZeneca \u00e8 il secondo a essere pubblicato, dopo che CureVac ha accettato di pubblicare il suo <a href=\"https:\/\/ec.europa.eu\/commission\/presscorner\/detail\/it\/qanda_20_2467\">accordo preliminare di acquisto<\/a> con la Commissione europea.<\/p>\n<p>Per la Commissione, la tutela della salute pubblica e la conclusione dei migliori accordi possibili con le aziende, in modo che i vaccini siano economicamente accessibili, sicuri ed efficaci, sono fattori di fondamentale importanza.<\/p>\n<p>Il contratto negoziato dalla Commissione europea unitamente agli Stati membri dell&#8217;UE, che \u00e8 finanziato dallo <a href=\"https:\/\/ec.europa.eu\/info\/live-work-travel-eu\/coronavirus-response\/emergency-support-instrument_it\">strumento per il sostegno di emergenza<\/a>, \u00e8 stato approvato il 14 agosto ed \u00e8 entrato in vigore il 27 agosto.<\/p>\n<p>In virt\u00f9 di questo contratto, gli Stati membri possono acquistare 300 milioni di dosi del vaccino prodotto da AstraZeneca, con un&#8217;opzione per l&#8217;acquisto di ulteriori 100 milioni di dosi da distribuire in proporzione alla popolazione. Il contratto consente inoltre agli Stati membri di donare le loro dosi di vaccino a paesi a reddito medio-basso o di ridistribuirlo ad altri paesi europei.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A seguito della rinnovata richiesta della Commissione europea, il 27 gennaio 2021 la societ\u00e0 farmaceutica AstraZeneca ha accettato di pubblicare la versione espunta delle informazioni riservate del contratto preliminare di acquisto firmato tra le due parti il 27 agosto 2020. La Commissione accoglie con favore l&#8217;impegno di AstraZeneca per una maggiore trasparenza nell&#8217;ambito della sua [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1042,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[128],"tags":[1030,1561],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Vaccini, pubblicato il contratto tra la Commissione europea e AstraZeneca -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/vaccini-pubblicato-il-contratto-tra-la-commissione-europea-e-astrazeneca\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vaccini, pubblicato il contratto tra la Commissione europea e AstraZeneca -\" \/>\n<meta property=\"og:description\" content=\"A seguito della rinnovata richiesta della Commissione europea, il 27 gennaio 2021 la societ\u00e0 farmaceutica AstraZeneca ha accettato di pubblicare la versione espunta delle informazioni riservate del contratto preliminare di acquisto firmato tra le due parti il 27 agosto 2020. La Commissione accoglie con favore l&#8217;impegno di AstraZeneca per una maggiore trasparenza nell&#8217;ambito della sua [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/vaccini-pubblicato-il-contratto-tra-la-commissione-europea-e-astrazeneca\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2021-02-01T08:38:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/06\/laptop-3196481_960_720.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/vaccini-pubblicato-il-contratto-tra-la-commissione-europea-e-astrazeneca\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/vaccini-pubblicato-il-contratto-tra-la-commissione-europea-e-astrazeneca\/\",\"name\":\"Vaccini, pubblicato il contratto tra la Commissione europea e AstraZeneca -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/vaccini-pubblicato-il-contratto-tra-la-commissione-europea-e-astrazeneca\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/vaccini-pubblicato-il-contratto-tra-la-commissione-europea-e-astrazeneca\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/06\/laptop-3196481_960_720.jpg\",\"datePublished\":\"2021-02-01T08:38:21+00:00\",\"dateModified\":\"2021-02-01T08:38:21+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/vaccini-pubblicato-il-contratto-tra-la-commissione-europea-e-astrazeneca\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/vaccini-pubblicato-il-contratto-tra-la-commissione-europea-e-astrazeneca\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/vaccini-pubblicato-il-contratto-tra-la-commissione-europea-e-astrazeneca\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/06\/laptop-3196481_960_720.jpg\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/06\/laptop-3196481_960_720.jpg\",\"width\":960,\"height\":640},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/vaccini-pubblicato-il-contratto-tra-la-commissione-europea-e-astrazeneca\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vaccini, pubblicato il contratto tra la Commissione europea e AstraZeneca\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vaccini, pubblicato il contratto tra la Commissione europea e AstraZeneca -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/vaccini-pubblicato-il-contratto-tra-la-commissione-europea-e-astrazeneca\/","og_locale":"it_IT","og_type":"article","og_title":"Vaccini, pubblicato il contratto tra la Commissione europea e AstraZeneca -","og_description":"A seguito della rinnovata richiesta della Commissione europea, il 27 gennaio 2021 la societ\u00e0 farmaceutica AstraZeneca ha accettato di pubblicare la versione espunta delle informazioni riservate del contratto preliminare di acquisto firmato tra le due parti il 27 agosto 2020. La Commissione accoglie con favore l&#8217;impegno di AstraZeneca per una maggiore trasparenza nell&#8217;ambito della sua [&hellip;]","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/vaccini-pubblicato-il-contratto-tra-la-commissione-europea-e-astrazeneca\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2021-02-01T08:38:21+00:00","og_image":[{"width":960,"height":640,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/06\/laptop-3196481_960_720.jpg","type":"image\/jpeg"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/vaccini-pubblicato-il-contratto-tra-la-commissione-europea-e-astrazeneca\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/vaccini-pubblicato-il-contratto-tra-la-commissione-europea-e-astrazeneca\/","name":"Vaccini, pubblicato il contratto tra la Commissione europea e AstraZeneca -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/vaccini-pubblicato-il-contratto-tra-la-commissione-europea-e-astrazeneca\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/vaccini-pubblicato-il-contratto-tra-la-commissione-europea-e-astrazeneca\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/06\/laptop-3196481_960_720.jpg","datePublished":"2021-02-01T08:38:21+00:00","dateModified":"2021-02-01T08:38:21+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/vaccini-pubblicato-il-contratto-tra-la-commissione-europea-e-astrazeneca\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/vaccini-pubblicato-il-contratto-tra-la-commissione-europea-e-astrazeneca\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/vaccini-pubblicato-il-contratto-tra-la-commissione-europea-e-astrazeneca\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/06\/laptop-3196481_960_720.jpg","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/06\/laptop-3196481_960_720.jpg","width":960,"height":640},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/vaccini-pubblicato-il-contratto-tra-la-commissione-europea-e-astrazeneca\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"Vaccini, pubblicato il contratto tra la Commissione europea e AstraZeneca"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/5269"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=5269"}],"version-history":[{"count":1,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/5269\/revisions"}],"predecessor-version":[{"id":5270,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/5269\/revisions\/5270"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/1042"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=5269"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=5269"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=5269"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}