{"id":5305,"date":"2021-02-04T16:16:43","date_gmt":"2021-02-04T15:16:43","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=5305"},"modified":"2021-02-04T16:16:43","modified_gmt":"2021-02-04T15:16:43","slug":"bollette-impazzite-6-mila-euro-di-luce-da-nord-a-sud-acqua-luce-e-gas-da-migliaia-di-euro-cosa-fare","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/bollette-impazzite-6-mila-euro-di-luce-da-nord-a-sud-acqua-luce-e-gas-da-migliaia-di-euro-cosa-fare\/","title":{"rendered":"Bollette impazzite. 6 mila euro di luce. Da nord a sud acqua, luce e gas da migliaia di euro. cosa fare?"},"content":{"rendered":"<div>\n<div>\n<div class=\"entry-content\">\n<div class=\"entry-content\">\n<div class=\"entry-content\">\n<div class=\"entry-content\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div>\n<div class=\"entry-content\">\n<div class=\"entry-content\">\n<div class=\"entry-content\">\n<div class=\"entry-content\">\n<p><span class=\"dropcap dropcap3\">L<\/span>\u2019ultima in ordine di tempo \u00e8 una bolletta per la fornitura di\u00a0<strong>energia elettrica domestica\u00a0<\/strong>pari a\u00a0<strong>6.854,05 euro<\/strong>\u00a0con scadenza febbraio 2021 per un ricalcolo che va dal 2015 al 2019.\u00a0<strong>Federcontribuenti: \u2018<\/strong>\u20181334,63 di accise e Iva, 2038,96 di spesa oneri di sistema, 2401,60 di spesa energia.<\/p>\n<p>Le holding che gestiscono a livello nazionale acqua, luce e gas, grazie alla classe politica indaffarata costantemente nella trattativa poltronificio, hanno trovato il modo di beffarsi della Legge che vietava il conguaglio oltre il biennio. A questi utenti penseremo noi, tuttavia ci\u00f2 che stanno facendo \u00e8 vergognoso\u201d. <strong>Cosa fare in caso di una bolletta impazzita?<\/strong><\/p>\n<p>Gli utenti devono sapere di avere dei diritti e degli strumenti di cui possono avvalersi senza intraprendere azioni legali lunghe e costose: \u201dqueste bollette vanno sempre contestate in ogni sede affinch\u00e9 non si lascino le aziende libere di speculare sulla pelle dei consumatori\u201d.<\/p>\n<p>Gli utenti possono agire da soli o farsi assistere da una Associazione\u201d.<\/p>\n<p><strong>Cosa sta succedendo nei mercati e nella gestione della filiera di luce, gas e acqua?<\/strong><\/p>\n<p>\u201dSta predendo forma quella struttura pseudo monopolistica, che da anni stiamo denunciando senza ricevere la giusta attenzione. Sono quattro le holding, quotate in borsa, che in Italia gestiscono tutta la filiera dell\u2019energia elettrica, gas e acqua. Fingendo di assimilare una normativa europea con la Legge 481 del 1995 viene istituita L\u2019<strong>ARERA<\/strong>, un\u2019autorit\u00e0 amministrativa indipendente della Repubblica Italiana che ha la funzione di favorire lo sviluppo di mercati concorrenziali nelle filiere elettriche, del gas naturale e dell\u2019acqua potabile, tramite la regolazione tariffaria, dell\u2019accesso alle reti, dello standard di qualit\u00e0 dei servizi, del funzionamento dei mercati e la tutela dei clienti e degli utenti finali. Le risorse per il suo funzionamento non provengono dal bilancio dello Stato, ma da un\u00a0<strong>contributo sui ricavi degli operatori regolati;\u00a0<\/strong>tale autorit\u00e0, \u00e8 un organo collegiale composto dal presidente e da quattro componenti nominati con decreto del\u00a0<strong>Presidente della Repubblica<\/strong>, previa\u00a0<strong>deliberazione del Consiglio dei ministri<\/strong>\u00a0su proposta dei ministri competenti e con il parere favorevole di almeno due terzi dei componenti delle competenti\u00a0<strong>commissioni parlamentari.<\/strong><\/p>\n<p>In questi ultimi mesi le aziende fornitrici, sotto strutture delle holding principali, in forza a delle circolari Arera approvate fin dal 2017, dietro al paravento degli investimenti per potenziare o per la manutenzione delle reti esistenti possono aumentare le tariffe che ricadono cos\u00ec sugli utenti finali. In questo modo la legge che prescrive il conguaglio ogni due anni viene del tutto raggirata (il conguaglio diventa ricalcolo retroattivo).<\/p>\n<p>\u201dSu ogni santa bolletta gli utenti pagano gi\u00e0 la manutenzione pi\u00f9 tasse \u2013 accise \u2013 IVA; autorizzare il ricalcolo retroattivo (in questo caso dal 2015 ) \u00e8 semplicemente fare speculazione; lasciare che sia la sola ARERA, la quale riceve i contributi direttamente dai ricavi degli operatori regolati, a stabilire le tariffe \u00e8 perversione allo stato puro per motivi talmente palesi da non spiegarci come le nostre commissioni parlamentari componenti non abbiano mai pensato di impedire questa grave ingiustizia a danno dei consumatori.<\/p>\n<p>Se tale Autorit\u00e0 amministrativa indipendente viene istituita in seguito alla decisioni dell\u2019Unione europea del 1996 e del 1998 relative alla l<strong>iberalizzazione<\/strong>\u00a0del settore dell\u2019energia elettrica e quello del gas naturale, per\u00a0<strong>sostituire<\/strong>\u00a0di fatto<strong>\u00a0i monopoli<\/strong>\u00a0presenti nella maggior parte degli Stati membri, non diventa essa stessa una struttura monopolisitica? La liberalizzazione del mercato e tanto meno la libera concorrenza restano un miraggio. Trattandosi di forniture indispensabili dovrebbe essere il governo solo a stabilire norme e tariffe a tutela degli stessi consumatori.<\/p>\n<p>&nbsp;<\/p>\n<h3><\/h3>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019ultima in ordine di tempo \u00e8 una bolletta per la fornitura di\u00a0energia elettrica domestica\u00a0pari a\u00a06.854,05 euro\u00a0con scadenza febbraio 2021 per un ricalcolo che va dal 2015 al 2019.\u00a0Federcontribuenti: \u2018\u20181334,63 di accise e Iva, 2038,96 di spesa oneri di sistema, 2401,60 di spesa energia. Le holding che gestiscono a livello nazionale acqua, luce e gas, grazie [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5306,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[56],"tags":[1574,913,1573],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Bollette impazzite. 6 mila euro di luce. Da nord a sud acqua, luce e gas da migliaia di euro. cosa fare? -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/bollette-impazzite-6-mila-euro-di-luce-da-nord-a-sud-acqua-luce-e-gas-da-migliaia-di-euro-cosa-fare\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bollette impazzite. 6 mila euro di luce. Da nord a sud acqua, luce e gas da migliaia di euro. cosa fare? -\" \/>\n<meta property=\"og:description\" content=\"L\u2019ultima in ordine di tempo \u00e8 una bolletta per la fornitura di\u00a0energia elettrica domestica\u00a0pari a\u00a06.854,05 euro\u00a0con scadenza febbraio 2021 per un ricalcolo che va dal 2015 al 2019.\u00a0Federcontribuenti: \u2018\u20181334,63 di accise e Iva, 2038,96 di spesa oneri di sistema, 2401,60 di spesa energia. Le holding che gestiscono a livello nazionale acqua, luce e gas, grazie [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/bollette-impazzite-6-mila-euro-di-luce-da-nord-a-sud-acqua-luce-e-gas-da-migliaia-di-euro-cosa-fare\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2021-02-04T15:16:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2021\/02\/energia-elettrica-e1612451772855.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"655\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/bollette-impazzite-6-mila-euro-di-luce-da-nord-a-sud-acqua-luce-e-gas-da-migliaia-di-euro-cosa-fare\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/bollette-impazzite-6-mila-euro-di-luce-da-nord-a-sud-acqua-luce-e-gas-da-migliaia-di-euro-cosa-fare\/\",\"name\":\"Bollette impazzite. 6 mila euro di luce. Da nord a sud acqua, luce e gas da migliaia di euro. cosa fare? -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/bollette-impazzite-6-mila-euro-di-luce-da-nord-a-sud-acqua-luce-e-gas-da-migliaia-di-euro-cosa-fare\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/bollette-impazzite-6-mila-euro-di-luce-da-nord-a-sud-acqua-luce-e-gas-da-migliaia-di-euro-cosa-fare\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2021\/02\/energia-elettrica-e1612451772855.jpg\",\"datePublished\":\"2021-02-04T15:16:43+00:00\",\"dateModified\":\"2021-02-04T15:16:43+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/bollette-impazzite-6-mila-euro-di-luce-da-nord-a-sud-acqua-luce-e-gas-da-migliaia-di-euro-cosa-fare\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/bollette-impazzite-6-mila-euro-di-luce-da-nord-a-sud-acqua-luce-e-gas-da-migliaia-di-euro-cosa-fare\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/bollette-impazzite-6-mila-euro-di-luce-da-nord-a-sud-acqua-luce-e-gas-da-migliaia-di-euro-cosa-fare\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2021\/02\/energia-elettrica-e1612451772855.jpg\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2021\/02\/energia-elettrica-e1612451772855.jpg\",\"width\":768,\"height\":655},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/bollette-impazzite-6-mila-euro-di-luce-da-nord-a-sud-acqua-luce-e-gas-da-migliaia-di-euro-cosa-fare\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bollette impazzite. 6 mila euro di luce. Da nord a sud acqua, luce e gas da migliaia di euro. cosa fare?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bollette impazzite. 6 mila euro di luce. Da nord a sud acqua, luce e gas da migliaia di euro. cosa fare? -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/bollette-impazzite-6-mila-euro-di-luce-da-nord-a-sud-acqua-luce-e-gas-da-migliaia-di-euro-cosa-fare\/","og_locale":"it_IT","og_type":"article","og_title":"Bollette impazzite. 6 mila euro di luce. Da nord a sud acqua, luce e gas da migliaia di euro. cosa fare? -","og_description":"L\u2019ultima in ordine di tempo \u00e8 una bolletta per la fornitura di\u00a0energia elettrica domestica\u00a0pari a\u00a06.854,05 euro\u00a0con scadenza febbraio 2021 per un ricalcolo che va dal 2015 al 2019.\u00a0Federcontribuenti: \u2018\u20181334,63 di accise e Iva, 2038,96 di spesa oneri di sistema, 2401,60 di spesa energia. Le holding che gestiscono a livello nazionale acqua, luce e gas, grazie [&hellip;]","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/bollette-impazzite-6-mila-euro-di-luce-da-nord-a-sud-acqua-luce-e-gas-da-migliaia-di-euro-cosa-fare\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2021-02-04T15:16:43+00:00","og_image":[{"width":768,"height":655,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2021\/02\/energia-elettrica-e1612451772855.jpg","type":"image\/jpeg"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/bollette-impazzite-6-mila-euro-di-luce-da-nord-a-sud-acqua-luce-e-gas-da-migliaia-di-euro-cosa-fare\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/bollette-impazzite-6-mila-euro-di-luce-da-nord-a-sud-acqua-luce-e-gas-da-migliaia-di-euro-cosa-fare\/","name":"Bollette impazzite. 6 mila euro di luce. Da nord a sud acqua, luce e gas da migliaia di euro. cosa fare? -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/bollette-impazzite-6-mila-euro-di-luce-da-nord-a-sud-acqua-luce-e-gas-da-migliaia-di-euro-cosa-fare\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/bollette-impazzite-6-mila-euro-di-luce-da-nord-a-sud-acqua-luce-e-gas-da-migliaia-di-euro-cosa-fare\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2021\/02\/energia-elettrica-e1612451772855.jpg","datePublished":"2021-02-04T15:16:43+00:00","dateModified":"2021-02-04T15:16:43+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/bollette-impazzite-6-mila-euro-di-luce-da-nord-a-sud-acqua-luce-e-gas-da-migliaia-di-euro-cosa-fare\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/bollette-impazzite-6-mila-euro-di-luce-da-nord-a-sud-acqua-luce-e-gas-da-migliaia-di-euro-cosa-fare\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/bollette-impazzite-6-mila-euro-di-luce-da-nord-a-sud-acqua-luce-e-gas-da-migliaia-di-euro-cosa-fare\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2021\/02\/energia-elettrica-e1612451772855.jpg","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2021\/02\/energia-elettrica-e1612451772855.jpg","width":768,"height":655},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/bollette-impazzite-6-mila-euro-di-luce-da-nord-a-sud-acqua-luce-e-gas-da-migliaia-di-euro-cosa-fare\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"Bollette impazzite. 6 mila euro di luce. Da nord a sud acqua, luce e gas da migliaia di euro. cosa fare?"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/5305"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=5305"}],"version-history":[{"count":1,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/5305\/revisions"}],"predecessor-version":[{"id":5307,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/5305\/revisions\/5307"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/5306"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=5305"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=5305"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=5305"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}