{"id":5429,"date":"2021-02-18T12:40:27","date_gmt":"2021-02-18T11:40:27","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=5429"},"modified":"2021-02-18T12:40:27","modified_gmt":"2021-02-18T11:40:27","slug":"coronavirus-misure-insufficienti-per-piegare-curva-contagi","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-misure-insufficienti-per-piegare-curva-contagi\/","title":{"rendered":"Coronavirus, misure insufficienti per piegare curva contagi"},"content":{"rendered":"<p><span class=\"dropcap dropcap3\">I<\/span>l monitoraggio indipendente della Fondazione GIMBE conferma nella settimana 10-16 febbraio 2021, rispetto alla precedente, un numero stabile di nuovi casi (84.272 vs 84.711) . Scendono i casi attualmente positivi (393.686 vs 413.967), le persone in isolamento domiciliare (373.149 vs 392.312), i ricoveri con sintomi (18.463 vs 19.512), le terapie intensive (2.074 vs 2.143) e i decessi (2.169 vs 2.658) . In dettaglio, rispetto alla settimana precedente, si registrano le seguenti variazioni:<\/p>\n<ul>\n<li>Decessi: 2.169 (-18,4%)<\/li>\n<li>Terapia intensiva: -69 (-3,2%)<\/li>\n<li>Ricoverati con sintomi: -1.049 (-5,4%)<\/li>\n<li>Isolamento domiciliare: -19.163 (-4,9%)<\/li>\n<li>Nuovi casi: 84.272 (-0,5%)<\/li>\n<li>Casi attualmente positivi: -20.281 (-4,9%)<\/li>\n<\/ul>\n<p>\u00abAnche <a class=\"matchTooltip\">questa settimana<\/a> \u2013 afferma Nino Cartabellotta, Presidente della Fondazione GIMBE \u2013 nonostante i dati riflettano i contagi avvenuti in un\u2019Italia tinta di rosso e arancione, i nuovi casi non accennano a diminuire. E guardando ai dati regionali si rilevano segnali di incremento, favoriti dalla circolazione delle nuove varianti\u00bb. Infatti, in 12 Regioni aumentano i casi attualmente positivi per 100.000 abitanti rispetto alla settimana precedente (tabella 1) e l\u2019incremento percentuale dei casi negli ultimi 7 giorni, in apparenza stabile a livello regionale, supera il 5% in 17 Province . Sul fronte ospedaliero, l\u2019occupazione da parte di pazienti COVID supera in 3 Regioni la soglia del 40% in area medica e in 5 Regioni quella del 30% delle terapie intensive.<\/p>\n<p><b>Varianti virali.<\/b> La prima indagine condotta dall\u2019Istituto Superiore di Sanit\u00e0 ha rilevato la presenza della variante inglese in 14 su 16 Regioni, con una prevalenza media del 17,8% (range 0-59%). \u00abIn attesa dei risultati della nuova indagine che sar\u00e0 condotta anche sulle varianti brasiliana e sudafricana \u2013 dichiara Cartabellotta \u2013 invitiamo le Istituzioni a rendere pubblici i dati di prevalenza per le singole Regioni\u00bb. In un momento in cui la campagna vaccinale progredisce a rilento, la maggiore trasmissibilit\u00e0 delle varianti richiede infatti sia di attuare restrizioni tempestive ove necessario, sia di potenziare l\u2019attivit\u00e0 di sequenziamento, ancora molto lontana dagli standard fissati dalla Commissione Europea: almeno il 5%, idealmente il 10% dei tamponi molecolari positivi al SARS-CoV-2.<\/p>\n<p><b>Strategia mitigazione vs \u201czero-COVID\u201d<\/b>. Nonostante gli effetti del sistema delle Regioni \u201ca colori\u201d, introdotto pi\u00f9 di 3 mesi fa, tutte le curve si trovano in un plateau d\u2019alta quota: quasi 390 mila positivi, oltre 18.200 persone in ospedale e pi\u00f9 di 2.000 in terapia intensiva. Di conseguenza, spiega Cartabellotta \u00abse il nuovo Esecutivo manterr\u00e0 la strategia di mitigazione con il solo obiettivo di contenere il sovraccarico degli ospedali, bisogna accettare lo sfiancante stop&amp;go degli ultimi mesi almeno per tutto il 2021. Se invece intende perseguire l\u2019obiettivo europeo <a href=\"https:\/\/u7959543.ct.sendgrid.net\/ls\/click?upn=V4a3HWGduUkDrYrpMo1P8oqOiKs6u0Ll1cFJY7b6qy-2B-2BtlE2OBiQ0sGtCUaRMUJMqMs-_mLoYh0p4AWg4foFr5HgrZwPzJf04Y0URTwB4KZvNv5j0finY14j6wHCqtH3PJDKMhIichiR1lEIoCrc9bmfdLpFuriRvTZ0fl7d5S7ahJbtBnqeRJZAhLJ9q8pH89K-2B3I5iVu2eKzZylSWgedhK6GL8tn-2B2grlchjCXrxTGW-2FjkseMfOXAJbGuy1EL3-2BCh-2FawXmtbs8vbsN4IzIb6yC2-2BEHLFrffgnc7tz1teb81QhU-3D\" target=\"_blank\" rel=\"noopener noreferrer\">zero-COVID<\/a>, sulla scia della strategia tedesca <a href=\"https:\/\/u7959543.ct.sendgrid.net\/ls\/click?upn=XZ-2FJYyQDkfWzjSPGRhSChVLMuV-2BnppYphd800aESOlGCS88prujHCmigqnz20ub7GIKmW3FrIe2cNsMYC12gVZbEkB-2Fml-2FY3oskwrerKtD8DVCFX-2FbrPieXRNJdOO-2BqVtBLC_mLoYh0p4AWg4foFr5HgrZwPzJf04Y0URTwB4KZvNv5j0finY14j6wHCqtH3PJDKMhIichiR1lEIoCrc9bmfdLl8juy6sXVFudqlYnoNgocTrduDkxCfjHR9V4VjoMfxiKUXcyfi6-2FRL7egv-2B1FmNerN-2FpTN847-2B21bBPcb98xS0fy81XugumYihTdsI52QWiW4dvI1PJpRcbJefI4kkijztXLeWBSoVzFwdqfVBHSY8-3D\" target=\"_blank\" rel=\"noopener noreferrer\">No-COVID<\/a>, questo \u00e8 il momento per abbattere la curva dei contagi con un lockdown rigoroso di 2-3 settimane al fine di riprendere il tracciamento, allentare la pressione sul sistema sanitario, accelerare le vaccinazioni e contenere l\u2019emergenza varianti\u00bb. Ovviamente questa strategia presuppone che il sistema (sanitario e non) sia predisposto a far fruttare i risultati del lockdown: dal potenziamento dei sistemi di testing alla ripresa del contact tracing anche con strumenti elettronici; dal passaggio della quarantena fiduciaria a quella monitorata; dal potenziamento del trasporto locale alla messa in sicurezza di scuole, Universit\u00e0 e luoghi pubblici su areazione e deumidificazione dei locali; da rigorose politiche per controllare frontiere e flussi turistici a strategie di coinvolgimento attivo dei cittadini e misure pi\u00f9 rigorose per il rispetto delle regole.<\/p>\n<p><b>Vaccini: forniture. <\/b>Al 17 febbraio (aggiornamento ore 15:00) sono state consegnate alle Regioni 4,07 milioni dosi di vaccino, il 31,8% dei 12,8 milioni attesi per il primo trimestre 2021. In dettaglio:<\/p>\n<ul>\n<li>Pfizer\/BioNTech: 3.288.870 dosi pari al 44,7% di quelle previste (7,3 milioni), escluse le 6,6 milioni di dosi aggiuntive la cui consegna \u00e8 prevista entro giugno, ma senza dettagli sulla ripartizione trimestrale<\/li>\n<li>Moderna: 244.600 dosi pari all\u201918,4% di quelle previste (1,3 milioni)<\/li>\n<li>AstraZeneca: 542.400 dosi pari al 13% di quelle previste (4,2 milioni)<\/li>\n<\/ul>\n<p>\u00abPer rispettare la tabella di marcia delle forniture \u2013 afferma Renata Gili, responsabile Ricerca sui Servizi Sanitari della Fondazione GIMBE \u2013 entro fine marzo dovrebbero essere consegnate in media 1,45 milioni di dosi\/settimana, a fronte delle quasi 600 mila attuali\u00bb. Dal canto loro le Regioni devono essere pronte ad accelerare le somministrazioni, che <a class=\"matchTooltip\">oggi<\/a> viaggiano ad una media di circa 480 mila per settimana. \u00abPeraltro se da un lato vengono correttamente accantonate le dosi per il richiamo \u2013 puntualizza Cartabellotta \u2013 dall\u2019altro nell\u2019ultima settimana si rileva un rallentamento delle somministrazioni di quasi il 30%, possibile spia di difficolt\u00e0 organizzative della campagna vaccinale fuori da ospedali e RSA\u00bb .<\/p>\n<p><b>Vaccini: somministrazioni.<\/b> Al 17 febbraio (aggiornamento ore 15:00) hanno completato il ciclo vaccinale con la seconda dose 1.298.844 persone (2,18% della popolazione), con marcate differenze regionali: dal 1,46% della Calabria al 4,15% della Provincia Autonoma di Bolzano (figura 5). Il 66% delle dosi \u00e8 stato somministrato a \u201coperatori sanitari e sociosanitari\u201d, il 19% a \u201cpersonale non sanitario\u201d, l\u201911% a \u201cpersonale ed ospiti delle RSA\u201d e il 4% a \u201cpersone di et\u00e0 \u226580 anni\u201d, con notevoli differenze regionali (figura 6). \u00abLa vera criticit\u00e0 di questa fase 1 \u2013 precisa Gili \u2013 \u00e8 che solo il 5,9% (n. 261.008) degli over 80 ha ricevuto almeno una dose di vaccino, e solo il 2,7% (n. 117.537) ha completato il ciclo vaccinale, percentuali molto lontane dal target raccomandato dalla Commissione Europea per questa fascia di et\u00e0: 80% entro il 31 marzo 2021. Per raggiungere questo obiettivo bisognerebbe vaccinare entro quella data circa 3,5 milioni di over 80, di cui quasi 3,3 milioni non hanno ancora ricevuto la prima dose\u00bb.<\/p>\n<p>\u00abNel suo discorso al Senato \u2013 conclude Cartabellotta \u2013 il Presidente Draghi ha indicato nella lotta alla pandemia l\u2019obiettivo prioritario del suo Governo, da attuarsi attraverso il potenziamento di forniture e somministrazioni del vaccino. Una strategia necessaria ma non sufficiente, considerato che l\u2019attuale sistema delle Regioni a colori, oltre ad esasperare i cittadini e a danneggiare le attivit\u00e0 economiche con decisioni <i>last minute<\/i>, non \u00e8 riuscito a piegare la curva dei contagi e mantiene ospedali e terapie intensive al limite della saturazione, con la minaccia delle varianti che da un giorno all\u2019altro potrebbero mandare in tilt i servizi sanitari. Ma forse la politica, oltre a temere le conseguenze sociali ed economiche di un nuovo lockdown, dubita che il Paese sia davvero pronto a perseguire la strategia zero-COVID\u00bb.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il monitoraggio indipendente della Fondazione GIMBE conferma nella settimana 10-16 febbraio 2021, rispetto alla precedente, un numero stabile di nuovi casi (84.272 vs 84.711) . Scendono i casi attualmente positivi (393.686 vs 413.967), le persone in isolamento domiciliare (373.149 vs 392.312), i ricoveri con sintomi (18.463 vs 19.512), le terapie intensive (2.074 vs 2.143) e [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4309,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[35],"tags":[877,880],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Coronavirus, misure insufficienti per piegare curva contagi -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-misure-insufficienti-per-piegare-curva-contagi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Coronavirus, misure insufficienti per piegare curva contagi -\" \/>\n<meta property=\"og:description\" content=\"Il monitoraggio indipendente della Fondazione GIMBE conferma nella settimana 10-16 febbraio 2021, rispetto alla precedente, un numero stabile di nuovi casi (84.272 vs 84.711) . Scendono i casi attualmente positivi (393.686 vs 413.967), le persone in isolamento domiciliare (373.149 vs 392.312), i ricoveri con sintomi (18.463 vs 19.512), le terapie intensive (2.074 vs 2.143) e [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-misure-insufficienti-per-piegare-curva-contagi\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2021-02-18T11:40:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/10\/Schermata-2020-10-05-alle-10.54.32.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1612\" \/>\n\t<meta property=\"og:image:height\" content=\"1008\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-misure-insufficienti-per-piegare-curva-contagi\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-misure-insufficienti-per-piegare-curva-contagi\/\",\"name\":\"Coronavirus, misure insufficienti per piegare curva contagi -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-misure-insufficienti-per-piegare-curva-contagi\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-misure-insufficienti-per-piegare-curva-contagi\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/10\/Schermata-2020-10-05-alle-10.54.32.png\",\"datePublished\":\"2021-02-18T11:40:27+00:00\",\"dateModified\":\"2021-02-18T11:40:27+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-misure-insufficienti-per-piegare-curva-contagi\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-misure-insufficienti-per-piegare-curva-contagi\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-misure-insufficienti-per-piegare-curva-contagi\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/10\/Schermata-2020-10-05-alle-10.54.32.png\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/10\/Schermata-2020-10-05-alle-10.54.32.png\",\"width\":1612,\"height\":1008},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-misure-insufficienti-per-piegare-curva-contagi\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Coronavirus, misure insufficienti per piegare curva contagi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Coronavirus, misure insufficienti per piegare curva contagi -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-misure-insufficienti-per-piegare-curva-contagi\/","og_locale":"it_IT","og_type":"article","og_title":"Coronavirus, misure insufficienti per piegare curva contagi -","og_description":"Il monitoraggio indipendente della Fondazione GIMBE conferma nella settimana 10-16 febbraio 2021, rispetto alla precedente, un numero stabile di nuovi casi (84.272 vs 84.711) . Scendono i casi attualmente positivi (393.686 vs 413.967), le persone in isolamento domiciliare (373.149 vs 392.312), i ricoveri con sintomi (18.463 vs 19.512), le terapie intensive (2.074 vs 2.143) e [&hellip;]","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-misure-insufficienti-per-piegare-curva-contagi\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2021-02-18T11:40:27+00:00","og_image":[{"width":1612,"height":1008,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/10\/Schermata-2020-10-05-alle-10.54.32.png","type":"image\/png"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-misure-insufficienti-per-piegare-curva-contagi\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-misure-insufficienti-per-piegare-curva-contagi\/","name":"Coronavirus, misure insufficienti per piegare curva contagi -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-misure-insufficienti-per-piegare-curva-contagi\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-misure-insufficienti-per-piegare-curva-contagi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/10\/Schermata-2020-10-05-alle-10.54.32.png","datePublished":"2021-02-18T11:40:27+00:00","dateModified":"2021-02-18T11:40:27+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-misure-insufficienti-per-piegare-curva-contagi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-misure-insufficienti-per-piegare-curva-contagi\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-misure-insufficienti-per-piegare-curva-contagi\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/10\/Schermata-2020-10-05-alle-10.54.32.png","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/10\/Schermata-2020-10-05-alle-10.54.32.png","width":1612,"height":1008},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/coronavirus-misure-insufficienti-per-piegare-curva-contagi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"Coronavirus, misure insufficienti per piegare curva contagi"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/5429"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=5429"}],"version-history":[{"count":1,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/5429\/revisions"}],"predecessor-version":[{"id":5430,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/5429\/revisions\/5430"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/4309"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=5429"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=5429"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=5429"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}