{"id":5540,"date":"2021-03-07T16:23:02","date_gmt":"2021-03-07T15:23:02","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=5540"},"modified":"2021-03-07T16:23:02","modified_gmt":"2021-03-07T15:23:02","slug":"8-marzo-florovivaisti-italiani-ottima-annata-per-mimose","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/8-marzo-florovivaisti-italiani-ottima-annata-per-mimose\/","title":{"rendered":"8 marzo: Florovivaisti Italiani, ottima annata per mimose"},"content":{"rendered":"<p><span class=\"dropcap dropcap3\">D<\/span>opo un San Valentino positivo, boom di ordinativi per il tradizionale mercato delle mimose dell\u20198 marzo e piena soddisfazione dei produttori, dopo un 2020 che ha messo in ginocchio il florovivaismo italiano. Secondo l\u2019Associazione dei Florovivaisti Italiani, le mimose sono state vendute a 11 euro\/Kg, con un giro d\u2019affari da 15 milioni (+20% sul 2020), concentrato \u2013come sempre- nei giorni precedenti la festa della donna.<\/p>\n<p>Si erano diffuse voci di precoce fioritura nel Sud Italia, ma gli effetti si sono dimostrati insignificanti a livello nazionale, perch\u00e9 il 90% delle mimose \u00e8 coltivato nell\u2019entroterra del Ponente ligure (provincia di Imperia), dove il fiore \u00e8 sbocciato nei tempi attesi. Si segnala solo una leggera contrazione di prodotto dovuta all\u2019incertezza causata dalla crisi pandemica, che ha diminuito del 20% la raccolta. Restano ottime le performance dell\u2019export, che si rafforza in Russia, Polonia e Francia (+25%). Al consumo i prezzi sono stabili: i mazzetti vanno dai 5 ai 10 euro, che arrivano a 15 con l\u2019inserimento di una rosa nel bouquet.<\/p>\n<p>Il consolidamento dei mercati esteri rappresenta una promettente opportunit\u00e0 per i giovani florovivaisti che vogliano investire in una pianta simbolo del Made in Italy, perch\u00e9 coltivata ormai solo nel nostro Paese. Se in Francia le vendite sono aumentate a partire da dicembre, in Russia si concentrano durante la Maslenica, festa tradizionale ortodossa della settimana precedente la Quaresima e corrisponde al nostro carnevale. A quelle latitudini, il colore giallo vivo della mimosa porta con s\u00e9 l&#8217;ottimismo, la freschezza e la luminosit\u00e0 del sole del Mediterraneo.<\/p>\n<p>La mimosa pu\u00f2 essere, inoltre, acquistata come pianta, il prezzo varia in base alla grandezza del vaso -dai 10 euro fino ai 70 euro- e viene anche utilizzata come fronda per rendere pi\u00f9 lucenti i bouquet floreali. Per il mantenimento domestico si consiglia di collocare i fiori in piena luce, ma lontano da fonti di calore dirette. La mimosa, infatti, mal sopporta le alte temperature e l&#8217;aria secca.<\/p>\n<p>\u201cLa\u00a0produzione di\u00a0mimose, tipicamente italiana, rappresenta il 5% della produzione floricola\u00a0\u2013dichiara Aldo Alberto, presidente dei Florovivaisti Italiani- e funge abitualmente da traino ai commerci in primavera. Il trend positivo di questo 8 marzo \u00e8 un segnale positivo che d\u00e0 fiducia e ottimismo per la ripartenza che noi tutti auspichiamo\u201d.<br \/>\nIl florovivaismo \u00e8 sempre pi\u00f9 legato a celebrazioni e ricorrenze: la festa della donna e San Valentino valgono da soli il 15% del fatturato complessivo. La\u00a0mimosa\u00a0\u00e8 coltivata in Italia\u00a0su una superficie di quasi\u00a0200 ettari di terreno, che fruttano intorno\u00a0ai 30mila quintali e 150 milioni di steli.\u00a0 Ad oggi, la Liguria \u00e8 il maggior produttore di questi fiori con le sue circa\u00a01500 aziende\u00a0che la\u00a0coltivano in modo ecocompatibile\u00a0sui tipici terrazzamenti -la\u00a0pianta non ha, infatti, bisogno di trattamenti chimici.\u00a0Le variet\u00e0 pi\u00f9 diffuse sono la Turner (fiore piccolo) e la Gaulois (fiore grande), che \u00e8 la pi\u00f9 rigogliosa e pi\u00f9 rilevante commercialmente.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dopo un San Valentino positivo, boom di ordinativi per il tradizionale mercato delle mimose dell\u20198 marzo e piena soddisfazione dei produttori, dopo un 2020 che ha messo in ginocchio il florovivaismo italiano. Secondo l\u2019Associazione dei Florovivaisti Italiani, le mimose sono state vendute a 11 euro\/Kg, con un giro d\u2019affari da 15 milioni (+20% sul 2020), [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5541,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[56],"tags":[1663,1664,1665],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>8 marzo: Florovivaisti Italiani, ottima annata per mimose -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/8-marzo-florovivaisti-italiani-ottima-annata-per-mimose\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"8 marzo: Florovivaisti Italiani, ottima annata per mimose -\" \/>\n<meta property=\"og:description\" content=\"Dopo un San Valentino positivo, boom di ordinativi per il tradizionale mercato delle mimose dell\u20198 marzo e piena soddisfazione dei produttori, dopo un 2020 che ha messo in ginocchio il florovivaismo italiano. Secondo l\u2019Associazione dei Florovivaisti Italiani, le mimose sono state vendute a 11 euro\/Kg, con un giro d\u2019affari da 15 milioni (+20% sul 2020), [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/8-marzo-florovivaisti-italiani-ottima-annata-per-mimose\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-07T15:23:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2021\/03\/mimose-scaled-e1615130568262.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1708\" \/>\n\t<meta property=\"og:image:height\" content=\"1241\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/8-marzo-florovivaisti-italiani-ottima-annata-per-mimose\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/8-marzo-florovivaisti-italiani-ottima-annata-per-mimose\/\",\"name\":\"8 marzo: Florovivaisti Italiani, ottima annata per mimose -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/8-marzo-florovivaisti-italiani-ottima-annata-per-mimose\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/8-marzo-florovivaisti-italiani-ottima-annata-per-mimose\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2021\/03\/mimose-scaled-e1615130568262.jpg\",\"datePublished\":\"2021-03-07T15:23:02+00:00\",\"dateModified\":\"2021-03-07T15:23:02+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/8-marzo-florovivaisti-italiani-ottima-annata-per-mimose\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/8-marzo-florovivaisti-italiani-ottima-annata-per-mimose\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/8-marzo-florovivaisti-italiani-ottima-annata-per-mimose\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2021\/03\/mimose-scaled-e1615130568262.jpg\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2021\/03\/mimose-scaled-e1615130568262.jpg\",\"width\":1708,\"height\":1241},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/8-marzo-florovivaisti-italiani-ottima-annata-per-mimose\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"8 marzo: Florovivaisti Italiani, ottima annata per mimose\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"8 marzo: Florovivaisti Italiani, ottima annata per mimose -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/8-marzo-florovivaisti-italiani-ottima-annata-per-mimose\/","og_locale":"it_IT","og_type":"article","og_title":"8 marzo: Florovivaisti Italiani, ottima annata per mimose -","og_description":"Dopo un San Valentino positivo, boom di ordinativi per il tradizionale mercato delle mimose dell\u20198 marzo e piena soddisfazione dei produttori, dopo un 2020 che ha messo in ginocchio il florovivaismo italiano. Secondo l\u2019Associazione dei Florovivaisti Italiani, le mimose sono state vendute a 11 euro\/Kg, con un giro d\u2019affari da 15 milioni (+20% sul 2020), [&hellip;]","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/8-marzo-florovivaisti-italiani-ottima-annata-per-mimose\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2021-03-07T15:23:02+00:00","og_image":[{"width":1708,"height":1241,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2021\/03\/mimose-scaled-e1615130568262.jpg","type":"image\/jpeg"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/8-marzo-florovivaisti-italiani-ottima-annata-per-mimose\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/8-marzo-florovivaisti-italiani-ottima-annata-per-mimose\/","name":"8 marzo: Florovivaisti Italiani, ottima annata per mimose -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/8-marzo-florovivaisti-italiani-ottima-annata-per-mimose\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/8-marzo-florovivaisti-italiani-ottima-annata-per-mimose\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2021\/03\/mimose-scaled-e1615130568262.jpg","datePublished":"2021-03-07T15:23:02+00:00","dateModified":"2021-03-07T15:23:02+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/8-marzo-florovivaisti-italiani-ottima-annata-per-mimose\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/8-marzo-florovivaisti-italiani-ottima-annata-per-mimose\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/8-marzo-florovivaisti-italiani-ottima-annata-per-mimose\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2021\/03\/mimose-scaled-e1615130568262.jpg","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2021\/03\/mimose-scaled-e1615130568262.jpg","width":1708,"height":1241},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/8-marzo-florovivaisti-italiani-ottima-annata-per-mimose\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"8 marzo: Florovivaisti Italiani, ottima annata per mimose"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/5540"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=5540"}],"version-history":[{"count":1,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/5540\/revisions"}],"predecessor-version":[{"id":5542,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/5540\/revisions\/5542"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/5541"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=5540"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=5540"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=5540"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}