{"id":5706,"date":"2021-04-06T19:13:54","date_gmt":"2021-04-06T17:13:54","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=5706"},"modified":"2021-04-06T19:13:54","modified_gmt":"2021-04-06T17:13:54","slug":"dl-sostegni-cia-attenzione-a-filiere-in-crisi-e-liquidita-aziende","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/dl-sostegni-cia-attenzione-a-filiere-in-crisi-e-liquidita-aziende\/","title":{"rendered":"Dl Sostegni, Cia: attenzione a filiere in crisi e liquidit\u00e0 aziende"},"content":{"rendered":"<p><span class=\"dropcap dropcap3\">C<\/span>on l\u2019economia nazionale soffocata da pi\u00f9 di un anno di restrizioni per la pandemia, occorre prestare estrema attenzione alle filiere agricole pi\u00f9 crisi e garantire liquidit\u00e0 agli imprenditori a rischio tracollo.<\/p>\n<p>Cos\u00ec Cia-Agricoltori Italiani nell\u2019audizione in Commissioni riunite Bilancio e Finanze del Senato sul Dl Sostegni, rimarcando la necessit\u00e0 di interventi che incidano concretamente sul bilancio degli agricoltori in difficolt\u00e0.<\/p>\n<p>Positive per Cia alcune misure incluse nel provvedimento, in particolar modo l\u2019inserimento, a pieno titolo, del settore agricolo nel ristoro a fondo perduto, come anche il finanziamento, destinato a tutte le aziende agricole, di 300 milioni di euro per la decontribuzione previdenziale del mese di gennaio e, ancora, l\u2019aggiunta di 150 milioni per le filiere in crisi.<\/p>\n<p>Rispetto alle filiere, Cia chiede pi\u00f9 spazio per il settore zootecnico, incrementando la compensazione IVA; per il settore ortofrutticolo che oltre ai disagi per il Covid, ha sofferto gli eventi atmosferici e per i comparti di qualit\u00e0 che trovano sbocco nell\u2019Horeca, primo fra tutti il vino. Non pu\u00f2 pi\u00f9 aspettare, con l\u2019alta stagione alle porte, neanche il comparto agrituristico che per Cia necessit\u00e0 di promozione ampia coinvolgendo anche il turismo.<\/p>\n<p>Infine, per Cia il riavvio delle riscossioni fiscali, come previsto dal cronoprogramma del Decreto, rischia di procurare crisi di liquidit\u00e0 alle aziende e occorre adottare un procedimento che, pur nel rispetto degli adempimenti, possa scongiurarne il fallimento.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con l\u2019economia nazionale soffocata da pi\u00f9 di un anno di restrizioni per la pandemia, occorre prestare estrema attenzione alle filiere agricole pi\u00f9 crisi e garantire liquidit\u00e0 agli imprenditori a rischio tracollo. Cos\u00ec Cia-Agricoltori Italiani nell\u2019audizione in Commissioni riunite Bilancio e Finanze del Senato sul Dl Sostegni, rimarcando la necessit\u00e0 di interventi che incidano concretamente sul [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":194,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[537],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Dl Sostegni, Cia: attenzione a filiere in crisi e liquidit\u00e0 aziende -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/dl-sostegni-cia-attenzione-a-filiere-in-crisi-e-liquidita-aziende\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dl Sostegni, Cia: attenzione a filiere in crisi e liquidit\u00e0 aziende -\" \/>\n<meta property=\"og:description\" content=\"Con l\u2019economia nazionale soffocata da pi\u00f9 di un anno di restrizioni per la pandemia, occorre prestare estrema attenzione alle filiere agricole pi\u00f9 crisi e garantire liquidit\u00e0 agli imprenditori a rischio tracollo. Cos\u00ec Cia-Agricoltori Italiani nell\u2019audizione in Commissioni riunite Bilancio e Finanze del Senato sul Dl Sostegni, rimarcando la necessit\u00e0 di interventi che incidano concretamente sul [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/dl-sostegni-cia-attenzione-a-filiere-in-crisi-e-liquidita-aziende\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-06T17:13:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/08\/agricoltura.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"625\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/dl-sostegni-cia-attenzione-a-filiere-in-crisi-e-liquidita-aziende\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/dl-sostegni-cia-attenzione-a-filiere-in-crisi-e-liquidita-aziende\/\",\"name\":\"Dl Sostegni, Cia: attenzione a filiere in crisi e liquidit\u00e0 aziende -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/dl-sostegni-cia-attenzione-a-filiere-in-crisi-e-liquidita-aziende\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/dl-sostegni-cia-attenzione-a-filiere-in-crisi-e-liquidita-aziende\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/08\/agricoltura.jpg\",\"datePublished\":\"2021-04-06T17:13:54+00:00\",\"dateModified\":\"2021-04-06T17:13:54+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/dl-sostegni-cia-attenzione-a-filiere-in-crisi-e-liquidita-aziende\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/dl-sostegni-cia-attenzione-a-filiere-in-crisi-e-liquidita-aziende\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/dl-sostegni-cia-attenzione-a-filiere-in-crisi-e-liquidita-aziende\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/08\/agricoltura.jpg\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/08\/agricoltura.jpg\",\"width\":960,\"height\":625},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/dl-sostegni-cia-attenzione-a-filiere-in-crisi-e-liquidita-aziende\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dl Sostegni, Cia: attenzione a filiere in crisi e liquidit\u00e0 aziende\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dl Sostegni, Cia: attenzione a filiere in crisi e liquidit\u00e0 aziende -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/dl-sostegni-cia-attenzione-a-filiere-in-crisi-e-liquidita-aziende\/","og_locale":"it_IT","og_type":"article","og_title":"Dl Sostegni, Cia: attenzione a filiere in crisi e liquidit\u00e0 aziende -","og_description":"Con l\u2019economia nazionale soffocata da pi\u00f9 di un anno di restrizioni per la pandemia, occorre prestare estrema attenzione alle filiere agricole pi\u00f9 crisi e garantire liquidit\u00e0 agli imprenditori a rischio tracollo. Cos\u00ec Cia-Agricoltori Italiani nell\u2019audizione in Commissioni riunite Bilancio e Finanze del Senato sul Dl Sostegni, rimarcando la necessit\u00e0 di interventi che incidano concretamente sul [&hellip;]","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/dl-sostegni-cia-attenzione-a-filiere-in-crisi-e-liquidita-aziende\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2021-04-06T17:13:54+00:00","og_image":[{"width":960,"height":625,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/08\/agricoltura.jpg","type":"image\/jpeg"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/dl-sostegni-cia-attenzione-a-filiere-in-crisi-e-liquidita-aziende\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/dl-sostegni-cia-attenzione-a-filiere-in-crisi-e-liquidita-aziende\/","name":"Dl Sostegni, Cia: attenzione a filiere in crisi e liquidit\u00e0 aziende -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/dl-sostegni-cia-attenzione-a-filiere-in-crisi-e-liquidita-aziende\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/dl-sostegni-cia-attenzione-a-filiere-in-crisi-e-liquidita-aziende\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/08\/agricoltura.jpg","datePublished":"2021-04-06T17:13:54+00:00","dateModified":"2021-04-06T17:13:54+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/dl-sostegni-cia-attenzione-a-filiere-in-crisi-e-liquidita-aziende\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/dl-sostegni-cia-attenzione-a-filiere-in-crisi-e-liquidita-aziende\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/dl-sostegni-cia-attenzione-a-filiere-in-crisi-e-liquidita-aziende\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/08\/agricoltura.jpg","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/08\/agricoltura.jpg","width":960,"height":625},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/dl-sostegni-cia-attenzione-a-filiere-in-crisi-e-liquidita-aziende\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"Dl Sostegni, Cia: attenzione a filiere in crisi e liquidit\u00e0 aziende"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/5706"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=5706"}],"version-history":[{"count":1,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/5706\/revisions"}],"predecessor-version":[{"id":5707,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/5706\/revisions\/5707"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/194"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=5706"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=5706"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=5706"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}