{"id":573,"date":"2019-04-26T21:23:13","date_gmt":"2019-04-26T19:23:13","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=573"},"modified":"2019-04-26T21:23:13","modified_gmt":"2019-04-26T19:23:13","slug":"expo-2020-dubai-ultimi-giorni-per-diventare-partner-tecnico-del-padiglione-italia","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/expo-2020-dubai-ultimi-giorni-per-diventare-partner-tecnico-del-padiglione-italia\/","title":{"rendered":"Expo 2020 Dubai: ultimi giorni per diventare Partner Tecnico del Padiglione Italia"},"content":{"rendered":"<p><strong>Invitalia<\/strong>, per conto del Commissariato Generale per la partecipazione italiana all\u2019<strong>Expo 2020 di Dubai<\/strong>, ha pubblicato una Request for Proposal (RFP) per selezionare <strong>Partner Tecnici<\/strong> tra realt\u00e0 imprenditoriali, enti pubblici ed enti di ricerca, anche consorziati con imprese, che rappresentano la competenza italiana e l\u2019innovazione tecnologica pi\u00f9 avanzata e sostenibile.<\/p>\n<p>I Partner potranno partecipare direttamente alla realizzazione del Padiglione Italia mediante le diverse forme di contribuzione previste dalla normativa vigente e descritte nella documentazione di gara.<\/p>\n<p>La Request for Proposal (RFP) \u00e8 aperta a tutti gli operatori interessati a diventare Partner Tecnici, anche tra coloro che non hanno risposto alla precedente Manifestazione di interesse, del 9 novembre 2018, che aveva la finalit\u00e0 di indagare l\u2019interesse degli operatori e gli ambiti merceologici di riferimento.<\/p>\n<p>La Request for Proposal (RFP) fa seguito alla conclusione del Concorso internazionale e all\u2019aggiudicazione del Progetto del Padiglione Italia a Expo 2020 Dubai di cui sono state resi pubblici dal Commissariato sul proprio sito Concept e prime immagini dei rendering.<\/p>\n<p>Come previsto dal progetto aggiudicatario, il Padiglione Italia sar\u00e0 un Innovation Hub che dovr\u00e0 interpretare con creativit\u00e0 e innovazione il tema specifico scelto dall\u2019Italia \u201cla Bellezza unisce le Persone\u201d, con una struttura non semplicemente espositiva ma dimostrativa del migliore ingegno italiano.<\/p>\n<p>L\u2019obiettivo \u00e8 quello di offrire ai visitatori una memorabile esperienza, mostrando al mondo competenze e talenti multidisciplinari che possono diventare promotori di nuove opportunit\u00e0 formative, professionali e imprenditoriali.<\/p>\n<p>Per il tramite di questa Request for Proposal (RFP), il Padiglione Italia sar\u00e0 realizzato con il contributo di Partner Tecnici chiamati a fornire le migliori componenti costruttive, impiantistiche, tecnologiche e scenografiche, capaci di dimostrare le competenze pi\u00f9 innovative impegnate oggi nella sostenibilit\u00e0, nell\u2019economia circolare, nell\u2019architettura digitale.<\/p>\n<p>Gli operatori interessati possono trovare, allegato alla Request for Proposal (RFP), l\u2019ambito merceologico specifico con l\u2019elenco delle componenti tecniche ricercate, funzionali alla costruzione e messa in opera del Padiglione Italia.<\/p>\n<p>A fronte dei loro contributi, i Partner Tecnici per il Padiglione Italia a Expo 2020 Dubai potranno operare su una vetrina globale, unica per reputation e brand building, ricevere grande visibilit\u00e0 su spazi esterni, interni e virtuali, realizzare azioni di co-marketing e attivit\u00e0 B2B e B2C durante i sei mesi dell\u2019evento per il quale sono attesi 25 milioni di visitatori da tutto il mondo.<\/p>\n<p>La procedura \u00e8 interamente gestita attraverso la piattaforma telematica di e-procurement di Invitalia sulla quale sono reperibili tutte le informazioni relative a condizioni, modalit\u00e0 di cooperazione e aspetti specifici, ivi compresi i criteri di valutazione delle proposte ricevute, per l\u2019affidamento di contratti di partnership tecnica.<\/p>\n<p>Il testo integrale e tutti i dettagli per partecipare alla procedura Request for Proposal (RFP) sono disponibili su:<\/p>\n<ul>\n<li><a href=\"https:\/\/gareappalti.invitalia.it\">https:\/\/gareappalti.invitalia.it<\/a><\/li>\n<li><a href=\"https:\/\/italyexpo2020.it\">https:\/\/italyexpo2020.it<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Invitalia, per conto del Commissariato Generale per la partecipazione italiana all\u2019Expo 2020 di Dubai, ha pubblicato una Request for Proposal (RFP) per selezionare Partner Tecnici tra realt\u00e0 imprenditoriali, enti pubblici ed enti di ricerca, anche consorziati con imprese, che rappresentano la competenza italiana e l\u2019innovazione tecnologica pi\u00f9 avanzata e sostenibile. I Partner potranno partecipare direttamente [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":574,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[56],"tags":[257,256,101,31],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Expo 2020 Dubai: ultimi giorni per diventare Partner Tecnico del Padiglione Italia -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/expo-2020-dubai-ultimi-giorni-per-diventare-partner-tecnico-del-padiglione-italia\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Expo 2020 Dubai: ultimi giorni per diventare Partner Tecnico del Padiglione Italia -\" \/>\n<meta property=\"og:description\" content=\"Invitalia, per conto del Commissariato Generale per la partecipazione italiana all\u2019Expo 2020 di Dubai, ha pubblicato una Request for Proposal (RFP) per selezionare Partner Tecnici tra realt\u00e0 imprenditoriali, enti pubblici ed enti di ricerca, anche consorziati con imprese, che rappresentano la competenza italiana e l\u2019innovazione tecnologica pi\u00f9 avanzata e sostenibile. I Partner potranno partecipare direttamente [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/expo-2020-dubai-ultimi-giorni-per-diventare-partner-tecnico-del-padiglione-italia\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2019-04-26T19:23:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/04\/expo2020.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/expo-2020-dubai-ultimi-giorni-per-diventare-partner-tecnico-del-padiglione-italia\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/expo-2020-dubai-ultimi-giorni-per-diventare-partner-tecnico-del-padiglione-italia\/\",\"name\":\"Expo 2020 Dubai: ultimi giorni per diventare Partner Tecnico del Padiglione Italia -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/expo-2020-dubai-ultimi-giorni-per-diventare-partner-tecnico-del-padiglione-italia\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/expo-2020-dubai-ultimi-giorni-per-diventare-partner-tecnico-del-padiglione-italia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/04\/expo2020.jpg\",\"datePublished\":\"2019-04-26T19:23:13+00:00\",\"dateModified\":\"2019-04-26T19:23:13+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/expo-2020-dubai-ultimi-giorni-per-diventare-partner-tecnico-del-padiglione-italia\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/expo-2020-dubai-ultimi-giorni-per-diventare-partner-tecnico-del-padiglione-italia\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/expo-2020-dubai-ultimi-giorni-per-diventare-partner-tecnico-del-padiglione-italia\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/04\/expo2020.jpg\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/04\/expo2020.jpg\",\"width\":800,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/expo-2020-dubai-ultimi-giorni-per-diventare-partner-tecnico-del-padiglione-italia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Expo 2020 Dubai: ultimi giorni per diventare Partner Tecnico del Padiglione Italia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Expo 2020 Dubai: ultimi giorni per diventare Partner Tecnico del Padiglione Italia -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/expo-2020-dubai-ultimi-giorni-per-diventare-partner-tecnico-del-padiglione-italia\/","og_locale":"it_IT","og_type":"article","og_title":"Expo 2020 Dubai: ultimi giorni per diventare Partner Tecnico del Padiglione Italia -","og_description":"Invitalia, per conto del Commissariato Generale per la partecipazione italiana all\u2019Expo 2020 di Dubai, ha pubblicato una Request for Proposal (RFP) per selezionare Partner Tecnici tra realt\u00e0 imprenditoriali, enti pubblici ed enti di ricerca, anche consorziati con imprese, che rappresentano la competenza italiana e l\u2019innovazione tecnologica pi\u00f9 avanzata e sostenibile. I Partner potranno partecipare direttamente [&hellip;]","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/expo-2020-dubai-ultimi-giorni-per-diventare-partner-tecnico-del-padiglione-italia\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2019-04-26T19:23:13+00:00","og_image":[{"width":800,"height":600,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/04\/expo2020.jpg","type":"image\/jpeg"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/expo-2020-dubai-ultimi-giorni-per-diventare-partner-tecnico-del-padiglione-italia\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/expo-2020-dubai-ultimi-giorni-per-diventare-partner-tecnico-del-padiglione-italia\/","name":"Expo 2020 Dubai: ultimi giorni per diventare Partner Tecnico del Padiglione Italia -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/expo-2020-dubai-ultimi-giorni-per-diventare-partner-tecnico-del-padiglione-italia\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/expo-2020-dubai-ultimi-giorni-per-diventare-partner-tecnico-del-padiglione-italia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/04\/expo2020.jpg","datePublished":"2019-04-26T19:23:13+00:00","dateModified":"2019-04-26T19:23:13+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/expo-2020-dubai-ultimi-giorni-per-diventare-partner-tecnico-del-padiglione-italia\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/expo-2020-dubai-ultimi-giorni-per-diventare-partner-tecnico-del-padiglione-italia\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/expo-2020-dubai-ultimi-giorni-per-diventare-partner-tecnico-del-padiglione-italia\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/04\/expo2020.jpg","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/04\/expo2020.jpg","width":800,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/expo-2020-dubai-ultimi-giorni-per-diventare-partner-tecnico-del-padiglione-italia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"Expo 2020 Dubai: ultimi giorni per diventare Partner Tecnico del Padiglione Italia"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/573"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=573"}],"version-history":[{"count":1,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/573\/revisions"}],"predecessor-version":[{"id":575,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/573\/revisions\/575"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/574"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=573"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=573"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=573"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}