{"id":5765,"date":"2021-04-20T18:44:33","date_gmt":"2021-04-20T16:44:33","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=5765"},"modified":"2021-04-20T18:44:45","modified_gmt":"2021-04-20T16:44:45","slug":"confesercenti-incontra-boschi-imprese-hanno-bisogno-di-sostegni-e-credito","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/confesercenti-incontra-boschi-imprese-hanno-bisogno-di-sostegni-e-credito\/","title":{"rendered":"Confesercenti incontra Boschi, &#8220;Imprese hanno bisogno di sostegni e credito"},"content":{"rendered":"<p><span class=\"dropcap dropcap3\">S<\/span>ostegni migliori, credito pi\u00f9 veloce e sostenibile, e un PNRR pi\u00f9 attento alle imprese\u00a0del\u00a0terziario e del turismo, le pi\u00f9 colpite dalla crisi innescata da pandemia e restrizioni.<\/p>\n<p>Sono stati questi i temi posti da Confesercenti all\u2019attenzione dell\u2019onorevole Maria Elena Boschi, Capogruppo di Italia Viva alla Camera dei Deputati, che oggi ha incontrato a Roma i vertici dell\u2019associazione delle imprese del terziario, dei servizi e del turismo.<\/p>\n<p>\u201cDopo oltre un anno di restrizioni &#8211; commenta la Presidente De Luise &#8211; le attivit\u00e0 economiche, soprattutto quelle dei nostri settori, le pi\u00f9 colpite da divieti e limitazioni, hanno bisogno di interventi mirati. A partire dagli interventi sul credito: servono misure per renderlo pi\u00f9 rapido ed accessibile per tutti ed in particolare per le attivit\u00e0 di minori dimensioni, ma anche una proroga delle moratorie esistenti e un piano di rifinanziamento dei Confidi che permetta di sostenere meglio le necessit\u00e0 delle imprese\u201d.<\/p>\n<p>\u201cAllo stesso modo sono necessari anche\u00a0un nuovo modello di sostegni &#8211; che tenga conto non solo delle perdite subite dalle imprese ma anche dei costi fissi sostenuti durante lo stop &#8211; ed un PNRR che guardi veramente al futuro, dando priorit\u00e0 alla ripresa e al rilancio dei comparti del turismo e del terziario, che sono quelli che stanno pagando il prezzo pi\u00f9 alto della crisi. Proposte\u00a0\u2013 conclude De Luise &#8211;\u00a0che l\u2019onorevole Boschi ha ascoltato con interesse e disponibilit\u00e0, impegnandosi a proseguire il confronto con Confesercenti su questi temi gi\u00e0 nei prossimi giorni\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sostegni migliori, credito pi\u00f9 veloce e sostenibile, e un PNRR pi\u00f9 attento alle imprese\u00a0del\u00a0terziario e del turismo, le pi\u00f9 colpite dalla crisi innescata da pandemia e restrizioni. Sono stati questi i temi posti da Confesercenti all\u2019attenzione dell\u2019onorevole Maria Elena Boschi, Capogruppo di Italia Viva alla Camera dei Deputati, che oggi ha incontrato a Roma i [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5002,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[56],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Confesercenti incontra Boschi, &quot;Imprese hanno bisogno di sostegni e credito -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/confesercenti-incontra-boschi-imprese-hanno-bisogno-di-sostegni-e-credito\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Confesercenti incontra Boschi, &quot;Imprese hanno bisogno di sostegni e credito -\" \/>\n<meta property=\"og:description\" content=\"Sostegni migliori, credito pi\u00f9 veloce e sostenibile, e un PNRR pi\u00f9 attento alle imprese\u00a0del\u00a0terziario e del turismo, le pi\u00f9 colpite dalla crisi innescata da pandemia e restrizioni. Sono stati questi i temi posti da Confesercenti all\u2019attenzione dell\u2019onorevole Maria Elena Boschi, Capogruppo di Italia Viva alla Camera dei Deputati, che oggi ha incontrato a Roma i [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/confesercenti-incontra-boschi-imprese-hanno-bisogno-di-sostegni-e-credito\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-20T16:44:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-20T16:44:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2021\/01\/Schermata-2021-01-03-alle-15.40.37.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1360\" \/>\n\t<meta property=\"og:image:height\" content=\"890\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/confesercenti-incontra-boschi-imprese-hanno-bisogno-di-sostegni-e-credito\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/confesercenti-incontra-boschi-imprese-hanno-bisogno-di-sostegni-e-credito\/\",\"name\":\"Confesercenti incontra Boschi, \\\"Imprese hanno bisogno di sostegni e credito -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/confesercenti-incontra-boschi-imprese-hanno-bisogno-di-sostegni-e-credito\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/confesercenti-incontra-boschi-imprese-hanno-bisogno-di-sostegni-e-credito\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2021\/01\/Schermata-2021-01-03-alle-15.40.37.png\",\"datePublished\":\"2021-04-20T16:44:33+00:00\",\"dateModified\":\"2021-04-20T16:44:45+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/confesercenti-incontra-boschi-imprese-hanno-bisogno-di-sostegni-e-credito\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/confesercenti-incontra-boschi-imprese-hanno-bisogno-di-sostegni-e-credito\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/confesercenti-incontra-boschi-imprese-hanno-bisogno-di-sostegni-e-credito\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2021\/01\/Schermata-2021-01-03-alle-15.40.37.png\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2021\/01\/Schermata-2021-01-03-alle-15.40.37.png\",\"width\":1360,\"height\":890},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/confesercenti-incontra-boschi-imprese-hanno-bisogno-di-sostegni-e-credito\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Confesercenti incontra Boschi, &#8220;Imprese hanno bisogno di sostegni e credito\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Confesercenti incontra Boschi, \"Imprese hanno bisogno di sostegni e credito -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/confesercenti-incontra-boschi-imprese-hanno-bisogno-di-sostegni-e-credito\/","og_locale":"it_IT","og_type":"article","og_title":"Confesercenti incontra Boschi, \"Imprese hanno bisogno di sostegni e credito -","og_description":"Sostegni migliori, credito pi\u00f9 veloce e sostenibile, e un PNRR pi\u00f9 attento alle imprese\u00a0del\u00a0terziario e del turismo, le pi\u00f9 colpite dalla crisi innescata da pandemia e restrizioni. Sono stati questi i temi posti da Confesercenti all\u2019attenzione dell\u2019onorevole Maria Elena Boschi, Capogruppo di Italia Viva alla Camera dei Deputati, che oggi ha incontrato a Roma i [&hellip;]","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/confesercenti-incontra-boschi-imprese-hanno-bisogno-di-sostegni-e-credito\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2021-04-20T16:44:33+00:00","article_modified_time":"2021-04-20T16:44:45+00:00","og_image":[{"width":1360,"height":890,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2021\/01\/Schermata-2021-01-03-alle-15.40.37.png","type":"image\/png"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/confesercenti-incontra-boschi-imprese-hanno-bisogno-di-sostegni-e-credito\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/confesercenti-incontra-boschi-imprese-hanno-bisogno-di-sostegni-e-credito\/","name":"Confesercenti incontra Boschi, \"Imprese hanno bisogno di sostegni e credito -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/confesercenti-incontra-boschi-imprese-hanno-bisogno-di-sostegni-e-credito\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/confesercenti-incontra-boschi-imprese-hanno-bisogno-di-sostegni-e-credito\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2021\/01\/Schermata-2021-01-03-alle-15.40.37.png","datePublished":"2021-04-20T16:44:33+00:00","dateModified":"2021-04-20T16:44:45+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/confesercenti-incontra-boschi-imprese-hanno-bisogno-di-sostegni-e-credito\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/confesercenti-incontra-boschi-imprese-hanno-bisogno-di-sostegni-e-credito\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/confesercenti-incontra-boschi-imprese-hanno-bisogno-di-sostegni-e-credito\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2021\/01\/Schermata-2021-01-03-alle-15.40.37.png","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2021\/01\/Schermata-2021-01-03-alle-15.40.37.png","width":1360,"height":890},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/confesercenti-incontra-boschi-imprese-hanno-bisogno-di-sostegni-e-credito\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"Confesercenti incontra Boschi, &#8220;Imprese hanno bisogno di sostegni e credito"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/5765"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=5765"}],"version-history":[{"count":2,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/5765\/revisions"}],"predecessor-version":[{"id":5767,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/5765\/revisions\/5767"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/5002"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=5765"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=5765"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=5765"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}